{"id":1542,"date":"2023-06-20T01:57:35","date_gmt":"2023-06-20T01:57:35","guid":{"rendered":"https:\/\/gearboxes-worm.top\/china-12mm-mini-coreless-dc-motor-with-brush-50rpm-60rpm-1-5v-2v-2-5v-3v-3-7v-6v-brushed-mini-coreless-metal-gear-motor-for-smart-home-worm-gearbox-design\/"},"modified":"2023-06-20T01:57:35","modified_gmt":"2023-06-20T01:57:35","slug":"china-12mm-mini-coreless-dc-motor-with-brush-50rpm-60rpm-1-5v-2v-2-5v-3v-3-7v-6v-brushed-mini-coreless-metal-gear-motor-for-smart-home-worm-gearbox-design","status":"publish","type":"post","link":"https:\/\/gearboxes-worm.top\/as\/china-12mm-mini-coreless-dc-motor-with-brush-50rpm-60rpm-1-5v-2v-2-5v-3v-3-7v-6v-brushed-mini-coreless-metal-gear-motor-for-smart-home-worm-gearbox-design\/","title":{"rendered":"\u09ac\u09cd\u09f0\u09be\u099b\u09f0 \u09b8\u09c8\u09a4\u09c7 12MM \u09ae\u09bf\u09a8\u09bf \u0995\u09cb\u09f0\u09b2\u09c7\u099b \u09a1\u09bf\u099a\u09bf \u09ae\u099f\u09f0 50Rpm 60Rpm 1.5V 2V 2.5V 3V 3.7V 6V \u09ac\u09cd\u09f0\u09be\u099b \u0995\u09f0\u09be \u09ae\u09bf\u09a8\u09bf \u0995\u09cb\u09f0\u09b2\u09c7\u099b \u09ae\u09c7\u099f\u09be\u09b2 \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09ae\u099f\u09f0 \u09b8\u09cd\u09ae\u09be\u09f0\u09cd\u099f \u09b9\u09cb\u09ae \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09a1\u09bf\u099c\u09be\u0987\u09a8\u09f0 \u09ac\u09be\u09ac\u09c7"},"content":{"rendered":"<p>\u09f1\u09be\u09f0\u09c7\u09a3\u09cd\u099f\u09c0: \u09e9\u09ae\u09be\u09b9-\u09e7\u09ac\u099b\u09f0<br \/>\u09a1\u09bf\u099c\u09be\u0987\u09a8\u09f0 \u09aa\u09f0\u09bf\u09ae\u09be\u09a3: \u099c\u09bf\u098f\u09ae\u09e8\u09ea-\u09e7\u09e8\u09e8\u09e7<br \/>\u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0: \u09a8\u09be\u0993, \u09ac\u09be\u09b9\u09a8, \u09b8\u09ae\u09cd\u09aa\u09a4\u09cd\u09a4\u09bf\u09f0 \u09b8\u0981\u099c\u09c1\u09b2\u09bf, \u09aa\u09cd\u09f0\u09b8\u09be\u09a7\u09a8 \u09af\u09a8\u09cd\u09a4\u09cd\u09f0, \u09b8\u09cd\u09ae\u09be\u09f0\u09cd\u099f \u09b8\u09ae\u09cd\u09aa\u09a4\u09cd\u09a4\u09bf, \u09b8\u09cd\u09ac\u09be\u09b8\u09cd\u09a5\u09cd\u09af\u09b8\u09c7\u09f1\u09be\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0<br \/>\u099b\u09f0\u09cd\u099f: \u09ae\u09bf\u09a8\u09bf \u0995\u09cb\u09f0\u09b2\u09c7\u099b \u0995\u099f\u09f0, \u09ae\u09bf\u09a8\u09bf \u0995\u09cb\u09f0\u09b2\u09c7\u099b \u0995\u099f\u09f0<br \/>\u099f\u09f0\u09cd\u0995: \u09e9\u09ed\u0997\u09cd\u09f0\u09be\u09ae.\u099a\u09c7.\u09ae\u09bf<br \/>\u09ac\u09bf\u09b2\u09cd\u09a1\u09bf\u0982: \u09a6\u09c0\u09f0\u09cd\u0998\u09ae\u09cd\u09af\u09be\u09a6\u09c0 \u099a\u09c1\u09ae\u09cd\u09ac\u0995<br \/>\u0995\u09ae\u09bf\u0989\u099f\u09c7\u099a\u09a8: \u09ac\u09cd\u09f0\u09be\u099b<br \/>\u09b8\u09c1\u09f0\u0995\u09cd\u09b7\u09be \u09ac\u09c8\u09b6\u09bf\u09b7\u09cd\u099f\u09cd\u09af: \u09b8\u09ae\u09cd\u09aa\u09c2\u09f0\u09cd\u09a3\u09f0\u09c2\u09aa\u09c7 \u0986\u09ac\u09a6\u09cd\u09a7<br \/>\u09ac\u09c7\u0997(\u0986\u09f0 \u09aa\u09bf \u098f\u09ae): \u09ea\u09e6~\u09e7\u09ee\u09e6 \u0986\u09f0 \u09aa\u09bf \u098f\u09ae<br \/>\u09b7\u09cd\u099f\u09c7\u09a1\u09bf \u09aa\u09cd\u09f0\u09c7\u099c\u09c7\u09a3\u09cd\u099f(A): 20mA<br \/>\u0995\u09be\u09f0\u09cd\u09af\u09cd\u09af\u0995\u09cd\u09b7\u09ae\u09a4\u09be: \u09ec\u09eb~\u09ee\u09eb\u09e7\u099f\u09bf\u09aa\u09bf\u09e9\u099f\u09bf<br \/>\u0998\u09c2\u09f0\u09cd\u09a3\u09a8\u09f0 \u09a6\u09bf\u09b6: CW\/CCW<br \/>\u09a8\u09cb-\u09b2\u09cb\u09a1 \u0997\u09a4\u09bf: \u099a\u09b2\u09cd\u09b2\u09bf\u09b6~\u09e7\u09ee\u09e6\u09eb\u09e6\u0986\u09f0\u09aa\u09bf\u098f\u09ae<br \/>\u09f0\u09c7\u099f\u09bf\u0982 \u09ac\u09c7\u0997: 30 ~ 1800RPM<br \/>\u09f0\u09c7\u099f\u09c7\u09a1 \u099f\u09f0\u09cd\u0995: .01 ~ 37g.cm<br \/>\u09ae\u099f\u09f0\u09f0 \u09ae\u09be\u09a4\u09cd\u09f0\u09be: \u09e7\u09e8\u09ae\u09bf\u09ae\u09bf*\u09e8\u09e7\u09ae\u09bf\u09ae\u09bf<br \/>\u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09ae\u09be\u09a4\u09cd\u09f0\u09be: \u09e8\u09ea\u09ae\u09bf\u09ae\u09bf*\u09e7\u09e6\u09ae\u09bf\u09ae\u09bf*\u09ef\u09ae\u09bf\u09ae\u09bf<br \/>\u09aa\u09cd\u09f0\u09ae\u09be\u09a3\u09c0\u0995\u09f0\u09a3: RoHS, ISO9001<br \/>\u09aa\u09c7\u0995\u09c7\u099c\u09bf\u0982\u09f0 \u09ac\u09bf\u09f1\u09f0\u09a3: \u09b8\u09be\u09a7\u09be\u09f0\u09a3 \u0995\u09be\u09f0\u09cd\u099f\u09a8 \u0986\u09f0\u09c1 \u09ab\u09c7\u09a8\u09f0 \u0993\u09aa\u09f0\u09a4 \u0997\u09a3\u09a8\u09be \u0995\u09f0\u0995<br \/>\u09ac\u09a8\u09cd\u09a6\u09f0: \u09b9\u09be\u0982\u099d\u09cc<\/p>\n<p><font>\u0986\u09ae\u09be\u09f0 \u0995\u09be\u09b7\u09cd\u099f\u09ae\u09be\u0987\u099c\u09a1 \u09b8\u09ae\u09be\u09a7\u09be\u09a8\u09b8\u09ae\u09c2\u09b9 \u09b9'\u09b2:<\/font> \u09ac\u09cd\u09af\u09f1\u09b8\u09be\u09af\u09bc\u09bf\u0995 \u09b8\u09be\u09ae\u0997\u09cd\u09f0\u09c0\u09f0 \u09ac\u09bf\u09f1\u09f0\u09a3 <font>\u09ac\u09cd\u09f0\u09be\u099b\u09f0 \u09b8\u09c8\u09a4\u09c7 12MM \u09ae\u09bf\u09a8\u09bf \u0995\u09cb\u09f0\u09b2\u09c7\u099b \u09a1\u09bf\u099a\u09bf \u09ae\u099f\u09f0 50Rpm 60Rpm 1.5V 2V 2.5V 3V 3.7V 6V \u09ac\u09cd\u09f0\u09be\u099b \u0995\u09f0\u09be \u09ae\u09bf\u09a8\u09bf \u0995\u09cb\u09f0\u09b2\u09c7\u099b \u09ae\u09c7\u099f\u09be\u09b2\u09bf\u0995 \u09b8\u0981\u099c\u09c1\u09b2\u09bf \u09ae\u099f\u09f0 \u09b8\u09cd\u09ae\u09be\u09f0\u09cd\u099f \u09b9\u09cb\u09ae\u09f0 \u09ac\u09be\u09ac\u09c7<\/font> <table><tr><td colspan=\"3\" rowspan=\"1\">\u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09ae\u099f\u09f0 \u099c\u099f\u09bf\u09b2 \u09a4\u09a5\u09cd\u09af<\/td><td rowspan=\"0\"><\/td><td rowspan=\"0\"><\/td><td colspan=\"7\" rowspan=\"1\"><\/td><td rowspan=\"0\"><\/td><td rowspan=\"0\"><\/td><td rowspan=\"0\"><\/td><td rowspan=\"0\"><\/td><td rowspan=\"0\"><\/td><td rowspan=\"0\"><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">\u09f0\u09bf\u09a1\u09c1\u09ad\u099a\u09a8 rtio<\/td><td colspan=\"1\" rowspan=\"1\"><\/td><td colspan=\"1\" rowspan=\"1\">26<\/td><td colspan=\"1\" rowspan=\"1\">50<\/td><td colspan=\"1\" rowspan=\"1\">110<\/td><td colspan=\"1\" rowspan=\"1\">293<\/td><td colspan=\"1\" rowspan=\"1\">350<\/td><td colspan=\"1\" rowspan=\"1\">380<\/td><td colspan=\"1\" rowspan=\"1\">500<\/td><td colspan=\"1\" rowspan=\"1\">250<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">\u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u0986\u0995\u09be\u09f0<\/td><td colspan=\"1\" rowspan=\"1\">\u09ae\u09bf.\u09ae\u09bf<\/td><td colspan=\"1\" rowspan=\"1\">10<\/td><td colspan=\"1\" rowspan=\"1\">10<\/td><td colspan=\"1\" rowspan=\"1\">10<\/td><td colspan=\"1\" rowspan=\"1\">10<\/td><td colspan=\"1\" rowspan=\"1\">10<\/td><td colspan=\"1\" rowspan=\"1\">10<\/td><td colspan=\"1\" rowspan=\"1\">10<\/td><td colspan=\"1\" rowspan=\"1\">10<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">\u09a8\u09cb-\u09b2\u09cb\u09a1 \u09aa\u09c7\u099a<\/td><td colspan=\"1\" rowspan=\"1\">\u0986\u09f0 \u09aa\u09bf \u098f\u09ae<\/td><td colspan=\"1\" rowspan=\"1\">288<\/td><td colspan=\"1\" rowspan=\"1\">150<\/td><td colspan=\"1\" rowspan=\"1\">68<\/td><td colspan=\"1\" rowspan=\"1\">26<\/td><td colspan=\"1\" rowspan=\"1\">21<\/td><td colspan=\"1\" rowspan=\"1\">20<\/td><td colspan=\"1\" rowspan=\"1\">15<\/td><td colspan=\"1\" rowspan=\"1\">30<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">\u09f0\u09c7\u099f\u09c7\u09a1 \u09b8\u09cd\u09aa\u09c0\u09a1<\/td><td colspan=\"1\" rowspan=\"1\">\u0986\u09f0 \u09aa\u09bf \u098f\u09ae<\/td><td colspan=\"1\" rowspan=\"1\">259.9<\/td><td colspan=\"1\" rowspan=\"1\">135.2<\/td><td colspan=\"1\" rowspan=\"1\">61.4<\/td><td colspan=\"1\" rowspan=\"1\">23.1<\/td><td colspan=\"1\" rowspan=\"1\">\u09e7\u09ef.\u09a4\u09bf\u09a8\u09bf<\/td><td colspan=\"1\" rowspan=\"1\">\u09e7\u09ed.\u0986\u09a0<\/td><td colspan=\"1\" rowspan=\"1\">13.5<\/td><td colspan=\"1\" rowspan=\"1\">27.<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">\u09f0\u09c7\u099f\u09c7\u09a1 \u099f\u09f0\u09cd\u0995<\/td><td colspan=\"1\" rowspan=\"1\">\u0995\u09c7\u099c\u09bf.\u099a\u09c7.\u09ae\u09bf<\/td><td colspan=\"1\" rowspan=\"1\">0.019<\/td><td colspan=\"1\" rowspan=\"1\">0.037<\/td><td colspan=\"1\" rowspan=\"1\">0.082<\/td><td colspan=\"1\" rowspan=\"1\">0.220<\/td><td colspan=\"1\" rowspan=\"1\">0.260<\/td><td colspan=\"1\" rowspan=\"1\">0.286<\/td><td colspan=\"1\" rowspan=\"1\">0.377<\/td><td colspan=\"1\" rowspan=\"1\">0.180<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Max.momentarytolerance \u099f\u09f0\u09cd\u0995<\/td><td colspan=\"1\" rowspan=\"1\">\u0995\u09c7\u099c\u09bf.\u099a\u09c7.\u09ae\u09bf<\/td><td colspan=\"1\" rowspan=\"1\">\u09e6.\u09b8\u09be\u09a4\u09aa\u099e\u09cd\u099a\u09be\u09b6<\/td><td colspan=\"1\" rowspan=\"1\">1.09<\/td><td colspan=\"1\" rowspan=\"1\">\u09e8.\u099a\u09b2\u09cd\u09b2\u09bf\u09b6<\/td><td colspan=\"1\" rowspan=\"1\">6.41<\/td><td colspan=\"1\" rowspan=\"1\">7.66<\/td><td colspan=\"1\" rowspan=\"1\">8.31<\/td><td colspan=\"1\" rowspan=\"1\">\u09e7\u09e6.\u09a8\u09ac\u09cd\u09ac\u09c8<\/td><td colspan=\"1\" rowspan=\"1\">\u09eb.\u09b8\u09be\u09a4\u099a\u09b2\u09cd\u09b2\u09bf\u09b6<\/td><\/tr><\/table> \u098f\u09aa\u09cd\u09b2\u09bf\u0995\u09c7\u099a\u09a8 \u0995\u09cd\u09f0\u09c7\u09a4\u09be\u09f0 \u09ae\u09a4\u09be\u09ae\u09a4 <font> <font> \u0986\u09ae\u09be\u09f0 \u0995\u09cd\u09b2\u09be\u09af\u09bc\u09c7\u09a8\u09cd\u099f\u09b8\u0995\u09b2\u09c7 \u0986\u09ae\u09be\u09f0 \u09aa\u09cd\u09f0\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u09ae\u09be\u09a8\u09a6\u09a3\u09cd\u09a1\u0995 \u0997\u09a3\u09cd\u09af \u0995\u09f0\u09bf\u099b\u09c7, \u0986\u09f0\u09c1 \u0986\u09ae\u09be\u09f0 \u09b8\u09ae\u09af\u09bc\u09ae\u09a4\u09c7 \u0995\u09be\u09f0\u09cd\u0997\u09cb \u0986\u09f0\u09c1 \u09b8\u09c7\u09f1\u09be\u0995 \u0986\u09ae\u09be\u09f0 \u0995\u09cd\u09f0\u09c7\u09a4\u09be\u09b8\u0995\u09b2\u09c7 \u0985\u09a4\u09bf\u09b6\u09af\u09bc \u09aa\u09cd\u09f0\u09b6\u0982\u09b8\u09be \u0995\u09f0\u09bf\u099b\u09c7\u0964<\/font><\/font> '\u0986\u09ae\u09bf \u09ae\u09be\u0987\u0995\u09cd\u09f0' \u09ae\u099f\u09f0, \u09a1\u09bf\u099a\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09ae\u099f\u09f0, \u09b7\u09cd\u099f\u09c7\u09aa\u09be\u09f0 \u09b8\u0981\u099c\u09c1\u09b2\u09bf \u09ae\u099f\u09f0, \u0997\u09cd\u09f0\u09b9\u09f0 \u09b8\u0981\u099c\u09c1\u09b2\u09bf \u09ae\u099f\u09f0, \u0986\u09f0\u09c1 \u09ac\u09b9\u09c1\u09a4\u09cb \u0989\u09ce\u09aa\u09be\u09a6\u09a8\u09a4 \u09ac\u09bf\u09b6\u09c7\u09b7\u099c\u09cd\u099e IOS9001 \u0985\u09a8\u09c1\u099c\u09cd\u099e\u09be\u09aa\u09a4\u09cd\u09f0\u09aa\u09cd\u09f0\u09be\u09aa\u09cd\u09a4 \u09aa\u09cd\u09f0\u09a4\u09bf\u09b7\u09cd\u09a0\u09be\u09a8\u0964 \u0986\u09ae\u09a6\u09be\u09a8\u09bf\u0995\u09c3\u09a4 WAHLI \u09ae\u09c7\u099a\u09bf\u09a8\u09f0 \u09b8\u09c8\u09a4\u09c7, \u09eb\u09ec \u099c\u09a8 \u0995\u09f0\u09cd\u09ae\u099a\u09be\u09f0\u09c0\u09f0 \u09b2\u09c7\u09a5, \u09af\u09be\u09f0 \u09ad\u09bf\u09a4\u09f0\u09a4 \u098f\u0987 \u09aa\u09cd\u09b2\u09c7\u099f\u09b8\u09ae\u09c2\u09b9 \u099c\u09be\u09aa\u09be\u09a8 \u0986\u09f0\u09c1 ZheJiang \u09f0 \u09aa\u09f0\u09be \u0986\u09ae\u09a6\u09be\u09a8\u09bf \u0995\u09f0\u09be \u09b9\u09af\u09bc, \u09a4\u09ce\u0995\u09cd\u09b7\u09a3\u09be\u09a4 \u09b9\u09ac\u09bf\u0982 \u0995\u09f0\u09be \u09b8\u0981\u099c\u09c1\u09b2\u09bf\u09b8\u09ae\u09c2\u09b9\u09c7 \u0986\u09ae\u09be\u09f0 \u0995\u09cd\u09f0\u09c7\u09a4\u09be\u09b8\u0995\u09b2\u0995 \u09a8\u09a4\u09c1\u09a8 \u09aa\u09a3\u09cd\u09af \u0989\u09a8\u09cd\u09a8\u09a4\u09bf\u09f0 \u09ac\u09be\u09ac\u09c7 \u09a6\u0995\u09cd\u09b7 \u09b8\u09c7\u09f1\u09be \u09aa\u09cd\u09f0\u09af\u09c1\u0995\u09cd\u09a4\u09bf\u0997\u09a4 \u0989\u09a6\u09cd\u09ad\u09be\u09f1\u09a8 \u09aa\u09cd\u09f0\u09a6\u09be\u09a8 \u0995\u09f0\u09c7, \u09af\u09bf\u09af\u09bc\u09c7 \u0986\u09aa\u09cb\u09a8\u09be\u09f0 \u09ac\u09be\u09ac\u09c7 \u09ac\u09bf\u09ad\u09bf\u09a8\u09cd\u09a8 \u099c\u099f\u09bf\u09b2 \u09b8\u09ae\u09b8\u09cd\u09af\u09be \u09b8\u09ae\u09be\u09a7\u09be\u09a8 \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09c7\u0964 \u09ae\u09cb\u09f0 \u09a1\u09be\u0999\u09f0 \u099a\u09bf\u09b7\u09cd\u099f\u09c7\u09ae \u0986\u099b\u09c7, \u0995\u09f0\u09cd\u09ae\u09c0\u09b8\u0995\u09b2\u09c7 \u09aa\u09cd\u09f0\u099c\u09a8\u09cd\u09ae \u09aa\u09a6\u09cd\u09a7\u09a4\u09bf \u0995\u09a0\u09cb\u09f0\u09ad\u09be\u09f1\u09c7 \u09ae\u09be\u09a8\u09bf \u099a\u09b2\u09c7, \u0986\u09f0\u09c1 \u0989\u099a\u09cd\u099a\u09ae\u09be\u09a8\u09f0 \u09aa\u09f0\u09bf\u09a6\u09f0\u09cd\u09b6\u09a8 \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u0995\u09be\u09f0\u09bf\u0995\u09f0\u09c0 \u0995\u09f0\u09cd\u09ae\u09c0 \u0986\u099b\u09c7\u0964 \u09b8\u09ae\u09be\u09a7\u09be\u09a8 \u09aa\u09f0\u09bf\u09a6\u09f0\u09cd\u09b6\u09a8\u09a4 \u0989\u09a4\u09cd\u09a4\u09c0\u09f0\u09cd\u09a3 \u09b9\u09c8\u099b\u09c7 \u0986\u09f0\u09c1 \u0986\u0997\u09ac\u09a2\u09bc\u09be\u09ac \u09aa\u09be\u09f0\u09bf\u0964 'TS2C Clamp type curved jaw coupling Sizzling Sale Manufacturing unit \u09ae\u09c2\u09b2\u09cd\u09af \u099f\u09c7\u0997 \u09b8\u09cd\u09ac\u09be\u09ad\u09be\u09f1\u09bf\u0995 \u099c\u09cb\u0996-\u09ae\u09be\u0996 \u0985\u09ad\u09bf\u09af\u09cb\u099c\u09bf\u09a4 \u0996\u09be\u09a6 \u09b8\u0982\u09af\u09cb\u0997\u0995\u09be\u09f0\u09c0 \u0995\u09be\u09aa\u09b2\u09bf\u0982 \u0995\u09cb\u09ae\u09cd\u09aa\u09be\u09a8\u09c0 \u09b6\u09c0\u09f0\u09cd\u09b7 \u09ae\u09be\u09a8\u09a6\u09a3\u09cd\u09a1 \u09aa\u09cd\u09f0\u09a5\u09ae, \u09aa\u09cd\u09f0\u09af\u09c1\u0995\u09cd\u09a4\u09bf\u0997\u09a4 \u09aa\u09f0\u09bf\u09b6\u09cb\u09a7\u09a8, \u0986\u09f0\u09c1 \u0985\u0996\u09a3\u09cd\u09a1\u09a4\u09be \u09ac\u09cd\u09af\u09f1\u09b8\u09cd\u09a5\u09be\u09aa\u09a8\u09be\u201d, \u0986\u09f0\u09c1 \u0985\u09a7\u09bf\u0995 \u0986\u09f0\u09c1 \u09ac\u09b9\u09c1\u09a4 \u09ac\u09c7\u099b\u09bf \u0995\u09cd\u09f0\u09c7\u09a4\u09be\u0987 \u09a8\u09bf\u09f0\u09cd\u09ac\u09be\u099a\u09bf\u09a4 \u0986\u09f0\u09c1 \u09b8\u09cd\u09ac\u09c0\u0995\u09be\u09f0 \u0995\u09f0\u09be \u09b9\u09c8\u099b\u09c7\u0964 \u0986\u09ae\u09bf \u0986\u09aa\u09cb\u09a8\u09be\u09f0 \u09af\u09cb\u0997\u09a6\u09be\u09a8\u09f0 \u09ac\u09be\u09ac\u09c7 CZPT \u09a6\u09c7\u0996\u09be \u09a6\u09bf\u0993\u0981, \u0986\u09f0\u09c1 \u0986\u09ae\u09bf \u0987\u099c\u09a8\u09c7 \u09b8\u09bf\u099c\u09a8\u09f0 \u09b8\u09c8\u09a4\u09c7 \u09ac\u09b9\u09c1\u09a4 \u09ad\u09be\u09b2 \u0985\u0982\u09b6\u09c0\u09a6\u09be\u09f0\u09bf\u09a4\u09cd\u09ac \u0997\u09a2\u09bc\u09bf \u09a4\u09c1\u09b2\u09bf\u09ae\u0964 1.Common \u09f0\u09aa\u09cd\u09a4\u09be\u09a8\u09bf \u0995\u09be\u09f0\u09cd\u099f\u09a8 \u09ac\u09be Styrofoam \u09ac\u0995\u09cd\u09b8 \u09ac\u09be \u09ab\u09cb\u09b9\u09be Tray2.\u09f0\u09aa\u09cd\u09a4\u09be\u09a8\u09bf \u0995\u09be\u09f0\u09cd\u099f\u09a8 + Pallet 3.As \u0997\u09cd\u09f0\u09be\u09b9\u0995\u09f0 requested4.Port :HangZhou \u09b6\u09bf\u09aa\u09ae\u09c7\u09a8\u09cd\u099f <table><tr><td colspan=\"5\" rowspan=\"1\">\u09b6\u09bf\u09aa\u09bf\u0982 \u09b8\u09ae\u09af\u09bc<\/td><td rowspan=\"0\"><\/td><td rowspan=\"0\"><\/td><td rowspan=\"0\"><\/td><td rowspan=\"0\"><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">DHL:<\/td><td colspan=\"1\" rowspan=\"1\">\u09e9-\u09eb \u0995\u09f0\u09cd\u09ae\u09a6\u09bf\u09a8<\/td><td colspan=\"1\" rowspan=\"1\">\u09ab\u09c7\u09a1\u098f\u0995\u09cd\u09b8<\/td><td colspan=\"2\" rowspan=\"1\">\u09ed-\u09ef \u0995\u09f0\u09cd\u09ae\u09a6\u09bf\u09a8<\/td><td rowspan=\"0\"><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">\u0987\u0989 \u09aa\u09bf \u098f\u099b<\/td><td colspan=\"1\" rowspan=\"1\">\u09e9-\u09eb \u099f\u09be \u0985\u09aa\u09be\u09f0\u09c7\u099f\u09bf\u0982 \u09b8\u09ae\u09af\u09bc<\/td><td colspan=\"1\" rowspan=\"1\">\u0987\u098f\u09ae\u098f\u099b<\/td><td colspan=\"2\" rowspan=\"1\">\u09e7\u09e8-\u09aa\u09cb\u09a8\u09cd\u09a7\u09f0\u099f\u09be \u0995\u09be\u09ae\u09f0 \u09b8\u09ae\u09af\u09bc<\/td><td rowspan=\"0\"><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">\u099f\u09bf\u098f\u09a8\u099f\u09bf<\/td><td colspan=\"1\" rowspan=\"1\">\u09eb-\u09ed \u0995\u09f0\u09cd\u09ae\u09a6\u09bf\u09a8<\/td><td colspan=\"1\" rowspan=\"1\">\u09b8\u09be\u0997\u09f0<\/td><td colspan=\"2\" rowspan=\"1\">\u0995\u09cb\u09a8\u099f\u09cb \u0985\u099e\u09cd\u099a\u09b2\u09b2\u09c8 \u099c\u09be\u09b9\u09be\u099c\u09f0 \u0993\u09aa\u09f0\u09a4 \u09a8\u09bf\u09f0\u09cd\u09ad\u09f0 \u0995\u09f0\u09c7<\/td><td rowspan=\"0\"><\/td><\/tr><tr><td colspan=\"5\" rowspan=\"1\">\u0986\u09b2\u09bf\u09ac\u09be\u09ac\u09be \u09ac\u09cd\u09af\u09f1\u09b8\u09cd\u09a5\u09be\u09a4 \u09ac\u09b9\u09c1\u09a4 \u09ac\u09c7\u099b\u09bf \u09b2\u099c\u09bf\u09b7\u09cd\u099f\u09bf\u0995 \u09ac\u09bf\u0995\u09b2\u09cd\u09aa \u0986\u099b\u09c7, \u0986\u09ae\u09be\u09f0 \u09b8\u09c8\u09a4\u09c7 \u09aa\u09f0\u09c0\u0995\u09cd\u09b7\u09be \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u09b8\u09cd\u09ac\u09be\u0997\u09a4\u09ae<\/td><td rowspan=\"0\"><\/td><td rowspan=\"0\"><\/td><td rowspan=\"0\"><\/td><td rowspan=\"0\"><\/td><\/tr><\/table> FAQ <font>one.\u0986\u09ae\u09bf \u0995\u09cb\u09a8?<\/font>\u0986\u09ae\u09bf ZheJiang \u09a4 \u09ad\u09bf\u09a4\u09cd\u09a4\u09bf \u0995\u09f0\u09bf , \u099a\u09c0\u09a8, 2571 \u09f0 \u09aa\u09f0\u09be \u0986\u09f0\u09ae\u09cd\u09ad, \u0998\u09f0\u09c1\u09f1\u09be \u09ac\u099c\u09be\u09f0\u09b2\u09c8 \u0989\u09a8\u09cd\u09a8\u09c0\u09a4(\u09a4\u09c7\u09f0\u09aa\u099e\u09cd\u099a\u09be\u09b6.00%),\u0989\u09a4\u09cd\u09a4\u09f0 \u0986\u09ae\u09be\u09f0(35.00%),\u09a6\u0995\u09cd\u09b7\u09bf\u09a3\u0986\u09ae\u09c7\u09f0\u09bf\u0995\u09be(10.00%),\u09a6\u0995\u09cd\u09b7\u09bf\u09a3-\u09aa\u09c2\u09ac \u098f\u099b\u09bf\u09af\u09bc\u09be(2.00%). \u0986\u09ae\u09be\u09f0 \u0995\u09f0\u09cd\u09ae\u09b8\u09cd\u09a5\u09b2\u09c0\u09a4 \u09b8\u09be\u09ae\u0997\u09cd\u09f0\u09bf\u0995\u09ad\u09be\u09f1\u09c7 \u09aa\u09cd\u09f0\u09be\u09af\u09bc \u09eb\u09e7-\u09e7\u09e6\u09e6 \u099c\u09a8 \u09ac\u09cd\u09af\u0995\u09cd\u09a4\u09bf \u0986\u099b\u09c7\u0964<font><\/font><font>\u09e8\/ \u0986\u09ae\u09bf \u0995\u09c7\u09a8\u09c7\u0995\u09c8 \u09b6\u09c0\u09f0\u09cd\u09b7 \u09ae\u09be\u09a8\u09f0 \u09a8\u09bf\u09b6\u09cd\u099a\u09af\u09bc\u09a4\u09be \u09a6\u09bf\u09ac \u09aa\u09be\u09f0\u09cb?<\/font>\u09b8\u09be\u09a7\u09be\u09f0\u09a3\u09a4\u09c7 \u0997\u09a3 \u0989\u09ce\u09aa\u09be\u09a6\u09a8\u09f0 \u0986\u0997\u09a4\u09c7 \u098f\u099f\u09be \u09aa\u09cd\u09f0\u09bf-\u099c\u09c7\u09a8\u09c7\u09f0\u09c7\u099a\u09a8 \u09a8\u09ae\u09c1\u09a8\u09be\u09b8\u09a6\u09be\u09af\u09bc \u09ae\u09be\u09b2\u09ac\u09be\u09b9\u09c0 \u09b8\u09be\u09ae\u0997\u09cd\u09f0\u09c0\u09f0 \u0986\u0997\u09a4\u09c7 \u09b6\u09c7\u09b7 \u09aa\u09f0\u09bf\u09a6\u09f0\u09cd\u09b6\u09a8<font>3.\u0986\u09aa\u09c1\u09a8\u09bf \u0986\u09ae\u09be\u09f0 \u09aa\u09f0\u09be \u0995\u09bf \u0995\u09cd\u09f0\u09af\u09bc \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09c7?<\/font>\u0997\u09cd\u09f0\u09b9\u09f0 \u09a1\u09bf\u099a\u09bf \u09b8\u0981\u099c\u09c1\u09b2\u09bf \u09ae\u099f\u09f0,steppr \u09ae\u099f\u09f0,\u09ac\u09cd\u09f0\u09be\u099b\u09b2\u09c7\u099b \u09ae\u099f\u09f0,\u0995\u09c3\u09ae\u09bf \u09b8\u0981\u099c\u09c1\u09b2\u09bf \u09ae\u099f\u09f0,\u09aa\u09cd\u09b2\u09be\u09b7\u09cd\u099f\u09bf\u0995 \u0997\u09cd\u09f0\u09b9\u09f0 \u09ae\u099f\u09f0<font>\u099a\u09be\u09f0\u09bf\u099f\u09be\u0964 \u0986\u09aa\u09c1\u09a8\u09bf \u0995\u09bf\u09af\u09bc \u0986\u09a8 \u09af\u09cb\u0997\u09be\u09a8\u0995\u09be\u09f0\u09c0\u09f0 \u09aa\u09f0\u09be \u09a8\u09b9\u09af\u09bc \u0986\u09ae\u09be\u09f0 \u09aa\u09f0\u09be \u0995\u09bf\u09a8\u09be \u0989\u099a\u09bf\u09a4?<\/font>\u0986\u09ae\u09be\u09f0 \u09ae\u099f\u09f0\u09b8\u09ae\u09c2\u09b9 \u09b8\u09c1\u09b8\u09cd\u09a5\u09bf\u09f0 \u09b8\u09be\u09ae\u0997\u09cd\u09f0\u09bf\u0995 \u09aa\u09f0\u09bf\u09f1\u09c7\u09b6\u09a8, \u0995\u09c7\u099a\u09bf \u099a\u09c7\u0987\u09a8 \u09b8\u09cd\u09aa\u09cd\u09f0\u0995\u09c7\u099f \u0995\u09be\u09aa\u09b2\u09bf\u0982 \u09aa\u09cd\u09f0\u09af\u09cb\u099c\u0995 \u09b6\u09be\u09a8\u09cd\u09a4\u09bf\u09aa\u09c2\u09f0\u09cd\u09a3, \u0989\u099a\u09cd\u099a \u099f\u09f0\u09cd\u0995, \u0995\u09ae \u09b6\u0995\u09cd\u09a4\u09bf \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0986\u09f0\u09c1 \u0995\u09c7\u0987\u09ac\u09be\u099f\u09be\u0993 sizesoptions \u09b8\u09b9 \u09b8\u09cd\u09a5\u09bf\u09a4\u09bf\u09b8\u09cd\u09a5\u09be\u09aa\u0995 \u09b9'\u09ac\u09b2\u09c8 \u09b8\u09c3\u09b7\u09cd\u099f\u09bf \u0995\u09f0\u09be \u09b9\u09af\u09bc.<font>\u09aa\u09be\u0981\u099a\u0964 \u0986\u09ae\u09bf \u0995\u09bf \u09b8\u09c7\u09f1\u09be \u09a6\u09bf\u09ac \u09aa\u09be\u09f0\u09cb?<\/font>\u09b8\u09cd\u09ac\u09c0\u0995\u09c3\u09a4\u09bf\u09aa\u09cd\u09f0\u09be\u09aa\u09cd\u09a4 \u09af\u09cb\u0997\u09be\u09a8\u09f0 \u099a\u09f0\u09cd\u09a4: FOB,CFR,CIF,EXW,CIP;\u0997\u09cd\u09f0\u09b9\u09a3 \u0995\u09f0\u09be \u09aa\u09c7\u09ae\u09c7\u09a8\u09cd\u099f \u09ae\u09c1\u09a6\u09cd\u09f0\u09be:USD,EUR,JPY,CAD,AUD,HKD,GBP,CNYAccepted \u09aa\u09c7\u09ae\u09c7\u09a8\u09cd\u099f \u09b8\u099c\u09be\u0987 \u09a4\u09cb\u09b2\u09be: T\/T,L\/C,\u0995\u09cd\u09f0\u09c7\u09a1\u09bf\u099f \u09f0\u09c7\u099f\u09bf\u0982 \u0995\u09be\u09f0\u09cd\u09a1,PayPal,\u09f1\u09c7\u09b7\u09cd\u099f\u09be\u09f0\u09cd\u09a3 \u0987\u0989\u09a8\u09bf\u09af\u09bc\u09a8 \u099f\u09c7\u0987\u09b2\u09be\u09f0\u09a1 \u09a1\u09be\u09ac\u09b2 CZPT \u09af\u09cb\u0997\u09a6\u09be\u09a8 \u0987\u09b2\u09be\u09b7\u09cd\u099f\u09bf\u0995 \u09a1\u09bf\u09b8\u09cd\u0995 \u0995\u09be\u09aa\u09b2\u09bf\u0982 \u09aa\u0981\u099a\u09be\u09b2\u09cd\u09b2\u09bf\u09b6# \u09a7\u09be\u09a4\u09c1 \u09a1\u09be\u09af\u09bc\u09c7\u09ab\u09cd\u09f0\u09be\u09ae \u0996\u09be\u09a6 \u09b8\u0982\u09af\u09cb\u0997\u0995\u09be\u09f0\u09c0 \u09b9\u099f \u09ac\u09bf\u0995\u09cd\u09f0\u09c0 \u09ad\u09be\u09b7\u09be \u0995\u09a5\u09bf\u09a4:\u0987\u0982\u09f0\u09be\u099c\u09c0, \u099a\u09c0\u09a8\u09be<\/p>\n<p><p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/T_worm_reducer_1.webp\" alt=\"worm reducer\" width=\"800\" \/><\/p>\n<h2>\u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u0995\u09bf?<\/h2>\n<p>\u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09b9\u09c8\u099b\u09c7 \u098f\u099f\u09be \u09af\u09be\u09a8\u09cd\u09a4\u09cd\u09f0\u09bf\u0995 \u09af\u09a8\u09cd\u09a4\u09cd\u09f0 \u09af\u09bf\u09af\u09bc\u09c7 \u0998\u09c2\u09f0\u09cd\u09a3\u09a8\u09b6\u09c0\u09b2 \u0996\u09be\u09a6\u09f0 \u0997\u09a4\u09bf \u09b9\u09cd\u09f0\u09be\u09b8 \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u0986\u09f0\u09c1 \u0995\u09c3\u09ae\u09bf \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09c7\u0964 \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09c7 \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u0985\u09a8\u09c1\u09aa\u09be\u09a4 \u0985\u09a8\u09c1\u09b8\u09f0\u09bf \u0987\u099e\u09cd\u099c\u09bf\u09a8\u09f0 \u0986\u0989\u099f\u09aa\u09c1\u099f \u099f\u09f0\u09cd\u0995 \u09ac\u09c3\u09a6\u09cd\u09a7\u09bf \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09c7\u0964 \u098f\u0987 \u09a7\u09f0\u09a3\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u09ac\u09c8\u09b6\u09bf\u09b7\u09cd\u099f\u09cd\u09af \u09b9\u09c8\u099b\u09c7 \u0987\u09af\u09bc\u09be\u09f0 \u09a8\u09ae\u09a8\u09c0\u09af\u09bc\u09a4\u09be \u0986\u09f0\u09c1 \u0995\u09ae\u09aa\u09c7\u0995\u09cd\u099f \u0986\u0995\u09be\u09f0\u0964 \u0987\u09af\u09bc\u09be\u09f0 \u0989\u09aa\u09f0\u09bf\u0993 \u0987 \u09a1\u09cd\u09f0\u09be\u0987\u09ad\u09f0 \u09b6\u0995\u09cd\u09a4\u09bf \u0986\u09f0\u09c1 \u0995\u09be\u09f0\u09cd\u09af\u0995\u09cd\u09b7\u09ae\u09a4\u09be \u09ac\u09c3\u09a6\u09cd\u09a7\u09bf \u0995\u09f0\u09c7\u0964<\/p>\n<h2>\u09ab\u09c1\u099f\u09be \u0996\u09be\u09a6 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8<\/h2>\n<p>\u09ab\u09c1\u099f\u09be \u0996\u09be\u09a6 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09b9\u09c8\u099b\u09c7 \u09ac\u09bf\u09ad\u09bf\u09a8\u09cd\u09a8 \u09ae\u099f\u09f0 \u0986\u09f0\u09c1 \u0985\u09a8\u09cd\u09af\u09be\u09a8\u09cd\u09af \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09b8\u0982\u09af\u09cb\u0997 \u0995\u09f0\u09be \u098f\u099f\u09be \u0985\u09a4\u09bf\u09f0\u09bf\u0995\u09cd\u09a4 \u0986\u0989\u099f\u09aa\u09c1\u099f \u0996\u09be\u09a6\u0964 \u0985\u09a8\u09c1\u09ad\u09c2\u09ae\u09bf\u0995 \u09ac\u09be \u0989\u09b2\u09ae\u09cd\u09ac\u09ad\u09be\u09f1\u09c7 \u09b8\u09cd\u09a5\u09be\u09aa\u09a8 \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09bf\u0964 \u0986\u0995\u09be\u09f0 \u0986\u09f0\u09c1 \u09b8\u09cd\u0995\u09c7\u09b2\u09f0 \u0993\u09aa\u09f0\u09a4 \u09a8\u09bf\u09f0\u09cd\u09ad\u09f0 \u0995\u09f0\u09bf \u09ea\u099c\u09bf\u098f\u09a8\u09f0 \u09aa\u09f0\u09be \u09eb\u099c\u09bf\u098f\u0995\u09cd\u09b8\u09b2\u09c8\u0995\u09c7 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u09b8\u09c8\u09a4\u09c7 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09bf\u0964<br \/>\u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09b8\u09be\u09a7\u09be\u09f0\u09a3\u09a4\u09c7 \u09b9\u09c7\u09b2\u09bf\u0995\u09c7\u09b2 \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u09b8\u09c8\u09a4\u09c7 \u09b8\u0982\u09af\u09c1\u0995\u09cd\u09a4\u09ad\u09be\u09f1\u09c7 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09be \u09b9\u09af\u09bc\u0964 \u09aa\u09bf\u099b\u09f0\u099f\u09cb \u09f1\u09f0\u09cd\u09ae \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u0987\u09a8\u09aa\u09c1\u099f \u09ab\u09be\u09b2\u09c7 \u09ae\u09be\u0989\u09a3\u09cd\u099f \u0995\u09f0\u09be \u09b9\u09af\u09bc \u0986\u09f0\u09c1 \u0987 \u0989\u099a\u09cd\u099a \u0986\u0989\u099f\u09aa\u09c1\u099f \u09ae\u099f\u09f0\u09f0 \u0997\u09a4\u09bf \u09b9\u09cd\u09f0\u09be\u09b8 \u0995\u09f0\u09be\u09f0 \u098f\u0995 \u0989\u09a4\u09cd\u09a4\u09ae \u0989\u09aa\u09be\u09af\u09bc\u0964 \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u0995\u09be\u09f0\u09cd\u09af\u0995\u09cd\u09b7\u09ae\u09a4\u09be \u0989\u099a\u09cd\u099a, \u0997\u09a4\u09bf \u0995\u09ae, \u09b6\u09ac\u09cd\u09a6 \u0995\u09ae, \u0995\u09ae\u09cd\u09aa\u09a8 \u0995\u09ae \u0986\u09f0\u09c1 \u09b6\u0995\u09cd\u09a4\u09bf \u0996\u09f0\u099a \u0995\u09ae\u0964<br \/>\u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u0995\u09a0\u09bf\u09a8 \u09a4\u09c0\u0996\u09be \u09ac\u09be \u0985\u09b2\u09cc\u09b9 \u09a7\u09be\u09a4\u09c1\u09f0\u09c7 \u09a8\u09bf\u09f0\u09cd\u09ae\u09bf\u09a4, \u09af\u09be\u09f0 \u09ab\u09b2\u09a4 \u0987\u09af\u09bc\u09be\u09f0 \u0995\u09be\u09f0\u09cd\u09af\u0995\u09cd\u09b7\u09ae\u09a4\u09be \u09ac\u09c3\u09a6\u09cd\u09a7\u09bf \u09aa\u09be\u09af\u09bc\u0964 \u0995\u09bf\u09a8\u09cd\u09a4\u09c1 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u09cb\u09f0 \u0985\u09ac\u09bf\u09a8\u09be\u09b6\u09c0 \u09a8\u09b9\u09af\u09bc, \u0986\u09f0\u09c1 \u099a\u09b2\u09bf \u09a5\u09be\u0995\u09bf\u09ac \u09a8\u09cb\u09f1\u09be\u09f0\u09bf\u09b2\u09c7 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09a4\u09c7\u09b2 \u09ae\u09f0\u09bf\u099b\u09be \u09ac\u09be \u0987\u09ae\u09be\u09b2\u099a\u09bf\u09ab\u09be\u0987 \u09b9\u2019\u09ac \u09aa\u09be\u09f0\u09c7\u0964 \u0987\u09af\u09bc\u09be\u09f0 \u0995\u09be\u09f0\u09a3 \u09b9\u2019\u09b2 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u0995\u09be\u09ae \u0986\u09f0\u09c1 \u09ac\u09a8\u09cd\u09a7 \u09b9\u09cb\u09f1\u09be\u09f0 \u09b8\u09ae\u09af\u09bc\u09a4 \u09b9\u09cb\u09f1\u09be \u0986\u09f0\u09cd\u09a6\u09cd\u09f0\u09a4\u09be \u0998\u09a8\u09c0\u09ad\u09c2\u09a4\u0995\u09f0\u09a3\u0964 \u0998\u09a8\u09c0\u09ad\u09c2\u09a4\u0995\u09f0\u09a3 \u09f0\u09cb\u09a7 \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u09ac\u09c7\u09af\u09bc\u09be\u09f0\u09bf\u0999\u09f0 \u09b8\u09ae\u09be\u09ac\u09c7\u09b6 \u09aa\u09cd\u09f0\u0995\u09cd\u09f0\u09bf\u09af\u09bc\u09be \u0986\u09f0\u09c1 \u0997\u09c1\u09a3\u0997\u09a4 \u09ae\u09be\u09a8 \u0997\u09c1\u09f0\u09c1\u09a4\u09cd\u09ac\u09aa\u09c2\u09f0\u09cd\u09a3 \u0995\u09be\u09f0\u0995\u0964<br \/>\u09ab\u09c1\u099f\u09be \u0996\u09be\u09a6 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09ac\u09bf\u09ad\u09bf\u09a8\u09cd\u09a8 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u0997\u09a4 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09bf\u0964 \u09b8\u09be\u09a7\u09be\u09f0\u09a3\u09a4\u09c7 \u09ae\u09c7\u099a\u09bf\u09a8 \u099f\u09c1\u09b2, \u09ad\u09c7\u09f0\u09bf\u09af\u09bc\u09c7\u09ac\u09b2 \u09b8\u09cd\u09aa\u09c0\u09a1 \u09a1\u09cd\u09f0\u09be\u0987\u09ad \u0986\u09f0\u09c1 \u0985\u099f\u09cb\u09ae\u09cb\u099f\u09bf\u09ad \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u0997\u09a4 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09be \u09b9\u09af\u09bc\u0964 \u0995\u09bf\u09a8\u09cd\u09a4\u09c1 \u09a7\u09be\u09f0\u09be\u09ac\u09be\u09b9\u09bf\u0995\u09ad\u09be\u09f1\u09c7 \u099a\u09b2\u09cb\u09f1\u09be\u09f0 \u09ac\u09be\u09ac\u09c7 \u0989\u09aa\u09af\u09cb\u0997\u09c0 \u09a8\u09b9\u09af\u09bc\u0964 \u09af\u09a6\u09bf \u0986\u09aa\u09c1\u09a8\u09bf \u098f\u099f\u09be \u09ab\u09c1\u099f\u09be \u0996\u09be\u09a6 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09be\u09f0 \u09aa\u09f0\u09bf\u0995\u09b2\u09cd\u09aa\u09a8\u09be \u0995\u09f0\u09bf\u099b\u09c7, \u09a4\u09c7\u09a8\u09cd\u09a4\u09c7 \u0986\u09aa\u09cb\u09a8\u09be\u09f0 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u099c\u09a8 \u0985\u09a8\u09c1\u09b8\u09f0\u09bf \u09b8\u09a0\u09bf\u0995\u099f\u09cb \u09ac\u09be\u099b\u09bf \u09b2\u09cb\u09f1\u09be\u099f\u09cb \u09a8\u09bf\u09b6\u09cd\u099a\u09bf\u09a4 \u0995\u09f0\u0995\u0964<\/p>\n<h2>\u09a1\u09be\u09ac\u09b2 \u09a5\u09cd\u09f0\u2019\u099f \u09f1\u09f0\u09cd\u09ae \u0997\u09bf\u09af\u09bc\u09be\u09f0<\/h2>\n<p>\u09f1\u09f0\u09cd\u09ae \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09a4 \u0987\u09a8\u09aa\u09c1\u099f \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b9\u09bf\u099a\u09be\u09aa\u09c7 \u09f1\u09f0\u09cd\u09ae \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09be \u09b9\u09af\u09bc\u0964 \u09ac\u09c8\u09a6\u09cd\u09af\u09c1\u09a4\u09bf\u0995 \u09ae\u099f\u09f0 \u09ac\u09be \u09b8\u09cd\u09aa\u09cd\u09f0\u0995\u09c7\u099f\u09c7 \u0995\u09c3\u09ae\u09bf\u099f\u09cb\u0995 \u099a\u09b2\u09be\u09af\u09bc, \u09af\u09bf\u099f\u09cb \u098f\u09a8\u09cd\u099f\u09bf-\u09ab\u09cd\u09f0\u09bf\u0995\u099a\u09a8 \u09f0\u09cb\u09b2\u09be\u09f0 \u09ac\u09c7\u09af\u09bc\u09be\u09f0\u09bf\u0999\u09f0 \u09a6\u09cd\u09ac\u09be\u09f0\u09be \u09b8\u09ae\u09f0\u09cd\u09a5\u09bf\u09a4\u0964 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09a6\u09be\u0981\u09a4\u09a4 \u0985\u09a7\u09bf\u0995 \u0998\u09f0\u09cd\u09b7\u09a3\u09f0 \u09ac\u09be\u09ac\u09c7 \u0995\u09c3\u09ae\u09bf\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u09cb\u09f0 \u09aa\u09f0\u09bf\u09a7\u09be\u09a8 \u09b9\u09cb\u09f1\u09be\u09f0 \u09aa\u09cd\u09f0\u09f1\u09a3\u09a4\u09be \u09a5\u09be\u0995\u09c7\u0964 \u0987\u09af\u09bc\u09be\u09f0 \u09ab\u09b2\u09a4 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u09cb\u09f0\u09f0 \u0986\u09f1\u09a6\u09cd\u09a7 \u09aa\u09c3\u09b7\u09cd\u09a0\u09a4 \u099c\u09be\u09f0\u09a3 \u09b9\u09af\u09bc\u0964<br \/>\u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09aa\u09bf\u099a\u09f0 \u09ac\u09cd\u09af\u09be\u09b8 \u0986\u09f0\u09c1 \u0995\u09be\u09ae\u09f0 \u0997\u09ad\u09c0\u09f0\u09a4\u09be \u0997\u09c1\u09f0\u09c1\u09a4\u09cd\u09ac\u09aa\u09c2\u09f0\u09cd\u09a3\u0964 \u09aa\u09bf\u099a \u09ac\u09c3\u09a4\u09cd\u09a4\u09f0 \u09ac\u09cd\u09af\u09be\u09b8 \u09b9\u2019\u09b2 \u0995\u09c3\u09ae\u09bf \u0986\u09f0\u09c1 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u099c\u09be\u09b2 \u09b9\u09cb\u09f1\u09be \u0995\u09be\u09b2\u09cd\u09aa\u09a8\u09bf\u0995 \u09ac\u09c3\u09a4\u09cd\u09a4\u09f0 \u09ac\u09cd\u09af\u09be\u09b8\u0964 \u0995\u09be\u09ae\u09f0 \u0997\u09ad\u09c0\u09f0\u09a4\u09be \u09b9\u2019\u09b2 \u09ac\u09c7\u0995\u09b2\u09c7\u099b\u09b2\u09c8 \u09ac\u09bf\u09b8\u09cd\u09a4\u09c3\u09a4 \u09b9\u09cb\u09f1\u09be \u0995\u09c3\u09ae\u09bf\u09f0 \u09b8\u09c2\u09a4\u09be\u09f0 \u09b8\u09f0\u09cd\u09ac\u09be\u09a7\u09bf\u0995 \u09aa\u09f0\u09bf\u09ae\u09be\u09a3\u0964 \u09a1\u09bf\u0999\u09bf\u09f0 \u09ac\u09cd\u09af\u09be\u09b8 \u09b9\u2019\u09b2 \u0995\u09c3\u09ae\u09bf\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09ae\u09c1\u0996\u09f0 \u0986\u099f\u09be\u0987\u09a4\u0995\u09c8 \u09a4\u09b2\u09f0 \u09ac\u09bf\u09a8\u09cd\u09a6\u09c1\u09a4 \u09a5\u0995\u09be \u09ac\u09c3\u09a4\u09cd\u09a4\u09f0 \u09ac\u09cd\u09af\u09be\u09b8\u0964<br \/>\u09af\u09c7\u09a4\u09bf\u09af\u09bc\u09be \u0995\u09c3\u09ae\u09bf \u0986\u09f0\u09c1 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09ae\u09be\u099c\u09f0 \u0998\u09f0\u09cd\u09b7\u09a3 \u0995\u09cb\u09a3\u09c7 \u0995\u09c3\u09ae\u09bf\u09f0 \u09b8\u09c0\u09b9\u09f0 \u0995\u09cb\u09a3 \u0985\u09a4\u09bf\u0995\u09cd\u09f0\u09ae \u0995\u09f0\u09c7 \u09a4\u09c7\u09a4\u09bf\u09af\u09bc\u09be \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u099f\u09cb \u09b8\u09cd\u09ac\u09af\u09bc\u0982\u0995\u09cd\u09f0\u09bf\u09af\u09bc\u09ad\u09be\u09f1\u09c7 \u09b2\u0995 \u09b9\u09c8 \u09a5\u09be\u0995\u09c7\u0964 \u098f\u0987 \u09ac\u09c8\u09b6\u09bf\u09b7\u09cd\u099f\u09cd\u09af \u0989\u09a4\u09cd\u09a4\u09cb\u09b2\u09a8 \u09b8\u0981\u099c\u09c1\u09b2\u09bf\u09f0 \u09ac\u09be\u09ac\u09c7 \u0989\u09aa\u09af\u09cb\u0997\u09c0, \u0995\u09bf\u09a8\u09cd\u09a4\u09c1 \u09ac\u09bf\u09aa\u09f0\u09c0\u09a4 \u09b8\u0982\u09ac\u09c7\u09a6\u09a8\u09b6\u09c0\u09b2\u09a4\u09be\u09f0 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u099c\u09a8 \u09b9\u09cb\u09f1\u09be \u09ac\u09cd\u09af\u09f1\u09b8\u09cd\u09a5\u09be\u09aa\u09cd\u09f0\u09a3\u09be\u09b2\u09c0\u09f0 \u09ac\u09be\u09ac\u09c7 \u0995\u09cd\u09b7\u09a4\u09bf\u0995\u09be\u09f0\u0995 \u09b9\u09ac \u09aa\u09be\u09f0\u09c7\u0964 \u098f\u0987 \u09ac\u09cd\u09af\u09f1\u09b8\u09cd\u09a5\u09be\u09b8\u09ae\u09c2\u09b9\u09a4 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09b8\u09ae\u09c2\u09b9\u09f0 \u09b8\u09cd\u09ac-\u09b2\u0995 \u0995\u09f0\u09be\u09f0 \u0995\u09cd\u09b7\u09ae\u09a4\u09be \u098f\u099f\u09be \u09ae\u09c2\u09b2 \u09b8\u09c0\u09ae\u09be\u09ac\u09a6\u09cd\u09a7\u09a4\u09be\u0964<br \/>\u09a1\u09be\u09ac\u09b2 \u09a5\u09cd\u09f0\u2019\u099f \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09c7 \u0995\u09c3\u09ae\u09bf \u0986\u09f0\u09c1 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09ae\u09be\u099c\u09a4 \u0986\u099f\u09be\u0987\u09a4\u0995\u09c8 \u0995\u099f\u0995\u099f\u09c0\u09af\u09bc\u09be \u09b8\u0982\u09af\u09cb\u0997 \u09aa\u09cd\u09f0\u09a6\u09be\u09a8 \u0995\u09f0\u09c7\u0964 \u09b8\u09f0\u09cd\u09ac\u09be\u09a7\u09bf\u0995 \u0995\u09be\u09f0\u09cd\u09af\u0995\u09cd\u09b7\u09ae\u09a4\u09be \u09a8\u09bf\u09b6\u09cd\u099a\u09bf\u09a4 \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b8\u09a0\u09bf\u0995\u09ad\u09be\u09f1\u09c7 \u09b8\u09cd\u09a5\u09be\u09aa\u09a8 \u0995\u09f0\u09bf\u09ac \u09b2\u09be\u0997\u09bf\u09ac\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b8\u09ae\u09be\u09ac\u09c7\u09b6 \u09b8\u09cd\u09a5\u09be\u09aa\u09a8 \u0995\u09f0\u09be\u09f0 \u098f\u099f\u09be \u0989\u09aa\u09be\u09af\u09bc \u09b9\u2019\u09b2 \u098f\u099f\u09be \u0995\u09c0\u09f1\u09c7\u0964 \u0995\u09c0\u09f1\u09c7\u0987 \u0996\u09be\u09a6\u099f\u09cb\u0995 \u0998\u09c2\u09f0\u09bf\u09ac \u09a8\u09cb\u09f1\u09be\u09f0\u09c7, \u09af\u09bf\u099f\u09cb \u099f\u09f0\u09cd\u0995 \u09aa\u09cd\u09f0\u09c7\u09f0\u09a3\u09f0 \u09ac\u09be\u09ac\u09c7 \u0985\u09a4\u09bf \u0997\u09c1\u09f0\u09c1\u09a4\u09cd\u09ac\u09aa\u09c2\u09f0\u09cd\u09a3\u0964 \u09a4\u09be\u09f0 \u09aa\u09bf\u099b\u09a4 \u099b\u09c7\u099f \u09b8\u09cd\u0995\u09cd\u09f0\u09c1 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u099f\u09cb \u09b9\u09be\u09ac\u09f0 \u09b2\u0997\u09a4 \u09b8\u0982\u09b2\u0997\u09cd\u09a8 \u0995\u09f0\u0995\u0964<br \/>\u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u0985\u0995\u09cd\u09b7\u09c0\u09af\u09bc \u0986\u09f0\u09c1 \u09aa\u09f0\u09bf\u09a7\u09bf\u09f0 \u09aa\u09bf\u099a \u09a1\u09be\u0999\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09aa\u09bf\u099a \u09ac\u09cd\u09af\u09be\u09b8\u09f0 \u09b8\u09c8\u09a4\u09c7 \u09ae\u09bf\u09b2\u09bf\u09ac \u09b2\u09be\u0997\u09c7\u0964 \u098f\u0995\u0995 \u09a1\u09bf\u0999\u09bf\u09f0 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u098f\u0995\u0995 \u09b8\u09c2\u09a4\u09be\u09af\u09c1\u0995\u09cd\u09a4, \u0986\u09f0\u09c1 \u09a6\u09c1\u099f\u09be \u09a1\u09bf\u0999\u09bf\u09f0 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09a6\u09c1\u099f\u09be \u09a1\u09bf\u0999\u09bf\u09f0\u0964 \u098f\u0995\u0995 \u09b8\u09c2\u09a4\u09be\u09f0 \u09a1\u09bf\u099c\u09be\u0987\u09a8\u09c7 \u098f\u099f\u09be \u09a6\u09be\u0981\u09a4 \u0986\u0997\u09c1\u09f1\u09be\u0987 \u09b2\u09c8 \u09af\u09be\u09af\u09bc, \u0986\u09a8\u09b9\u09be\u09a4\u09c7 \u09a6\u09c1\u099f\u09be \u09b8\u09c2\u09a4\u09be\u09f0 \u09a1\u09bf\u099c\u09be\u0987\u09a8\u09c7 \u09a6\u09c1\u099f\u09be \u09a6\u09be\u0981\u09a4 \u0986\u0997\u09c1\u09f1\u09be\u0987 \u09b2\u09c8 \u09af\u09be\u09af\u09bc\u0964 \u09b8\u09c2\u09a4\u09be\u09f0 \u09b8\u0982\u0996\u09cd\u09af\u09be \u09b8\u0982\u0997\u09ae \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09b8\u0982\u0996\u09cd\u09af\u09be\u09f0 \u09b8\u09c8\u09a4\u09c7 \u09ae\u09bf\u09b2\u09bf\u09ac \u09b2\u09be\u0997\u09c7\u0964<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/C_worm_reducer_1.webp\" alt=\"worm reducer\" width=\"800\" \/><\/p>\n<h2>\u09b8\u09cd\u09ac-\u09b2\u0995 \u0995\u09f0\u09be \u0995\u09be\u09f0\u09cd\u09af\u09cd\u09af<\/h2>\n<p>\u0995\u09c3\u09ae\u09bf \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u098f\u099f\u09be \u09ac\u09bf\u09b6\u09bf\u09b7\u09cd\u099f \u09ac\u09c8\u09b6\u09bf\u09b7\u09cd\u099f\u09cd\u09af \u09b9\u2019\u09b2 \u0987\u09af\u09bc\u09be\u09f0 \u09b8\u09cd\u09ac-\u09b2\u0995 \u0995\u09f0\u09be \u0995\u09be\u09f0\u09cd\u09af\u09cd\u09af, \u09af\u09bf\u09af\u09bc\u09c7 \u0987\u09a8\u09aa\u09c1\u099f \u0986\u09f0\u09c1 \u0986\u0989\u099f\u09aa\u09c1\u099f \u0996\u09be\u09a6 \u09ac\u09bf\u09a8\u09bf\u09ae\u09af\u09bc \u0995\u09f0\u09be\u09a4 \u09ac\u09be\u09a7\u09be \u09a6\u09bf\u09af\u09bc\u09c7\u0964 \u0994\u09a6\u09cd\u09af\u09cb\u0997\u09bf\u0995 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u0997\u09f0 \u09ac\u09be\u09ac\u09c7 \u09b8\u09cd\u09ac-\u09b2\u0995 \u0995\u09f0\u09be \u0995\u09be\u09f0\u09cd\u09af\u09cd\u09af \u0986\u09a6\u09f0\u09cd\u09b6 \u09af'\u09a4 \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09ac\u0995\u09cd\u09b8 \u09ac\u09c3\u09a6\u09cd\u09a7\u09bf \u09a8\u0995\u09f0\u09be\u0995\u09c8 \u09ac\u09c3\u09b9\u09ce \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b9\u09cd\u09f0\u09be\u09b8 \u0985\u09a8\u09c1\u09aa\u09be\u09a4\u09f0 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u099c\u09a8 \u09b9\u09af\u09bc\u0964<br \/>\u0995\u09c3\u09ae\u09bf \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u09b8\u09cd\u09ac-\u09b2\u0995 \u0995\u09f0\u09be \u0995\u09be\u09f0\u09cd\u09af\u09cd\u09af \u09b8\u09a0\u09bf\u0995 \u09a7\u09f0\u09a3\u09f0 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09ac\u09be\u099b\u09bf \u09b2\u2019\u09b2\u09c7 \u09b8\u09ae\u09cd\u09ad\u09f1 \u09b9\u2019\u09ac \u09aa\u09be\u09f0\u09c7\u0964 \u0995\u09bf\u09a8\u09cd\u09a4\u09c1 \u09ae\u09a8 \u0995\u09f0\u09bf\u09ac\u09b2\u0997\u09c0\u09af\u09bc\u09be \u09af\u09c7 \u098f\u0987 \u09ac\u09c8\u09b6\u09bf\u09b7\u09cd\u099f\u09cd\u09af \u09b8\u0995\u09b2\u09cb \u09a7\u09f0\u09a3\u09f0 \u09f1\u09f0\u09cd\u09ae \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09a4 \u0989\u09aa\u09b2\u09ac\u09cd\u09a7 \u09a8\u09b9\u09af\u09bc\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u09cb\u09f0 \u09b8\u09cd\u09ac\u09af\u09bc\u0982 \u09b2\u0995 \u09b9\u09af\u09bc \u09af\u09c7\u09a4\u09bf\u09af\u09bc\u09be \u098f\u099f\u09be \u09a8\u09bf\u09f0\u09cd\u09a6\u09bf\u09b7\u09cd\u099f \u0997\u09a4\u09bf \u0985\u09a8\u09c1\u09aa\u09be\u09a4\u09a4 \u0989\u09aa\u09a8\u09c0\u09a4 \u09b9\u09af\u09bc\u0964 \u09af\u09c7\u09a4\u09bf\u09af\u09bc\u09be \u0997\u09a4\u09bf \u0985\u09a8\u09c1\u09aa\u09be\u09a4 \u0985\u09a4\u09bf \u0995\u09ae \u09b9\u09af\u09bc, \u09a4\u09c7\u09a4\u09bf\u09af\u09bc\u09be \u09b8\u09cd\u09ac-\u09b2\u0995 \u0995\u09f0\u09be \u0995\u09be\u09f0\u09cd\u09af\u09cd\u09af\u0987 \u09ab\u09b2\u09aa\u09cd\u09f0\u09b8\u09c2\u09ad\u09be\u09f1\u09c7 \u0995\u09be\u09ae \u09a8\u0995\u09f0\u09c7\u0964<br \/>\u0995\u09c3\u09ae\u09bf \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u09b8\u09cd\u09ac-\u09b2\u0995 \u0995\u09f0\u09be\u09f0 \u0985\u09f1\u09b8\u09cd\u09a5\u09be \u09b8\u09c0\u09b9, \u099a\u09be\u09aa \u0986\u09f0\u09c1 \u0998\u09f0\u09cd\u09b7\u09a3\u09f0 \u09b8\u09b9\u0997 \u09a6\u09cd\u09ac\u09be\u09f0\u09be \u09a8\u09bf\u09f0\u09cd\u09a7\u09be\u09f0\u09bf\u09a4 \u09b9\u09af\u09bc\u0964 \u09ac\u09bf\u0982\u09b6 \u09b6\u09a4\u09bf\u0995\u09be\u09f0 \u0986\u09f0\u09ae\u09cd\u09ad\u09a3\u09bf\u09a4\u09c7 \u0997\u09be\u09a1\u09bc\u09c0\u09ac\u09cb\u09f0\u09c7 \u099f\u09be\u09af\u09bc\u09be\u09f0 \u099a\u09c7\u09aa\u09c7\u099f\u09be \u0995\u09f0\u09bf \u09b7\u09cd\u099f\u09bf\u09af\u09bc\u09be\u09f0\u09bf\u0982 \u0995\u09be\u09b7\u09f0 \u09ab\u09be\u09b2\u09c7 \u099f\u09be\u09a8\u09bf \u09a8\u09bf\u09af\u09bc\u09be\u09f0 \u09aa\u09cd\u09f0\u09f1\u09a3\u09a4\u09be \u0986\u099b\u09bf\u09b2\u0964 \u098f\u099f\u09be \u0995\u09c3\u09ae\u09bf \u09a1\u09cd\u09f0\u09be\u0987\u09ad\u09c7 \u0998\u09f0\u09cd\u09b7\u09a3 \u09ac\u09b2 \u09b9\u09cd\u09f0\u09be\u09b8 \u0995\u09f0\u09bf \u0986\u09f0\u09c1 \u09b7\u09cd\u099f\u09bf\u09af\u09bc\u09be\u09f0\u09bf\u0982 \u09ac\u09b2 \u099a\u0995\u09be\u09b2\u09c8 \u09aa\u09cd\u09f0\u09c7\u09f0\u09a3 \u0995\u09f0\u09bf \u098f\u0987 \u09aa\u09cd\u09f0\u09f1\u09a3\u09a4\u09be \u09b9\u09cd\u09f0\u09be\u09b8 \u0995\u09f0\u09bf\u099b\u09bf\u09b2, \u09af\u09bf\u09af\u09bc\u09c7 \u09b7\u09cd\u099f\u09bf\u09af\u09bc\u09be\u09f0\u09bf\u0982\u09a4 \u09b8\u09b9\u09be\u09af\u09bc \u0995\u09f0\u09c7 \u0986\u09f0\u09c1 \u09aa\u09f0\u09bf\u09a7\u09be\u09a8 \u0986\u09f0\u09c1 \u099b\u09bf\u0999\u09bf \u09af\u09cb\u09f1\u09be \u09b9\u09cd\u09f0\u09be\u09b8 \u0995\u09f0\u09c7\u0964<br \/>\u09b8\u09cd\u09ac\u09af\u09bc\u0982 \u09b2\u0995 \u0995\u09f0\u09be \u0995\u09c3\u09ae\u09bf \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09b9\u09c8\u099b\u09c7 \u0995\u09ae \u09af\u09be\u09a8\u09cd\u09a4\u09cd\u09f0\u09bf\u0995 \u0995\u09be\u09f0\u09cd\u09af\u0995\u09cd\u09b7\u09ae\u09a4\u09be \u09a5\u0995\u09be \u098f\u099f\u09be \u09b8\u09b9\u099c-\u09ae\u09c7\u099a\u09bf\u09a8\u0964 \u098f\u099f\u09be \u09ae\u09c2\u09f0\u09f0 \u0995\u09be\u09ae \u0986\u09a8\u099f\u09cb \u09ae\u09c2\u09f0\u09f0 \u0995\u09be\u09ae\u09a4\u0995\u09c8 \u09a1\u09be\u0999\u09f0 \u09b9\u2019\u09b2\u09c7 \u0987 \u09b8\u09cd\u09ac\u09af\u09bc\u0982\u0995\u09cd\u09f0\u09bf\u09af\u09bc\u09ad\u09be\u09f1\u09c7 \u09b2\u0995 \u0995\u09f0\u09be \u09b9\u09af\u09bc\u0964 \u09af\u09a6\u09bf\u09b9\u09c7 \u0995\u09c3\u09ae\u09bf \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u09af\u09be\u09a8\u09cd\u09a4\u09cd\u09f0\u09bf\u0995 \u0995\u09be\u09f0\u09cd\u09af\u0995\u09cd\u09b7\u09ae\u09a4\u09be \u09eb\u09e6\u09e7\u099f\u09bf\u09aa\u09bf\u09e9\u099f\u09bf\u09a4\u0995\u09c8 \u0995\u09ae \u09b9\u09af\u09bc, \u09a4\u09c7\u09a8\u09cd\u09a4\u09c7 \u0998\u09f0\u09cd\u09b7\u09a3\u09f0 \u09ab\u09b2\u09a4 \u09b2\u09cb\u0995\u099a\u09be\u09a8 \u09b9\u2019\u09ac\u0964 \u0987\u09af\u09bc\u09be\u09f0 \u0989\u09aa\u09f0\u09bf\u0993, \u09a1\u09cd\u09f0\u09be\u0987\u09ad\u099f\u09cb \u0993\u09b2\u09cb\u099f\u09be \u09b9'\u09b2\u09c7 \u09b8\u09cd\u09ac-\u09b2\u0995 \u0995\u09f0\u09be \u0995\u09be\u09f0\u09cd\u09af\u09cd\u09af \u09aa\u09cd\u09f0\u09af\u09cb\u099c\u09cd\u09af \u09a8\u09b9\u09af\u09bc\u0964 \u098f\u0987 \u09ac\u09c8\u09b6\u09bf\u09b7\u09cd\u099f\u09cd\u09af\u0987 \u09b8\u09cd\u09ac\u09af\u09bc\u0982-\u09b2\u0995 \u0995\u09f0\u09be \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u0995 \u0989\u09a4\u09cd\u09a4\u09cb\u09b2\u09a8 \u0986\u09f0\u09c1 \u09a8\u09ae\u09be\u0987 \u0985\u09a8\u09be \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u0997\u09f0 \u09ac\u09be\u09ac\u09c7 \u0986\u09a6\u09f0\u09cd\u09b6 \u0995\u09f0\u09bf \u09a4\u09cb\u09b2\u09c7\u0964<br \/>\u0995\u09c3\u09ae\u09bf \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u0986\u09a8 \u098f\u099f\u09be \u09ac\u09c8\u09b6\u09bf\u09b7\u09cd\u099f\u09cd\u09af \u09b9\u2019\u09b2 \u0987\u09af\u09bc\u09be\u09f0 \u0985\u0995\u09cd\u09b7\u09c0\u09af\u09bc\u09ad\u09be\u09f1\u09c7 \u09b9\u09cd\u09f0\u09be\u09b8 \u0995\u09f0\u09be\u09f0 \u0995\u09cd\u09b7\u09ae\u09a4\u09be\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09a1\u09be\u09ac\u09b2-\u09b2\u09bf\u09a1 \u09ac\u09be \u098f\u0995\u0995-\u09b2\u09bf\u09a1 \u09b9\u2019\u09ac \u09aa\u09be\u09f0\u09c7, \u0986\u09f0\u09c1 \u09a6\u09be\u0981\u09a4\u09f0 \u09aa\u09f0\u09bf\u09a7\u09be\u09a8\u09f0 \u0995\u09cd\u09b7\u09a4\u09bf\u09aa\u09c2\u09f0\u09a3\u09f0 \u09ac\u09be\u09ac\u09c7 \u0987\u09af\u09bc\u09be\u09f0 \u09ac\u09c7\u0995\u09b2\u09c7\u099b \u09b8\u09be\u09ae\u099e\u09cd\u099c\u09b8\u09cd\u09af \u0995\u09f0\u09be \u09b8\u09ae\u09cd\u09ad\u09f1\u0964<\/p>\n<h2>\u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09a6\u09cd\u09ac\u09be\u09f0\u09be \u0989\u09ce\u09aa\u09a8\u09cd\u09a8 \u09b9\u09cb\u09f1\u09be \u09a4\u09be\u09aa<\/h2>\n<p>\u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09c7 \u09af\u09a5\u09c7\u09b7\u09cd\u099f \u09aa\u09f0\u09bf\u09ae\u09be\u09a3\u09f0 \u09a4\u09be\u09aa \u0989\u09ce\u09aa\u09a8\u09cd\u09a8 \u0995\u09f0\u09c7\u0964 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u09cb\u09f0\u09f0 \u0995\u09be\u09f0\u09cd\u09af\u0995\u09cd\u09b7\u09ae\u09a4\u09be \u09ac\u09c3\u09a6\u09cd\u09a7\u09bf \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u098f\u0987 \u09a4\u09be\u09aa \u0995\u09ae \u0995\u09f0\u09be\u099f\u09cb \u0985\u09a4\u09bf \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u099c\u09a8\u09c0\u09af\u09bc\u0964 \u0995\u09c3\u09ae\u09bf\u09ac\u09cb\u09f0\u0995 \u09ae\u09b8\u09c3\u09a3 \u09aa\u09c3\u09b7\u09cd\u09a0\u09f0 \u09a1\u09bf\u099c\u09be\u0987\u09a8 \u0995\u09f0\u09bf \u098f\u0987 \u09a4\u09be\u09aa \u0995\u09ae \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09bf\u0964 \u09b8\u09be\u09a7\u09be\u09f0\u09a3\u09a4\u09c7 \u0995\u09c3\u09ae\u09bf\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u09cb\u09f0\u09c7 \u09af\u09bf \u0997\u09a4\u09bf\u09f0\u09c7 \u099c\u09be\u09b2 \u0995\u09f0\u09c7, \u09b8\u09c7\u09af\u09bc\u09be \u09e8\u09e6\u09f0 \u09aa\u09f0\u09be \u09e8\u09ea \u0986\u09f0 \u098f\u09ae\u09f0 \u09ad\u09bf\u09a4\u09f0\u09a4 \u09b9\u2019\u09ac \u09b2\u09be\u0997\u09c7\u0964<br \/>\u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u0995\u09be\u09f0\u09cd\u09af\u0995\u09cd\u09b7\u09ae\u09a4\u09be \u0997\u09a3\u09a8\u09be\u09f0 \u09ac\u09be\u09ac\u09c7 \u09ac\u09b9\u09c1\u09a4\u09cb \u09aa\u09a6\u09cd\u09a7\u09a4\u09bf \u0986\u099b\u09c7\u0964 \u0995\u09bf\u09a8\u09cd\u09a4\u09c1 \u0986\u09a8 \u0995\u09cb\u09a8\u09cb \u09aa\u09a6\u09cd\u09a7\u09a4\u09bf\u09a4 \u09a4\u09be\u09aa\u09c0\u09af\u09bc \u09a8\u09c7\u099f\u09f1\u09f0\u09cd\u0995 \u09a8\u09bf\u09f0\u09cd\u09ae\u09be\u09a3\u09f0 \u09ac\u09be\u09ac\u09c7 \u09b8\u09cd\u09ac\u09af\u09bc\u0982\u0995\u09cd\u09f0\u09bf\u09af\u09bc \u09aa\u09a6\u09cd\u09a7\u09a4\u09bf \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09be \u09a8\u09b9\u09af\u09bc\u0964 \u0986\u09a8 \u09aa\u09a6\u09cd\u09a7\u09a4\u09bf\u09b8\u09ae\u09c2\u09b9\u09c7 \u09b9\u09af\u09bc \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u0995 \u09b8\u09ae\u09a4\u09be\u09aa\u09c0\u09af\u09bc \u09ac\u09cd\u09af\u09f1\u09b8\u09cd\u09a5\u09be \u09b9\u09bf\u099a\u09be\u09aa\u09c7 \u09ac\u09bf\u09ae\u09c2\u09f0\u09cd\u09a4\u09ad\u09be\u09f1\u09c7 \u0985\u09a8\u09c1\u09b8\u09a8\u09cd\u09a7\u09be\u09a8 \u0995\u09f0\u09c7 \u09a8\u09b9\u09af\u09bc \u099f\u09bf\u098f\u09a8\u098f\u09ae\u0995 \u09b8\u09cd\u09a5\u09bf\u09a4\u09bf\u09b6\u09c0\u09b2\u09ad\u09be\u09f1\u09c7 \u09a8\u09bf\u09f0\u09cd\u09ae\u09be\u09a3 \u0995\u09f0\u09c7\u0964 \u098f\u0987 \u0997\u09f1\u09c7\u09b7\u09a3\u09be \u09aa\u09a4\u09cd\u09f0\u0996\u09a8\u09a4 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09ac\u09be\u09ac\u09c7 \u09a4\u09be\u09aa\u09f0 \u09ad\u09be\u09f0\u09b8\u09be\u09ae\u09cd\u09af \u0986\u09f0\u09c1 \u0995\u09be\u09f0\u09cd\u09af\u0995\u09cd\u09b7\u09ae\u09a4\u09be \u09b8\u09cd\u09ac\u09af\u09bc\u0982\u0995\u09cd\u09f0\u09bf\u09af\u09bc\u09ad\u09be\u09f1\u09c7 \u0997\u09a3\u09a8\u09be \u0995\u09f0\u09be\u09f0 \u09ac\u09be\u09ac\u09c7 \u098f\u0995 \u09a8\u09a4\u09c1\u09a8 \u09aa\u09a6\u09cd\u09a7\u09a4\u09bf\u09f0 \u09ac\u09f0\u09cd\u09a3\u09a8\u09be \u0995\u09f0\u09be \u09b9\u09c8\u099b\u09c7\u0964<br \/>\u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09a6\u09cd\u09ac\u09be\u09f0\u09be \u0989\u09ce\u09aa\u09a8\u09cd\u09a8 \u09b9\u09cb\u09f1\u09be \u09a4\u09be\u09aa \u09b6\u0995\u09cd\u09a4\u09bf \u09b9\u09c7\u09f0\u09c1\u09f1\u09be\u09f0 \u098f\u0995 \u0989\u09b2\u09cd\u09b2\u09c7\u0996\u09af\u09cb\u0997\u09cd\u09af \u0989\u09ce\u09b8\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09ac\u09c8\u09b6\u09bf\u09b7\u09cd\u099f\u09cd\u09af \u09b8\u09be\u09a7\u09be\u09f0\u09a3\u09a4\u09c7 \u09a6\u09be\u0981\u09a4\u09f0 \u09b8\u0982\u09b8\u09cd\u09aa\u09f0\u09cd\u09b6\u09a4 \u0985\u09a7\u09bf\u0995 \u09b8\u09cd\u09b2\u09be\u0987\u09a1\u09bf\u0982 \u0997\u09a4\u09bf \u09a5\u09be\u0995\u09c7, \u09af\u09be\u09f0 \u09ab\u09b2\u09a4 \u0985\u09a7\u09bf\u0995 \u0998\u09f0\u09cd\u09b7\u09a3\u09c0\u09af\u09bc \u09a4\u09be\u09aa \u0986\u09f0\u09c1 \u09ac\u09c3\u09a6\u09cd\u09a7\u09bf \u09aa\u09cb\u09f1\u09be \u09a4\u09be\u09aa\u09c0\u09af\u09bc \u099a\u09be\u09aa \u09b9\u09af\u09bc\u0964 \u09ab\u09b2\u09a4 \u0985\u09a8\u09c1\u0995\u09c2\u09b2 \u0995\u09be\u09f0\u09cd\u09af\u09cd\u09af\u0995\u09b2\u09be\u09aa \u09a8\u09bf\u09b6\u09cd\u099a\u09bf\u09a4 \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u09b8\u09a0\u09bf\u0995 \u0997\u09a3\u09a8\u09be\u09f0 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u099c\u09a8 \u09b9\u09af\u09bc\u0964 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09ac\u09cd\u09af\u09f1\u09b8\u09cd\u09a5\u09be\u09f0 \u0995\u09be\u09f0\u09cd\u09af\u0995\u09cd\u09b7\u09ae\u09a4\u09be \u09a8\u09bf\u09f0\u09cd\u09a3\u09af\u09bc \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u09aa\u09cd\u09f0\u09b8\u09cd\u09a4\u09c1\u09a4\u0995\u09be\u09f0\u09c0\u09b8\u0995\u09b2\u09c7 \u09aa\u09cd\u09f0\u09be\u09af\u09bc\u09c7 \u09a4\u09be\u09aa\u09f0 \u0995\u09cd\u09b7\u09a4\u09bf \u0986\u09f0\u09c1 \u0995\u09be\u09f0\u09cd\u09af\u0995\u09cd\u09b7\u09ae\u09a4\u09be \u0997\u09a3\u09a8\u09be \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u099a\u09bf\u09ae\u09c1\u09b2\u09c7\u099a\u09a8 \u09aa\u09cd\u09f0\u0997\u09cd\u09f0\u09c7\u09ae WTplus \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09c7\u0964 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u09a8\u2019-\u09b2\u09cb\u09a1 \u0986\u09f0\u09c1 \u09b2\u09cb\u09a1-\u09a8\u09bf\u09f0\u09cd\u09ad\u09f0\u09b6\u09c0\u09b2 \u09b6\u0995\u09cd\u09a4\u09bf\u09f0 \u0995\u09cd\u09b7\u09a4\u09bf \u09af\u09cb\u0997 \u0995\u09f0\u09bf \u09a4\u09be\u09aa\u09f0 \u09ad\u09be\u09f0\u09b8\u09be\u09ae\u09cd\u09af \u0997\u09a3\u09a8\u09be \u0995\u09f0\u09be \u09b9\u09af\u09bc\u0964<br \/>\u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09a4 \u09ac\u09bf\u09b6\u09c7\u09b7 \u09a7\u09f0\u09a3\u09f0 \u09b2\u09c1\u09ac\u09cd\u09f0\u09bf\u0995\u09c7\u09a3\u09cd\u099f\u09f0 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u099c\u09a8 \u09b9\u09af\u09bc\u0964 \u0985\u099a\u09c1\u09ae\u09cd\u09ac\u0995\u09c0\u09af\u09bc \u0986\u09f0\u09c1 \u0995\u09ae \u0998\u09f0\u09cd\u09b7\u09a3 \u09b8\u09b9\u0997 \u09a5\u0995\u09be \u0995\u09c3\u09a4\u09cd\u09f0\u09bf\u09ae \u09a4\u09c7\u09b2 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09be \u09b9\u09af\u09bc\u0964 \u0995\u09bf\u09a8\u09cd\u09a4\u09c1 \u0995\u09c3\u09ae\u09bf\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b2\u09c1\u09ac\u09cd\u09f0\u09bf\u0995\u09c7\u099f \u0995\u09f0\u09be\u09f0 \u09ac\u09be\u09ac\u09c7 \u09a4\u09c7\u09b2\u099f\u09cb \u098f\u099f\u09be \u09ac\u09bf\u0995\u09b2\u09cd\u09aa \u09ae\u09be\u09a4\u09cd\u09f0\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u0986\u09af\u09bc\u09c1\u09b8 \u09ac\u09c3\u09a6\u09cd\u09a7\u09bf \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u09b9\u2019\u09b2\u09c7 \u09b2\u09c1\u09ac\u09cd\u09f0\u09bf\u0995\u09c7\u09a3\u09cd\u099f\u09a4 \u09aa\u09cd\u09f0\u09be\u0995\u09c3\u09a4\u09bf\u0995 \u09af\u09cb\u0997\u0995\u09f0\u09a3 \u09af\u09cb\u0997 \u0995\u09f0\u09be\u09f0 \u0995\u09a5\u09be\u0993 \u09ac\u09bf\u09ac\u09c7\u099a\u09a8\u09be \u0995\u09f0\u09bf\u09ac \u09b2\u09be\u0997\u09c7\u0964<br \/>\u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09b9\u09cd\u09f0\u09be\u09b8 \u0985\u09a8\u09c1\u09aa\u09be\u09a4 \u0985\u09a4\u09bf \u0989\u099a\u09cd\u099a \u09b9\u2019\u09ac \u09aa\u09be\u09f0\u09c7\u0964 \u09aa\u09cd\u09f0\u099a\u09b2\u09bf\u09a4 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u099b\u09c7\u099f\u09f0 \u09a4\u09c1\u09b2\u09a8\u09be\u09a4 \u0987\u09b9\u0981\u09a4\u09c7 \u0995\u09ae \u0995\u09b7\u09cd\u099f\u09f0\u09c7 \u09ac\u09c3\u09b9\u09ce \u09aa\u09f0\u09bf\u09ae\u09be\u09a3\u09f0 \u09b9\u09cd\u09f0\u09be\u09b8 \u09b2\u09be\u09ad \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09c7, \u09af\u09bf\u09ac\u09cb\u09f0\u09a4 \u098f\u0995\u09be\u09a7\u09bf\u0995 \u09b9\u09cd\u09f0\u09be\u09b8\u09f0 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u099c\u09a8 \u09b9\u09af\u09bc\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09a4 \u09aa\u09cd\u09f0\u099a\u09b2\u09bf\u09a4 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09a4\u0995\u09c8\u0993 \u0995\u09ae \u099a\u09b2\u09a8\u09cd\u09a4 \u0985\u0982\u09b6 \u0986\u09f0\u09c1 \u09ac\u09bf\u0995\u09b2 \u09b9\u09cb\u09f1\u09be\u09f0 \u09a0\u09be\u0987 \u09a5\u09be\u0995\u09c7\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u098f\u099f\u09be \u0985\u09b8\u09c1\u09ac\u09bf\u09a7\u09be \u09b9\u2019\u09b2 \u0987 \u0989\u09b2\u099f\u09bf\u09ac \u09a8\u09cb\u09f1\u09be\u09f0\u09be, \u09af\u09be\u09f0 \u09ab\u09b2\u09a4 \u0987\u09af\u09bc\u09be\u09f0 \u0995\u09be\u09f0\u09cd\u09af\u0995\u09cd\u09b7\u09ae\u09a4\u09be \u09b8\u09c0\u09ae\u09bf\u09a4 \u09b9\u09af\u09bc\u0964<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/B_worm_reducer_1.webp\" alt=\"worm reducer\" width=\"800\" \/><\/p>\n<h2>\u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u0986\u0995\u09be\u09f0<\/h2>\n<p>\u0998\u09c2\u09f0\u09cd\u09a3\u09a8\u09b6\u09c0\u09b2 \u0996\u09be\u09a6\u09f0 \u0997\u09a4\u09bf \u09b9\u09cd\u09f0\u09be\u09b8 \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09bf\u0964 \u09b8\u09be\u09a7\u09be\u09f0\u09a3\u09a4\u09c7 \u09b8\u09cb\u0981\u0995\u09cb\u09a3\u09a4 \u09a6\u09c1\u099f\u09be \u0996\u09be\u09a6\u09f0\u09c7 \u09a1\u09bf\u099c\u09be\u0987\u09a8 \u0995\u09f0\u09be \u09b9\u09af\u09bc\u0964 \u0995\u09c3\u09ae\u09bf\u09f0 \u099a\u0995\u09be\u099f\u09cb\u09f1\u09c7 \u09aa\u09bf\u09a8\u09bf\u09af\u09bc\u09a8 \u0986\u09f0\u09c1 \u09f0\u09c7\u0995 \u09a6\u09c1\u09af\u09bc\u09cb\u099f\u09be \u0995\u09be\u09ae \u0995\u09f0\u09c7\u0964 \u0995\u09c7\u09a8\u09cd\u09a6\u09cd\u09f0\u09c0\u09af\u09bc \u0995\u09cd\u09f0\u099b \u099b\u09c7\u0995\u099a\u09a8\u09c7 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u0986\u0997\u09ac\u09be\u09a2\u09bc\u09bf \u09af\u09cb\u09f1\u09be \u0986\u09f0\u09c1 \u09aa\u09bf\u099b\u09c1\u09f1\u09be\u0987 \u09af\u09cb\u09f1\u09be \u09ab\u09be\u09b2\u09f0 \u09ae\u09be\u099c\u09f0 \u09b8\u09c0\u09ae\u09be \u0997\u09a0\u09a8 \u0995\u09f0\u09c7\u0964<br \/>\u09f1\u09f0\u09cd\u09ae \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u0986\u0989\u099f\u09aa\u09c1\u099f \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09ac\u09cd\u09af\u09be\u09b8 \u0987\u09a8\u09aa\u09c1\u099f \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09a4\u09c1\u09b2\u09a8\u09be\u09a4 \u09b8\u09f0\u09c1\u0964 \u0987\u09af\u09bc\u09be\u09f0 \u09ab\u09b2\u09a4 \u0989\u099a\u09cd\u099a \u099f\u09f0\u09cd\u0995 \u0986\u0989\u099f\u09aa\u09c1\u099f \u0989\u09ce\u09aa\u09a8\u09cd\u09a8 \u0995\u09f0\u09be\u09f0 \u09b8\u09ae\u09af\u09bc\u09a4 \u0995\u09ae \u0997\u09a4\u09bf\u09f0\u09c7 \u0995\u09be\u09ae \u0995\u09f0\u09bf\u09ac \u09aa\u09f0\u09be \u09af\u09be\u09af\u09bc\u0964 \u0987\u09af\u09bc\u09be\u09f0 \u09ab\u09b2\u09a4 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09b8\u09ae\u09c2\u09b9 \u09b8\u09cd\u09a5\u09be\u09a8-\u09b8\u099e\u09cd\u099a\u09af\u09bc \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u0997\u09f0 \u09ac\u09be\u09ac\u09c7 \u0985\u09a4\u09bf \u0989\u09a4\u09cd\u09a4\u09ae \u09b9\u09af\u09bc\u0964 \u09aa\u09cd\u09f0\u09be\u09f0\u09ae\u09cd\u09ad\u09bf\u0995 \u0996\u09f0\u099a\u09cb \u0995\u09ae\u0964<br \/>\u09f1\u09f0\u09cd\u09ae \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09b9\u09c8\u099b\u09c7 \u09b8\u09cd\u09aa\u09c0\u09a1 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u0985\u09a8\u09cd\u09af\u09a4\u09ae \u099c\u09a8\u09aa\u09cd\u09f0\u09bf\u09af\u09bc \u09aa\u09cd\u09f0\u0995\u09be\u09f0\u0964 \u0987\u09b9\u0981\u09a4 \u09b8\u09f0\u09c1 \u0986\u09f0\u09c1 \u09b6\u0995\u09cd\u09a4\u09bf\u09b6\u09be\u09b2\u09c0 \u09b9\u2019\u09ac \u09aa\u09be\u09f0\u09c7 \u0986\u09f0\u09c1 \u09aa\u09cd\u09f0\u09be\u09af\u09bc\u09c7 \u09b6\u0995\u09cd\u09a4\u09bf \u09b8\u099e\u09cd\u099a\u09be\u09f0\u09a3 \u09ac\u09cd\u09af\u09f1\u09b8\u09cd\u09a5\u09be\u09a4 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09be \u09b9\u09af\u09bc\u0964 \u098f\u0987 \u0987\u0989\u09a8\u09bf\u099f\u09b8\u09ae\u09c2\u09b9 \u09b2\u09bf\u09ab\u09cd\u099f, \u0995\u09a8\u09ad\u09c7\u09af\u09bc\u09f0 \u09ac\u09c7\u09b2\u09cd\u099f, \u09a8\u09bf\u09f0\u09be\u09aa\u09a4\u09cd\u09a4\u09be \u0997\u09c7\u099f, \u0986\u09f0\u09c1 \u099a\u09bf\u0995\u09bf\u09ce\u09b8\u09be \u09b8\u0981\u099c\u09c1\u09b2\u09bf\u09a4 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09bf\u0964 \u0995\u09c3\u09ae\u09bf\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09bf\u0982 \u09aa\u09cd\u09f0\u09be\u09af\u09bc\u09c7 \u09b8\u09f0\u09c1 \u0986\u09f0\u09c1 \u09a1\u09be\u0999\u09f0 \u0986\u0995\u09be\u09f0\u09f0 \u09ae\u09c7\u099a\u09bf\u09a8\u09a4 \u09aa\u09cb\u09f1\u09be \u09af\u09be\u09af\u09bc\u0964<br \/>\u0995\u09c3\u09ae\u09bf\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u09cb\u09f0\u09cb \u09b8\u09be\u09ae\u099e\u09cd\u099c\u09b8\u09cd\u09af \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09bf\u0964 \u09a1\u09c1\u09f1\u09c7\u09b2 \u09b2\u09bf\u09a1\u09af\u09c1\u0995\u09cd\u09a4 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09ac\u09be\u0993\u0981 \u0986\u09f0\u09c1 \u09b8\u09cb\u0981 \u09a6\u09be\u0981\u09a4\u09f0 \u09aa\u09c3\u09b7\u09cd\u09a0\u09a4 \u09ac\u09c7\u09b2\u09c7\u0997 \u09ac\u09c7\u09b2\u09c7\u0997 \u09b2\u09bf\u09a1 \u09a5\u09be\u0995\u09c7\u0964 \u0987\u09af\u09bc\u09be\u09f0 \u09ab\u09b2\u09a4 \u0995\u09c3\u09ae\u09bf\u09f0 \u0985\u0995\u09cd\u09b7\u09c0\u09af\u09bc \u0997\u09a4\u09bf\u09f0 \u09b8\u09c1\u09ac\u09bf\u09a7\u09be \u09b9\u09af\u09bc \u0986\u09f0\u09c1 \u09ac\u09c7\u0995\u09b2\u09c7\u099b \u0995\u09ae \u0995\u09f0\u09bf\u09ac\u09b2\u09c8\u0993 \u0987\u09af\u09bc\u09be\u0995 \u09b8\u09be\u09ae\u099e\u09cd\u099c\u09b8\u09cd\u09af \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09bf\u0964 \u0995\u09c3\u09ae\u09bf\u099f\u09cb \u0995\u09cd\u09b7\u09af\u09bc \u09b9\u09cb\u09f1\u09be\u09f0 \u09b2\u0997\u09c7 \u09b2\u0997\u09c7 \u09ac\u09c7\u0995\u09b2\u09c7\u099b \u098f\u09a1\u099c\u09be\u09b7\u09cd\u099f\u09ae\u09c7\u09a3\u09cd\u099f\u09f0 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u099c\u09a8 \u09b9\u2019\u09ac \u09aa\u09be\u09f0\u09c7\u0964 \u0995\u09bf\u099b\u09c1\u09ae\u09be\u09a8 \u0995\u09cd\u09b7\u09c7\u09a4\u09cd\u09f0\u09a4 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09ae\u09be\u099c\u09f0 \u0995\u09c7\u09a8\u09cd\u09a6\u09cd\u09f0\u09f0 \u09a6\u09c2\u09f0\u09a4\u09cd\u09ac \u09b8\u09be\u09ae\u099e\u09cd\u099c\u09b8\u09cd\u09af \u0995\u09f0\u09bf \u098f\u0987 \u09ac\u09c7\u0995\u09b2\u09c7\u099b \u09a8\u09bf\u09af\u09bc\u09a8\u09cd\u09a4\u09cd\u09f0\u09a3 \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09bf\u0964<br \/>\u09f1\u09f0\u09cd\u09ae \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u0986\u0995\u09be\u09f0 \u0987\u09af\u09bc\u09be\u09f0 \u0995\u09be\u09f0\u09cd\u09af\u09cd\u09af\u09f0 \u0993\u09aa\u09f0\u09a4 \u09a8\u09bf\u09f0\u09cd\u09ad\u09f0 \u0995\u09f0\u09c7\u0964 \u0989\u09a6\u09be\u09b9\u09f0\u09a3\u09b8\u09cd\u09ac\u09f0\u09c2\u09aa\u09c7, \u09af\u09a6\u09bf \u09f1\u09f0\u09cd\u09ae \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09bf \u0985\u099f\u09cb\u09ae\u2019\u09ac\u09be\u0987\u09b2\u09f0 \u0997\u09a4\u09bf \u09b9\u09cd\u09f0\u09be\u09b8 \u0995\u09f0\u09be \u09b9\u09af\u09bc, \u09a4\u09c7\u09a8\u09cd\u09a4\u09c7 \u09b8\u09c7\u09af\u09bc\u09be \u09b8\u09f0\u09c1 \u0997\u09be\u09a1\u09bc\u09c0\u09a4 \u09b8\u09cd\u09a5\u09be\u09aa\u09a8 \u0995\u09f0\u09bf\u09ac \u09aa\u09f0\u09be \u09ae\u09a1\u09c7\u09b2 \u09b9\u2019\u09ac \u09b2\u09be\u0997\u09c7\u0964<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/gearbox\/gearbox-l1.webp\" alt=\"China 12MM Mini Coreless DC Motor with Brush 50Rpm 60Rpm 1.5V 2V 2.5V 3V 3.7V 6V Brushed Mini Coreless Metal Gear Motor for Smart Home     worm gearbox design\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/gearbox\/gearbox-l2.webp\" alt=\"China 12MM Mini Coreless DC Motor with Brush 50Rpm 60Rpm 1.5V 2V 2.5V 3V 3.7V 6V Brushed Mini Coreless Metal Gear Motor for Smart Home     worm gearbox design\"><br \/>\u09b8\u09ae\u09cd\u09aa\u09be\u09a6\u0995 Cx 2023-06-20 \u09a6\u09cd\u09ac\u09be\u09f0\u09be<\/p>","protected":false},"excerpt":{"rendered":"<p>Warranty: 3months-1yearDesign Quantity: GM24-1221Utilization: BOAT, Vehicle, Property Equipment, Cosmetic instrument, Smart Property, Healthcare GearSort: Mini Coreless Cotor, Mini Coreless CotorTorque: 37g.cmBuilding: Long term MagnetCommutation: BrushSafeguard Feature: Completely EnclosedVelocity(RPM): 40~180RPMSteady Present(A): 20mAPerformance: 65~85%Direction of rotation: CW\/CCWNo-load pace: forty~18050RPMRated velocity: 30~1800RPMRated torque: .01~37g.cmMotor Dimensions: 12mm*21mmGear Dimensions: 24mm*10mm*9mmCertification: RoHS, ISO9001Packaging Particulars: Count on Common Carton and FoamPort: HangZhou [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[696,697,698,699,700,258,701,702,703,704,705,706,707,708,247,652,709,259,12,66,260,711,710,712,376,377,713,714,263,264,382,266,383,384,261,373,387,13,425,77,14,715,716,78,717,718,719,79,720,217,19,218,20,21,272,22,721,84,274,722,25,723,724,725,726,727,728,729,730,731,732,733,734,735,736,737,738,739,740,741,742,743,98,276,744,277,407,99,100,279,745,746,103,235,236,747,41,42,244,45,46,748,243,245,50],"class_list":["post-1542","post","type-post","status-publish","format-standard","hentry","category-gearboxes-worm","tag-12mm-dc-gear-motor","tag-12mm-gear-motor","tag-12mm-mini-gear-motor","tag-3v-6v-gear-motor","tag-3v-dc-gear-motor","tag-3v-dc-motor","tag-3v-gear-motor","tag-50rpm","tag-6v-dc-gear-motor","tag-6v-dc-gearbox","tag-6v-dc-motor","tag-6v-dc-motor-gearbox","tag-6v-dc-motor-with-gear","tag-6v-gear-motor","tag-6v-gearbox","tag-brush-motor","tag-brushed-dc-motor","tag-china-dc-motor","tag-china-gearbox","tag-china-motor","tag-china-motor-dc","tag-coreless-dc-motor","tag-coreless-motor","tag-dc-3v-gear-motor","tag-dc-gear","tag-dc-gear-motor","tag-dc-gear-motor-3v","tag-dc-gear-motor-6v","tag-dc-gearbox-motor","tag-dc-motor","tag-dc-motor-gear","tag-dc-motor-gearbox","tag-dc-motor-gearbox-worm","tag-dc-motor-with-gear","tag-dc-motor-with-gearbox","tag-dc-worm-gear","tag-dc-worm-gear-motor","tag-gear","tag-gear-design","tag-gear-for-motor","tag-gear-gearbox","tag-gear-mini","tag-gear-mini-motor","tag-gear-motor","tag-gear-motor-3v","tag-gear-motor-6v","tag-gear-motor-dc-6v","tag-gear-motor-gearbox","tag-gear-motor-mini","tag-gear-with-motor","tag-gear-worm","tag-gear-worm-motor","tag-gearbox","tag-gearbox-china","tag-gearbox-dc","tag-gearbox-gear","tag-gearbox-mini","tag-gearbox-motor","tag-gearbox-motor-dc","tag-gearbox-motor-mini","tag-gearbox-with","tag-home-smart-gear","tag-metal-gear","tag-metal-gear-dc-motor","tag-metal-gear-metal-gear","tag-metal-gear-motor","tag-metal-gearbox","tag-metal-gearbox-motor","tag-mini-dc-gear-motor","tag-mini-dc-motor","tag-mini-dc-motor-gear","tag-mini-dc-motor-gearbox","tag-mini-gear","tag-mini-gear-motor","tag-mini-gearbox","tag-mini-metal-gear-motor","tag-mini-motor","tag-mini-motor-dc","tag-mini-motor-gearbox","tag-mini-motor-with-gear","tag-mini-worm-gear","tag-mini-worm-gearbox","tag-motor","tag-motor-3v","tag-motor-3v-6v-gear","tag-motor-dc","tag-motor-gear-dc","tag-motor-gearbox","tag-motor-gearbox-china","tag-motor-gearbox-dc","tag-motor-home","tag-motor-mini","tag-motor-motor","tag-motor-worm","tag-motor-worm-gearbox","tag-smart-motor","tag-worm-gear","tag-worm-gear-gearbox","tag-worm-gear-motor","tag-worm-gear-worm","tag-worm-gearbox","tag-worm-gearbox-mini","tag-worm-motor","tag-worm-motor-gear","tag-worm-worm-gear"],"_links":{"self":[{"href":"https:\/\/gearboxes-worm.top\/as\/wp-json\/wp\/v2\/posts\/1542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearboxes-worm.top\/as\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearboxes-worm.top\/as\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearboxes-worm.top\/as\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearboxes-worm.top\/as\/wp-json\/wp\/v2\/comments?post=1542"}],"version-history":[{"count":0,"href":"https:\/\/gearboxes-worm.top\/as\/wp-json\/wp\/v2\/posts\/1542\/revisions"}],"wp:attachment":[{"href":"https:\/\/gearboxes-worm.top\/as\/wp-json\/wp\/v2\/media?parent=1542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearboxes-worm.top\/as\/wp-json\/wp\/v2\/categories?post=1542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearboxes-worm.top\/as\/wp-json\/wp\/v2\/tags?post=1542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}