{"id":1555,"date":"2023-07-12T05:15:15","date_gmt":"2023-07-12T05:15:15","guid":{"rendered":"https:\/\/gearboxes-worm.top\/china-high-quality-custom-worm-gear-set-worm-gearbox-exploded-view\/"},"modified":"2023-07-12T05:15:15","modified_gmt":"2023-07-12T05:15:15","slug":"china-high-quality-custom-worm-gear-set-worm-gearbox-exploded-view","status":"publish","type":"post","link":"https:\/\/gearboxes-worm.top\/as\/china-high-quality-custom-worm-gear-set-worm-gearbox-exploded-view\/","title":{"rendered":"\u099a\u09c0\u09a8 \u0989\u099a\u09cd\u099a\u09ae\u09be\u09a8\u09f0 \u0995\u09be\u09b7\u09cd\u099f\u09ae \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u099b\u09c7\u099f \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09ac\u09bf\u09b8\u09cd\u09ab\u09cb\u09f0\u09a3 \u09a6\u09c3\u09b6\u09cd\u09af"},"content":{"rendered":"<p>\u0985\u09f1\u09b8\u09cd\u09a5\u09be: \u09a8\u09a4\u09c1\u09a8<br \/>\u09f1\u09be\u09f0\u09c7\u09a3\u09cd\u099f\u09c0: \u0989\u09aa\u09b2\u09ac\u09cd\u09a7 \u09a8\u09b9\u09af\u09bc<br \/>\u0986\u0995\u09c3\u09a4\u09bf: \u0995\u09c3\u09ae\u09bf<br \/>\u09aa\u09cd\u09f0\u09af\u09cb\u099c\u09cd\u09af \u0989\u09a6\u09cd\u09af\u09cb\u0997: \u09b9\u09cb\u099f\u09c7\u09b2, \u09a8\u09bf\u09f0\u09cd\u09ae\u09be\u09a3 \u09b8\u09be\u09ae\u0997\u09cd\u09f0\u09c0\u09f0 \u09a6\u09cb\u0995\u09be\u09a8, \u0989\u09ce\u09aa\u09be\u09a6\u09a8 \u0989\u09a6\u09cd\u09af\u09cb\u0997, \u09af\u09a8\u09cd\u09a4\u09cd\u09f0\u09aa\u09be\u09a4\u09bf \u09ae\u09c7\u09f0\u09be\u09ae\u09a4\u09bf\u09f0 \u09a6\u09cb\u0995\u09be\u09a8, \u09aa\u09be\u09ae, \u0996\u09c1\u099a\u09c1\u09f0\u09be, \u09a8\u09bf\u09f0\u09cd\u09ae\u09be\u09a3 \u0995\u09be\u09ae , \u09b6\u0995\u09cd\u09a4\u09bf \u0986\u09f0\u09c1 \u0996\u09a8\u09bf, \u09ac\u09bf\u099c\u09cd\u099e\u09be\u09aa\u09a8 \u0995\u09cb\u09ae\u09cd\u09aa\u09be\u09a8\u09c0<br \/>\u09f1\u09be\u09f0\u09c7\u09a3\u09cd\u099f\u09c0 \u09b8\u09c7\u09f1\u09be\u09f0 \u09aa\u09bf\u099b\u09a4: \u0995\u09cb\u09a8\u09cb \u09b8\u09c7\u09f1\u09be \u09a8\u09be\u0987<br \/>\u09b8\u09cd\u09a5\u09be\u09a8\u09c0\u09af\u09bc \u09b8\u09c7\u09f1\u09be\u09f0 \u09b8\u09cd\u09a5\u09be\u09a8: \u09a8\u09be\u0987<br \/>\u09b6\u09cd\u09ac\u2019\u09f0\u09c1\u09ae\u09f0 \u09b8\u09cd\u09a5\u09be\u09a8: \u09a8\u09be\u0987<br \/>\u09ad\u09bf\u09a1\u09bf\u0985' \u0986\u0989\u099f\u0997\u09cb\u09af\u09bc\u09bf\u0982-\u09aa\u09f0\u09bf\u09a6\u09f0\u09cd\u09b6\u09a8: \u09aa\u09cd\u09f0\u09a6\u09be\u09a8 \u0995\u09f0\u09be \u09b9\u09c8\u099b\u09c7<br \/>\u09af\u09a8\u09cd\u09a4\u09cd\u09f0\u09aa\u09be\u09a4\u09bf \u09aa\u09f0\u09c0\u0995\u09cd\u09b7\u09be\u09f0 \u09aa\u09cd\u09f0\u09a4\u09bf\u09ac\u09c7\u09a6\u09a8: \u09aa\u09cd\u09f0\u09a6\u09be\u09a8 \u0995\u09f0\u09be \u09b9\u09c8\u099b\u09c7<br \/>\u09ac\u09bf\u09aa\u09a3\u09a8\u09f0 \u09a7\u09f0\u09a3: \u09b8\u09be\u09a7\u09be\u09f0\u09a3 \u09b8\u09be\u09ae\u0997\u09cd\u09f0\u09c0<br \/>\u09ae\u09c2\u09b2 \u0989\u09aa\u09be\u09a6\u09be\u09a8\u09b8\u09ae\u09c2\u09b9\u09f0 \u09f1\u09be\u09f0\u09c7\u09a3\u09cd\u099f\u09c0: \u09e7 \u09ac\u099b\u09f0<br \/>\u09ae\u09c2\u09b2 \u0989\u09aa\u09be\u09a6\u09be\u09a8\u09b8\u09ae\u09c2\u09b9: \u0997\u09bf\u09af\u09bc\u09be\u09f0, \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8<br \/>\u09b8\u09be\u09ae\u0997\u09cd\u09f0\u09c0: \u09b7\u09cd\u099f\u09c7\u0987\u09a8\u09b2\u09c7\u099b \u09b7\u09cd\u099f\u09c0\u09b2<br \/>\u09ae\u09be\u09a8\u0995 \u09ac\u09be \u0985\u09ae\u09be\u09a8\u09cd\u09af: \u0985\u09ae\u09be\u09a8\u09cd\u09af<br \/>\u09a6\u09bf\u09b6: \u09a0\u09bf\u0995\u09c7\u0987 \u0986\u099b\u09c7<br \/>\u09ab\u09bf\u09a8\u09bf\u099b: \u09ae\u09bf\u09f0\u2019\u09f0 \u09aa\u09b2\u09bf\u099a \u09ac\u09be \u09ac\u09cd\u09f0\u09be\u099b<br \/>\u0986\u0995\u09be\u09f0: \u0995\u09be\u09b7\u09cd\u099f\u09ae<br \/>\u09aa\u09cd\u09f0\u09ae\u09be\u09a3\u09aa\u09a4\u09cd\u09f0: ROHS, ex5 \u099a\u09c0\u09a8 \u09a8\u09bf\u09f0\u09cd\u09ae\u09be\u09a3 420 SETS \u09ae\u099f\u09f0 \u099a\u09be\u0987\u0995\u09c7\u09b2 sprockets ISO<br \/>\u0997\u09c1\u09a3\u0997\u09a4 \u09ae\u09be\u09a8: \u09e7\u09e6\u09e6\u09e7\u099f\u09bf\u09aa\u09bf\u09e9\u099f\u09bf \u09aa\u09f0\u09bf\u09a6\u09f0\u09cd\u09b6\u09a8<br \/>MOQ: \u09e7\u09e6\u09e6\u09aa\u09bf\u099a\u09bf<br \/>\u09aa\u09c7\u0995\u09bf\u0982: \u0995\u09be\u09b7\u09cd\u099f\u09ae\u09be\u0987\u099c\u09a1 \u09aa\u09c7\u0995\u09bf\u0982<br \/>\u09b8\u09b9\u09a8\u09b6\u09c0\u09b2\u09a4\u09be: \u09e6.\u09e6\u09e6\u09eb\u09ae\u09bf\u09ae\u09bf \u2013 \u09e6.\u09e7\u09ae\u09bf\u09ae\u09bf<br \/>\u09f0\u0982: \u0995\u09be\u09b7\u09cd\u099f\u09ae\u09be\u0987\u099c\u09a1 \u09f0\u0982<br \/>\u09b8\u09c1\u09ac\u09bf\u09a7\u09be: \u0995\u09ae \u09b8\u09b9\u09a8\u09b6\u09c0\u09b2\u09a4\u09be<br \/>\u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u0997: \u099f\u09cd\u09f0\u09c7\u09a8\u09cd\u09b8\u09ae\u09bf\u099b\u09a8 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8<br \/>\u09aa\u09c7\u0995\u09c7\u099c\u09bf\u0982 \u09ac\u09bf\u09f1\u09f0\u09a3: \u09aa\u09bf\u09aa\u09bf \u09ac\u09c7\u0997 ,\u0995\u09be\u09f0\u09cd\u099f\u09a8 \u09ac\u09be \u0997\u09cd\u09f0\u09be\u09b9\u0995\u09f0 requirments \u0985\u09a8\u09c1\u09b8\u09f0\u09bfCustom \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b8\u09c7\u099f<br \/>\u09ac\u09a8\u09cd\u09a6\u09f0: \u09b9\u09be\u0982\u099d\u09cc<\/p>\n<table>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\u09b8\u09be\u09ae\u0997\u09cd\u09f0\u09c0<\/td>\n<td colspan=\"4\" rowspan=\"1\">\u0995\u09be\u09b7\u09cd\u099f\u09ae \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u099a\u09c7\u099f<\/td>\n<td rowspan=\"0\"><\/td>\n<td rowspan=\"0\"><\/td>\n<td rowspan=\"0\"><\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\u0986\u0995\u09be\u09f0\u00a0<\/td>\n<td colspan=\"4\" rowspan=\"1\">\u0995\u09be\u09b7\u09cd\u099f\u09ae\u09be\u0987\u099c\u09a1<\/td>\n<td rowspan=\"0\"><\/td>\n<td rowspan=\"0\"><\/td>\n<td rowspan=\"0\"><\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\u09b8\u09be\u09ae\u0997\u09cd\u09f0\u09c0<\/td>\n<td colspan=\"4\" rowspan=\"1\">\u09b7\u09cd\u099f\u09c7\u0987\u09a8\u09b2\u09c7\u099b \u09b7\u09cd\u099f\u09c0\u09b2<\/td>\n<td rowspan=\"0\"><\/td>\n<td rowspan=\"0\"><\/td>\n<td rowspan=\"0\"><\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\u09aa\u09c3\u09b7\u09cd\u09a0<\/td>\n<td colspan=\"4\" rowspan=\"1\">\u09b6\u09c7\u09b7 \u0995\u09f0\u0995 \u09aa\u09f0\u09bf\u09b7\u09cd\u0995\u09be\u09f0 \u09ac\u09be \u09aa\u09b2\u09bf\u099a \u0995\u09f0\u0995<\/td>\n<td rowspan=\"0\"><\/td>\n<td rowspan=\"0\"><\/td>\n<td rowspan=\"0\"><\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\u09b8\u09b9\u09a8\u09b6\u09c0\u09b2\u09a4\u09be<\/td>\n<td colspan=\"4\" rowspan=\"1\">\u00b1\u09e6.\u09e6\u09e7\u09ae\u09bf\u09ae\u09bf<\/td>\n<td rowspan=\"0\"><\/td>\n<td rowspan=\"0\"><\/td>\n<td rowspan=\"0\"><\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">MOQ<\/td>\n<td colspan=\"4\" rowspan=\"1\">\u09e7\u09e6\u09e6\u09e6\u09aa\u09bf\u099a\u09bf<\/td>\n<td rowspan=\"0\"><\/td>\n<td rowspan=\"0\"><\/td>\n<td rowspan=\"0\"><\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\u09ac\u09a8\u09cd\u09a6\u09f0<\/td>\n<td colspan=\"4\" rowspan=\"1\">\u09b9\u09be\u0982\u099d\u09cc\u00a0<\/td>\n<td rowspan=\"0\"><\/td>\n<td rowspan=\"0\"><\/td>\n<td rowspan=\"0\"><\/td>\n<\/tr>\n<\/table>\n<p> \u0997\u09cd\u09f0\u09be\u09b9\u0995\u09f0 \u09aa\u09a3\u09cd\u09af\u09f0 \u09aa\u09f0\u09be\u09ae\u09f0\u09cd\u09b6 \u0995\u09cb\u09ae\u09cd\u09aa\u09be\u09a8\u09c0 \u09aa\u09cd\u09f0\u09ab\u09be\u0987\u09b2 \u0986\u09ae\u09be\u0995 \u0995\u09bf\u09af\u09bc \u09ac\u09be\u099b\u09bf \u09b2\u0993\u0995 \u0986\u09ae\u09be\u09f0 \u09b8\u09c1\u09ac\u09bf\u09a7\u09be\u09b8\u09ae\u09c2\u09b9 \u0997\u09cd\u09f0\u09be\u09b9\u0995\u09f0 \u09ab\u099f\u09cb \u09aa\u09a3\u09cd\u09af \u09ab\u099f\u09cb FAQQQ: \u0986\u09aa\u09c1\u09a8\u09bf \u0995\u09cb\u09ae\u09cd\u09aa\u09be\u09a8\u09c0 \u09ac\u09be \u09aa\u09cd\u09f0\u09b8\u09cd\u09a4\u09c1\u09a4\u0995\u09be\u09f0\u0995 \u09ac\u09cd\u09af\u09f1\u09b8\u09be\u09af\u09bc \u0995\u09f0\u09c7 \u09a8\u09c7\u0995\u09bf ?A: \u0986\u09ae\u09bf factory.Q: \u09ae\u0987 \u0989\u09a6\u09cd\u09a7\u09c3\u09a4\u09bf \u0995\u09c7\u09a8\u09c7\u0995\u09c8 \u09aa\u09be\u09ac \u09aa\u09be\u09f0\u09cb?A: \u0989\u09a6\u09cd\u09a7\u09c3\u09a4\u09bf\u09f0 \u09ac\u09be\u09ac\u09c7 \u0986\u09ae\u09be\u0995 \u09a4\u09a5\u09cd\u09af \u09aa\u09be\u09a0\u09be\u0993\u0995: \u0985\u0982\u0995\u09a8, \u09b8\u09be\u09ae\u0997\u09cd\u09f0\u09c0, \u0993\u099c\u09a8, \u09aa\u09f0\u09bf\u09ae\u09be\u09a3 \u0986\u09f0\u09c1 \u0985\u09a8\u09c1\u09f0\u09cb\u09a7,w PDF, ISGS, Thinkrider \u0989\u099a\u09cd\u099a\u09ae\u09be\u09a8\u09f0 \u099a\u09be\u0987\u0995\u09c7\u09b2 \u0985\u0982\u09b6 \u09ac\u09be\u0987\u0995 \u099a\u09b2\u0995 \u0995\u09c7\u099b\u09c7\u099f \u0997\u09cd\u09f0\u09b9\u09a3 \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09c7 11 Speed \u200b\u200bCassette DWG, STEP fileformat.If \u0986\u09aa\u09a8\u09bf \u0985\u0982\u0995\u09a8 \u09a8\u09be\u09a5\u09be\u0995\u09c7, \u0985\u09a8\u09c1\u0997\u09cd\u09b0\u09b9 \u0995\u09b0\u09c7 \u09a8\u09ae\u09c1\u09a8\u09be \u09aa\u09a0\u09be\u0993\u0995,\u0986\u09ae\u09b0\u09be \u0986\u09aa\u09a8\u09be\u09b0 sample too.Q \u09ad\u09bf\u09a4\u09cd\u09a4\u09bf\u0995 \u0989\u09a6\u09cd\u09a7\u09c3\u09a4\u09bf \u0995\u09b0\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8: '\u098f\u0987\u099f\u09cb \u09ac\u09bf\u09a8\u09be\u09ae\u09c2\u09b2\u09c0\u09af\u09bc\u09be \u09a8\u09c7 \u0985\u09a4\u09bf\u09f0\u09bf\u0995\u09cd\u09a4 ?\u0989\u09a4\u09cd\u09a4\u09f0: \u09b9\u09af\u09bc, \u0986\u09ae\u09bf \u09a8\u09ae\u09c1\u09a8\u09be\u099f\u09cb \u09ac\u09bf\u09a8\u09be\u09ae\u09c2\u09b2\u09c0\u09af\u09bc\u09be \u099a\u09be\u09f0\u09cd\u099c\u09f0 \u09ac\u09be\u09ac\u09c7 \u0986\u0997\u09ac\u09a2\u09bc\u09be\u09ac \u09aa\u09be\u09f0\u09bf\u09b2\u09cb\u0981\u09b9\u09c7\u0981\u09a4\u09c7\u09a8 \u0995\u09bf\u09a8\u09cd\u09a4\u09c1 \u09ae\u09be\u09b2\u09ac\u09be\u09b9\u09c0\u09f0 \u0996\u09f0\u099a \u09a8\u09bf\u09a6\u09bf\u0993\u0981\u0964 \u09aa\u09cd\u09f0\u09b6\u09cd\u09a8: \u0997\u09a3 \u0989\u09ce\u09aa\u09be\u09a6\u09a8\u09f0 \u09ac\u09be\u09ac\u09c7 \u0986\u0997\u09b6\u09be\u09f0\u09c0\u09f0 \u09b8\u09ae\u09af\u09bc\u09f0 \u09ac\u09bf\u09b7\u09af\u09bc\u09c7 \u0995\u09bf \u0995'\u09ac \u09aa\u09be\u09f0\u09bf? \u0989\u09a4\u09cd\u09a4\u09f0: \u09b8\u0981\u099a\u09be\u0995\u09c8\u09af\u09bc\u09c7, \u0987 \u0985\u09f0\u09cd\u09a1\u09be\u09f0\u09f0 \u09aa\u09f0\u09bf\u09ae\u09be\u09a3\u09f0 \u0993\u09aa\u09f0\u09a4 \u09a8\u09bf\u09f0\u09cd\u09ad\u09f0 \u0995\u09f0\u09c7\u0964 \u09b8\u09be\u09a7\u09be\u09f0\u09a3\u09a4\u09c7, \u0986\u09aa\u09cb\u09a8\u09be\u09f0 \u099c\u09ae\u09be \u09a7\u09a8\u09f0 \u09e7\u09eb \u09a6\u09bf\u09a8\u09f0 \u09aa\u09f0\u09be \u09e8\u09e6 \u09a6\u09bf\u09a8\u09f0 \u09aa\u09bf\u099b\u09a4 \u09af\u09a6\u09bf \u0995\u09cb\u09a8\u09cb \u09b8\u0981\u099c\u09c1\u09b2\u09bf\u09f0 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u099c\u09a8 \u09a8\u09b9\u09af\u09bc\u0964 \u09aa\u09cd\u09f0\u09b6\u09cd\u09a8: \u09af\u09a6\u09bf \u0985\u0982\u09b6\u09ac\u09cb\u09f0 \u09ad\u09be\u09b2 \u09a8\u09b9\u09af\u09bc \u09a4\u09c7\u09a8\u09cd\u09a4\u09c7 \u0995\u09bf \u09b9'\u09ac?\u0989\u09a4\u09cd\u09a4\u09f0:\u0986\u09ae\u09bf \u09ad\u09be\u09b2 \u09ae\u09be\u09a8\u09f0 \u09a8\u09bf\u09b6\u09cd\u099a\u09af\u09bc\u09a4\u09be \u09a6\u09bf\u09ac \u09aa\u09be\u09f0\u09cb, WY125 \u09f0 \u09ac\u09be\u09ac\u09c7 428H-128L 39T 15T \u09b8\u09cd\u09aa\u09cd\u09f0\u0995\u09c7\u099f \u0995\u09bf\u099f \u09ae\u099f\u09f0 \u099a\u09be\u0987\u0995\u09c7\u09b2 \u09b9\u09c7\u09ad\u09bf \u09a1\u09bf\u0989\u099f\u09bf \u200b\u200b\u099f\u09cd\u09f0\u09c7\u09a8\u09cd\u09b8\u09ae\u09bf\u099b\u09a8 \u0995\u09bf\u099f \u0995\u09bf\u09a8\u09cd\u09a4\u09c1 \u09af\u09a6\u09bf \u0998\u099f\u09c7,\u0985\u09a8\u09c1\u0997\u09cd\u09f0\u09b9 \u0995\u09f0\u09bf \u09a4\u09ce\u0995\u09cd\u09b7\u09a3\u09be\u09a4 \u0986\u09ae\u09be\u09f0 \u09b8\u09c8\u09a4\u09c7 \u09af\u09cb\u0997\u09be\u09af\u09cb\u0997 \u0995\u09f0\u0995, \u0995\u09bf\u099b\u09c1\u09ae\u09be\u09a8 \u099b\u09ac\u09bf \u09b2\u0993\u0995, \u0986\u09ae\u09bf \u09b8\u09ae\u09b8\u09cd\u09af\u09be\u099f\u09cb \u09aa\u09f0\u09c0\u0995\u09cd\u09b7\u09be \u0995\u09f0\u09bf\u09ae, \u0986\u09f0\u09c1 \u09b8\u09ae\u09be\u09a7\u09be\u09a8 \u0995\u09f0\u09bf\u09ae asap.Q: \u0986\u09aa\u09cb\u09a8\u09be\u09f0 \u09aa\u09c7\u09ae\u09c7\u09a3\u09cd\u099f\u09f0 \u099a\u09f0\u09cd\u09a4\u09b8\u09ae\u09c2\u09b9 \u0995\u09bf ?A: \u09aa\u09c7\u09ae\u09c7\u09a8\u09cd\u099f=1000USD, 30% T\/T \u0986\u0997\u09a4\u09c0\u09af\u09bc\u09be\u0995\u09c8 ,shippment \u0986\u0997\u09a4 \u09ad\u09be\u09f0\u09b8\u09be\u09ae\u09cd\u09af<\/p>\n<p><p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/T_worm_reducer_1.webp\" alt=\"worm reducer\" width=\"800\" \/><\/p>\n<h2>\u0995\u09c3\u09ae\u09bf \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u2013 \u0986\u09aa\u09c1\u09a8\u09bf \u0995\u09bf \u099c\u09be\u09a8\u09bf\u09ac \u09b2\u09be\u0997\u09bf\u09ac<\/h2>\n<p>Worm reducer gearbox \u09f0 \u09ac\u09be\u09ac\u09c7 \u09ac\u099c\u09be\u09f0 \u0995\u09f0\u09be\u09f0 \u09b8\u09ae\u09af\u09bc\u09a4 \u0987\u0989\u09a8\u09bf\u099f\u099f\u09cb\u09f0 \u0995\u09be\u09f0\u09cd\u09af\u09cd\u09af \u0986\u09f0\u09c1 \u09ac\u09c8\u09b6\u09bf\u09b7\u09cd\u099f\u09cd\u09af\u09b8\u09ae\u09c2\u09b9 \u09ac\u09bf\u09ac\u09c7\u099a\u09a8\u09be \u0995\u09f0\u09be\u099f\u09cb \u0997\u09c1\u09f0\u09c1\u09a4\u09cd\u09ac\u09aa\u09c2\u09f0\u09cd\u09a3\u0964 \u0987\u09af\u09bc\u09be\u09f0 \u0996\u09f0\u099a\u09cb \u09b2\u0995\u09cd\u09b7\u09cd\u09af \u0995\u09f0\u09be\u099f\u09cb \u0997\u09c1\u09f0\u09c1\u09a4\u09cd\u09ac\u09aa\u09c2\u09f0\u09cd\u09a3\u0964 \u0986\u09ae\u09bf \u09ac\u09bf\u09ad\u09bf\u09a8\u09cd\u09a8 \u09a7\u09f0\u09a3\u09f0 \u0995\u09c3\u09ae\u09bf \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u0986\u09f0\u09c1 \u0987\u09af\u09bc\u09be\u0995 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09bf\u09ac \u09aa\u09f0\u09be \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u0997\u09b8\u09ae\u09c2\u09b9 \u099a\u09be\u09ae\u0964 \u0987\u09af\u09bc\u09be\u09f0 \u09a6\u09cd\u09ac\u09be\u09f0\u09be \u0986\u09aa\u09cb\u09a8\u09be\u09f0 \u098f\u09aa\u09cd\u09b2\u09bf\u0995\u09c7\u099a\u09a8\u09f0 \u09ac\u09be\u09ac\u09c7 \u09b8\u09a0\u09bf\u0995 \u0987\u0989\u09a8\u09bf\u099f \u09ac\u09be\u099b\u09bf \u09b2\u09cb\u09f1\u09be\u09a4 \u09b8\u09b9\u09be\u09af\u09bc\u0995 \u09b9\u2019\u09ac\u0964<\/p>\n<h2>\u09ac\u09c8\u09b6\u09bf\u09b7\u09cd\u099f\u09cd\u09af\u09b8\u09ae\u09c2\u09b9<\/h2>\n<p>\u09a6\u09cd\u09f0\u09c1\u09a4\u09ad\u09be\u09f1\u09c7 \u09f0\u0996\u09be\u09f0 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u099c\u09a8 \u09b9\u09cb\u09f1\u09be \u09af\u09a8\u09cd\u09a4\u09cd\u09f0 \u09af\u09c7\u09a8\u09c7 \u09b2\u09bf\u09ab\u09cd\u099f \u0986\u09f0\u09c1 \u09b2\u09bf\u09ab\u09cd\u099f\u09a4 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u099c\u09a8\u09aa\u09cd\u09f0\u09bf\u09af\u09bc\u0964 \u0987\u09b9\u0981\u09a4\u09f0 \u0995\u09cb\u09ae\u09b2 \u09aa\u09a6\u09be\u09f0\u09cd\u09a5\u0987 \u0987\u09b9\u0981\u09a4\u0995 \u09b6\u09cd\u09ac\u0995 \u09b6\u09cb\u09b7\u09a3 \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u0985\u09a8\u09c1\u09ae\u09a4\u09bf \u09a6\u09bf\u09af\u09bc\u09c7, \u09af\u09be\u09f0 \u09ab\u09b2\u09a4 \u09ac\u09bf\u0995\u09b2 \u09b9\u09cb\u09f1\u09be\u09f0 \u09b8\u09ae\u09cd\u09ad\u09be\u09f1\u09a8\u09be \u0995\u09ae \u09b9\u09af\u09bc\u0964 \u0997\u09a7\u09c1\u09f0 \u09af\u09a8\u09cd\u09a4\u09cd\u09f0, \u09af\u09c7\u09a8\u09c7 \u09b6\u09bf\u09b2 \u0997\u09c1\u09a1\u09bc\u09bf \u0995\u09f0\u09be \u09af\u09a8\u09cd\u09a4\u09cd\u09f0\u09a4\u09cb \u0987 \u0989\u09aa\u0995\u09be\u09f0\u09c0\u0964 \u0995\u09bf\u099b\u09c1\u09ae\u09be\u09a8 \u09aa\u09cd\u09f0\u09b8\u09cd\u09a4\u09c1\u09a4\u0995\u09be\u09f0\u09c0\u09af\u09bc\u09c7 \u09b6\u09c2\u09a8\u09cd\u09af \u09ac\u09c7\u0995\u09b2\u09c7\u099b \u0986\u09f0\u09c1 \u0989\u099a\u09cd\u099a-\u09b8\u09a0\u09bf\u0995\u09a4\u09be \u09b9\u09cd\u09f0\u09be\u09b8\u09f0 \u09b8\u09c8\u09a4\u09c7 \u09ac\u09bf\u09b6\u09c7\u09b7 \u0995\u09c3\u09ae\u09bf \u0986\u0997\u09ac\u09a2\u09bc\u09be\u09af\u09bc\u0964 \u0995\u09c3\u09ae\u09bf \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09a4 \u0985\u0995\u09cd\u09b7\u09c0\u09af\u09bc \u09aa\u09bf\u099a \u0986\u09f0\u09c1 \u09ac\u09c3\u09a4\u09cd\u09a4\u09be\u0995\u09be\u09f0 \u09aa\u09bf\u099a\u0995\u09c7 \u09a7\u09f0\u09bf \u09ac\u09bf\u09ad\u09bf\u09a8\u09cd\u09a8 \u09ac\u09c8\u09b6\u09bf\u09b7\u09cd\u099f\u09cd\u09af \u0986\u099b\u09c7\u0964 \u0995\u09c3\u09ae\u09bf\u09f0 \u0985\u0995\u09cd\u09b7\u09c0\u09af\u09bc \u09aa\u09bf\u099a \u09a1\u09be\u0999\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09ac\u09c3\u09a4\u09cd\u09a4\u09be\u0995\u09be\u09f0 \u09aa\u09bf\u099a\u09f0 \u09b2\u0997\u09a4 \u09ae\u09bf\u09b2\u09bf\u09ac \u09b2\u09be\u0997\u09bf\u09ac\u0964 \u0987\u09af\u09bc\u09be\u09f0 \u09b8\u09c2\u09a4\u09be \u09ac\u09be\u0993\u0981 \u09ac\u09be \u09b8\u09cb\u0981\u09b9\u09be\u09a4\u09f0 \u09b9\u09af\u09bc \u0986\u09f0\u09c1 \u0987\u09af\u09bc\u09be\u09f0 \u09b8\u09c0\u09b9\u09f0 \u0995\u09cb\u09a3 \u09b9'\u09b2 \u0995\u09c3\u09ae\u09bf\u09f0 \u09ac\u09bf\u09aa\u09cd\u09b2\u09f1\u09f0 \u09b8\u09ae\u09af\u09bc\u09a4 \u09b8\u09c2\u09a4\u09be\u09f0 \u098f\u099f\u09be \u09ac\u09bf\u09a8\u09cd\u09a6\u09c1\u09f1\u09c7 \u09af\u09be\u09a4\u09cd\u09f0\u09be \u0995\u09f0\u09be \u09a6\u09c2\u09f0\u09a4\u09cd\u09ac\u0964 \u0995\u09c3\u09ae\u09bf\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09ac\u09b9\u09c1\u09b2\u09ad\u09be\u09f1\u09c7 \u0989\u09aa\u09b2\u09ac\u09cd\u09a7, \u0986\u09f0\u09c1 \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09a8\u09bf\u09f0\u09cd\u09ae\u09be\u09a4\u09be\u09b8\u0995\u09b2\u09c7 \u09b8\u09be\u09a7\u09be\u09f0\u09a3\u09a4\u09c7 \u0987\u09af\u09bc\u09be\u09f0 \u09ac\u09c3\u09b9\u09ce \u09a4\u09a5\u09cd\u09af \u09f0\u09be\u0996\u09c7\u0964 \u09af\u09bf\u09b9\u09c7\u09a4\u09c1 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09b8\u09ae\u09c2\u09b9 \u09aa\u09cd\u09f0\u09be\u09ae\u09be\u09a3\u09bf\u0995, \u0987\u09af\u09bc\u09be\u09f0 \u09ae\u09be\u0989\u09a3\u09cd\u099f\u09bf\u0982 \u09ae\u09be\u09a4\u09cd\u09f0\u09be \u09b8\u09be\u09a7\u09be\u09f0\u09a3\u09a4\u09c7 \u09aa\u09cd\u09f0\u09b8\u09cd\u09a4\u09c1\u09a4\u0995\u09be\u09f0\u0995\u09b8\u0995\u09b2\u09f0 \u09ae\u09be\u099c\u09a4 \u098f\u0995\u09c7\u0964 \u0987\u09af\u09bc\u09be\u09f0 \u0985\u09f0\u09cd\u09a5 \u09b9'\u09b2 \u098f\u099f\u09be \u09ac\u09be\u099b\u09a8\u09bf \u0995\u09f0\u09bf\u09b2\u09c7 \u0986\u09aa\u09c1\u09a8\u09bf \u0986\u0989\u099f\u09aa\u09c1\u099f \u0996\u09be\u09a6\u09f0 \u0989\u099a\u09cd\u099a\u09a4\u09be, \u09a6\u09c8\u09f0\u09cd\u0998\u09cd\u09af \u09ac\u09be \u09ac\u09cd\u09af\u09be\u09b8 \u09b8\u09b2\u09a8\u09bf \u0995\u09f0\u09be\u09f0 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u099c\u09a8 \u09a8\u09b9'\u09ac\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u09ae\u09be\u09a4\u09cd\u09f0\u09bf\u0995 \u09b8\u09be\u09ae\u099e\u09cd\u099c\u09b8\u09cd\u09af\u0993 \u09a5\u09be\u0995\u09c7\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u0985\u09a4\u09bf \u0995\u09be\u09f0\u09cd\u09af\u0995\u09cd\u09b7\u09ae\u0964 \u0987\u09b9\u0981\u09a4\u09f0 \u09ac\u09cb\u099c\u09be \u0995\u09cd\u09b7\u09ae\u09a4\u09be \u09ac\u09c7\u099b\u09bf \u0986\u09f0\u09c1 \u0998\u09f0\u09cd\u09b7\u09a3 \u09b8\u09b9\u0997 \u0995\u09ae\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u09cb\u09f0\u09f0 \u098f\u099f\u09be \u09a8\u09bf\u0996\u09c1\u0981\u09a4 \u09a6\u09be\u0981\u09a4\u09f0 \u09aa\u09cd\u09f0\u09ab\u09be\u0987\u09b2\u0993 \u09a5\u09be\u0995\u09c7, \u09af\u09be\u09f0 \u09ab\u09b2\u09a4 \u0997\u09a4\u09bf\u09f0 \u0989\u09a0\u09be-\u09a8\u09ae\u09be \u09b9\u09cd\u09f0\u09be\u09b8 \u09aa\u09be\u09af\u09bc \u0986\u09f0\u09c1 \u09a8\u09bf\u09b8\u09cd\u09a4\u09ac\u09cd\u09a7\u09ad\u09be\u09f1\u09c7 \u0995\u09be\u09ae \u0995\u09f0\u09bf\u09ac \u09aa\u09f0\u09be \u09af\u09be\u09af\u09bc\u0964<\/p>\n<h2>\u0995\u09be\u09f0\u09cd\u09af\u09cd\u09af\u09b8\u09ae\u09c2\u09b9<\/h2>\n<p>\u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u0995\u09be\u09ae \u09ac\u09c7\u09b2\u09c7\u0997 \u09ac\u09c7\u09b2\u09c7\u0997\u0964 \u09ac\u09bf\u09ad\u09bf\u09a8\u09cd\u09a8 \u09a7\u09f0\u09a3\u09f0 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u0997\u09a4 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09bf\u0964 \u0989\u09a6\u09be\u09b9\u09f0\u09a3\u09b8\u09cd\u09ac\u09f0\u09c2\u09aa\u09c7, \u09b2\u09bf\u09ab\u099f\u09f0 \u0993\u09aa\u09f0\u09a4 \u09ac\u09cb\u099c\u09be \u0995\u09ae \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u09b2\u09bf\u09ab\u099f\u09a4 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09bf\u0964 \u098f\u0987 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u09cb\u09f0\u09f0 \u09b6\u09ac\u09cd\u09a6\u09f0 \u09ae\u09be\u09a4\u09cd\u09f0\u09be\u0993 \u0995\u09ae \u0995\u09be\u09f0\u09a3 \u0987\u09b9\u0981\u09a4 \u0985\u09b8\u09a6\u09c3\u09b6 \u09a7\u09be\u09a4\u09c1\u09f0\u09c7 \u09a8\u09bf\u09f0\u09cd\u09ae\u09bf\u09a4\u0964 \u09a4\u09a6\u09c1\u09aa\u09f0\u09bf \u098f\u0987 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u09cb\u09f0 \u09b2\u09bf\u09ab\u099f\u09a4 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09bf \u0995\u09be\u09f0\u09a3 \u098f\u0987 \u09a7\u09f0\u09a3\u09f0 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u0997\u09f0 \u09ac\u09be\u09ac\u09c7 \u0989\u09aa\u09af\u09cb\u0997\u09c0\u0964 \u0995\u09bf\u09a8\u09cd\u09a4\u09c1 \u09b8\u09a0\u09bf\u0995\u09ad\u09be\u09f1\u09c7 \u0995\u09be\u09ae \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u0987\u09b9\u0981\u09a4\u0995 \u098f\u099f\u09be \u098f\u0995\u0995 \u09aa\u09f0\u09cd\u09af\u09be\u09af\u09bc\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u099c\u09a8 \u09b9\u09af\u09bc\u0964 \u0995\u09c3\u09ae\u09bf \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u0986\u09a8 \u098f\u099f\u09be \u0997\u09c1\u09f0\u09c1\u09a4\u09cd\u09ac\u09aa\u09c2\u09f0\u09cd\u09a3 \u09ac\u09c8\u09b6\u09bf\u09b7\u09cd\u099f\u09cd\u09af \u09b9\u2019\u09b2 \u0987 \u0993\u09b2\u09cb\u099f\u09be\u0995\u09c8 \u0995\u09be\u09ae \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09c7\u0964 \u0985\u09f0\u09cd\u09a5\u09be\u09ce \u0987\u09a8\u09aa\u09c1\u099f \u0996\u09be\u09a6\u099f\u09cb \u09aa\u09bf\u099b\u09b2\u09c8 \u0998\u09c2\u09f0\u09bf \u09a5\u09be\u0995\u09c7, \u0986\u09a8\u09b9\u09be\u09a4\u09c7 \u0986\u0989\u099f\u09aa\u09c1\u099f \u0996\u09be\u09a6\u099f\u09cb \u0986\u0997\u09b2\u09c8 \u0998\u09c2\u09f0\u09bf \u09a5\u09be\u0995\u09c7\u0964 \u098f\u09a8\u09c7 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u0997\u09f0 \u0989\u09a6\u09be\u09b9\u09f0\u09a3 \u09b9'\u09b2 \u09b9\u09be\u09a4\u09c7\u09f0\u09c7 \u0995\u09cd\u09f0\u09c7\u0982\u0995 \u0995\u09f0\u09be \u0995\u09c7\u09a8\u09cd\u09a6\u09cd\u09f0\u099a\u09be\u09b2\u09bf\u09a4, \u09b2\u09cb\u09b9\u09be\u09f0 \u0995\u09be\u09ae\u09f0 \u099c\u09be\u09b2 \u09ac\u09cd\u09b2'\u09f1\u09be\u09f0, \u0986\u09f0\u09c1 \u09b8\u0982\u0997\u09c0\u09a4\u09f0 \u09ac\u09be\u0995\u099a\u09f0 \u09ac\u09a4\u09be\u09b9\u09f0 \u0997\u09f1\u09f0\u09cd\u09a3\u09f0\u0964 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u099b\u09c7\u099f\u09f0 \u09aa\u09f0\u09be \u0986\u09f0\u09ae\u09cd\u09ad \u0995\u09f0\u09bf \u09b9\u09be\u0989\u099a\u09a1 \u0987\u0989\u09a8\u09bf\u099f\u09b2\u09c8\u0995\u09c7 \u09ac\u09bf\u09ad\u09bf\u09a8\u09cd\u09a8 \u0986\u0995\u09c3\u09a4\u09bf \u0986\u09f0\u09c1 \u0986\u0995\u09be\u09f0\u09a4 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u0989\u09aa\u09b2\u09ac\u09cd\u09a7\u0964 \u0987\u09af\u09bc\u09be\u0995 \u09ac\u09b9\u09c1-\u0997\u09a4\u09bf\u09f0 \u09a1\u09bf\u099c\u09be\u0987\u09a8 \u09b9\u09bf\u099a\u09be\u09aa\u09c7\u0993 \u0995\u09a8\u09ab\u09bf\u0997\u09be\u09f0 \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09bf\u0964 \u0995\u09bf\u099b\u09c1\u09ae\u09be\u09a8 \u09a8\u09bf\u09f0\u09cd\u09ae\u09be\u09a4\u09be\u0987 \u09ac\u09bf\u09b6\u09c7\u09b7 \u09a8\u09bf\u0996\u09c1\u0981\u09a4 \u0986\u09f0\u09c1 \u09b6\u09c2\u09a8\u09cd\u09af-\u09ac\u09c7\u0995\u09b2\u09c7\u099b \u0995\u09c3\u09ae\u09bf\u0993 \u0986\u0997\u09ac\u09a2\u09bc\u09be\u09af\u09bc\u0964 \u098f\u099f\u09be \u0995\u09c3\u09ae\u09bf \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u09a6\u09be\u0981\u09a4\u09f0 \u0986\u0995\u09c3\u09a4\u09bf \u09a1\u09bf\u09ad\u09be\u0987\u099a\u099f\u09cb\u09f0 \u0995\u09cd\u09b7\u09ae\u09a4\u09be \u09a8\u09bf\u09f0\u09cd\u09a3\u09af\u09bc \u0995\u09f0\u09be\u09a4 \u0997\u09c1\u09f0\u09c1\u09a4\u09cd\u09ac\u09aa\u09c2\u09f0\u09cd\u09a3\u0964 \u09b8\u09be\u09a7\u09be\u09f0\u09a3\u09a4\u09c7 \u098f\u0995\u0995 \u09b8\u09c0\u09b9\u09f0 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09ac\u09be\u0993\u0981 \u0986\u09f0\u09c1 \u09b8\u09cb\u0981 \u09a6\u09be\u0981\u09a4\u09f0 \u09aa\u09c3\u09b7\u09cd\u09a0\u09a4 \u098f\u0995\u09c7 \u09b2\u09bf\u09a1 \u09a5\u09be\u0995\u09c7 \u09af\u09a6\u09bf\u0993 \u09a6\u09cd\u09ac\u09c8\u09a4 \u09b8\u09c0\u09b9\u09f0 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09aa\u09cd\u09f0\u09a4\u09bf\u099f\u09cb \u09ab\u09be\u09b2\u09c7 \u09ac\u09c7\u09b2\u09c7\u0997 \u09ac\u09c7\u09b2\u09c7\u0997 \u09b2\u09bf\u09a1 \u09a5\u09be\u0995\u09c7\u0964 \u098f\u0987 \u09ac\u09c8\u09b6\u09bf\u09b7\u09cd\u099f\u09cd\u09af\u0987 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09a4 \u0996\u09c7\u09b2\u09be-\u09a7\u09c2\u09b2\u09be \u09a6\u09c2\u09f0 \u0995\u09f0\u09be\u09a4 \u09b8\u09b9\u09be\u09af\u09bc \u0995\u09f0\u09c7\u0964 \u0995\u09bf\u09a8\u09cd\u09a4\u09c1 \u09ae\u09a8 \u0995\u09f0\u09bf\u09ac\u09b2\u0997\u09c0\u09af\u09bc\u09be \u09af\u09c7 \u09ac\u09bf\u09ad\u09bf\u09a8\u09cd\u09a8 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u0997\u09f0 \u09ac\u09be\u09ac\u09c7 \u09ac\u09bf\u09ad\u09bf\u09a8\u09cd\u09a8 \u09a6\u09be\u0981\u09a4\u09f0 \u0986\u0995\u09c3\u09a4\u09bf\u09f0 \u0995\u09c3\u09ae\u09bf \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09aa\u09cd\u09f0\u09b8\u09cd\u09a4\u09c1\u09a4 \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09bf\u0964\u09aa\u09cd\u09f0\u099a\u09b2\u09bf\u09a4 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09ac\u09bf\u0995\u09b2\u09cd\u09aa \u09b9\u09bf\u099a\u09be\u09aa\u09c7 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u0964 \u0987 \u09b8\u09be\u09a7\u09be\u09f0\u09a3 \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09a1\u09cd\u09f0\u09be\u0987\u09ad\u09f0 \u09a6\u09f0\u09c7\u0987 \u0995\u09be\u09ae \u0995\u09f0\u09c7\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09ae\u09c2\u09b2 \u09b8\u09c1\u09ac\u09bf\u09a7\u09be\u099f\u09cb \u09b9\u2019\u09b2 \u0987 \u0998\u09c2\u09f0\u09cd\u09a3\u09a8\u09b6\u09c0\u09b2 \u0996\u09be\u09a6\u09f0 \u0998\u09c2\u09f0\u09cd\u09a3\u09a8\u09f0 \u0997\u09a4\u09bf \u0986\u09f0\u09c1 \u099f\u09f0\u09cd\u0995 \u09b9\u09cd\u09f0\u09be\u09b8 \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u09b8\u0995\u09cd\u09b7\u09ae \u09b9\u09af\u09bc\u0964 \u0987\u09af\u09bc\u09be\u09f0 \u0989\u09aa\u09f0\u09bf\u0993 \u0987\u09af\u09bc\u09be\u09f0 \u0985\u09a4\u09bf\u09f0\u09bf\u0995\u09cd\u09a4 \u09b8\u09c1\u09ac\u09bf\u09a7\u09be \u0986\u099b\u09c7 \u09af\u09c7 \u0987 \u09ef\u09e6 \u09a1\u09bf\u0997\u09cd\u09f0\u09c0 \u0995\u09cb\u09a3\u09a4 \u0997\u09a4\u09bf \u09b8\u09cd\u09a5\u09be\u09a8\u09be\u09a8\u09cd\u09a4\u09f0 \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09c7\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u098f\u0995\u09ae\u09be\u09a4\u09cd\u09f0 \u0985\u09b8\u09c1\u09ac\u09bf\u09a7\u09be \u09b9\u2019\u09b2 \u0987 \u0997\u09a4\u09bf \u0989\u09b2\u099f\u09bf\u09ac \u09a8\u09cb\u09f1\u09be\u09f0\u09c7\u0964<\/p>\n<h2>\u0986\u09ac\u09c7\u09a6\u09a8<\/h2>\n<p>\u098f\u0987 \u09ac\u099c\u09be\u09f0 \u09aa\u09cd\u09f0\u09a4\u09bf\u09ac\u09c7\u09a6\u09a8\u09c7 \u09ac\u09bf\u09b6\u09cd\u09ac\u09f0 \u09a6\u09c3\u09b7\u09cd\u099f\u09bf\u0995\u09cb\u09a3\u09f0 \u09aa\u09f0\u09be Worm reducer gearbox \u09ac\u099c\u09be\u09f0 \u09ac\u09bf\u09b6\u09cd\u09b2\u09c7\u09b7\u09a3 \u0995\u09f0\u09c7\u0964 \u0987\u09af\u09bc\u09be\u09a4 \u09ac\u09f0\u09cd\u09a4\u09ae\u09be\u09a8\u09f0 \u09ac\u099c\u09be\u09f0\u09f0 \u09a7\u09be\u09f0\u09be \u0986\u09f0\u09c1 \u09ad\u09f1\u09bf\u09b7\u09cd\u09af\u09a4\u09f0 \u09ac\u09c3\u09a6\u09cd\u09a7\u09bf\u09f0 \u09b8\u09ae\u09cd\u09ad\u09be\u09f1\u09a8\u09be\u09f0 \u09ac\u09bf\u09b8\u09cd\u09a4\u09c3\u09a4 \u09ac\u09bf\u09b6\u09cd\u09b2\u09c7\u09b7\u09a3 \u0985\u09a8\u09cd\u09a4\u09f0\u09cd\u09ad\u09c1\u0995\u09cd\u09a4 \u0995\u09f0\u09be \u09b9\u09c8\u099b\u09c7\u0964 \u0987\u09af\u09bc\u09be\u09f0 \u0989\u09aa\u09f0\u09bf\u0993 \u09aa\u09cd\u09f0\u09a4\u09bf\u09af\u09cb\u0997\u09bf\u09a4\u09be\u09ae\u09c2\u09b2\u0995 \u09aa\u09f0\u09bf\u09f1\u09c7\u09b6 \u0986\u09f0\u09c1 \u0989\u09a6\u09cd\u09af\u09cb\u0997\u099f\u09cb\u09f0 \u09ae\u09c2\u09b2 \u0996\u09c7\u09b2\u09c1\u09f1\u09c8\u09b8\u0995\u09b2\u09f0 \u09ac\u09bf\u09b7\u09af\u09bc\u09c7\u0993 \u09a4\u09a5\u09cd\u09af \u09aa\u09cd\u09f0\u09a6\u09be\u09a8 \u0995\u09f0\u09be \u09b9\u09af\u09bc\u0964 \u09aa\u09cd\u09f0\u09a4\u09bf\u09ac\u09c7\u09a6\u09a8\u09a4 \u09f1\u09f0\u09cd\u09ae \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09ac\u099c\u09be\u09f0\u09f0 \u09ac\u09c3\u09a6\u09cd\u09a7\u09bf\u09a4 \u09aa\u09cd\u09f0\u09ad\u09be\u09f1 \u09aa\u09c7\u09b2\u09cb\u09f1\u09be \u09ae\u09c2\u09b2 \u0995\u09be\u09f0\u0995\u09b8\u09ae\u09c2\u09b9\u09f0 \u0993\u09aa\u09f0\u09a4\u09cb \u0986\u09b2\u09cb\u0995\u09aa\u09be\u09a4 \u0995\u09f0\u09be \u09b9\u09c8\u099b\u09c7\u0964<br \/>\u09f1\u09f0\u09cd\u09ae \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u09aa\u09cd\u09f0\u09a7\u09be\u09a8 \u0986\u099e\u09cd\u099a\u09b2\u09bf\u0995 \u09ac\u099c\u09be\u09f0\u09b8\u09ae\u09c2\u09b9\u09f0 \u09ad\u09bf\u09a4\u09f0\u09a4 \u0989\u09a4\u09cd\u09a4\u09f0 \u0986\u09ae\u09c7\u09f0\u09bf\u0995\u09be, \u098f\u099b\u09bf\u09af\u09bc\u09be-\u09aa\u09c7\u099a\u09bf\u09ab\u09bf\u0995, \u09ae\u09a7\u09cd\u09af\u09aa\u09cd\u09f0\u09be\u099a\u09cd\u09af \u0986\u09f0\u09c1 \u0986\u09ab\u09cd\u09f0\u09bf\u0995\u09be, \u09b2\u09c7\u099f\u09bf\u09a8 \u0986\u09ae\u09c7\u09f0\u09bf\u0995\u09be, \u0986\u09f0\u09c1 \u0987\u0989\u09f0\u09cb\u09aa \u0985\u09a8\u09cd\u09a4\u09f0\u09cd\u09ad\u09c1\u0995\u09cd\u09a4\u0964 \u0985\u09b9\u09be \u0995\u09c7\u0987\u09ac\u099b\u09f0\u09ae\u09be\u09a8\u09f0 \u09ad\u09bf\u09a4\u09f0\u09a4 \u098f\u0987 \u0985\u099e\u09cd\u099a\u09b2\u09b8\u09ae\u09c2\u09b9\u09f0 \u09ac\u099c\u09be\u09f0\u0996\u09a8 \u09b8\u09c0\u09ae\u09bf\u09a4 \u09ac\u09c3\u09a6\u09cd\u09a7\u09bf\u09f0 \u09b8\u09c8\u09a4\u09c7 \u09b8\u09c1\u09b8\u09cd\u09a5\u09bf\u09f0 \u09b9\u09c8 \u09a5\u0995\u09be\u09f0 \u09b8\u09ae\u09cd\u09ad\u09be\u09f1\u09a8\u09be \u0986\u099b\u09c7\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b9\u09c8\u099b\u09c7 \u098f\u099f\u09be \u09b8\u09f0\u09c1 \u09af\u09be\u09a8\u09cd\u09a4\u09cd\u09f0\u09bf\u0995 \u09af\u09a8\u09cd\u09a4\u09cd\u09f0 \u09af\u09bf\u099f\u09cb \u09a1\u09be\u0999\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09b8\u09c8\u09a4\u09c7 \u09b8\u0982\u09af\u09c1\u0995\u09cd\u09a4 \u0995\u09f0\u09be \u09b9\u09af\u09bc\u0964 \u098f\u0995\u09c7\u09b2\u0997\u09c7 \u09b8\u0982\u09af\u09cb\u0997 \u0995\u09f0\u09bf\u09b2\u09c7 \u0987 \u0995\u09ae \u0986\u0989\u099f\u09aa\u09c1\u099f \u0997\u09a4\u09bf \u0995\u09bf\u09a8\u09cd\u09a4\u09c1 \u0989\u099a\u09cd\u099a \u099f\u09f0\u09cd\u0995 \u0989\u09ce\u09aa\u09a8\u09cd\u09a8 \u0995\u09f0\u09c7\u0964 \u0995\u09c3\u09ae\u09bf \u09a1\u09cd\u09f0\u09be\u0987\u09ad\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09bf\u0982 \u09b8\u09cb\u0981\u09b9\u09be\u09a4 \u09ac\u09be \u09ac\u09be\u0993\u0981\u09b9\u09be\u09a4\u09f0 \u09b9'\u09ac \u09aa\u09be\u09f0\u09c7, \u0986\u09f0\u09c1 \u0998\u09a1\u09bc\u09c0\u09f0 \u0995\u09be\u0981\u099f\u09be\u09f0 \u09a6\u09bf\u09b6\u09a4 \u09ac\u09be \u0998\u09a1\u09bc\u09c0\u09f0 \u0995\u09be\u0981\u099f\u09be\u09f0 \u09ac\u09bf\u09aa\u09f0\u09c0\u09a4 \u09a6\u09bf\u09b6\u09a4 \u0998\u09c2\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09c7\u0964 \u0995\u09c3\u09ae\u09bf\u09f0 \u09b9\u09c7\u09b2\u09bf\u0995\u09cd\u09b8 \u0995\u09cb\u09a3\u09f0 \u0993\u09aa\u09f0\u09a4 \u09a8\u09bf\u09f0\u09cd\u09ad\u09f0 \u0995\u09f0\u09bf \u09ac\u09c7\u0995-\u09a1\u09cd\u09f0\u09be\u0987\u09ad\u09bf\u0982 \u0986\u09f0\u09c1 \u0998\u09f0\u09cd\u09b7\u09a3 \u09b9\u09cd\u09f0\u09be\u09b8 \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09bf\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b9\u09be\u0989\u099a\u09a1 \u0987\u0989\u09a8\u09bf\u099f \u09ac\u09be \u0997\u09bf\u09af\u09bc\u09be\u09f0\u099b\u09c7\u099f\u09a4 \u0989\u09aa\u09b2\u09ac\u09cd\u09a7\u0964 \u0995\u09bf\u099b\u09c1\u09ae\u09be\u09a8 \u09a8\u09bf\u09f0\u09cd\u09ae\u09be\u09a4\u09be\u0987 \u09b8\u0982\u09b9\u09a4 \u099a\u09be\u09f0\u09cd\u09ad\u2019\u09ae\u099f\u09f0 \u0986\u09f0\u09c1 \u09ac\u09b9\u09c1 \u0997\u09a4\u09bf\u09f0 \u09a1\u09bf\u099c\u09be\u0987\u09a8 \u0986\u0997\u09ac\u09a2\u09bc\u09be\u09af\u09bc\u0964 \u0989\u099a\u09cd\u099a-\u09b8\u09a0\u09bf\u0995\u09a4\u09be \u0986\u09f0\u09c1 \u09b6\u09c2\u09a8\u09cd\u09af-\u09ac\u09c7\u0995\u09b2\u09c7\u099b \u0995\u09c3\u09ae\u09bf \u0989\u09aa\u09b2\u09ac\u09cd\u09a7\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09ac\u09bf\u09b6\u09c7\u09b7\u0995\u09c8 \u09a6\u09cd\u09f0\u09c1\u09a4 \u09b7\u09cd\u099f\u09aa\u09f0 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u099c\u09a8 \u09b9\u09cb\u09f1\u09be \u09af\u09a8\u09cd\u09a4\u09cd\u09f0\u09a4 \u099c\u09a8\u09aa\u09cd\u09f0\u09bf\u09af\u09bc\u0964 \u09b2\u09bf\u09ab\u09cd\u099f \u0986\u09f0\u09c1 \u09b2\u09bf\u09ab\u09cd\u099f\u09a4\u09cb \u09b8\u09be\u09a7\u09be\u09f0\u09a3\u09a4\u09c7 \u09a6\u09c7\u0996\u09be \u09af\u09be\u09af\u09bc\u0964 \u0987\u09b9\u0981\u09a4\u09f0 \u0995\u09cb\u09ae\u09b2 \u09aa\u09cd\u09f0\u0995\u09c3\u09a4\u09bf \u0986\u09f0\u09c1 \u0995\u09ae \u09b6\u09cd\u09ac\u0995\u09f0 \u09ac\u09c8\u09b6\u09bf\u09b7\u09cd\u099f\u09cd\u09af\u0987 \u0987\u09b9\u0981\u09a4\u0995 \u098f\u0987 \u09a7\u09f0\u09a3\u09f0 \u09ae\u09c7\u099a\u09bf\u09a8\u09f0 \u09ac\u09be\u09ac\u09c7 \u0985\u09a4\u09bf \u0989\u09aa\u09af\u09cb\u0997\u09c0 \u0995\u09f0\u09bf \u09a4\u09cb\u09b2\u09c7\u0964<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/C_worm_reducer_1.webp\" alt=\"worm reducer\" width=\"800\" \/><\/p>\n<h2>\u0996\u09f0\u099a<\/h2>\n<p>\u0995\u09c3\u09ae\u09bf \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09a8\u09bf\u09f0\u09cd\u09ac\u09be\u099a\u09a8 \u0995\u09f0\u09be\u09f0 \u09b8\u09ae\u09af\u09bc\u09a4 \u0996\u09f0\u099a \u098f\u099f\u09be \u0997\u09c1\u09f0\u09c1\u09a4\u09cd\u09ac\u09aa\u09c2\u09f0\u09cd\u09a3 \u09ac\u09bf\u09ac\u09c7\u099a\u09a8\u09be\u0964 \u09f1\u09f0\u09cd\u09ae \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u09aa\u09cd\u09f0\u09be\u09f0\u09ae\u09cd\u09ad\u09bf\u0995 \u0996\u09f0\u099a \u0985\u09a8\u09cd\u09af \u09a7\u09f0\u09a3\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09a4\u0995\u09c8 \u09af\u09a5\u09c7\u09b7\u09cd\u099f \u0995\u09ae\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09b8\u09ae\u09c2\u09b9\u09cb \u0985\u09a7\u09bf\u0995 \u09b6\u0995\u09cd\u09a4\u09bf-\u09a6\u0995\u09cd\u09b7, \u0986\u09f0\u09c1 \u09aa\u09cd\u09f0\u09a4\u09bf\u09af\u09cb\u0997\u09bf\u09a4\u09be\u09ae\u09c2\u09b2\u0995 \u09ac\u09cd\u09af\u09f1\u09b8\u09cd\u09a5\u09be\u09a4\u0995\u09c8 \u0985\u09a7\u09bf\u0995 \u0985\u09a4\u09bf\u09f0\u09bf\u0995\u09cd\u09a4 \u09ac\u09cb\u099c\u09be\u09f0 \u0995\u09cd\u09b7\u09ae\u09a4\u09be \u09a5\u09be\u0995\u09c7\u0964 \u09a4\u09b2\u09a4 \u09a6\u09bf\u09af\u09bc\u09be \u0995\u09be\u09f0\u0995\u09b8\u09ae\u09c2\u09b9\u09c7 \u098f\u099f\u09be \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u0996\u09f0\u099a\u09a4 \u09aa\u09cd\u09f0\u09ad\u09be\u09f1 \u09aa\u09c7\u09b2\u09be\u09af\u09bc\u0964 Agknx \u09f0 \u09aa\u09f0\u09be \u09b7\u09cd\u099f\u09c7\u0987\u09a8\u09b2\u09c7\u099b \u09b7\u09cd\u099f\u09c0\u09b2\u09f0 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09c7 \u09a7\u09a8\u09f0 \u09ac\u09be\u09ac\u09c7 \u09a1\u09be\u0999\u09f0 \u09ae\u09c2\u09b2\u09cd\u09af \u09aa\u09cd\u09f0\u09a6\u09be\u09a8 \u0995\u09f0\u09c7\u0964 \u09a4\u09c7\u0996\u09c7\u09a4\u09c7 \u09ab\u09cd\u09b2\u09c7\u0982\u0997 \u0987\u09a8\u09aa\u09c1\u099f \u0986\u09f0\u09c1 \u09ab\u09c1\u099f\u09be \u0986\u0989\u099f\u09aa\u09c1\u099f \u09ac'\u09f0\u09f0 \u0986\u0995\u09be\u09f0 \u09aa\u09cd\u09f0\u09a6\u09be\u09a8 \u0995\u09f0\u09c7, \u09b2\u0997\u09a4\u09c7 \u09e7.\u09ed\u09eb\u2032\u2032\u09f0 \u09aa\u09f0\u09be \u09e9.\u09e8\u09eb\u2032\u2032\u09b2\u09c8\u0995\u09c7 \u0995\u09c7\u09a8\u09cd\u09a6\u09cd\u09f0\u09f0 \u09a6\u09c2\u09f0\u09a4\u09cd\u09ac\u0993 \u09aa\u09cd\u09f0\u09a6\u09be\u09a8 \u0995\u09f0\u09c7\u0964 \u09b7\u09cd\u099f\u09c7\u09a3\u09cd\u09a1\u09be\u09f0\u09cd\u09a1 \u09b8\u0982\u09b8\u09cd\u0995\u09f0\u09a3\u09f0 \u0989\u09aa\u09f0\u09bf\u0993 \u09b7\u09cd\u099f\u09c7\u0987\u09a8\u09b2\u09c7\u099b \u09b7\u09cd\u099f\u09c0\u09b2\u09f0 \u09ac\u09c1\u099b\u09bf\u0982 \u0995\u09bf\u099f \u0989\u09aa\u09b2\u09ac\u09cd\u09a7, \u09af\u09bf\u09af\u09bc\u09c7 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0\u0995\u09be\u09f0\u09c0\u09b8\u0995\u09b2\u0995 \u09b9\u09c7\u09a1 \u0996\u09be\u09a6\u09f0 \u0986\u0995\u09be\u09f0\u09f0 \u09ac\u09b9\u09b2 \u09aa\u09f0\u09bf\u09b8\u09f0 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09be\u09f0 \u0985\u09a8\u09c1\u09ae\u09a4\u09bf \u09a6\u09bf\u09af\u09bc\u09c7\u0964 \u09b7\u09cd\u099f\u09c7\u0987\u09a8\u09b2\u09c7\u099b \u09b7\u09cd\u099f\u09c0\u09b2\u09f0 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 Agknx \u09f0 \u099b\u09af\u09bc\u099f\u09be \u0986\u099e\u09cd\u099a\u09b2\u09bf\u0995 \u0997\u09c1\u09a6\u09be\u09ae\u09f0 \u09aa\u09f0\u09be \u09b7\u09cd\u099f\u0995\u09a4 \u0989\u09aa\u09b2\u09ac\u09cd\u09a7\u0964 \u09f1\u09f0\u09cd\u09ae \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09aa\u09cd\u09f0\u09be\u09af\u09bc\u09c7 \u09aa\u09be\u09f1\u09be\u09f0 \u099f\u09cd\u09f0\u09c7\u09a8\u09cd\u09b8\u09ae\u09bf\u099b\u09a8 \u099a\u09bf\u09b7\u09cd\u099f\u09c7\u09ae, \u09b2\u09bf\u09ab\u09cd\u099f, \u0995\u09a8\u09ad\u09c7\u09af\u09bc\u09f0 \u09ac\u09c7\u09b2\u09cd\u099f, \u0986\u09f0\u09c1 \u099a\u09bf\u0995\u09bf\u09ce\u09b8\u09be \u09b8\u0981\u099c\u09c1\u09b2\u09bf\u09a4 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09be \u09b9\u09af\u09bc\u0964 \u098f\u0987 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u0997\u09b8\u09ae\u09c2\u09b9\u09a4, \u0987\u09b9\u0981\u09a4\u0995 \u098f\u099f\u09be \u09ac\u09cb\u099c\u09be\u09f0 \u0997\u09a4\u09bf \u09a8\u09bf\u09af\u09bc\u09a8\u09cd\u09a4\u09cd\u09f0\u09a3 \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u0986\u09f0\u09c1 \u0987\u09af\u09bc\u09be\u0995 \u09ae\u09c1\u0995\u09cd\u09a4\u09ad\u09be\u09f1\u09c7 \u09aa\u09a4\u09a8 \u09f0\u09cb\u09a7 \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09be \u09b9\u09af\u09bc\u0964 \u09af\u09a6\u09bf\u0993 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09b9\u09c7\u09b2\u09bf\u0995\u09c7\u09b2 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u09a6\u09f0\u09c7 \u0995\u09be\u09f0\u09cd\u09af\u0995\u09cd\u09b7\u09ae \u09a8\u09b9\u09af\u09bc, \u09a4\u09a5\u09be\u09aa\u09bf\u0993 \u0989\u099a\u09cd\u099a \u099f\u09f0\u09cd\u0995 \u09ac\u09be \u0989\u099a\u09cd\u099a \u0986\u0989\u099f\u09aa\u09c1\u099f \u09b9\u09be\u09f0\u09f0 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u099c\u09a8 \u09b9\u09cb\u09f1\u09be \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u0997\u09f0 \u09ac\u09be\u09ac\u09c7 \u0987 \u0985\u09a4\u09bf \u0989\u09aa\u09af\u09cb\u0997\u09c0\u0964 \u0986\u09aa\u09cb\u09a8\u09be\u09f0 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u0997\u09f0 \u09ac\u09be\u09ac\u09c7 \u09b8\u09a0\u09bf\u0995 \u09a7\u09f0\u09a3\u09f0 \u0995\u09c3\u09ae\u09bf \u09a8\u09bf\u09f0\u09cd\u09ac\u09be\u099a\u09a8 \u0995\u09f0\u09bf\u09ac\u09b2\u09c8, \u0986\u09aa\u09c1\u09a8\u09bf \u0987\u09af\u09bc\u09be\u09a4 \u09a5\u0995\u09be \u09a6\u09be\u0981\u09a4\u09f0 \u09b8\u0982\u0996\u09cd\u09af\u09be \u09ac\u09bf\u09ac\u09c7\u099a\u09a8\u09be \u0995\u09f0\u09bf\u09ac \u09b2\u09be\u0997\u09c7\u0964 \u09ae\u09c1\u09a0 \u09ea\u09e6\u099f\u09be \u09ac\u09be \u09a4\u09be\u09a4\u0995\u09c8 \u0985\u09a7\u09bf\u0995 \u09a6\u09be\u0981\u09a4 \u09a5\u0995\u09be \u0995\u09c3\u09ae\u09bf \u09a8\u09bf\u09f0\u09cd\u09ac\u09be\u099a\u09a8 \u0995\u09f0\u09be\u099f\u09cb \u09ad\u09be\u09b2\u0964<\/p>\n<h2>\u09a6\u09bf\u09b6<\/h2>\n<p>\u0995\u09c3\u09ae\u09bf \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u0986\u0995\u09be\u09f0 \u09ac\u09c7\u09b2\u09c7\u0997 \u09ac\u09c7\u09b2\u09c7\u0997\u0964 \u0987\u09b9\u0981\u09a4\u09f0 \u098f\u099f\u09be, \u09a6\u09c1\u099f\u09be \u09ac\u09be \u09a4\u09be\u09a4\u0995\u09c8 \u0985\u09a7\u09bf\u0995 \u09b8\u09c2\u09a4\u09be \u09a5\u09be\u0995\u09c7\u0964 \u09aa\u09cd\u09f0\u09a4\u09bf\u099f\u09cb \u09b8\u09c2\u09a4\u09be\u09f0 \u098f\u099f\u09be \u09b8\u09c0\u09b9\u09f0 \u0995\u09cb\u09a3 \u09a5\u09be\u0995\u09c7\u0964 \u0989\u099a\u09cd\u099a \u0985\u09a8\u09c1\u09aa\u09be\u09a4\u09a4 \u0995\u09ae \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09a4\u0995\u09c8 \u09ac\u09c7\u099b\u09bf \u09a6\u09be\u0981\u09a4 \u09a5\u09be\u0995\u09c7, \u0986\u09f0\u09c1 \u0995\u09ae \u0985\u09a8\u09c1\u09aa\u09be\u09a4\u09a4 \u0995\u09ae \u09a6\u09be\u0981\u09a4 \u09a5\u09be\u0995\u09c7\u0964 \u098f\u0987 \u09aa\u09be\u09f0\u09cd\u09a5\u0995\u09cd\u09af\u09ac\u09cb\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09bf\u0999\u09f0 \u09ab\u09b2\u0964 \u09f1\u09f0\u09cd\u09ae \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u0986\u0995\u09be\u09f0 \u09a8\u09bf\u09f0\u09cd\u09a6\u09bf\u09b7\u09cd\u099f \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u0997 \u0985\u09a8\u09c1\u09b8\u09f0\u09bf \u09a8\u09bf\u09f0\u09cd\u09ac\u09be\u099a\u09a8 \u0995\u09f0\u09bf\u09ac \u09b2\u09be\u0997\u09c7\u0964 \u09f1\u09f0\u09cd\u09ae \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09c7 \u09a0\u09be\u0987 \u09f0\u09be\u09b9\u09bf \u0995\u09f0\u09c7 \u0986\u09f0\u09c1 \u0985\u09a7\u09bf\u0995 \u099f\u09f0\u09cd\u0995 \u09aa\u09cd\u09f0\u09a6\u09be\u09a8 \u0995\u09f0\u09c7\u0964 Agknx Gearbox \u098f \u09b8\u09be\u09a7\u09be\u09f0\u09a3 \u09ae\u09a8\u09cd\u09a5\u09f0\u09a4\u09be\u09f0 \u09aa\u09cd\u09f0\u09a4\u09cd\u09af\u09be\u09b9\u09cd\u09ac\u09be\u09a8\u09b8\u09ae\u09c2\u09b9 \u0985\u09a4\u09bf\u0995\u09cd\u09f0\u09ae \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u09ac\u09bf\u09ad\u09bf\u09a8\u09cd\u09a8 \u09ae\u09a1\u09c7\u09b2 \u09a4\u09c8\u09af\u09bc\u09be\u09f0 \u0995\u09f0\u09bf\u099b\u09c7, \u09ae\u09be\u09a8\u0995 \u09ac\u099c\u09be\u09f0\u09f0 \u09aa\u09f0\u09be \u09b8\u09cd\u09ac\u09be\u09b8\u09cd\u09a5\u09cd\u09af\u09b8\u09a8\u09cd\u09ae\u09a4 \u09ac\u099c\u09be\u09f0\u09b2\u09c8\u0995\u09c7\u0964 \u0989\u099a\u09cd\u099a\u09ae\u09be\u09a8\u09f0 \u099f\u09cd\u09f0\u09c7\u09a8\u09cd\u09b8\u09ae\u09bf\u099b\u09a8 Agknx \u09f0\u09c7\u099e\u09cd\u099c \u09b8\u09be\u09a7\u09be\u09f0\u09a3 \u09ae\u09a8\u09cd\u09a5\u09f0\u09a4\u09be\u09f0 \u09aa\u09cd\u09f0\u09a4\u09cd\u09af\u09be\u09b9\u09cd\u09ac\u09be\u09a8 \u09b8\u09ae\u09be\u09a7\u09be\u09a8 \u0986\u09f0\u09c1 \u0985\u09a8\u09be\u09ae\u09af\u09bc \u0989\u09a6\u09cd\u09af\u09cb\u0997\u09f0 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u099c\u09a8\u09c0\u09af\u09bc\u09a4\u09be \u09aa\u09c2\u09f0\u09a3 \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u09b8\u09ae\u09cd\u09aa\u09cd\u09f0\u09b8\u09be\u09f0\u09a3 \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u09a1\u09bf\u099c\u09be\u0987\u09a8 \u0995\u09f0\u09be \u09b9\u09c8\u099b\u09c7\u0964 \u0995\u09c3\u09ae\u09bf \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u09ac\u09cd\u09af\u09be\u09b8 \u098f\u099f\u09be \u0997\u09c1\u09f0\u09c1\u09a4\u09cd\u09ac\u09aa\u09c2\u09f0\u09cd\u09a3 \u09ac\u09bf\u09ac\u09c7\u099a\u09a8\u09be\u0964 \u0987\u09af\u09bc\u09be\u09f0 \u09ac\u09cd\u09af\u09be\u09b8 \u09aa\u09bf\u09b9\u09bf \u09b2\u09cb\u09f1\u09be \u099a\u0995\u09be \u09ac\u09be \u09b8\u0981\u099c\u09c1\u09b2\u09bf\u09f0 \u09ac\u09cd\u09af\u09be\u09b8\u09f0 \u09b8\u09ae\u09be\u09a8 \u09ac\u09be \u0985\u09b2\u09aa \u09a1\u09be\u0999\u09f0 \u09b9\u2019\u09ac \u09b2\u09be\u0997\u09c7\u0964 \u0987\u09af\u09bc\u09be\u09f0 \u09ab\u09b2\u09a4 \u099a\u09be\u09aa\u09f0 \u0995\u09cb\u09a3\u09a4 \u09aa\u09cd\u09f0\u09ad\u09be\u09f1 \u09aa\u09f0\u09bf\u09ac\u0964 \u0995\u09c3\u09ae\u09bf \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u099a\u09be\u09aa\u09f0 \u0995\u09cb\u09a3 \u0987\u09af\u09bc\u09be\u09f0 \u09ac\u09cd\u09af\u09be\u09b8 \u0986\u09f0\u09c1 \u09b8\u09c0\u09b9\u09f0 \u0995\u09cb\u09a3\u0995\u09c7 \u09a7\u09f0\u09bf \u0995\u09c7\u0987\u09ac\u09be\u099f\u09be\u0993 \u0995\u09be\u09f0\u0995\u09f0 \u0993\u09aa\u09f0\u09a4 \u09a8\u09bf\u09f0\u09cd\u09ad\u09f0 \u0995\u09f0\u09c7\u0964 \u0997\u09cd\u09f0\u09be\u0987\u09a3\u09cd\u09a1\u09bf\u0982 \u09b9\u09c1\u0987\u09b2 \u09ac\u09be \u09b8\u0981\u099c\u09c1\u09b2\u09bf\u09f0 \u09ac\u09cd\u09af\u09be\u09b8\u09c7\u0993 \u0995\u09c3\u09ae\u09bf\u09f0 \u09aa\u09cd\u09f0\u09ab\u09be\u0987\u09b2\u09a4 \u09aa\u09cd\u09f0\u09ad\u09be\u09f1 \u09aa\u09c7\u09b2\u09be\u09af\u09bc\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09b8\u09be\u09a7\u09be\u09f0\u09a3\u0964 \u09ac\u09b9\u09c1\u09a4\u09cb \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09a8\u09bf\u09f0\u09cd\u09ae\u09be\u09a4\u09be \u0995\u09cb\u09ae\u09cd\u09aa\u09be\u09a8\u09c0\u09a4 \u098f\u0987 \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u09ac\u09c3\u09b9\u09ce \u09b7\u09cd\u099f\u0995 \u0986\u099b\u09c7\u0964 \u09af\u09bf\u09b9\u09c7\u09a4\u09c1 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09b8\u09ae\u09c2\u09b9 \u09ae\u09be\u09a8\u0995, \u09b8\u09c7\u09af\u09bc\u09c7\u09b9\u09c7 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09ae\u09be\u0989\u09a3\u09cd\u099f\u09bf\u0982 \u09ae\u09be\u09a4\u09cd\u09f0\u09be\u0993 \u09a8\u09bf\u09f0\u09cd\u09ae\u09be\u09a4\u09be\u09b8\u0995\u09b2\u09f0 \u09ae\u09be\u099c\u09a4 \u09b8\u09be\u09a7\u09be\u09f0\u09a3\u0964 \u0987 \u0986\u09aa\u09cb\u09a8\u09be\u09f0 \u09aa\u09cd\u09f0\u09af\u09bc\u09cb\u0997\u09f0 \u09ac\u09be\u09ac\u09c7 \u098f\u099f\u09be \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09a8\u09bf\u09f0\u09cd\u09ac\u09be\u099a\u09a8 \u0995\u09f0\u09be\u099f\u09cb \u09b8\u09b9\u099c \u0995\u09f0\u09bf \u09a4\u09cb\u09b2\u09c7\u0964 \u0987\u09af\u09bc\u09be\u09f0 \u0989\u09aa\u09f0\u09bf\u0993 \u09f1\u09f0\u09cd\u09ae \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09b8\u09cd\u09a5\u09be\u09aa\u09a8 \u0986\u09f0\u09c1 \u09f0\u0995\u09cd\u09b7\u09a3\u09be\u09ac\u09c7\u0995\u09cd\u09b7\u09a3 \u0995\u09f0\u09be\u099f\u09cb \u09b8\u09b9\u099c\u0964<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/B_worm_reducer_1.webp\" alt=\"worm reducer\" width=\"800\" \/><\/p>\n<h2>\u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09a4\u09c7\u09b2<\/h2>\n<p>\u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09a4 \u09b8\u09be\u09a7\u09be\u09f0\u09a3\u09a4\u09c7 \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09a4\u09c7\u09b2 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09be \u09b9\u09af\u09bc\u0964 \u0995\u09c3\u09a4\u09cd\u09f0\u09bf\u09ae, \u09aa\u09b2\u09bf\u098f\u09b2\u0995\u09be\u0987\u09b2\u09bf\u09a8 \u0997\u09cd\u09b2\u09be\u0987\u0995\u09b2, \u0996\u09a8\u09bf\u099c \u09a4\u09c7\u09b2 \u0986\u09a6\u09bf \u0995\u09c7\u0987\u09ac\u09be\u09ac\u09bf\u09a7\u09cb \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09a4\u09c7\u09b2 \u0989\u09aa\u09b2\u09ac\u09cd\u09a7\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09a4 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09be \u09a4\u09c7\u09b2\u09f0 \u0986\u09a0\u09be\u09b2\u09a4\u09c0\u09af\u09bc\u09be\u09a4\u09be \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u09ac\u09be\u09ac\u09c7 \u0989\u09aa\u09af\u09c1\u0995\u09cd\u09a4 \u09b9\u2019\u09ac \u09b2\u09be\u0997\u09bf\u09ac\u0964 \u0995\u09bf\u099b\u09c1\u09ae\u09be\u09a8 \u09a4\u09c7\u09b2 \u0986\u09a8\u09a4\u0995\u09c8 \u09ac\u09c7\u099b\u09bf \u099c\u09be\u09f0\u09a3\u0995\u09be\u09f0\u09c0 \u0986\u09f0\u09c1 \u09aa\u09f0\u09bf\u09f1\u09c7\u09b6 \u09ac\u09bf\u09b7\u09be\u0995\u09cd\u09a4 \u09b9\u2019\u09b2\u09c7 \u09aa\u09f0\u09bf\u09b9\u09be\u09f0 \u0995\u09f0\u09bf\u09ac \u09b2\u09be\u0997\u09c7\u0964\u09f1\u09f0\u09cd\u09ae \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09f0\u09bf\u09a1\u09be\u0995\u09cd\u099f\u09f0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u09a4\u09c7\u09b2 \u099c\u09be\u09f0\u09a3, \u09aa\u09f0\u09bf\u09a7\u09be\u09a8 \u0986\u09f0\u09c1 \u0998\u09f0\u09cd\u09b7\u09a3\u09f0 \u09aa\u09f0\u09be \u09f0\u0995\u09cd\u09b7\u09be \u0995\u09f0\u09bf\u09ac \u09b2\u09be\u0997\u09bf\u09ac\u0964 \u0995\u09ae \u0998\u09f0\u09cd\u09b7\u09a3\u09f0 \u09b9\u09be\u09f0, \u0989\u099a\u09cd\u099a \u0985\u0995\u09cd\u09b8\u09bf\u09a1\u09c7\u099a\u09a8 \u09aa\u09cd\u09f0\u09a4\u09bf\u09f0\u09cb\u09a7 \u0995\u09cd\u09b7\u09ae\u09a4\u09be \u0986\u09f0\u09c1 \u09ad\u09be\u09b2 \u098f\u09a8\u09cd\u099f\u09bf-\u09f1\u09c7\u09af\u09bc\u09be\u09f0 \u09aa\u09cd\u09f0\u099f\u09c7\u0995\u099a\u09a8 \u09a5\u0995\u09be \u09b2\u09c1\u09ac\u09cd\u09f0\u09bf\u0995\u09c7\u09a3\u09cd\u099f \u09ac\u09be\u099b\u09bf \u09b2\u09cb\u09f1\u09be\u099f\u09cb \u09ad\u09be\u09b2\u0964 \u0996\u09a8\u09bf\u099c \u09a4\u09c7\u09b2 \u0986\u099f\u09be\u0987\u09a4\u0995\u09c8 \u09b8\u09be\u09a7\u09be\u09f0\u09a3 \u09a7\u09f0\u09a3\u09f0 \u09b2\u09c1\u09ac\u09cd\u09f0\u09bf\u0995\u09c7\u09a3\u09cd\u099f \u09b9\u2019\u09b2\u09c7\u0993 \u0995\u09c3\u09a4\u09cd\u09f0\u09bf\u09ae \u09ad\u09bf\u09a4\u09cd\u09a4\u09bf \u09a4\u09c7\u09b2\u09c7 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09f0 \u0995\u09be\u09f0\u09cd\u09af\u0995\u09cd\u09b7\u09ae\u09a4\u09be \u09ac\u09c3\u09a6\u09cd\u09a7\u09bf \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09c7 \u0986\u09f0\u09c1 \u0985\u09aa\u09be\u09f0\u09c7\u099f\u09bf\u0982 \u0989\u09b7\u09cd\u09a3\u09a4\u09be \u09b9\u09cd\u09f0\u09be\u09b8 \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09c7\u0964 \u0995\u09be\u09f0\u09a3 \u0986\u09f0\u09cd\u09b9\u09c7\u09a8\u09bf\u09af\u09bc\u09be\u099b \u09b9\u09be\u09f0\u09f0 \u09a8\u09bf\u09af\u09bc\u09ae\u09a4 \u0995\u09cb\u09f1\u09be \u09b9\u09c8\u099b\u09c7 \u09af\u09c7 \u09aa\u09cd\u09f0\u09a4\u09bf \u09e7\u09e6 \u09a1\u09bf\u0997\u09cd\u09f0\u09c0 \u099a\u09c7\u09b2\u099b\u09bf\u09af\u09bc\u09be\u099b \u0989\u09b7\u09cd\u09a3\u09a4\u09be \u09ac\u09c3\u09a6\u09cd\u09a7\u09bf\u09f0 \u09ac\u09be\u09ac\u09c7 \u09a4\u09c7\u09b2\u09a4 \u09f0\u09be\u09b8\u09be\u09af\u09bc\u09a8\u09bf\u0995 \u09ac\u09bf\u0995\u09cd\u09f0\u09bf\u09af\u09bc\u09be \u09a6\u09c1\u0997\u09c1\u09a3 \u09b9\u09af\u09bc\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u09b9\u09cd\u09f0\u09be\u09b8\u0995\u09be\u09f0\u09c0 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8 \u09ac\u09bf\u09ad\u09bf\u09a8\u09cd\u09a8 \u0986\u0995\u09be\u09f0 \u0986\u09f0\u09c1 \u09b8\u0982\u09f0\u09c2\u09aa\u09a4 \u0989\u09aa\u09b2\u09ac\u09cd\u09a7\u0964 \u09b8\u0995\u09b2\u09cb \u09a7\u09f0\u09a3\u09f0 \u09ae\u09c7\u099a\u09bf\u09a8 \u0986\u09f0\u09c1 \u09b8\u0981\u099c\u09c1\u09b2\u09bf\u09f0 \u09ac\u09be\u09ac\u09c7 \u0989\u09aa\u09af\u09cb\u0997\u09c0\u0964 \u0995\u09c3\u09ae\u09bf \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u0986\u09f0\u09c1 \u0986\u0989\u099f\u09aa\u09c1\u099f \u0996\u09be\u09a6\u09f0 \u09ae\u09be\u099c\u09a4 \u09b8\u09cd\u09b2\u09be\u0987\u09a1\u09bf\u0982 \u0995\u09cd\u09f0\u09bf\u09af\u09bc\u09be\u0987 \u0989\u099a\u09cd\u099a \u099f\u09f0\u09cd\u0995 \u0986\u09f0\u09c1 \u0989\u099a\u09cd\u099a \u0995\u09be\u09f0\u09cd\u09af\u0995\u09cd\u09b7\u09ae\u09a4\u09be \u0989\u09ce\u09aa\u09a8\u09cd\u09a8 \u0995\u09f0\u09c7\u0964 \u09af\u09a6\u09bf \u099f\u09cd\u09f0\u09c7\u09a8\u09cd\u09b8\u09ae\u09bf\u099b\u09a8\u09f0 \u0997\u09a4\u09bf \u0995\u09ae \u09b9\u09af\u09bc, \u09a4\u09c7\u09a8\u09cd\u09a4\u09c7 \u09b8\u09f0\u09cd\u09ac\u09cb\u099a\u09cd\u099a \u0995\u09be\u09f0\u09cd\u09af\u0995\u09cd\u09b7\u09ae\u09a4\u09be\u09f0 \u09ac\u09be\u09ac\u09c7 \u09f1\u09f0\u09cd\u09ae \u0997\u09bf\u09af\u09bc\u09be\u09f0 \u0986\u09f0\u09c1 \u0986\u0989\u099f\u09aa\u09c1\u099f \u0996\u09be\u09a6 \u098f\u0995\u09a4\u09cd\u09f0\u09bf\u09a4 \u0995\u09f0\u09bf\u09ac \u09aa\u09be\u09f0\u09bf\u0964 \u0995\u09bf\u09a8\u09cd\u09a4\u09c1 \u09a8\u09bf\u09af\u09bc\u09ae\u09c0\u09af\u09bc\u09be \u09a4\u09c7\u09b2 \u099b\u09ae\u09be\u09b9\u09f0 \u09ae\u09c2\u09f0\u09c7 \u09ae\u09c2\u09f0\u09c7 \u09ac\u09be \u09e8\u09eb\u09e6\u09e6 \u0998\u09a3\u09cd\u099f\u09be\u09f0 \u09ae\u09c2\u09f0\u09c7 \u09ae\u09c2\u09f0\u09c7 \u09b8\u09b2\u09a8\u09bf \u0995\u09f0\u09bf\u09ac \u09b2\u09be\u0997\u09c7, \u09af\u09bf\u099f\u09cb \u09aa\u09cd\u09f0\u09a5\u09ae\u09c7 \u0986\u09b9\u09c7\u0964 \u09b2\u0997\u09a4\u09c7, \u09b2\u09c1\u09ac\u09cd\u09f0\u09bf\u0995\u09c7\u099a\u09a8\u09f0 \u09b2\u0997\u09a4 \u099c\u09a1\u09bc\u09bf\u09a4 \u0997\u09bf\u09af\u09bc\u09be\u09f0\u09ac\u0995\u09cd\u09b8\u09f0 \u09ac\u09bf\u0995\u09b2\u09a4\u09be \u09f0\u09cb\u09a7 \u0995\u09f0\u09bf\u09ac\u09b2\u09c8 \u09a4\u09c7\u09b2\u09f0 \u09ae\u09be\u09a4\u09cd\u09f0\u09be \u09a8\u09bf\u09af\u09bc\u09ae\u09bf\u09a4\u09ad\u09be\u09f1\u09c7 \u09a8\u09bf\u09f0\u09c0\u0995\u09cd\u09b7\u09a3 \u0995\u09f0\u09be\u099f\u09cb \u09ad\u09be\u09b2\u0964 \u0995\u09c3\u09a4\u09cd\u09f0\u09bf\u09ae \u09a4\u09c7\u09b2 \u09ac\u09cd\u09af\u09f1\u09b9\u09be\u09f0 \u0995\u09f0\u09be\u099f\u09cb\u0993 \u09ac\u09c1\u09a6\u09cd\u09a7\u09bf\u09ae\u09be\u09a8\u09f0 \u0995\u09be\u09ae, \u0995\u09bf\u09af\u09bc\u09a8\u09cb \u09a4\u09c7\u09b2 \u09b8\u09b2\u09a8\u09bf \u0995\u09f0\u09be\u09f0 \u09ae\u09be\u099c\u09a4 \u0987 \u09ac\u09c7\u099b\u09bf \u09a6\u09bf\u09a8 \u099f\u09bf\u0995\u09bf \u09a5\u09be\u0995\u09bf\u09ac\u0964<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/gearbox\/gearbox-l1.webp\" alt=\"China high quality Custom worm gear set     worm gearbox exploded view\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/gearbox\/gearbox-l2.webp\" alt=\"China high quality Custom worm gear set     worm gearbox exploded view\"><br \/>\u09b8\u09ae\u09cd\u09aa\u09be\u09a6\u0995 Cx 2023-07-12 \u09a6\u09cd\u09ac\u09be\u09f0\u09be<\/p>","protected":false},"excerpt":{"rendered":"<p>Condition: NewWarranty: UnavailableShape: WormApplicable Industries: Hotels, Building Material Shops, Manufacturing Plant, Machinery Repair Shops, Farms, Retail, Construction works\u00a0, Energy &amp; Mining, Advertising CompanyAfter Warranty Service: No serviceLocal Service\u00a0Location: NoneShowroom Location: NoneVideo outgoing-inspection: ProvidedMachinery Test Report: ProvidedMarketing Type: Ordinary ProductWarranty of core components: 1 YearCore Components: Gear, gearboxMaterial: Stainless steelStandard or Nonstandard: NonstandardDirection: rightFinis: Mirror polish [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1555","post","type-post","status-publish","format-standard","hentry","category-gearboxes-worm"],"_links":{"self":[{"href":"https:\/\/gearboxes-worm.top\/as\/wp-json\/wp\/v2\/posts\/1555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearboxes-worm.top\/as\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearboxes-worm.top\/as\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearboxes-worm.top\/as\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearboxes-worm.top\/as\/wp-json\/wp\/v2\/comments?post=1555"}],"version-history":[{"count":0,"href":"https:\/\/gearboxes-worm.top\/as\/wp-json\/wp\/v2\/posts\/1555\/revisions"}],"wp:attachment":[{"href":"https:\/\/gearboxes-worm.top\/as\/wp-json\/wp\/v2\/media?parent=1555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearboxes-worm.top\/as\/wp-json\/wp\/v2\/categories?post=1555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearboxes-worm.top\/as\/wp-json\/wp\/v2\/tags?post=1555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}