{"id":1486,"date":"2022-09-01T11:54:15","date_gmt":"2022-09-01T11:54:15","guid":{"rendered":"http:\/\/gearboxes-worm.top\/china-good-quality-gear-box-motor-steel-small-speed-reducer-gearbox-nmrv-series-130-nmrv-series-150-near-me-manufacturer\/"},"modified":"2022-09-01T11:54:15","modified_gmt":"2022-09-01T11:54:15","slug":"china-good-quality-gear-box-motor-steel-small-speed-reducer-gearbox-nmrv-series-130-nmrv-series-150-near-me-manufacturer","status":"publish","type":"post","link":"https:\/\/gearboxes-worm.top\/de\/china-good-quality-gear-box-motor-steel-small-speed-reducer-gearbox-nmrv-series-130-nmrv-series-150-near-me-manufacturer\/","title":{"rendered":"Hochwertige Getriebemotoren aus Stahl, kleine Untersetzungsgetriebe der Serien NMRV 130 und NMRV 150 aus China \u2013 Hersteller in Ihrer N\u00e4he"},"content":{"rendered":"<p><p>Warranty: 3 years, 1 Year<br \/>Applicable Industries: Garment Shops, Building Material Shops, Manufacturing Plant, Farms, Construction works<br \/>Weight (KG): 15 KG<br \/>Customized support: OEM, ODM, OBM, ODM<br \/>Gearing Arrangement: Planetary<br \/>Output Torque: 1.5-118N.m<br \/>Input Speed: 750-1800rpm<br \/>Output Speed: 200-1000rpm<br \/>Color:: Silver\/Blue<br \/>Packing: Carton Box<br \/>Certificate:: ISO9001:2008<br \/>Application: Machine Tool<br \/>Color: Blue\/Silver Or On Customer Request<br \/>Type: Reduction Motor<br \/>Keyword: small speed reducer gearbox<br \/>Model: Nmrv Series 150<br \/>Packaging Details: standard packing or OEM request<br \/>Port: NINGNO<\/p>\n<p>WELCOME TO INYOUNG <font color=\"#2196ed\">FACTORY<\/font>OUR ADVANTAGES:* Engine bearing * High speed,high temperature * Competitive price * OEM&amp;ODM Products Description BrandINYOUNGType:gearbox WPAModel: NMRVseries25,NMRVseries30,NMRVseries40,NMRVseries50,NMRVseries63, Customized Marine Spline Shaft Handheld Mower Drive Spline Shaft NMRVseries75,NMRVseries90,NMRVseries110,NMRVseries130,NMRVseries150Ratio:1:10,15,20,25,30,40,50,60Color:Blue\/Silver Or On Customer RequestMaterial:Housing: Die-Cast Iron castWorm Gear-Copper-10-3#Worm-20CrMn Ti with carburizing and quenching, surface harness is 56-62HRCShaft-chromium steel-45#Packing:Carton and Wooden CaseBearing:C&amp;U BearingSeal:NAK OTHERWarranty:1 YearInput Power:0.06KW,0.09KWUsages:Industrial Machine: Food Stuff, Free Flow Conveyor Double Plus Chain Ceramics,CHEMICAL,Packing,Dyeing,Woodworking,Glass. <font>Different bearing size or type \uff0cWelcome to contact us <\/font> Low price rv mini mechanical chinese gearbox drill lpg stepper electric motor worm gear speed reducer More Products Company Profile Our Factory Exhibition Display Certifications Shipping&amp;Payment <font>1.Bearings<\/font> <font>2.Bearing with tube<\/font> <font>3.Bearing with carton.<\/font> FAQ Q1: Are you a Manufacturer or trading company?We are professional manufactuer of bearings with super great stock, professional quality working over 2years Q2: Can I get a sample to check out the quality?Answer: Sure, free samples are available for stock products if you can pay for the shipping cost. Q3: Can you do OEM to print my logo\/brand on the products?Answer: Yes, we can print your logo\/brand on the products, you just need to send us your logo\/brand files, we will show you how it looks like.We can also make custom package to your request. Q4: How soon can I expect my order to be finished?Answer: We have regular stock for standard bearings that can be shipped right after your payment. It will take 15-60 days for new production order,which depends on your order quantity. Q5: What if I receive defective products for my order?Answer: All our bearings are 100% inspected strictly before packing. If any defective products received, please provide photos and video to show us the problem and help us improve the quality. New products will be sent to you as replacement if the probelm is product quality.<\/p>\n<\/p>\n<h2>Was ist ein Getriebe?<\/h2>\n<p>Bei der Auswahl eines Getriebes sind verschiedene Faktoren zu ber\u00fccksichtigen. Das Zahnflankenspiel ist beispielsweise ein wichtiger Aspekt. Es bezeichnet den Winkel, um den sich die Abtriebswelle drehen kann, ohne dass sich die Antriebswelle bewegt. W\u00e4hrend dies bei Anwendungen ohne Lastwechsel nicht relevant ist, spielt es bei Pr\u00e4zisionsanwendungen mit Lastwechseln eine wichtige Rolle. Beispiele hierf\u00fcr sind Automatisierung und Robotik. Wenn das Zahnflankenspiel ein Problem darstellt, sollten Sie weitere Faktoren wie die Z\u00e4hnezahl der einzelnen Zahnr\u00e4der in Betracht ziehen.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/gearbox\/t-gearbox-1.webp\" alt=\"gearbox\" width=\"800\" \/><\/p>\n<h2>Funktion eines Getriebes<\/h2>\n<p>Ein Getriebe ist eine mechanische Einheit, die aus einer Kette oder einem Satz Zahnr\u00e4der besteht. Die Zahnr\u00e4der sind auf einer Welle montiert und werden von W\u00e4lzlagern gehalten. Diese Bauteile ver\u00e4ndern die Drehzahl oder das Drehmoment der Maschine, in der sie eingesetzt werden. Getriebe finden in einer Vielzahl von Anwendungen Verwendung. Hier sind einige Beispiele f\u00fcr die Funktionsweise von Getrieben. Lesen Sie weiter, um mehr \u00fcber die Zahnr\u00e4der eines Getriebes zu erfahren.<br \/>Unabh\u00e4ngig vom Getriebetyp verf\u00fcgen die meisten Getriebe \u00fcber ein Prim\u00e4r- und ein Sekund\u00e4rgetriebe. Obwohl die \u00dcbersetzungsverh\u00e4ltnisse beider Getriebe gleich sind, k\u00f6nnen sich die Getriebe in Gr\u00f6\u00dfe und Wirkungsgrad unterscheiden. Hochleistungsrennwagen verwenden typischerweise ein Getriebe mit zwei gr\u00fcnen und einem blauen Gang. Getriebe sind h\u00e4ufig vor oder hinter dem Motor montiert.<br \/>Die Hauptfunktion eines Getriebes besteht darin, Drehmoment von einer Welle auf eine andere zu \u00fcbertragen. Das \u00dcbersetzungsverh\u00e4ltnis des Antriebszahnrads zum Gegenzahnrad bestimmt die H\u00f6he des \u00fcbertragenen Drehmoments. Ein hohes \u00dcbersetzungsverh\u00e4ltnis bewirkt, dass sich die Hauptwelle langsamer dreht und im Vergleich zur Gegenwelle ein hohes Drehmoment erzeugt. Umgekehrt erm\u00f6glicht ein niedriges \u00dcbersetzungsverh\u00e4ltnis, dass sich das Fahrzeug mit geringerer Geschwindigkeit dreht und ein geringeres Drehmoment erzeugt.<br \/>Ein herk\u00f6mmliches Getriebe verf\u00fcgt \u00fcber Eingangs- und Ausgangszahnr\u00e4der. Die Vorgelegewelle ist mit einer Kardanwelle verbunden. Eingangs- und Ausgangszahnr\u00e4der sind so angeordnet, dass Drehzahl und Drehmoment aufeinander abgestimmt sind. Das \u00dcbersetzungsverh\u00e4ltnis bestimmt die H\u00f6chstgeschwindigkeit und das maximale Drehmoment eines Fahrzeugs. Die meisten herk\u00f6mmlichen Getriebe arbeiten mit vier \u00dcbersetzungsverh\u00e4ltnissen und einem R\u00fcckw\u00e4rtsgang. Einige Getriebe haben zwei Wellen und drei Eing\u00e4nge. Bei hohen \u00dcbersetzungsverh\u00e4ltnissen kann es jedoch zu Drehmomentverlusten im Motor kommen.<br \/>Im Rahmen der Untersuchung der Getriebeleistung wurden umfangreiche Daten erhoben. Ein aufw\u00e4ndiger Segmentierungsprozess lieferte fast 20.000 Merkmalsvektoren. Diese Ergebnisse stellen die detailliertesten und umfassendsten aller verf\u00fcgbaren Daten dar. Die Forschung steht jedoch vor zwei Herausforderungen: Zum einen dem gro\u00dfen Datenvolumen, das zur Charakterisierung erhoben wurde, zum anderen der hohen Dimensionalit\u00e4t. Letztere stellt eine Komplikation dar, die auftritt, wenn das experimentelle Getriebe nicht auf optimale Leistung ausgelegt ist.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/gearbox\/c-gearbox-1.webp\" alt=\"gearbox\" width=\"800\" \/><\/p>\n<h2>Bzvacklash<\/h2>\n<p>Die Hauptfunktion eines Getriebes besteht darin, ein Drehmoment zu verst\u00e4rken und einen mechanischen Vorteil zu erzeugen. Zahnflankenspiel kann jedoch verschiedene Probleme im System verursachen, darunter eine beeintr\u00e4chtigte Positioniergenauigkeit und eine verminderte Gesamtleistung. Ein spielfreies Getriebe kann die durch Zahnflankenspiel verursachten Bewegungsverluste eliminieren und die Gesamtleistung des Systems verbessern. Im Folgenden werden einige h\u00e4ufige Probleme im Zusammenhang mit Zahnflankenspiel und deren Behebung beschrieben. Sobald Sie die Behebung von Zahnflankenspiel im Getriebe verstanden haben, k\u00f6nnen Sie eine Maschine konstruieren, die Ihren Anforderungen entspricht.<br \/>Um das Getriebespiel zu reduzieren, versuchen viele Konstrukteure, den Achsabstand der Zahnr\u00e4der zu verringern. Dies verringert jedoch den Platz f\u00fcr Schmierstoffe und beg\u00fcnstigt einen \u00fcberm\u00e4\u00dfigen Zahneingriff, was zu vorzeitigem Verschlei\u00df f\u00fchren kann. Um das Getriebespiel zu minimieren, kann ein Zahnradhersteller die beiden Zahnradteile trennen und den Achsabstand zwischen ihnen anpassen. Dazu wird ein Zahnrad relativ zum feststehenden Zahnrad gedreht, w\u00e4hrend gleichzeitig die effektive Zahndicke des anderen Zahnrads ver\u00e4ndert wird.<br \/>Verschiedene Fertigungsprozesse k\u00f6nnen Fehler verursachen, die durch die Reduzierung der Zahndicke minimiert werden k\u00f6nnen. Kegelr\u00e4der sind hierf\u00fcr ein Paradebeispiel. Diese Zahnradart weist im Vergleich zum Gegenrad eine geringere Z\u00e4hnezahl auf. Neben der reduzierten Zahndicke verringern Kegelr\u00e4der auch das Zahnflankenspiel. Obwohl Kegelr\u00e4der weniger Z\u00e4hne als das Gegenrad besitzen, wird das gesamte Zahnflankenspiel auf das gr\u00f6\u00dfere Zahnrad \u00fcbertragen.<br \/>Das Zahnflankenspiel kann die Effizienz eines Getriebes beeintr\u00e4chtigen. Im Idealfall ist das Zahnflankenspiel null. Ist es jedoch zu gro\u00df, kann es die Zahnr\u00e4der besch\u00e4digen und zu Fehlfunktionen f\u00fchren. Daher ist es wichtig, dieses Problem zu minimieren. Hierf\u00fcr kann ein Mikrometer erforderlich sein. Um das ben\u00f6tigte Zahnflankenspiel zu bestimmen, k\u00f6nnen Sie eine Messuhr oder eine F\u00fchlerlehre verwenden.<br \/>Wenn Sie nach einer M\u00f6glichkeit suchen, Zahnflankenspiel zu reduzieren, k\u00f6nnte das Zahnflankenspiel im Getriebe die L\u00f6sung sein. Zahnflankenspiel ist jedoch kein Vorwurf an den Hersteller. Es handelt sich um einen nat\u00fcrlichen Bewegungsfehler in Getriebesystemen mit Richtungswechsel. Wird er nicht ber\u00fccksichtigt, kann er zu erheblichem Verschlei\u00df der Zahnr\u00e4der und sogar zur Besch\u00e4digung des gesamten Systems f\u00fchren. In diesem Artikel erkl\u00e4ren wir, wie sich Zahnflankenspiel auf Zahnr\u00e4der und die Leistung eines Getriebes auswirkt.<\/p>\n<h2>Design<\/h2>\n<p>Die Konstruktion von Getrieben h\u00e4ngt von verschiedenen Faktoren ab, darunter das verwendete Material, der Leistungsbedarf, die Drehzahl und das Untersetzungsverh\u00e4ltnis sowie der vorgesehene Anwendungsbereich. Der Konstruktionsprozess beginnt \u00fcblicherweise mit einer Beschreibung der Maschine bzw. des Getriebes und seines Verwendungszwecks. Weitere wichtige Parameter sind die Gr\u00f6\u00dfe und das Gewicht der Zahnr\u00e4der, das Gesamt\u00fcbersetzungsverh\u00e4ltnis und die Anzahl der Untersetzungen sowie die verwendeten Schmierverfahren.<br \/>Im Rahmen des Designprozesses nehmen Kunde und Lieferant an verschiedenen Designpr\u00fcfungen teil. Dazu geh\u00f6ren die Konzept- bzw. Erstdesignpr\u00fcfung, die Validierung des Fertigungsdesigns, die kritische Designpr\u00fcfung und die finale Designpr\u00fcfung. Der Kunde kann den Prozess auch durch die Initiierung einer DFMEA (Design-Fundamental-Evaluation and Methods) ansto\u00dfen. Nach der ersten Designfreigabe durchl\u00e4uft das Design mehrere Iterationen, bevor die finale Version festgelegt wird. In manchen F\u00e4llen verlangt der Kunde eine DFMEA des Getriebes.<br \/>\u00dcbersetzungsgetriebe erfordern besondere Konstruktions\u00fcberlegungen. Diese Getriebe arbeiten typischerweise mit hohen Drehzahlen, was zu Problemen mit der Getriebedynamik f\u00fchren kann. Zudem erh\u00f6hen die hohen Drehzahlen die Reibungs- und Widerstandskr\u00e4fte. Eine geeignete Konstruktion dieser Komponente sollte die Auswirkungen dieser Kr\u00e4fte minimieren. Um diese Probleme zu l\u00f6sen, sollte ein Getriebe \u00fcber ein Bremssystem verf\u00fcgen. In manchen F\u00e4llen k\u00f6nnen auch \u00e4u\u00dfere Kr\u00e4fte die Reibungskr\u00e4fte erh\u00f6hen.<br \/>In Getrieben kommen verschiedene Zahnradanordnungen zum Einsatz. Die Zahnform der Zahnr\u00e4der spielt dabei eine entscheidende Rolle. Stirnr\u00e4der sind ein Beispiel f\u00fcr eine solche Anordnung, bei der die Z\u00e4hne parallel zur Drehachse verlaufen. Sie erm\u00f6glichen hohe \u00dcbersetzungsverh\u00e4ltnisse und werden h\u00e4ufig in mehreren Stufen eingesetzt. So l\u00e4sst sich ein Getriebe konstruieren, das optimal auf Ihre Anwendung zugeschnitten ist.<br \/>Die Konstruktion von Getrieben ist der komplexeste Prozess im Maschinenbau. Diese komplexen Bauteile bestehen aus verschiedenen Zahnradtypen und sind auf Wellen montiert. Sie werden von W\u00e4lzlagern gest\u00fctzt und finden in vielf\u00e4ltigen Anwendungen Verwendung. Im Allgemeinen dienen Getriebe der Drehzahl- und Drehmomentreduzierung sowie der Richtungs\u00e4nderung. Getriebe werden h\u00e4ufig in Kraftfahrzeugen eingesetzt, sind aber auch in Fahrr\u00e4dern und station\u00e4ren Maschinen zu finden.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/gearbox\/b-gearbox-1.webp\" alt=\"gearbox\" width=\"800\" \/><\/p>\n<h2>Hersteller<\/h2>\n<p>Der Getriebemarkt l\u00e4sst sich in mehrere Hauptsegmente unterteilen, darunter Industrie, Bergbau und Automobil. Getriebehersteller m\u00fcssen die Anwendungsbereiche und Anwenderbranchen genau kennen, um Getriebe zu entwickeln, die deren spezifischen Anforderungen entsprechen. Grundkenntnisse der Metallurgie sind unerl\u00e4sslich. Multinationale Unternehmen bieten zudem Getriebel\u00f6sungen f\u00fcr die Energieerzeugung, die Schifffahrt und die Automobilindustrie an. Um ihre Produkte wettbewerbsf\u00e4higer zu gestalten, m\u00fcssen sie sich auf Produktinnovationen, geografische Expansion und Kundenbindung konzentrieren.<br \/>Die CZPT-Gruppe begann 1976 als kleines Unternehmen und hat sich seitdem zu einem weltweit f\u00fchrenden Anbieter von mechanischen Getrieben entwickelt. Das Produktportfolio umfasst Zahnr\u00e4der, Untersetzungsgetriebe und Getriebemotoren. Als erstes Unternehmen in Italien erhielt CZPT die ISO-Zertifizierung und z\u00e4hlt weiterhin zu den weltweit f\u00fchrenden Herstellern von Seriengetrieben. Mit der Weiterentwicklung der Branche setzt CZPT auf Forschung und Entwicklung, um stets bessere Produkte zu entwickeln.<br \/>Die Landwirtschaft nutzt Getriebe f\u00fcr vielf\u00e4ltige Prozesse. Sie kommen in Traktoren, Pumpen und Landmaschinen zum Einsatz. Auch die Automobilindustrie verwendet Getriebe in Fahrzeugen, aber sie finden sich auch in Maschinen f\u00fcr den Bergbau und die Teeverarbeitung. Industriegetriebe spielen zudem eine wichtige Rolle bei Vorschub- und Drehzahlantrieben. Die Getriebeindustrie verf\u00fcgt \u00fcber ein breites Spektrum an Herstellern und Zulieferern. Hier einige Beispiele f\u00fcr Getriebe:<br \/>Getriebe sind komplexe Bauteile. Um optimale Effizienz und lange Lebensdauer zu gew\u00e4hrleisten, m\u00fcssen sie sachgem\u00e4\u00df eingesetzt werden. Hersteller nutzen fortschrittliche Technologien und strenge Qualit\u00e4tskontrollen, um sicherzustellen, dass ihre Produkte h\u00f6chsten Standards entsprechen. Neben Fertigungspr\u00e4zision und Zuverl\u00e4ssigkeit gew\u00e4hrleisten Getriebehersteller die sichere Verwendung ihrer Produkte in der Industriemaschinenproduktion. Sie werden auch in B\u00fcromaschinen und Medizinger\u00e4ten eingesetzt. Der Markt f\u00fcr Automobilgetriebe wird jedoch zunehmend wettbewerbsintensiver.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/gearbox\/gearbox-l1.webp\" alt=\"China Good quality Gear Box Motor Steel Small Speed Reducer Gearbox Nmrv Series 130 Nmrv Series 150  near me manufacturer \"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/gearbox\/gearbox-l2.webp\" alt=\"China Good quality Gear Box Motor Steel Small Speed Reducer Gearbox Nmrv Series 130 Nmrv Series 150  near me manufacturer \"><\/p>","protected":false},"excerpt":{"rendered":"<p>Warranty: 3 years, 1 YearApplicable Industries: Garment Shops, Building Material Shops, Manufacturing Plant, Farms, Construction worksWeight (KG): 15 KGCustomized support: OEM, ODM, OBM, ODMGearing Arrangement: PlanetaryOutput Torque: 1.5-118N.mInput Speed: 750-1800rpmOutput Speed: 200-1000rpmColor:: Silver\/BluePacking: Carton BoxCertificate:: ISO9001:2008Application: Machine ToolColor: Blue\/Silver Or On Customer RequestType: Reduction MotorKeyword: small speed reducer gearboxModel: Nmrv Series 150Packaging Details: standard packing [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[134,135,136,137,138,139,12,66,13,141,142,143,144,145,140,146,14,78,79,147,80,148,149,16,150,17,81,151,152,20,21,22,153,84,154,23,121,155,98,156,157,99,100,103,104,105,28,31,158,107,32,108,159,160,39,161,162,163,164,165,166,167,171,172,168,173,127,169,174,175,176,177,178,170,179],"class_list":["post-1486","post","type-post","status-publish","format-standard","hentry","category-gearboxes-worm","tag-130-motor","tag-130-motor-gearbox","tag-box-gear","tag-box-motor","tag-box-reducer","tag-china-gear-box","tag-china-gearbox","tag-china-motor","tag-gear","tag-gear-box","tag-gear-box-gearbox","tag-gear-box-manufacturer","tag-gear-box-motor","tag-gear-box-reducer","tag-gear-box-speed","tag-gear-box-speed-reducer","tag-gear-gearbox","tag-gear-motor","tag-gear-motor-gearbox","tag-gear-motor-near-me","tag-gear-motor-reducer","tag-gear-motor-small","tag-gear-motor-speed-reducer","tag-gear-reducer","tag-gear-reducer-box","tag-gear-reducer-gearbox","tag-gear-reducer-motor","tag-gear-reducer-speed","tag-gear-speed-reducer","tag-gearbox","tag-gearbox-china","tag-gearbox-gear","tag-gearbox-gear-box","tag-gearbox-motor","tag-gearbox-motor-speed-reducer","tag-gearbox-reducer","tag-gearbox-speed","tag-gearbox-speed-reducer","tag-motor","tag-motor-box","tag-motor-gear-box","tag-motor-gearbox","tag-motor-gearbox-china","tag-motor-motor","tag-motor-reducer","tag-motor-reducer-gearbox","tag-nmrv-gearbox","tag-reducer","tag-reducer-gear-box-motor","tag-reducer-gear-motor","tag-reducer-gearbox","tag-reducer-motor","tag-reducer-speed","tag-reducer-speed-box","tag-series-gear-reducer","tag-small-box-gear","tag-small-gear","tag-small-gear-motor","tag-small-gear-reducer","tag-small-gearbox","tag-small-speed-gear-box","tag-small-speed-reducer-gearbox","tag-speed-gear","tag-speed-gear-box","tag-speed-gear-motor","tag-speed-gear-reducer","tag-speed-gearbox","tag-speed-gearbox-reducer","tag-speed-reducer","tag-speed-reducer-gear","tag-speed-reducer-gear-box","tag-speed-reducer-gearbox","tag-speed-reducer-gearbox-motor","tag-speed-reducer-motor","tag-steel-reducer"],"_links":{"self":[{"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/posts\/1486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/comments?post=1486"}],"version-history":[{"count":0,"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/posts\/1486\/revisions"}],"wp:attachment":[{"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/media?parent=1486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/categories?post=1486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/tags?post=1486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}