{"id":1518,"date":"2023-01-18T18:54:01","date_gmt":"2023-01-18T18:54:01","guid":{"rendered":"http:\/\/gearboxes-worm.top\/china-rv-series-90-degree-worm-gearmotor-gearbox-for-belt-conveyor-worm-gearbox-assembly\/"},"modified":"2023-01-18T18:54:01","modified_gmt":"2023-01-18T18:54:01","slug":"china-rv-series-90-degree-worm-gearmotor-gearbox-for-belt-conveyor-worm-gearbox-assembly","status":"publish","type":"post","link":"https:\/\/gearboxes-worm.top\/de\/china-rv-series-90-degree-worm-gearmotor-gearbox-for-belt-conveyor-worm-gearbox-assembly\/","title":{"rendered":"China RV-Serie 90-Grad-Schneckengetriebemotor-Getriebe f\u00fcr Bandf\u00f6rderer, Schneckengetriebe-Baugruppe"},"content":{"rendered":"<p><h2>L\u00f6sungsbeschreibung<\/h2>\n<p>\n<p>\n<p>\u00a0<\/p>\n<p>\n<p>L\u00f6sungsbeschreibung<\/p>\n<p>\u00a0<\/p>\n<p><b>Artikelbeschreibung<\/b><\/p>\n<p><b>-RV-Sequenz-Schneckengetriebe<\/b><br \/>\u00a0<\/p>\n<p>\n<p>\n<p>\n<p><strong>Produkteigenschaften<\/strong><\/p>\n<p>1. Kompakte mechanische Struktur, klein und erfolgreich<br \/>zwei. Mit gr\u00f6\u00dferem \u00dcbersetzungsverh\u00e4ltnis, hohem Drehmoment, hoher Belastbarkeit, gleichm\u00e4\u00dfigem Lauf, geringer Ger\u00e4uschentwicklung und robuster Bauweise<br \/>3. Unkomplizierte Installation, flexibel, hervorragende Funktionalit\u00e4t, einfacher Wartungsaufwand<br \/>4. Ausgezeichnete W\u00e4rmeleistung insgesamt, schnelle W\u00e4rmeableitung<br \/>f\u00fcnf. Das Schneckengetriebe und das Schneckenuntersetzungsgetriebe nutzen fortschrittliche in- und ausl\u00e4ndische Technologie, ein unverwechselbares und neuartiges Geh\u00e4use, ein ansprechendes Erscheinungsbild, das aus hochwertigem Aluminium-Druckguss gefertigt ist.<\/p>\n<p><strong><strong>L\u00f6sungssoftware<\/strong><\/strong><\/p>\n<p>NMRV-Schneckengetriebe werden in zahlreichen Branchen eingesetzt, darunter Lebensmittel-, Keramik- und Chemieproduktion sowie Verpackung, Druck, F\u00e4rben und Kunststoffverarbeitung.<\/p>\n<p>\n<p>\n<p><p>L\u00f6sungsparameter<\/p>\n<p><p><strong>Technische Daten<\/strong><\/p>\n<p>\n<table>\n<colgroup>\n<col \/>\n<col \/>\n<col \/>\n<col \/>\n<col \/>\n<col \/>\n<col \/><\/colgroup>\n<tbody>\n<tr>\n<td><b>Typen<\/b><\/td>\n<td><b>Nennleistung<\/b><\/td>\n<td><b>Nennverh\u00e4ltnis<\/b><\/td>\n<td><b>Lochdurchmesser eingeben<\/b><\/td>\n<td><b>Eingangswellendurchmesser<\/b><\/td>\n<td><b>Ausgangsspaltdurchmesser<\/b><\/td>\n<td><b>Durchmesser der Abtriebswelle<\/b><\/td>\n<\/tr>\n<tr>\n<td>RV030<\/td>\n<td>0,06 kW bis 0,18 kW<\/td>\n<td>7.5~80<\/td>\n<td>\u03a69(\u03a611)<\/td>\n<td>\u03a69<\/td>\n<td>\u03a614<\/td>\n<td>\u03a614<\/td>\n<\/tr>\n<tr>\n<td>RV040<\/td>\n<td>0,12 kW bis 0,37 kW<\/td>\n<td>7,5 bis achtzig<\/td>\n<td>\u03a611(\u03a614)<\/td>\n<td>\u03a69<\/td>\n<td>\u03a614<\/td>\n<td>\u03a614<\/td>\n<\/tr>\n<tr>\n<td>RV050<\/td>\n<td>0,12 kW bis 0,75 kW<\/td>\n<td>sieben,5 bis einhundert<\/td>\n<td>\u03a611(\u03a614,\u03a619)<\/td>\n<td>\u03a614<\/td>\n<td>\u03a625(\u03a624)<\/td>\n<td>\u03a625<\/td>\n<\/tr>\n<tr>\n<td>RV063<\/td>\n<td>0,37 kW bis 1,5 kW<\/td>\n<td>sieben,5 bis einhundert<\/td>\n<td>\u03a614(\u03a619,\u03a624)<\/td>\n<td>\u03a619<\/td>\n<td>\u03a625(\u03a628)<\/td>\n<td>\u03a625<\/td>\n<\/tr>\n<tr>\n<td>RV075<\/td>\n<td>0,55 kW bis 4,0 kW<\/td>\n<td>7,5 bis hundert<\/td>\n<td>\u03a614(\u03a619,\u03a624,\u03a628)<\/td>\n<td>\u03a624<\/td>\n<td>\u03a628(\u03a635)<\/td>\n<td>\u03a628<\/td>\n<\/tr>\n<tr>\n<td>RV090<\/td>\n<td>0,75 kW bis 4,0 kW<\/td>\n<td>sieben,5 bis einhundert<\/td>\n<td>\u03a619(\u03a624,\u03a628)<\/td>\n<td>\u03a624<\/td>\n<td>\u03a635(\u03a638)<\/td>\n<td>\u03a635<\/td>\n<\/tr>\n<tr>\n<td>RV110<\/td>\n<td>1,1 kW bis 7,5 kW<\/td>\n<td>sieben,5 bis 100<\/td>\n<td>\u03a619(\u03a624,\u03a628,\u03a638)<\/td>\n<td>\u03a628<\/td>\n<td>\u03a642<\/td>\n<td>\u03a642<\/td>\n<\/tr>\n<tr>\n<td>RV130<\/td>\n<td>2,2 kW bis 7,5 kW<\/td>\n<td>sieben,5 bis hundert<\/td>\n<td>\u03a624(\u03a628,\u03a638)<\/td>\n<td>\u03a630<\/td>\n<td>\u03a645<\/td>\n<td>\u03a645<\/td>\n<\/tr>\n<tr>\n<td>Vielfalt<\/td>\n<td colspan=\"6\">Schneckengetriebe-Getriebe<\/td>\n<\/tr>\n<tr>\n<td>Verh\u00e4ltnis<\/td>\n<td colspan=\"6\">7,5, zehn, 15, zwanzig, f\u00fcnfundzwanzig, drei\u00dfig, vierzig, f\u00fcnfzig, 60, 80, 100<\/td>\n<\/tr>\n<tr>\n<td>Schatten<\/td>\n<td colspan=\"6\">Blau\/Silbergrau<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"4\">Material<\/td>\n<td colspan=\"6\">Aluminiumlegierung<\/td>\n<\/tr>\n<tr>\n<td colspan=\"6\">Schneckenrad: Verschlei\u00dffeste Zinnbronze-Legierung<\/td>\n<\/tr>\n<tr>\n<td colspan=\"6\">Schneckenwelle: 20Cr, karbonisieren und abschrecken<\/td>\n<\/tr>\n<tr>\n<td colspan=\"6\">Abtriebswelle: 40CrMnTi<\/td>\n<\/tr>\n<tr>\n<td>Verpackung<\/td>\n<td colspan=\"6\">Karton, Holzszenario. Holzpalette.<\/td>\n<\/tr>\n<tr>\n<td>Flansch<\/td>\n<td colspan=\"6\">IEC-Standardflansch oder kundenspezifisch gefertigt<\/td>\n<\/tr>\n<tr>\n<td>Eingangsleistung<\/td>\n<td colspan=\"6\">0,06 kW, 0,09 kW, 0,12 kW, 0,18 kW, 0,25 kW, 0,37 kW, 0,55 kW, 0,75 kW, 1,1 kW, 1,5 kW, 2,2 kW, 3,0 kW, 4,0 kW, 5,5 kW, 7,5 kW<\/td>\n<\/tr>\n<tr>\n<td>Verwendung<\/td>\n<td colspan=\"6\">Automatisierungssektor, Mittelmischer und so weiter.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\n<p>\n<p>\n<p>\n<p>\u00a0<\/p>\n<p><p>Umfassende Bilder<\/p>\n<p>\u00a0<\/p>\n<p>\n<p>\n<p>\n<p>\n<p>\n<p>\n<p>\n<p>\n<p>\u00a0<\/p>\n<p><p>Unser Herstellungsprozess<\/p>\n<p><p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><p>Unser Produktsortiment<\/p>\n<p><p>\u00a0<\/p>\n<p><p>Organisationsprofil<\/p>\n<p><p>\u00a0<\/p>\n<p><b>Firmenprofil<\/b><\/p>\n<p><p>Bode wurde 2007 gegr\u00fcndet und hat seinen Sitz in Hangzhou, Provinz Zhangzhou. Als spezialisierter Hersteller und Exporteur verf\u00fcgen wir \u00fcber mehr als 17 Jahre Erfahrung in der Forschung und Entwicklung von Schneckengetrieben, Getrieben, Wechselstrommotoren und den dazugeh\u00f6rigen Ersatzteilen. Unsere Produktionsst\u00e4tte ist mit modernster Fertigungs- und Pr\u00fcftechnik ausgestattet. Dank unserer qualifizierten Mitarbeiter und unserer hohen Produktionskapazit\u00e4t k\u00f6nnen wir unseren Kunden Produkte von h\u00f6chster Qualit\u00e4t anbieten. Unsere Produkte finden breite Anwendung in verschiedenen Branchen wie Metallurgie, Chemie, Hebetechnik, Bergbau, Erd\u00f6l, Textil, Medizin, Holzverarbeitung und vielen mehr. Unsere Hauptm\u00e4rkte sind China, Afrika, Australien, Vietnam, T\u00fcrkei, Japan, Korea und die Philippinen. Kontaktieren Sie uns gerne f\u00fcr Ihre Fragen. Wir freuen uns auf eine langfristige Zusammenarbeit und bieten Ihnen regelm\u00e4\u00dfig attraktive Angebote.<\/p>\n<p><p>H\u00e4ufig gestellte Fragen<\/p>\n<p><p><b>Frage 1: Sind Sie ein Handelsunternehmen oder ein Hersteller?<\/b><br \/>A: Wir sind eine Fabrik.<\/p>\n<p><b>Frage 2: Welche Getriebearten k\u00f6nnen Sie f\u00fcr uns herstellen?<\/b><br \/>A: Hauptprodukte unseres Unternehmens: Stirnradgetriebe der Serien R, S, K und F, Schneckenradgetriebe der Serie RV, Stirnradgetriebe der Serie H mit paralleler Welle<\/p>\n<p><b>F3: K\u00f6nnen Sie das f\u00fcr jede individuelle Zeichnung anfertigen?<\/b><br \/>A: Selbstverst\u00e4ndlich bieten wir ma\u00dfgeschneiderte L\u00f6sungen f\u00fcr unsere Kunden an.<\/p>\n<p><b>Frage 4: K\u00f6nnen wir von jedem Produkt 1 St\u00fcck f\u00fcr Qualit\u00e4tstests kaufen?<\/b><br \/>A: Ja, wir sind gerne bereit, uns mit dem Kauf eines Demoger\u00e4ts f\u00fcr eine qualitativ hochwertige Vorf\u00fchrung zufrieden zu geben.<\/p>\n<p><b>Frage 5: Welche Daten m\u00fcssen wir unmittelbar vor dem Absenden eines Get-Befehls angeben?<\/b><br \/>A: a) Vielfalt des Getriebes, \u00dcbersetzungsverh\u00e4ltnis, Eingangs- und Ausgangsart, Eingangsflansch, Montageort und Motorinformationen usw.<br \/>\u00a0 \u00a0 \u00a0b) Geh\u00e4usefarbe.<br \/>\u00a0\u00a0\u00a0\u00a0 c) Menge ermitteln.<br \/>\u00a0 \u00a0 \u00a0d) Sonstige besondere Spezifikationen.<\/p>\n<p><b>Frage 6: Wie lange ist Ihre Lieferzeit?<\/b><br \/>A: Im Allgemeinen betr\u00e4gt der Wert das 5- bis 10-Fache, wenn die Produkte auf Lager sind, oder das 15- bis 20-Fache, wenn die Produkte nicht auf Lager sind.<\/p>\n<p><b>Frage 7: Wie lauten Ihre Zahlungsbedingungen?<\/b><br \/>A: 301 TP3T Vorauszahlung per T\/T kurz nach Vertragsunterzeichnung. 701 TP3T im Voraus der Lieferung.<\/p>\n<p>Wenn Sie Interesse an unseren Produkten haben, kontaktieren Sie uns gerne.<br \/>Unser Team wird sein Bestes geben, um Ihren W\u00fcnschen gerecht zu werden \ud83d\ude42\u00a0<br \/>\u00a0<\/p>\n<p>\u00a0  <\/p>\n<p>\n<p>\n<p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr style=\"align-items: baseline;flex-wrap: wrap\" class=\"only-one-priceNum-tr\">\n<td style=\"padding: 0 !important\">\n                                        <span style=\"font-size: 20px;font-family: Roboto, Roboto-Bold;font-weight: 700;text-align: left;color: #e64545;padding-left: 0 !important\">US $20-300<\/span><br \/>\n                                        <span style=\"font-size: 14px;font-family: Roboto, Roboto-Regular;font-weight: 400;color: #888888;margin-right: 10px\">\/ St\u00fcck<\/span><br \/>\n                                        <span style=\"color: #e6ecf2\">|<\/span>\n                                    <\/td>\n<td class=\"sa-only-property-price only-one-priceNum-price\">\n                                        <span>1 St\u00fcck<\/span><br \/>\n                                        <span style=\"color: #888888\"><br \/>\n                                            (Mindestbestellmenge)<br \/>\n                                        <\/span>\n                                    <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Anwendung:<\/th>\n<td>Motoren, Maschinen, Schiffsmaschinen, Landmaschinen<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Funktion:<\/th>\n<td>Leistungsverteilung, Drehmoment\u00e4nderung, Drehzahl\u00e4nderung, Drehzahlreduzierung<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Layout:<\/th>\n<td>Koaxial<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">H\u00e4rte:<\/th>\n<td>Geh\u00e4rtete Zahnoberfl\u00e4che<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Installation:<\/th>\n<td>Industrie<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Schritt:<\/th>\n<td>Industrie<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Proben:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                        <strong class=\"red\">US$ 20\/St\u00fcck<\/strong><br \/>\n                                        <span title=\"1 St\u00fcck (Mindestbestellmenge)\">1 St\u00fcck (Mindestbestellmenge)<\/span>\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                                                                    <a class=\"\" target=\"_blank\" href=\" \" rel=\"nofollow noopener\"><i class=\"ob-icon icon-product\"><\/i>Muster anfordern<\/a>\n                                                                            <\/div>\n<div class=\"sample-order-desc\"><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Anpassung:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                            Verf\u00fcgbar\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                        <a target=\"_blank\" rel=\"nofollow noopener\" href=\" \"><br \/>\n                                        <i class=\"ob-icon icon-fill\"><\/i>Kundenspezifische Anfrage<br \/>\n                                        <\/a>\n                                    <\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<colgroup>\n<col \/>\n<col \/>\n<col \/>\n<col \/>\n<col \/>\n<col \/>\n<col \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"background-color:#dae2ed;height:14.4pt;text-align:left\"><span style=\"font-size:16px\"><b><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">Modelle<\/span><\/span><\/b><\/span><\/td>\n<td style=\"background-color:#dae2ed;text-align:left\"><span style=\"font-size:16px\"><b><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">Nennleistung<\/span><\/span><\/b><\/span><\/td>\n<td style=\"background-color:#dae2ed;text-align:left\"><span style=\"font-size:16px\"><b><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">Nennverh\u00e4ltnis<\/span><\/span><\/b><\/span><\/td>\n<td style=\"background-color:#dae2ed;text-align:left\"><span style=\"font-size:16px\"><b><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">Eingangslochdurchmesser<\/span><\/span><\/b><\/span><\/td>\n<td style=\"background-color:#dae2ed;text-align:left\"><span style=\"font-size:16px\"><b><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">Eingangswellendurchmesser<\/span><\/span><\/b><\/span><\/td>\n<td style=\"background-color:#dae2ed;text-align:left\"><span style=\"font-size:16px\"><b><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">Auslasslochdurchmesser<\/span><\/span><\/b><\/span><\/td>\n<td style=\"background-color:#dae2ed;text-align:left\"><span style=\"font-size:16px\"><b><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">Durchmesser der Abtriebswelle<\/span><\/span><\/b><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">RV030<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">0,06 kW bis 0,18 kW<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">7.5~80<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a69(\u03a611)<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a69<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a614<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a614<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:15.6pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">RV040<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">0,12 kW bis 0,37 kW<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">7.5~80<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a611(\u03a61<span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">4)<\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a69<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a614<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a614<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">RV050<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">0,12 kW bis 0,75 kW<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">7.5~100<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a611(\u03a614,\u03a619)<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a614<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a625(\u03a624)<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a625<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\">RV063<\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\">0,37 kW bis 1,5 kW<\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\">7.5~100<\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\">\u03a614(\u03a619,\u03a624)<\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\">\u03a619<\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\">\u03a625(\u03a628)<\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\">\u03a625<\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">RV075<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">0,55 kW bis 4,0 kW<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">7.5~100<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a614(\u03a619,\u03a624,\u03a628)<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a624<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a628(\u03a635)<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a628<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">RV090<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">0,75 kW bis 4,0 kW<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">7.5~100<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a619(\u03a624,\u03a628)<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a624<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a635(\u03a638)<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a635<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">RV110<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">1,1 kW bis 7,5 kW<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">7.5~100<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a619(\u03a624,\u03a628,\u03a638)<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a628<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a642<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a642<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">RV130<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">2,2 kW bis 7,5 kW<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">7.5~100<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a624(\u03a628,\u03a638)<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a630<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a645<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a645<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Typ<\/span><\/span><\/span><\/td>\n<td colspan=\"6\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Schneckengetriebe-Getriebe<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Verh\u00e4ltnis<\/span><\/span><\/span><\/td>\n<td colspan=\"6\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">7.5, 10, 15, 20, 25, 30, 40, 50, 60, 80, 100<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Farbe<\/span><\/span><\/span><\/td>\n<td colspan=\"6\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Blau\/Silbergrau<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td rowspan=\"4\" style=\"height:57.6pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Material<\/span><\/span><\/span><\/td>\n<td colspan=\"6\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Aluminiumlegierung<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td colspan=\"6\" style=\"height:14.4pt\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Schneckenrad: Verschlei\u00dffeste Zinnbronze-Legierung<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td colspan=\"6\" style=\"height:14.4pt\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Schneckenwelle: 20Cr, karbonisieren und abschrecken<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td colspan=\"6\" style=\"height:14.4pt\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Abtriebswelle: 40CrMnTi<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Verpackung<\/span><\/span><\/span><\/td>\n<td colspan=\"6\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Karton, Holzkiste. Holzpalette.<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Flansch<\/span><\/span><\/span><\/td>\n<td colspan=\"6\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">IEC-Norm<span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">&nbsp;Flansch oder kundenspezifisch<\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:27.0pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Eingangsleistung<\/span><\/span><\/span><\/td>\n<td colspan=\"6\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">0,06 kW, 0,09 kW, 0,12 kW, 0,18 kW, 0,25 kW, 0,37 kW, 0,55 kW, 0,75 kW, 1,1 kW, 1,5 kW, 2,2 kW, 3,0 kW, 4,0 kW, 5,5 kW, 7,5 kW<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Verwendung<\/span><\/span><\/span><\/td>\n<td colspan=\"6\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Automatisierungsindustrie, Mittelmischer und so weiter.<\/span><\/span><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr style=\"align-items: baseline;flex-wrap: wrap\" class=\"only-one-priceNum-tr\">\n<td style=\"padding: 0 !important\">\n                                        <span style=\"font-size: 20px;font-family: Roboto, Roboto-Bold;font-weight: 700;text-align: left;color: #e64545;padding-left: 0 !important\">US $20-300<\/span><br \/>\n                                        <span style=\"font-size: 14px;font-family: Roboto, Roboto-Regular;font-weight: 400;color: #888888;margin-right: 10px\">\/ St\u00fcck<\/span><br \/>\n                                        <span style=\"color: #e6ecf2\">|<\/span>\n                                    <\/td>\n<td class=\"sa-only-property-price only-one-priceNum-price\">\n                                        <span>1 St\u00fcck<\/span><br \/>\n                                        <span style=\"color: #888888\"><br \/>\n                                            (Mindestbestellmenge)<br \/>\n                                        <\/span>\n                                    <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Anwendung:<\/th>\n<td>Motoren, Maschinen, Schiffsmaschinen, Landmaschinen<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Funktion:<\/th>\n<td>Leistungsverteilung, Drehmoment\u00e4nderung, Drehzahl\u00e4nderung, Drehzahlreduzierung<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Layout:<\/th>\n<td>Koaxial<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">H\u00e4rte:<\/th>\n<td>Geh\u00e4rtete Zahnoberfl\u00e4che<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Installation:<\/th>\n<td>Industrie<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Schritt:<\/th>\n<td>Industrie<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Proben:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                        <strong class=\"red\">US$ 20\/St\u00fcck<\/strong><br \/>\n                                        <span title=\"1 St\u00fcck (Mindestbestellmenge)\">1 St\u00fcck (Mindestbestellmenge)<\/span>\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                                                                    <a class=\"\" target=\"_blank\" href=\" \" rel=\"nofollow noopener\"><i class=\"ob-icon icon-product\"><\/i>Muster anfordern<\/a>\n                                                                            <\/div>\n<div class=\"sample-order-desc\"><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Anpassung:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                            Verf\u00fcgbar\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                        <a target=\"_blank\" rel=\"nofollow noopener\" href=\" \"><br \/>\n                                        <i class=\"ob-icon icon-fill\"><\/i>Kundenspezifische Anfrage<br \/>\n                                        <\/a>\n                                    <\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<colgroup>\n<col \/>\n<col \/>\n<col \/>\n<col \/>\n<col \/>\n<col \/>\n<col \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"background-color:#dae2ed;height:14.4pt;text-align:left\"><span style=\"font-size:16px\"><b><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">Modelle<\/span><\/span><\/b><\/span><\/td>\n<td style=\"background-color:#dae2ed;text-align:left\"><span style=\"font-size:16px\"><b><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">Nennleistung<\/span><\/span><\/b><\/span><\/td>\n<td style=\"background-color:#dae2ed;text-align:left\"><span style=\"font-size:16px\"><b><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">Nennverh\u00e4ltnis<\/span><\/span><\/b><\/span><\/td>\n<td style=\"background-color:#dae2ed;text-align:left\"><span style=\"font-size:16px\"><b><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">Eingangslochdurchmesser<\/span><\/span><\/b><\/span><\/td>\n<td style=\"background-color:#dae2ed;text-align:left\"><span style=\"font-size:16px\"><b><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">Eingangswellendurchmesser<\/span><\/span><\/b><\/span><\/td>\n<td style=\"background-color:#dae2ed;text-align:left\"><span style=\"font-size:16px\"><b><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">Auslasslochdurchmesser<\/span><\/span><\/b><\/span><\/td>\n<td style=\"background-color:#dae2ed;text-align:left\"><span style=\"font-size:16px\"><b><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">Durchmesser der Abtriebswelle<\/span><\/span><\/b><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">RV030<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">0,06 kW bis 0,18 kW<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">7.5~80<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a69(\u03a611)<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a69<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a614<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a614<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:15.6pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">RV040<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">0,12 kW bis 0,37 kW<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">7.5~80<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a611(\u03a61<span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">4)<\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a69<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a614<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a614<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">RV050<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">0,12 kW bis 0,75 kW<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">7.5~100<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a611(\u03a614,\u03a619)<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a614<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a625(\u03a624)<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a625<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\">RV063<\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\">0,37 kW bis 1,5 kW<\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\">7.5~100<\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\">\u03a614(\u03a619,\u03a624)<\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\">\u03a619<\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\">\u03a625(\u03a628)<\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\">\u03a625<\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">RV075<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">0,55 kW bis 4,0 kW<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">7.5~100<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a614(\u03a619,\u03a624,\u03a628)<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a624<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a628(\u03a635)<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a628<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">RV090<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">0,75 kW bis 4,0 kW<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">7.5~100<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a619(\u03a624,\u03a628)<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a624<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a635(\u03a638)<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a635<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">RV110<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">1,1 kW bis 7,5 kW<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">7.5~100<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a619(\u03a624,\u03a628,\u03a638)<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a628<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a642<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a642<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">RV130<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">2,2 kW bis 7,5 kW<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">7.5~100<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a624(\u03a628,\u03a638)<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a630<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a645<\/span><\/span><\/span><\/td>\n<td style=\"text-align:left\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:black\">\u03a645<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Typ<\/span><\/span><\/span><\/td>\n<td colspan=\"6\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Schneckengetriebe-Getriebe<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Verh\u00e4ltnis<\/span><\/span><\/span><\/td>\n<td colspan=\"6\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">7.5, 10, 15, 20, 25, 30, 40, 50, 60, 80, 100<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Farbe<\/span><\/span><\/span><\/td>\n<td colspan=\"6\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Blau\/Silbergrau<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td rowspan=\"4\" style=\"height:57.6pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Material<\/span><\/span><\/span><\/td>\n<td colspan=\"6\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Aluminiumlegierung<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td colspan=\"6\" style=\"height:14.4pt\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Schneckenrad: Verschlei\u00dffeste Zinnbronze-Legierung<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td colspan=\"6\" style=\"height:14.4pt\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Schneckenwelle: 20Cr, karbonisieren und abschrecken<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td colspan=\"6\" style=\"height:14.4pt\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Abtriebswelle: 40CrMnTi<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Verpackung<\/span><\/span><\/span><\/td>\n<td colspan=\"6\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Karton, Holzkiste. Holzpalette.<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Flansch<\/span><\/span><\/span><\/td>\n<td colspan=\"6\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">IEC-Norm<span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">&nbsp;Flansch oder kundenspezifisch<\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:27.0pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Eingangsleistung<\/span><\/span><\/span><\/td>\n<td colspan=\"6\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">0,06 kW, 0,09 kW, 0,12 kW, 0,18 kW, 0,25 kW, 0,37 kW, 0,55 kW, 0,75 kW, 1,1 kW, 1,5 kW, 2,2 kW, 3,0 kW, 4,0 kW, 5,5 kW, 7,5 kW<\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:14.4pt;text-align:left\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Verwendung<\/span><\/span><\/span><\/td>\n<td colspan=\"6\"><span style=\"font-size:14px\"><span style=\"color:black\"><span style=\"font-family:Arial, Helvetica, sans-serif\">Automatisierungsindustrie, Mittelmischer und so weiter.<\/span><\/span><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><h2>Was ist ein Schneckengetriebe?<\/h2>\n<p>Ein Schneckengetriebe ist ein mechanisches Ger\u00e4t, das mithilfe eines Schneckenrades und einer Schnecke die Drehzahl einer rotierenden Welle reduziert. Das Getriebe kann, abh\u00e4ngig vom \u00dcbersetzungsverh\u00e4ltnis, das Drehmoment des Motors erh\u00f6hen. Diese Getriebeart zeichnet sich durch ihre Flexibilit\u00e4t und kompakte Bauweise aus. Zudem steigert sie die Kraft und Effizienz des Antriebs.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/T_worm_reducer_1.webp\" alt=\"worm reducer\" width=\"800\" \/><\/p>\n<h2>Hohlwellen-Schneckengetriebe<\/h2>\n<p>Das Hohlwellen-Schneckengetriebe ist eine zus\u00e4tzliche Abtriebswelle, die verschiedene Motoren und andere Getriebe miteinander verbindet. Es kann horizontal oder vertikal eingebaut werden. Je nach Gr\u00f6\u00dfe und Ausf\u00fchrung ist es mit Getrieben von 4GN bis 5GX kompatibel.<br \/>Schneckengetriebe werden \u00fcblicherweise in Kombination mit Stirnradgetrieben eingesetzt. Letztere sind eingangsseitig am Schneckengetriebe montiert und eignen sich hervorragend zur Drehzahlreduzierung von Motoren mit hoher Leistung. Das Stirnradgetriebe zeichnet sich durch hohen Wirkungsgrad, niedrigen Drehzahlbetrieb, geringe Ger\u00e4uschentwicklung, geringe Vibrationen und niedrigen Energieverbrauch aus.<br \/>Schneckengetriebe werden aus geh\u00e4rtetem Stahl oder Nichteisenmetallen gefertigt, was ihren Wirkungsgrad erh\u00f6ht. Dennoch sind auch Zahnr\u00e4der nicht unzerst\u00f6rbar, und ein Stillstand kann zu Rost oder Emulsionsbildung des Getriebe\u00f6ls f\u00fchren. Ursache hierf\u00fcr ist Kondenswasserbildung w\u00e4hrend des Betriebs und der Stillst\u00e4nde des Getriebes. Der Montageprozess und die Qualit\u00e4t der Lager sind wichtige Faktoren zur Vermeidung von Kondensation.<br \/>Hohlwellen-Schneckengetriebe finden in verschiedenen Anwendungen Verwendung. Sie werden h\u00e4ufig in Werkzeugmaschinen, Drehzahlreglern und Automobilen eingesetzt. Allerdings sind sie nicht f\u00fcr den Dauerbetrieb geeignet. Wenn Sie ein Hohlwellen-Schneckengetriebe einsetzen m\u00f6chten, achten Sie darauf, das passende Getriebe entsprechend Ihren Anforderungen auszuw\u00e4hlen.<\/p>\n<h2>Doppelkehl-Schneckengetriebe<\/h2>\n<p>Schneckengetriebe verwenden ein Schneckenrad als Antriebszahnrad. Ein Elektromotor oder ein Kettenrad treibt die Schnecke an, die in W\u00e4lzlagern gelagert ist. Schneckenr\u00e4der neigen aufgrund der hohen Reibung zwischen den Z\u00e4hnen zu Verschlei\u00df. Dies f\u00fchrt zu Korrosion an den Lauffl\u00e4chen der Zahnr\u00e4der.<br \/>Der Teilkreisdurchmesser und die Eingriffstiefe des Schneckengetriebes sind von Bedeutung. Der Teilkreisdurchmesser ist der Durchmesser des gedachten Kreises, in dem Schnecke und Schnecke ineinandergreifen. Die Eingriffstiefe ist die maximale Gewindel\u00e4nge der Schnecke, die in das Zahnflankenspiel hineinragt. Der Eingriffsdurchmesser ist der Durchmesser des Kreises am tiefsten Punkt der Schneckenradstirnfl\u00e4che.<br \/>Wenn der Reibungswinkel zwischen Schnecke und Zahnrad den Steigungswinkel der Schnecke \u00fcberschreitet, ist das Schneckengetriebe selbsthemmend. Diese Eigenschaft ist f\u00fcr Hebezeuge n\u00fctzlich, kann aber f\u00fcr Systeme, die eine R\u00fcckw\u00e4rtslaufempfindlichkeit erfordern, nachteilig sein. In solchen Systemen stellt die Selbsthemmung der Zahnr\u00e4der eine wesentliche Einschr\u00e4nkung dar.<br \/>Das Schneckengetriebe mit doppeltem Hals gew\u00e4hrleistet die engste Verbindung zwischen Schnecke und Zahnrad. F\u00fcr maximale Effizienz muss das Schneckengetriebe korrekt montiert sein. Eine M\u00f6glichkeit zur Montage ist die Verwendung einer Keilnut. Die Keilnut verhindert die Drehung der Welle, was f\u00fcr die Drehmoment\u00fcbertragung entscheidend ist. Anschlie\u00dfend wird das Zahnrad mithilfe der Stellschraube an der Nabe befestigt.<br \/>Die axiale und die Umfangsteilung des Schneckenrades m\u00fcssen dem Teilkreisdurchmesser des gr\u00f6\u00dferen Zahnrads entsprechen. Einschneckenr\u00e4der mit einem Gewindegang sind einstufig, zweischneckenr\u00e4der mit zwei Gewindeg\u00e4ngen. Ein einschneckenrad treibt einen Zahn weiter, ein zweischneckenrad zwei. Die Anzahl der Gewindeg\u00e4nge muss der Anzahl der Gegenzahnr\u00e4der entsprechen.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/C_worm_reducer_1.webp\" alt=\"worm reducer\" width=\"800\" \/><\/p>\n<h2>Selbstverriegelungsfunktion<\/h2>\n<p>Eine der herausragendsten Eigenschaften eines Schneckengetriebes ist seine Selbsthemmungsfunktion, die ein Vertauschen der Eingangs- und Ausgangswelle verhindert. Diese Selbsthemmungsfunktion ist ideal f\u00fcr industrielle Anwendungen, bei denen gro\u00dfe Untersetzungsverh\u00e4ltnisse ben\u00f6tigt werden, ohne das Getriebegeh\u00e4use zu vergr\u00f6\u00dfern.<br \/>Die Selbsthemmung eines Schneckengetriebes wird durch die Wahl des passenden Schneckenradtyps erreicht. Allerdings ist diese Funktion nicht bei allen Schneckengetrieben verf\u00fcgbar. Schneckenr\u00e4der sind nur dann selbsthemmend, wenn ein bestimmtes \u00dcbersetzungsverh\u00e4ltnis erreicht wird. Ist das \u00dcbersetzungsverh\u00e4ltnis zu klein, ist die Selbsthemmung nicht wirksam.<br \/>Der Selbsthemmungszustand eines Schneckengetriebes wird durch die Steigung, den Anpressdruck und den Reibungskoeffizienten bestimmt. Zu Beginn des 20. Jahrhunderts neigten Fahrzeuge mit einem platten Reifen dazu, zur Seite zu ziehen. Ein Schneckengetriebe verringerte diese Tendenz, indem es die Reibungskr\u00e4fte reduzierte und die Lenkkraft auf das Rad \u00fcbertrug, was das Lenken erleichterte und den Verschlei\u00df verringerte.<br \/>Ein selbsthemmendes Schneckengetriebe ist eine einfache Maschine mit geringem Wirkungsgrad. Es ist selbsthemmend, wenn die Arbeit an einem Ende gr\u00f6\u00dfer ist als die Arbeit am anderen. Liegt der Wirkungsgrad eines Schneckengetriebes unter 50%, entstehen Reibungsverluste. Zudem ist die Selbsthemmung bei umgekehrter Drehrichtung nicht gegeben. Aufgrund dieser Eigenschaften eignen sich selbsthemmende Schneckengetriebe ideal f\u00fcr Hebe- und Senkanwendungen.<br \/>Ein weiteres Merkmal von Schneckengetrieben ist ihre F\u00e4higkeit zur axialen Untersetzung. Schneckengetriebe k\u00f6nnen ein- oder zweig\u00e4ngig sein, und ihr Zahnflankenspiel l\u00e4sst sich einstellen, um Zahnverschlei\u00df auszugleichen.<\/p>\n<h2>Die von Schneckengetrieben erzeugte W\u00e4rme<\/h2>\n<p>Schneckengetriebe erzeugen erhebliche W\u00e4rmemengen. Um die Leistung der Getriebe zu verbessern, ist es unerl\u00e4sslich, diese W\u00e4rme zu reduzieren. Dies l\u00e4sst sich durch die Konstruktion der Schnecken mit glatteren Oberfl\u00e4chen erreichen. Im Allgemeinen sollte die Eingriffsgeschwindigkeit von Schneckengetrieben im Bereich von 20 bis 24 U\/min (Effektivwert) liegen.<br \/>Es gibt zahlreiche Ans\u00e4tze zur Berechnung des Wirkungsgrades von Schneckengetrieben. Keiner dieser Ans\u00e4tze nutzt jedoch ein automatisches Verfahren zum Aufbau des thermischen Netzwerks. Die anderen Methoden betrachten das Getriebe entweder abstrakt als isothermes System oder erstellen das thermische Netzwerk statisch. Dieser Artikel beschreibt eine neue Methode zur automatischen Berechnung der W\u00e4rmebilanz und des Wirkungsgrades von Schneckengetrieben.<br \/>Die von Schneckengetrieben erzeugte W\u00e4rme ist eine bedeutende Ursache f\u00fcr Leistungsverluste. Schneckengetriebe zeichnen sich typischerweise durch hohe Gleitgeschwindigkeiten in den Zahneingriffen aus, was zu hoher Reibungsw\u00e4rme und erh\u00f6hten thermischen Spannungen f\u00fchrt. Daher sind pr\u00e4zise Berechnungen f\u00fcr einen optimalen Betrieb unerl\u00e4sslich. Zur Bestimmung des Wirkungsgrades eines Getriebesystems nutzen Hersteller h\u00e4ufig das Simulationsprogramm WTplus zur Berechnung von W\u00e4rmeverlusten und Wirkungsgrad. Die W\u00e4rmebilanzberechnung erfolgt durch Addition der Leerlauf- und lastabh\u00e4ngigen Leistungsverluste des Getriebes.<br \/>Schneckengetriebe ben\u00f6tigen ein spezielles Schmiermittel. Zum Einsatz kommt ein synthetisches \u00d6l, das nicht magnetisch ist und einen niedrigen Reibungskoeffizienten aufweist. \u00d6l ist jedoch nur eine von mehreren M\u00f6glichkeiten zur Schmierung von Schneckengetrieben. Um die Lebensdauer von Schneckengetrieben zu verl\u00e4ngern, empfiehlt sich die Zugabe eines nat\u00fcrlichen Zusatzstoffs zum Schmiermittel.<br \/>Schneckengetriebe erm\u00f6glichen sehr hohe Untersetzungsverh\u00e4ltnisse. Im Vergleich zu herk\u00f6mmlichen Getrieben, die mehrere Untersetzungen ben\u00f6tigen, erzielen sie mit geringem Aufwand massive Untersetzungen. Zudem weisen Schneckengetriebe weniger bewegliche Teile und potenzielle Fehlerquellen auf. Ein Nachteil von Schneckengetrieben ist ihre fehlende Reversibilit\u00e4t, die ihren Wirkungsgrad begrenzt.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/B_worm_reducer_1.webp\" alt=\"worm reducer\" width=\"800\" \/><\/p>\n<h2>Gr\u00f6\u00dfe des Schneckengetriebes<\/h2>\n<p>Schneckengetriebe dienen zur Drehzahlreduzierung von Wellen. Sie bestehen \u00fcblicherweise aus zwei rechtwinklig zueinander angeordneten Wellen. Das Schneckenrad fungiert dabei als Ritzel und Zahnstange. Der zentrale Querschnitt bildet die Grenze zwischen der vor- und zur\u00fccklaufenden Seite des Schneckenrades.<br \/>Das Abtriebsrad eines Schneckengetriebes hat im Vergleich zum Antriebsrad einen kleinen Durchmesser. Dies erm\u00f6glicht einen Betrieb mit niedriger Drehzahl bei gleichzeitig hohem Drehmoment. Daher eignen sich Schneckengetriebe hervorragend f\u00fcr platzsparende Anwendungen. Zudem sind die Anschaffungskosten gering.<br \/>Schneckengetriebe geh\u00f6ren zu den g\u00e4ngigsten Untersetzungsgetrieben. Sie sind kompakt und leistungsstark und werden h\u00e4ufig in Kraft\u00fcbertragungssystemen eingesetzt. Man findet sie beispielsweise in Aufz\u00fcgen, F\u00f6rderb\u00e4ndern, Sicherheitsschleusen und Medizinger\u00e4ten. Schneckengetriebe kommen in kleinen wie gro\u00dfen Maschinen zum Einsatz.<br \/>Auch Schneckengetriebe lassen sich einstellen. Ein Schneckengetriebe mit zwei Steigungen hat unterschiedliche Steigungen an den linken und rechten Zahnfl\u00e4chen. Dies erm\u00f6glicht eine axiale Bewegung der Schnecke und kann zur Reduzierung des Zahnflankenspiels angepasst werden. Eine Zahnflankenspiel-Einstellung kann erforderlich sein, wenn die Schnecke verschlei\u00dft. In manchen F\u00e4llen l\u00e4sst sich dieses Spiel durch Ver\u00e4ndern des Achsabstands zwischen den Schneckenr\u00e4dern einstellen.<br \/>Die Gr\u00f6\u00dfe eines Schneckengetriebes h\u00e4ngt von seiner Funktion ab. Wird das Schneckengetriebe beispielsweise zur Drehzahlreduzierung eines Automobils eingesetzt, sollte es so dimensioniert sein, dass es in ein kleines Auto eingebaut werden kann.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/Worm_Reducer_l1.webp\" alt=\"China RV Series 90 Degree Worm Gearmotor Gearbox for Belt Conveyor     worm gearbox assembly\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/Worm_Reducer_l2.webp\" alt=\"China RV Series 90 Degree Worm Gearmotor Gearbox for Belt Conveyor     worm gearbox assembly\"><br \/>Bearbeitet von czh am 19.01.2023<\/p>","protected":false},"excerpt":{"rendered":"<p>L\u00f6sungsbeschreibung L\u00f6sungsbeschreibung Artikelbeschreibung - RV-Sequenz-Schneckengetriebe Produkteigenschaften 1. Kompakte mechanische Bauweise, klein und leistungsstark. 2. Gro\u00dfes \u00dcbersetzungsverh\u00e4ltnis, hohes Drehmoment, hohe Belastbarkeit, ruhiger Lauf, geringe Ger\u00e4uschentwicklung und robust. 3. Einfache Installation, flexibel, hervorragende Funktionalit\u00e4t, wartungsarm. 4. Ausgezeichnete W\u00e4rmeleitf\u00e4higkeit, schnelle W\u00e4rmeableitung. 5. Das Schneckenrad und [\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[54,56,12,67,72,20,82,520,21,83,36,46],"class_list":["post-1518","post","type-post","status-publish","format-standard","hentry","category-gearboxes-worm","tag-90-degree-gearbox","tag-belt","tag-china-gearbox","tag-conveyor-belt-gearbox","tag-degree-gearbox","tag-gearbox","tag-gearbox-90-degree","tag-gearbox-assembly","tag-gearbox-china","tag-gearbox-for-conveyor","tag-rv-gearbox","tag-worm-gearbox"],"_links":{"self":[{"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/posts\/1518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/comments?post=1518"}],"version-history":[{"count":0,"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/posts\/1518\/revisions"}],"wp:attachment":[{"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/media?parent=1518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/categories?post=1518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/tags?post=1518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}