{"id":1521,"date":"2023-02-02T22:25:51","date_gmt":"2023-02-02T22:25:51","guid":{"rendered":"http:\/\/gearboxes-worm.top\/china-eed-transmission-worm-gearbox-e-rv075-with-input-flange-90b14-with-great-quality\/"},"modified":"2023-02-02T22:25:51","modified_gmt":"2023-02-02T22:25:51","slug":"china-eed-transmission-worm-gearbox-e-rv075-with-input-flange-90b14-with-great-quality","status":"publish","type":"post","link":"https:\/\/gearboxes-worm.top\/de\/china-eed-transmission-worm-gearbox-e-rv075-with-input-flange-90b14-with-great-quality\/","title":{"rendered":"China Eed Transmission Schneckengetriebe E-RV075 mit Eingangsflansch 90b14 in hervorragender Qualit\u00e4t"},"content":{"rendered":"<p><h2>L\u00f6sungsbeschreibung<\/h2>\n<p>\n<p>   \u00dcberblick<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<br \/>Kurzinfo<br \/>Getriebeart: Schnecke Markenbezeichnung: EED<br \/>Eingangsdrehzahl: 1400 U\/min Ausgangsdrehzahl: 14 bis 186 U\/min<br \/>Nennleistung: 0,06 ~ 4 kW Drehmoment: 2,6\u2013479 Nm<br \/>Farbe: Blau\/Silber oder auf Anfrage Herkunft: Zhangzhou, China (Festland)\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<br \/>Garantie: 1 Jahr Anwendung: Markt \u00a0 \u00a0<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<br \/>Lieferf\u00e4higkeit<br \/>Angebotspotenzial: 20.000 St\u00fcck pro Monat<br \/>Zus\u00e4tzlicher Support: OEM-Auftr\u00e4ge sind willkommen \u00a0 \u00a0 \u00a0 \u00a0\u00a0<br \/>Qualit\u00e4tskontrollprogramm: ISO9001:2008<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<br \/>Verpackung &amp; Lieferung<br \/>Verpackung: Karton\/Papierkarton \u00a0 \u00a0<br \/>Hafen: Hangzhou\/Zhejiang oder auf Anfrage\u00a0 \u00a0 \u00a0<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p>\u00a0<\/p>\n<table>\n<tbody>\n<tr>\n<td>Art<\/td>\n<td>Schneckengetriebe<\/td>\n<\/tr>\n<tr>\n<td>Produkt<\/td>\n<td>NMRV-Sequenzdimensionen: 571, 30, 40, 50, 63, 75, 90, 110, 130, 150<\/td>\n<\/tr>\n<tr>\n<td>VERH\u00c4LTNIS<\/td>\n<td>f\u00fcnf, 7,5, zehn, 15, zwanzig, 25, 30, vierzig, 50, sechzig, 80, 100<\/td>\n<\/tr>\n<tr>\n<td>Schatten<\/td>\n<td>Blau (RAL 5571)\/Silbergrau (RAL 9571) oder nach Ihren W\u00fcnschen<\/td>\n<\/tr>\n<tr>\n<td>Material<\/td>\n<td>Geh\u00e4use: Aluminiumlegierung<\/td>\n<\/tr>\n<tr>\n<td>VERPACKUNG<\/td>\n<td>Karton\/Pappkiste \u00a0<\/td>\n<\/tr>\n<tr>\n<td>LAGER<\/td>\n<td>C&amp;U<\/td>\n<\/tr>\n<tr>\n<td>SIEGEL<\/td>\n<td>SKF<\/td>\n<\/tr>\n<tr>\n<td>Garantie<\/td>\n<td>1 Kalenderjahr<\/td>\n<\/tr>\n<tr>\n<td>Elektrische Energiezufuhr<\/td>\n<td>0,09 km - 15 km<\/td>\n<\/tr>\n<tr>\n<td>ANWENDUNGEN<\/td>\n<td>Lebensmittel, Keramik, Verpackungen, chemische Substanzen, Pharmazie, Kunststoffe, Papierherstellung, Ger\u00e4te und Werkzeuge<\/td>\n<\/tr>\n<tr>\n<td>IEC-FLANSCH<\/td>\n<td>IEC-Standardflansch oder auf Anfrage<\/td>\n<\/tr>\n<tr>\n<td>SCHMIERMITTEL<\/td>\n<td>Shell oder Henry<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\u00a0<\/p>\n<p>\u00dcber CZPT unter Ber\u00fccksichtigung dessen, dass 1984<\/p>\n<p>HangZhou Melchizedek Import &amp; Export Co., Ltd. ist seit 1984 ein f\u00fchrender Hersteller im Bereich Maschinenbau und Stanztechnik. Unsere Hauptprodukte, das Schneckengetriebe NMRV und die Stirnradgetriebe XDR, XDF, XDK und XDS, entsprechen dem hohen technischen Standard vergleichbarer europ\u00e4ischer und japanischer Produkte. Wir bieten Standardzahnr\u00e4der, Kettenr\u00e4der, Ketten, Riemenscheiben, Kupplungen, Buchsen usw. an. Gerne fertigen wir auch Sonderanfertigungen wie Zahnr\u00e4der, Wellen, Stanzteile etc. nach Kundenzeichnungen oder -mustern.\u00a0<\/p>\n<p>Unser Unternehmen verf\u00fcgt \u00fcber einen kompletten Maschinenpark, darunter CNC-Drehmaschinen, Fr\u00e4smaschinen, W\u00e4lzfr\u00e4smaschinen, Schleifmaschinen, Honmaschinen, Formmaschinen, Schneckenschleifmaschinen, Bohrmaschinen, Bohrmaschinen, Hobelmaschinen, Zeichenb\u00e4nke, Stanzmaschinen, Hydraulikpressen, Blechscheren und vieles mehr. Wir bieten au\u00dferdem erstklassige Siebanlagen.\u00a0<\/p>\n<p>Unser Unternehmen hat vorteilhafte Kooperationsbeziehungen mit Zulieferern aufgebaut, die unter anderem Gie\u00dfereiprodukte, Rohmaterialien, W\u00e4rmebehandlung und Oberfl\u00e4chenveredelung anbieten.<\/p>\n<p>Der gr\u00f6\u00dfte Vorteil des Geschwindigkeitsreduzierers liegt in der Technik der Kupferverkleidung, die den Okklusionsantrieb zwischen Bronze- und Hauptrad verst\u00e4rken kann.<\/p>\n<p>  <\/p>\n<p>\n<p>\n<p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr style=\"align-items: baseline;flex-wrap: wrap\" class=\"only-one-priceNum-tr\">\n<td style=\"padding: 0 !important\">\n                                        <span style=\"font-size: 20px;font-family: Roboto, Roboto-Bold;font-weight: 700;text-align: left;color: #e64545;padding-left: 0 !important\">US $10-500<\/span><br \/>\n                                        <span style=\"font-size: 14px;font-family: Roboto, Roboto-Regular;font-weight: 400;color: #888888;margin-right: 10px\">\/ St\u00fcck<\/span><br \/>\n                                        <span style=\"color: #e6ecf2\">|<\/span>\n                                    <\/td>\n<td class=\"sa-only-property-price only-one-priceNum-price\">\n                                        <span>10 St\u00fcck<\/span><br \/>\n                                        <span style=\"color: #888888\"><br \/>\n                                            (Mindestbestellmenge)<br \/>\n                                        <\/span>\n                                    <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Anwendung:<\/th>\n<td>Motoren, Maschinen, Schiffsmaschinen, Landmaschinen<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">H\u00e4rte:<\/th>\n<td>Geh\u00e4rtete Zahnoberfl\u00e4che<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Schritt:<\/th>\n<td>Einzelschritt<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Typ:<\/th>\n<td>Wurmreduzierer<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Transportpaket:<\/th>\n<td>Schrumpfverpackung, Kartonverpackung<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Warenzeichen:<\/th>\n<td>OEM; EED<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Anpassung:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                            Verf\u00fcgbar\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                        <a target=\"_blank\" rel=\"nofollow noopener\" href=\" \"><br \/>\n                                        <i class=\"ob-icon icon-fill\"><\/i>Kundenspezifische Anfrage<br \/>\n                                        <\/a>\n                                    <\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<td>TYP<\/td>\n<td>Schneckengetriebe \/ Schneckengetriebe<\/td>\n<\/tr>\n<tr>\n<td>MODELL<\/td>\n<td>NMRV-Seriengr\u00f6\u00dfe: 025, 030, 040, 050, 063, 075, 090, 110, 130, 150<\/td>\n<\/tr>\n<tr>\n<td>VERH\u00c4LTNIS<\/td>\n<td>5,7.5,10,15,20,25,30,40,50,60,80,100<\/td>\n<\/tr>\n<tr>\n<td>FARBE<\/td>\n<td>Blau (RAL 5010)\/Silbergrau (RAL 9022) oder nach Ihren W\u00fcnschen<\/td>\n<\/tr>\n<tr>\n<td>MATERIAL<\/td>\n<td>Geh\u00e4use: Aluminiumlegierung<\/td>\n<\/tr>\n<tr>\n<td>VERPACKUNG<\/td>\n<td>Holzkiste\/Papierkarton &nbsp;<\/td>\n<\/tr>\n<tr>\n<td>LAGER<\/td>\n<td>C&amp;U<\/td>\n<\/tr>\n<tr>\n<td>SIEGEL<\/td>\n<td>SKF<\/td>\n<\/tr>\n<tr>\n<td>GARANTIE<\/td>\n<td>1 Jahr<\/td>\n<\/tr>\n<tr>\n<td>Eingangsleistung<\/td>\n<td>0,09 km \u2013 15 km<\/td>\n<\/tr>\n<tr>\n<td>ANWENDUNGEN<\/td>\n<td>Lebensmittel, Keramik, Verpackung, Chemikalien, Pharmazie, Kunststoffe, Papierherstellung, Werkzeugmaschinen<\/td>\n<\/tr>\n<tr>\n<td>IEC-FLANSCH<\/td>\n<td>IEC-Standardflansch oder auf Anfrage<\/td>\n<\/tr>\n<tr>\n<td>SCHMIERMITTEL<\/td>\n<td>Shell oder Henry<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr style=\"align-items: baseline;flex-wrap: wrap\" class=\"only-one-priceNum-tr\">\n<td style=\"padding: 0 !important\">\n                                        <span style=\"font-size: 20px;font-family: Roboto, Roboto-Bold;font-weight: 700;text-align: left;color: #e64545;padding-left: 0 !important\">US $10-500<\/span><br \/>\n                                        <span style=\"font-size: 14px;font-family: Roboto, Roboto-Regular;font-weight: 400;color: #888888;margin-right: 10px\">\/ St\u00fcck<\/span><br \/>\n                                        <span style=\"color: #e6ecf2\">|<\/span>\n                                    <\/td>\n<td class=\"sa-only-property-price only-one-priceNum-price\">\n                                        <span>10 St\u00fcck<\/span><br \/>\n                                        <span style=\"color: #888888\"><br \/>\n                                            (Mindestbestellmenge)<br \/>\n                                        <\/span>\n                                    <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Anwendung:<\/th>\n<td>Motoren, Maschinen, Schiffsmaschinen, Landmaschinen<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">H\u00e4rte:<\/th>\n<td>Geh\u00e4rtete Zahnoberfl\u00e4che<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Schritt:<\/th>\n<td>Einzelschritt<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Typ:<\/th>\n<td>Wurmreduzierer<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Transportpaket:<\/th>\n<td>Schrumpfverpackung, Kartonverpackung<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Warenzeichen:<\/th>\n<td>OEM; EED<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Anpassung:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                            Verf\u00fcgbar\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                        <a target=\"_blank\" rel=\"nofollow noopener\" href=\" \"><br \/>\n                                        <i class=\"ob-icon icon-fill\"><\/i>Kundenspezifische Anfrage<br \/>\n                                        <\/a>\n                                    <\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<td>TYP<\/td>\n<td>Schneckengetriebe \/ Schneckengetriebe<\/td>\n<\/tr>\n<tr>\n<td>MODELL<\/td>\n<td>NMRV-Seriengr\u00f6\u00dfe: 025, 030, 040, 050, 063, 075, 090, 110, 130, 150<\/td>\n<\/tr>\n<tr>\n<td>VERH\u00c4LTNIS<\/td>\n<td>5,7.5,10,15,20,25,30,40,50,60,80,100<\/td>\n<\/tr>\n<tr>\n<td>FARBE<\/td>\n<td>Blau (RAL 5010)\/Silbergrau (RAL 9022) oder nach Ihren W\u00fcnschen<\/td>\n<\/tr>\n<tr>\n<td>MATERIAL<\/td>\n<td>Geh\u00e4use: Aluminiumlegierung<\/td>\n<\/tr>\n<tr>\n<td>VERPACKUNG<\/td>\n<td>Holzkiste\/Papierkarton &nbsp;<\/td>\n<\/tr>\n<tr>\n<td>LAGER<\/td>\n<td>C&amp;U<\/td>\n<\/tr>\n<tr>\n<td>SIEGEL<\/td>\n<td>SKF<\/td>\n<\/tr>\n<tr>\n<td>GARANTIE<\/td>\n<td>1 Jahr<\/td>\n<\/tr>\n<tr>\n<td>Eingangsleistung<\/td>\n<td>0,09 km \u2013 15 km<\/td>\n<\/tr>\n<tr>\n<td>ANWENDUNGEN<\/td>\n<td>Lebensmittel, Keramik, Verpackung, Chemikalien, Pharmazie, Kunststoffe, Papierherstellung, Werkzeugmaschinen<\/td>\n<\/tr>\n<tr>\n<td>IEC-FLANSCH<\/td>\n<td>IEC-Standardflansch oder auf Anfrage<\/td>\n<\/tr>\n<tr>\n<td>SCHMIERMITTEL<\/td>\n<td>Shell oder Henry<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><h2>Was ist ein Schneckengetriebe?<\/h2>\n<p>Das Schneckengetriebe dient zur \u00c4nderung der Abtriebsdrehzahl einer mechanischen Anlage. Es besteht aus Schnecken- und Schr\u00e4gverzahnungen, die auf der Eingangsseite der Anlage montiert sind. In manchen F\u00e4llen kann dieses Untersetzungssystem mehrstufig ausgef\u00fchrt sein, wodurch extrem niedrige Abtriebsdrehzahlen m\u00f6glich werden. Es zeichnet sich durch geringen Energieverbrauch und geringe Vibrationen aus.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/T_worm_reducer_3.webp\" alt=\"worm reducer\" width=\"800\" \/>Hohlwellen-Schneckengetriebe<\/h2>\n<p>Das Schneckengetriebe ist ein effektives Ger\u00e4t zur Drehzahlreduzierung von Maschinen. Die Verwendung von Hartstahl oder Nichteisenmetallen f\u00fcr die Schnecke erh\u00f6ht den Wirkungsgrad. Schnecken aus Hartstahl erzeugen mehr W\u00e4rme als solche aus Baustahl. Unterschiedliche W\u00e4rmeausdehnung f\u00fchrt zu Spaltma\u00dfen zwischen den Passfl\u00e4chen. Trotz seiner vielen Vorteile neigen Schneckengetriebe zu \u00d6lleckagen, was aus verschiedenen Gr\u00fcnden problematisch sein kann.<br \/>Hohlwellen-Schneckengetriebe sind in verschiedenen \u00dcbersetzungsverh\u00e4ltnissen erh\u00e4ltlich und mit vielen Motortypen kompatibel. Sie sind als Ein- und Zweiachsengetriebe verf\u00fcgbar und k\u00f6nnen horizontal oder vertikal montiert werden. Dar\u00fcber hinaus sind sie mit Zwischen\u00fcbersetzungen sowie als Vier- und F\u00fcnfganggetriebe erh\u00e4ltlich. Zus\u00e4tzliche Abtriebswellen k\u00f6nnen ebenfalls angeschlossen werden.<br \/>Eine weitere Bauart von Schneckengetrieben ist das mehrstufige Getriebe. Dieses Getriebe verf\u00fcgt \u00fcber mehrere Stufen und erm\u00f6glicht so extrem niedrige Ausgangsdrehzahlen. Neben dem hohen \u00dcbersetzungsverh\u00e4ltnis zeichnet sich das mehrstufige Getriebe durch geringe Ger\u00e4uschentwicklung, geringe Vibrationen und einen niedrigen Energieverbrauch aus.<br \/>Schneckengetriebe bieten platzsparende L\u00f6sungen und ein h\u00f6heres Drehmoment. Agknx Gearbox bietet Schneckengetriebe an, die g\u00e4ngige Probleme bei der Untersetzung l\u00f6sen. Das Unternehmen hat sein Produktsortiment zudem auf den Badezimmermarkt ausgeweitet. Im Vergleich zu Standardgetrieben zeichnen sich Schneckengetriebe durch einen niedrigeren Preis und ein h\u00f6heres Drehmoment aus.<br \/>Agknx Schneckengetriebe<\/h2>\n<p>Das Schneckengetriebe vom Typ Agknx verf\u00fcgt \u00fcber Linienkontakt und findet breite Anwendung in Schwermaschinen. Diese Getriebe zeichnen sich durch eine hohe Belastbarkeit aus, reagieren jedoch empfindlich auf Fluchtungs- und Fertigungsfehler. Durch den Einsatz von Punktkontakt l\u00e4sst sich die Zuverl\u00e4ssigkeit dieser Getriebe erh\u00f6hen und ihre Belastbarkeit verbessern.<br \/>Ein weiterer wesentlicher Vorteil des Agknx-Schneckengetriebes ist seine hohe Belastbarkeit. Das Zahnprofil der Zahnr\u00e4der weist ein hohes relatives Schlupfverh\u00e4ltnis auf, was die Effizienz und die Belastbarkeit verbessert. Dar\u00fcber hinaus sorgt der gro\u00dfe Winkel zwischen Gleitrichtung und Kontaktlinie f\u00fcr einen niedrigen Reibungskoeffizienten. Das Agknx-Schneckengetriebe zeichnet sich au\u00dferdem durch hochwertiges, einsatzgeh\u00e4rtetes Stahl- und Phosphorbronze-Guss aus, was ihm eine au\u00dfergew\u00f6hnliche Langlebigkeit verleiht. Zus\u00e4tzlich ist das Zahnprofil sehr pr\u00e4zise, \u200b\u200bder Lauf leise und die Drehzahlschwankungen sind gering.<br \/>Die Schneckengetriebe von Agknx sind f\u00fcr einen Dauerbetrieb von bis zu zehn Stunden t\u00e4glich unter gleichm\u00e4\u00dfiger Last ausgelegt. Die Konstruktion dieses Schneckengetriebes basiert auf der langj\u00e4hrigen Erfahrung von Sumitomo Heavy Industries im Bereich der Getriebetechnik. Die glatte Oberfl\u00e4chenstruktur und das pr\u00e4zise Zahnprofil der Zahnr\u00e4der gew\u00e4hrleisten, dass diese hohen Belastungen standhalten, ohne den Schmierfilm zu besch\u00e4digen. Dar\u00fcber hinaus sind die Schneckenwellen von Agknx speziell auf die optimale Steifigkeit ausgelegt.<br \/>Die Schneckengetriebe von Agknx sind so konstruiert, dass sie die Belastbarkeit maximieren und gleichzeitig den Energieverbrauch minimieren. Die vollst\u00e4ndig ineinandergreifenden Z\u00e4hne reduzieren den Fl\u00e4chendruck auf die Schneckenradz\u00e4hne und erh\u00f6hen so die Belastbarkeit.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/C_worm_reducer_3.webp\" alt=\"worm reducer\" width=\"800\" \/>Doppelkehl-Schneckengetriebe<\/h2>\n<p>Bei der Auswahl eines Schneckengetriebes mit zwei Zahnh\u00e4lsen sind einige Punkte zu beachten. Zun\u00e4chst muss der Durchmesser des Fu\u00dfkreises der Teilung des gr\u00f6\u00dferen Zahnrads entsprechen. Dies wird \u00fcblicherweise durch Messen des Abstands zwischen benachbarten Z\u00e4hnen ermittelt. Alternativ kann der Modul der Schnecke verwendet werden. Dieser Wert wird im Dialogfeld \u201eModul der Schnecke\u201c eingegeben. Dar\u00fcber hinaus sollte die axiale Steigung der Schnecke dem Teilkreisdurchmesser entsprechen.<br \/>Doppelschneckengetriebe sind eine ausgezeichnete Wahl f\u00fcr anspruchsvolle Anwendungen. Ihre Konstruktion ist ideal f\u00fcr hohe Belastungen, da sie eine engere Verbindung zwischen Schnecke und Zahnrad gew\u00e4hrleistet. Sie sind zudem kompakter als andere Getriebearten und vergleichbar mit einer Feingewindespindel.<br \/>Der Wirkungsgrad eines Schneckengetriebes mit doppeltem Eingriff h\u00e4ngt vom Material der Zahnr\u00e4der und der Schnecke ab. Typischerweise bestehen die Zahnr\u00e4der aus einsatzgeh\u00e4rtetem Stahl, w\u00e4hrend die Schneckengetriebe aus Bronze oder Gusseisen gefertigt sind. In manchen F\u00e4llen kann eine Kombination aus Gusseisen und Bronze verwendet werden.<br \/>Die Durchbiegung der Schneckenwelle wird auch von den Zahnparametern beeinflusst. Zahnh\u00f6he, Eingriffswinkel und Abmessungen wirken sich auf die Durchbiegung der Schneckenwelle aus. Dar\u00fcber hinaus ist die Anzahl der Schneckengewinde ein weiterer wichtiger Parameter, der die Durchbiegung der Schneckenwelle beeinflusst.<br \/>Doppelschneckengetriebe werden h\u00e4ufig in industriellen Anwendungen eingesetzt, in denen eine hohe Getriebeuntersetzung erforderlich ist. Die Schnecke besitzt eine konkave Innenverzahnung, die sich zur Erzielung verschiedener \u00dcbersetzungsverh\u00e4ltnisse anpassen l\u00e4sst. Schneckengetriebe und Schneckengetriebebaugruppen m\u00fcssen fachgerecht auf ihren Wellen montiert werden, um einen R\u00fccklauf zu verhindern.<br \/>Schneckengetriebe aus Messing<\/h2>\n<p>Das grundlegende Funktionsprinzip des Messing-Schneckengetriebes entspricht dem des herk\u00f6mmlichen Schneckengetriebes. Seine axiale Teilung muss der Umfangsteilung des gr\u00f6\u00dferen Zahnrads entsprechen. Bei eing\u00e4ngigen Schneckengetrieben wird pro Umdrehung ein Zahn weitergeschaltet, bei zweig\u00e4ngigen zwei. Das Schneckengewinde ist entweder links- oder rechtsg\u00e4ngig. Die Steigung einer Schnecke ist die Strecke, die ein Punkt auf dem Schneckengewinde bei einer Umdrehung zur\u00fccklegt. Der Steigungswinkel ist der Winkel zwischen der Steigung des Zylinders und der Schneckenachse.<br \/>Doppelgewinde-Schneckengetriebe eignen sich optimal f\u00fcr hohe Belastungen. Sie gew\u00e4hrleisten eine besonders feste Verbindung zwischen Schnecke und Schneckenrad. Die Montage des Schneckenrades erfordert pr\u00e4zises Arbeiten. Bei der Keilwellenmontage wird eine rechtwinklige Nut in die Zahnradbohrung gebohrt. Dies verhindert das Verdrehen der Schnecke auf der Welle und optimiert die Drehmoment\u00fcbertragung. Anschlie\u00dfend wird das Zahnrad mithilfe der Stellschraube an der Nabe befestigt.<br \/>Der gro\u00dfe Kraftstofftank tr\u00e4gt zur Sauberkeit des Schneckengetriebes bei und reduziert die W\u00e4rmeentwicklung. Er sorgt au\u00dferdem f\u00fcr Schmierung und damit f\u00fcr eine l\u00e4ngere Lebensdauer. Schneckengetriebe mit \u00d6lbeh\u00e4ltern gew\u00e4hrleisten eine optimale Schmierung und reibungsarme Oberfl\u00e4chen. Dar\u00fcber hinaus bietet das Getriebe Flexibilit\u00e4t bei der Montage in verschiedenen Positionen. Das Geh\u00e4use ist f\u00fcr pr\u00e4zise Ausrichtung quergefr\u00e4st und verf\u00fcgt \u00fcber interne Leitbleche f\u00fcr eine leckagefreie Bel\u00fcftung.<br \/>Die Schneckengetriebe der Serie I260 bestehen aus einteiligen Eisengeh\u00e4usen mit massiven oder hohlen Abtriebswellen und Kegelrollenlagern. Dieses Getriebe ist f\u00fcr Anwendungen mit niedriger bis mittlerer Leistung ausgelegt. Es bietet ein gutes Preis-Leistungs-Verh\u00e4ltnis durch geringe Anschaffungskosten, ein hohes \u00dcbersetzungsverh\u00e4ltnis und ein hohes Drehmoment in kompakter Bauweise. Zudem ist es sto\u00dffester als andere Getriebe.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/B_worm_reducer_3.webp\" alt=\"worm reducer\" width=\"800\" \/>Schneckengetriebe aus Messing<\/h2>\n<p>Ein Schneckengetriebe aus Messing ist ein Untersetzungsgetriebe. Diese Getriebeart erm\u00f6glicht eine hohe Untersetzung auf kleinem Raum. Es ist au\u00dferdem in der Lage, ein hohes Drehmoment zu erzeugen. Allerdings ist zu beachten, dass dieses Getriebe thermischen Beschr\u00e4nkungen unterliegt, die seinen Wirkungsgrad mindern. Die Wahl des Schmierstoffs ist sehr flexibel. Da Messing jedoch ein Buntmetall ist, muss der Schmierstoff reaktionsarm sein.<br \/>Schneckengetriebe finden in vielen Konsumg\u00fcter- und Industrieanwendungen Verwendung und zeichnen sich durch hohe Untersetzungsverh\u00e4ltnisse aus. Sie werden in verschiedenen Ausf\u00fchrungen und Gr\u00f6\u00dfen gefertigt. Schneckengetriebe \u00e4hneln Stirnr\u00e4dern, besitzen jedoch nicht parallele Wellen. Sie eignen sich besonders f\u00fcr Anwendungen, die eine niedrige Ausgangsdrehzahl bei gleichzeitig hohem Drehmoment erfordern.<br \/>Schneckengetriebe bieten gegen\u00fcber anderen Getrieben einige entscheidende Vorteile. Im Gegensatz zu Standardzahnr\u00e4dern dreht sich die Schnecke in einer wurmartigen Bewegung. Dieser Mechanismus verhindert eine R\u00fcckw\u00e4rtsbewegung, da der Steigungswinkel des Schneckengetriebes klein ist. Zus\u00e4tzlich blockieren die Schnecken selbst, was ebenfalls ein Zur\u00fcckdrehen verhindert. Allerdings ist dieser Mechanismus nicht v\u00f6llig zuverl\u00e4ssig. Schneckengetriebe finden Anwendung in Aufz\u00fcgen, Angelrollen, Kettenr\u00e4dern und Servolenkungen von Kraftfahrzeugen.<br \/>Ein weiterer Vorteil von Schneckengetrieben ist ihre einfache Fertigung. Das Prinzip dieser Konstruktion beruht auf zwei zueinander senkrechten Achsen. Anschlie\u00dfend werden dem Schneckenrad zwei oder mehr Gewindeg\u00e4nge hinzugef\u00fcgt. Die gemeinsame Tangente dieser beiden Achsen schneidet die Teilkreislinie der Schneckenwelle. Dies ist die Grundlage f\u00fcr die \u00dcbertragungsgeschwindigkeit.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/Worm_Reducer_l1.webp\" alt=\"China Eed Transmission Worm Gearbox E-RV075 with Input Flange 90b14     with Great quality \"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/Worm_Reducer_l2.webp\" alt=\"China Eed Transmission Worm Gearbox E-RV075 with Input Flange 90b14     with Great quality \"><br \/>Bearbeitet von czh am 03.02.2023<\/p>","protected":false},"excerpt":{"rendered":"<p>Solution Description Overview&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;Fast ParticularsGearing Arrangement:\u00a0 \u00a0 Worm\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[12,20,21,221,25,242,46],"class_list":["post-1521","post","type-post","status-publish","format-standard","hentry","category-gearboxes-worm","tag-china-gearbox","tag-gearbox","tag-gearbox-china","tag-gearbox-transmission","tag-gearbox-with","tag-transmission-gearbox","tag-worm-gearbox"],"_links":{"self":[{"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/posts\/1521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/comments?post=1521"}],"version-history":[{"count":0,"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/posts\/1521\/revisions"}],"wp:attachment":[{"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/media?parent=1521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/categories?post=1521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearboxes-worm.top\/de\/wp-json\/wp\/v2\/tags?post=1521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}