{"id":1567,"date":"2023-09-23T08:55:10","date_gmt":"2023-09-23T08:55:10","guid":{"rendered":"https:\/\/gearboxes-worm.top\/china-high-quality-new-type-of-shaft-mounted-multi-stage-100-high-transmission-ratio-helical-gear-box-with-great-quality\/"},"modified":"2023-09-23T08:55:10","modified_gmt":"2023-09-23T08:55:10","slug":"china-high-quality-new-type-of-shaft-mounted-multi-stage-100-high-transmission-ratio-helical-gear-box-with-great-quality","status":"publish","type":"post","link":"https:\/\/gearboxes-worm.top\/gl\/china-high-quality-new-type-of-shaft-mounted-multi-stage-100-high-transmission-ratio-helical-gear-box-with-great-quality\/","title":{"rendered":"Novo tipo de caixa de engrenaxes helicoidais multietapa 100% de alta relaci\u00f3n de transmisi\u00f3n montada no eixe de alta calidade de China con gran calidade"},"content":{"rendered":"<div class=\"et_pb_column et_pb_column_3_4 et_pb_column_0_tb_body  et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<p><h2>Descrici\u00f3n do produto<\/h2>\n<p>\n<p>   \u00a0<\/p>\n<p><h2><b>Descrici\u00f3n do produto<\/b><\/h2>\n<p>\n<p><b><strong><strong>Motor de engrenaxes helicoidais e c\u00f3nicas da serie K de Boqiang Drive<\/strong><\/strong><\/b><\/p>\n<p><strong><strong><b>Caracter\u00edsticas<\/b><\/strong><strong>:<\/strong><\/strong><br \/>-Alta eficiencia: 92%-97%;<br \/>-Estrutura compacta: pequena sa\u00edda de desprazamento, d\u00faas e tres etapas est\u00e1n na mesma caixa.<br \/>-Alta precisi\u00f3n: a engrenaxe est\u00e1 feita de aceiro de aliaxe de alta calidade forxado, tratamento de carbonitruraci\u00f3n e endurecemento, proceso de moenda para garantir unha alta precisi\u00f3n e un funcionamento estable.<br \/>-Alta intercambiabilidade: dese\u00f1o en serie altamente modular, forte versatilidade e intercambiabilidade.<\/p>\n<p>\n<p>\n<p>\n<p>\n<p><p><strong><strong>T\u00e9cnico<\/strong><\/strong><strong>\u00a0<\/strong><strong><strong>par\u00e1metro<\/strong><\/strong><strong><strong>s<\/strong><\/strong><\/p>\n<p>\n<table>\n<tbody>\n<tr>\n<td>Proporci\u00f3n<\/td>\n<td>3.41-289.74<\/td>\n<\/tr>\n<tr>\n<td>Potencia de entrada<\/td>\n<td>0,12-160 kW<\/td>\n<\/tr>\n<tr>\n<td>Par de sa\u00edda<\/td>\n<td>61-23200 N.m<\/td>\n<\/tr>\n<tr>\n<td>velocidade de sa\u00edda<\/td>\n<td>5-415 rpm<\/td>\n<\/tr>\n<tr>\n<td>Tipo de montaxe<\/td>\n<td>Montado con p\u00e9, montado con brida, montado con p\u00e9 e brida, montado con p\u00e9 dunha soa etapa, montado con brida CHINAMFG, montado con brida con cubo de rodamentos estendido<\/td>\n<\/tr>\n<tr>\n<td>M\u00e9todo de entrada<\/td>\n<td>Entrada de brida (AM), entrada de eixe (AD), entrada de motor de CA en li\u00f1a ou servomotor AQA<\/td>\n<\/tr>\n<tr>\n<td>Liberaci\u00f3n do freo<\/td>\n<td>Liberaci\u00f3n manual HF (bloqueo na posici\u00f3n de liberaci\u00f3n do freo), liberaci\u00f3n manual HR (posici\u00f3n de freado autom\u00e1tico)<\/td>\n<\/tr>\n<tr>\n<td>termistor<\/td>\n<td>TF (termisto PTC de protecci\u00f3n do termistor)<br \/>TH (Interruptor bimet\u00e1lico de protecci\u00f3n por termistor)<\/td>\n<\/tr>\n<tr>\n<td>Posici\u00f3n de montaxe<\/td>\n<td>M1, M2, M3, M4, M5, M6<\/td>\n<\/tr>\n<tr>\n<td>Tipo<\/td>\n<td>R17-R167<\/td>\n<\/tr>\n<tr>\n<td>Desprazamento do eixe de sa\u00edda.<\/td>\n<td>20 mm, 25 mm, 30 mm, 35 mm, 40 mm, 50 mm, 60 mm, 70 mm, 90 mm, 110 mm, 120 mm<\/td>\n<\/tr>\n<tr>\n<td>Material da carcasa<\/td>\n<td>Ferro fundido de alta resistencia HT200 desde R37,47,57,67,77,87<\/td>\n<\/tr>\n<tr>\n<td>Material da carcasa<\/td>\n<td>Ferro fundido de alta resistencia HT250 desde R97 107, 137, 147, 157, 167, 187<\/td>\n<\/tr>\n<tr>\n<td>Tecnolox\u00eda de tratamento t\u00e9rmico<\/td>\n<td>tratamento de carbonitruraci\u00f3n e endurecemento<\/td>\n<\/tr>\n<tr>\n<td>Eficiencia<\/td>\n<td>92%-97%<\/td>\n<\/tr>\n<tr>\n<td>Lubricante<\/td>\n<td>VG220<\/td>\n<\/tr>\n<tr>\n<td>Clase de protecci\u00f3n<\/td>\n<td>IP55, clase F<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><p>\u00a0<\/p>\n<p>Par\u00e1metros do produto<\/p>\n<p>\n<table>\n<tbody>\n<tr>\n<td><b>Modelos<\/b><\/td>\n<td><b>Di\u00e1metro do eixe de sa\u00edda<\/b><\/td>\n<td><b>Di\u00e1metro do eixe de entrada<\/b><\/td>\n<td><b>Potencia (kW)<\/b><\/td>\n<td><b>Proporci\u00f3n<\/b><\/td>\n<td><b>Par m\u00e1ximo (Nm)<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>R\/RF18<\/b><\/td>\n<td><b>20 mm<\/b><\/td>\n<td><b>&#8211;<\/b><\/td>\n<td><b>0.18~0.75<\/b><\/td>\n<td><b>3.83~74.84<\/b><\/td>\n<td><b>85<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>R\/RF28<\/b><\/td>\n<td><b>25 mm<\/b><\/td>\n<td><b>16 mm<\/b><\/td>\n<td><b>0.18~3<\/b><\/td>\n<td><b>3.37~135.09<\/b><\/td>\n<td><b>130<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>R\/RF38<\/b><\/td>\n<td><b>25 mm<\/b><\/td>\n<td><b>16 mm<\/b><\/td>\n<td><b>0.18~3<\/b><\/td>\n<td><b>3.41~134.82<\/b><\/td>\n<td><b>200<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>R\/RF48<\/b><\/td>\n<td><b>30 mm<\/b><\/td>\n<td><b>19 mm<\/b><\/td>\n<td><b>0.18~5.5<\/b><\/td>\n<td><b>3.83~176.88<\/b><\/td>\n<td><b>300<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>R\/RF58<\/b><\/td>\n<td><b>35 mm<\/b><\/td>\n<td><b>19 mm<\/b><\/td>\n<td><b>0.18~7.5<\/b><\/td>\n<td><b>4.39~186.89<\/b><\/td>\n<td><b>450<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>R\/RF68<\/b><\/td>\n<td><b>35 mm<\/b><\/td>\n<td><b>19 mm<\/b><\/td>\n<td><b>0.18~7.5<\/b><\/td>\n<td><b>4.29~199.81<\/b><\/td>\n<td><b>600<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>R\/RF78<\/b><\/td>\n<td><b>40 mm<\/b><\/td>\n<td><b>24 mm<\/b><\/td>\n<td><b>0.18~11<\/b><\/td>\n<td><b>5.21~195.24<\/b><\/td>\n<td><b>820<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>R\/RF88<\/b><\/td>\n<td><b>50 mm<\/b><\/td>\n<td><b>28 mm<\/b><\/td>\n<td><b>0.55~22<\/b><\/td>\n<td><b>5.36~246.54<\/b><\/td>\n<td><b>1550<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>R\/RF98<\/b><\/td>\n<td><b>60 mm<\/b><\/td>\n<td><b>38 mm<\/b><\/td>\n<td><b>0.55~30<\/b><\/td>\n<td><b>4.49~289.6<\/b><\/td>\n<td><b>3000<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>R\/RF108<\/b><\/td>\n<td><b>70 mm<\/b><\/td>\n<td><b>42 mm<\/b><\/td>\n<td><b>2.2~45<\/b><\/td>\n<td><b>5.06~245.5<\/b><\/td>\n<td><b>4300<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>R\/RF138<\/b><\/td>\n<td><b>90 mm<\/b><\/td>\n<td><b>55 mm<\/b><\/td>\n<td><b>5.5~55<\/b><\/td>\n<td><b>5.51~223.34<\/b><\/td>\n<td><b>8000<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>R\/RF148<\/b><\/td>\n<td><b>110 mm<\/b><\/td>\n<td><b>55 mm<\/b><\/td>\n<td><b>11~90<\/b><\/td>\n<td><b>5.00~163.46<\/b><\/td>\n<td><b>13000<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>R\/RF168<\/b><\/td>\n<td><b>120 mm<\/b><\/td>\n<td><b>70 mm<\/b><\/td>\n<td><b>11~160<\/b><\/td>\n<td><b>8.77~196.41<\/b><\/td>\n<td><b>18000<\/b><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\n<p><b>1 Etapa<\/b><\/p>\n<p>\n<table>\n<tbody>\n<tr>\n<td><b>Modelos<\/b><\/td>\n<td><b>Di\u00e1metro do eixe de sa\u00edda<\/b><\/td>\n<td><b>Di\u00e1metro do eixe de entrada<\/b><\/td>\n<td><b>Potencia (kW)<\/b><\/td>\n<td><b>Proporci\u00f3n<\/b><\/td>\n<td><b>Par m\u00e1ximo (Nm)<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>RX\/RXF38<\/b><\/td>\n<td><b>20 mm<\/b><\/td>\n<td><b>16 mm<\/b><\/td>\n<td><b>0.18~1.1<\/b><\/td>\n<td><b>1.6~3.76<\/b><\/td>\n<td><b>20<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>RX\/RXF58<\/b><\/td>\n<td><b>20 mm<\/b><\/td>\n<td><b>19 mm<\/b><\/td>\n<td><b>0.18~5.5<\/b><\/td>\n<td><b>1.3~5.5<\/b><\/td>\n<td><b>70<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>RX\/RXF68<\/b><\/td>\n<td><b>25 mm<\/b><\/td>\n<td><b>19 mm<\/b><\/td>\n<td><b>0.18~7.5<\/b><\/td>\n<td><b>1.4~6.07<\/b><\/td>\n<td><b>135<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>RX\/RXF78<\/b><\/td>\n<td><b>30 mm<\/b><\/td>\n<td><b>24 mm<\/b><\/td>\n<td><b>1.1~11<\/b><\/td>\n<td><b>1.42~5.63<\/b><\/td>\n<td><b>215<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>RX\/RXF88<\/b><\/td>\n<td><b>40 mm<\/b><\/td>\n<td><b>28 mm<\/b><\/td>\n<td><b>3~22<\/b><\/td>\n<td><b>1.39~6.44<\/b><\/td>\n<td><b>400<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>RX\/RXF98<\/b><\/td>\n<td><b>50 mm<\/b><\/td>\n<td><b>38 mm<\/b><\/td>\n<td><b>5.5~30<\/b><\/td>\n<td><b>1.42~5.82<\/b><\/td>\n<td><b>600<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>RX\/RXF108<\/b><\/td>\n<td><b>60 mm<\/b><\/td>\n<td><b>42 mm<\/b><\/td>\n<td><b>7.5~45<\/b><\/td>\n<td><b>1.44~6.65<\/b><\/td>\n<td><b>830<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>RX\/RXF128<\/b><\/td>\n<td><b>75 mm<\/b><\/td>\n<td><b>55 mm<\/b><\/td>\n<td><b>7.5~90<\/b><\/td>\n<td><b>1.56~6.47<\/b><\/td>\n<td><b>1110<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>RX\/RXF158<\/b><\/td>\n<td><b>90 mm<\/b><\/td>\n<td><b>70 mm<\/b><\/td>\n<td><b>11~132<\/b><\/td>\n<td><b>1.63~6.22<\/b><\/td>\n<td><b>1680<\/b><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\n<p><b>As unidades de engrenaxes da serie R est\u00e1n dispo\u00f1ibles nos seguintes dese\u00f1os:<\/b><\/p>\n<p>\n<p>\n<p>\n<p><p>1.R.. Y.. Redutor de engrenaxes helicoidais montado na extensi\u00f3n do eixe do p\u00e9<\/p>\n<p>\n<p>\n<p><p>2.RF.. Y.. Redutor de engrenaxes helicoidais montado na extensi\u00f3n do eixe da brida<\/p>\n<p>\n<p>\n<p>\n<p>\n<p><p>3.R.. R.. Y.. Redutor de engrenaxes helicoidais combinado montado na extensi\u00f3n do eixe base<\/p>\n<p>\n<p>\n<p><p>4.RF.. R.. Y.. Redutor de engrenaxes helicoidais combinado montado na extensi\u00f3n do eixe da brida<\/p>\n<p>\n<p>\n<p>\n<p>\n<p><p>5.R.. AD.. Instalaci\u00f3n da extensi\u00f3n do eixe de p\u00e9, redutor de engrenaxes helicoidais de entrada do eixe<\/p>\n<p>\n<p>\n<p><p>6.RF.. AD.. Instalaci\u00f3n de tipo extensi\u00f3n axial de brida, redutor de engrenaxes helicoidais de entrada do eixe<\/p>\n<p>\n<p>\n<p>\n<p>\n<p><p>7.R.. R.. AD.. Redutor de engrenaxes helicoidais de entrada de eixe combinado montado na extensi\u00f3n do eixe de p\u00e9<\/p>\n<p>\n<p>\n<p><p>8.RF.. R.. Y.. Redutor de engrenaxes helicoidais de entrada de eixe combinado montado na extensi\u00f3n do eixe de brida<\/p>\n<p>\n<p>\n<p>\n<p>\n<p><p>9.R ou RF.. P ou SF.. Redutor de engrenaxes helicoidais de tipo brida de acoplamento (\u00fasase cando o usuario do motor est\u00e1 equipado ou est\u00e1 equipado con motores especiais)<\/p>\n<p>\n<p>Posici\u00f3n de montaxe:<br \/>Posici\u00f3n da caixa t\u00e9rmica do motor:<\/p>\n<p>Potencia nominal de entrada e par admisible:<\/p>\n<p>Peso da unidade de engrenaxes:<br \/><b>Fotos da zona da f\u00e1brica<\/b><\/p>\n<p>\n<p>\n<p>\n<p><p><b>\u00a0 ZHangZhoug Boqiang Transmission Co., Ltd. foi fundada en 2002 e \u00e9 unha empresa de alta tecnolox\u00eda que integra dese\u00f1o, desenvolvemento, fabricaci\u00f3n e operaci\u00f3n, producindo e vendendo motores de reduci\u00f3n e equipos de transmisi\u00f3n de potencia. A empresa est\u00e1 situada na cidade de Oubei, no condado de HangZhoua, na vangarda da reforma e apertura nacional, co\u00f1ecida como o \"Pequeno Xihu (Lago Oeste) Dis.\" de HangZhou. Preto da estrada nacional 104 e ao leste do aeroporto internacional de HangZhou e da terminal internacional de contedores Xihu (Lago Oeste) Dis.; ao sur da estaci\u00f3n de tren de HangZhou e do centro de transporte de pasaxeiros; tam\u00e9n hai moitas atracci\u00f3ns tur\u00edsticas nacionais como a monta\u00f1a Yandang e o r\u00edo Xihu (Lago Oeste) Dis.. Cun transporte c\u00f3modo e unha localizaci\u00f3n xeogr\u00e1fica \u00fanica, \u00e9 moi ben recibida por usuarios nacionais e estranxeiros.<\/b><br \/><b>A nosa empresa produce 12 series de redutores de engrenaxes helicoidais para diversos fins, inclu\u00edndo redutores de engrenaxes helicoidais montados no eixe, redutores de engrenaxes c\u00f3nicas helicoidais, redutores de engrenaxes sen fin helicoidais, caixas de direcci\u00f3n de engrenaxes c\u00f3nicas en espiral, redutores de engrenaxes sen fin, transmisi\u00f3ns continuamente variables, elevadores en espiral e caixas de cambios grandes. A cobertura de potencia \u00e9 de 0,12-2000 kW, cunha relaci\u00f3n de reduci\u00f3n de 1,25-30000. Diversas combinaci\u00f3ns, deformaci\u00f3ns e produtos especializados poden satisfacer a maior\u00eda dos requisitos industriais. Os redutores das series R, K, F e S adoptan o principio de dese\u00f1o modular da estrutura unitaria, o que reduce considerablemente os tipos de compo\u00f1entes e o inventario, e acurta considerablemente o ciclo de entrega. Os compo\u00f1entes te\u00f1en unha forte universalidade e baixos custos de mantemento.<\/p>\n<p>Boqiang ocupa unha posici\u00f3n de liderado na China en termos de nivel tecnol\u00f3xico e cota de mercado de produtos. Os produtos util\u00edzanse amplamente en diversos campos como a metalurxia, a industria lixeira, o envasado, a medicina, o petr\u00f3leo, a industria qu\u00edmica, a elevaci\u00f3n e o transporte, o aparcamento tridimensional, a impresi\u00f3n e o tinguido, os ascensores, a enerx\u00eda e\u00f3lica, etc. A empresa Boqiang ten un excelente rendemento. Os expertos en tecnolox\u00eda de transmisi\u00f3n da sede central e os numerosos enxe\u00f1eiros de aplicaci\u00f3ns e t\u00e9cnicos de servizo posvenda de varias oficinas rexionais ofr\u00e9cenche unha consulta t\u00e9cnica r\u00e1pida e completa e servizos completos.<\/p>\n<p>Mirando cara atr\u00e1s, cara ao pasado e cara ao futuro, Boqiang sempre estivo no cami\u00f1o cara adiante, mellorando e super\u00e1ndose constantemente con produtos de alta calidade e servizos completos, ga\u00f1ando o favor do mercado e dos clientes. Estamos dispostos a traballar xunto con persoas con co\u00f1ecementos de todos os \u00e1mbitos da vida para crear un futuro m\u00e1is brillante.<\/b><br \/><b>Equipos de procesamento<br \/><\/b><b>Equipos de proba e control de calidade<\/b><br \/>Calidade: Insistir na mellora, esforzarse pola fabricaci\u00f3n de equipos de China. Co desenvolvemento da industria de fabricaci\u00f3n de equipos, o cliente nunca est\u00e1 satisfeito coa calidade actual dos nosos produtos, sen\u00f3n que, pola contra, creamos o valor da calidade.<br \/>Pol\u00edtica de calidade: mellorar o nivel xeral no campo da transmisi\u00f3n de enerx\u00eda \u00a0<br \/>Visi\u00f3n da calidade: mellora continua, busca da excelencia<br \/>Filosof\u00eda da calidade: a calidade crea valor<\/p>\n<p>\n<p>\n<p>\n<p>\n<p><p><b>Embalaxe e transporte<br \/><\/b><\/p>\n<h1>Preguntas frecuentes<br \/>P1: Quero mercar os vosos produtos, como podo pagar?<br \/>R: Podes pagar mediante T\/T (30%+70%), L\/C, D\/P, etc.\u00a0<\/p>\n<p>P2: Como podedes garantir a calidade?<br \/>R: Un ano de garant\u00eda contra a data de entrega\/librar\u00eda. Se tes alg\u00fan problema de calidade, env\u00edanos fotos ou v\u00eddeos para comprobalo. Prometemos enviarche pezas de reposto ou produtos novos para substitu\u00edlos. A nosa garant\u00eda non incl\u00fae un funcionamento inadecuado nin unha selecci\u00f3n de especificaci\u00f3ns incorrecta.\u00a0<\/p>\n<p>P3: Como seleccionamos modelos e especificaci\u00f3ns?<br \/>R: Podes enviarnos por correo electr\u00f3nico o c\u00f3digo da serie (por exemplo: caixa de cambios helicoidal da serie RC), as\u00ed como os detalles dos requisitos, como a potencia do motor, a velocidade ou relaci\u00f3n de sa\u00edda, o factor de servizo ou a t\u00faa aplicaci\u00f3n... tantos datos como sexa posible. Se podes proporcionar algunhas imaxes ou debuxos, estar\u00eda ben.\u00a0<\/p>\n<p>P4: Se non atopamos o que buscamos no seu sitio web, que debemos facer?<br \/>R: Ofrecemos 3 opci\u00f3ns:<br \/>1. Podes enviarnos por correo electr\u00f3nico as imaxes, os debuxos ou as descrici\u00f3ns detalladas. Tentaremos dese\u00f1ar os teus produtos base\u00e1ndonos nas nosas<br \/>modelos est\u00e1ndar.<br \/>2, o noso departamento de I+D \u00e9 profesional para produtos OEM\/ODM mediante debuxos\/mostras, podes enviarnos mostras, facemos dese\u00f1os personalizados para as t\u00faas compras a granel.<br \/>3, Podemos desenvolver novos produtos se te\u00f1en un bo mercado. Xa desenvolvemos moitos artigos para usos especiais con \u00e9xito, como caixas de cambios especiais para axitadores, transportadores de cemento, m\u00e1quinas para zapatos, etc.\u00a0<\/p>\n<p>P5: Podemos mercar 1 unidade de cada artigo para probas de calidade?<br \/>R: Si, estamos encantados de aceptar pedidos de proba para probas de calidade.<\/p>\n<p>P6: Que tal o tempo de entrega do produto?<br \/>R: Normalmente, para un contedor de 20', leva de 25 a 30 d\u00edas laborables para a caixa de engrenaxes sen fin da serie RV e de 35 a 40 d\u00edas laborables para os motores de engrenaxes helicoidais.<\/h1>\n<p>\u00a0  <\/p>\n<p>\n<p>\n<p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\"><\/div>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Garant\u00eda:<\/th>\n<td>un ano<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Potencia de entrada:<\/th>\n<td>0,12-200 kW<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Probas:<\/th>\n<td>Cada m\u00e1quina ser\u00e1 probada antes de embalar.<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Paso:<\/th>\n<td>Paso \u00fanico<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Automatizaci\u00f3n:<\/th>\n<td>Automatizaci\u00f3n<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Certificaci\u00f3n:<\/th>\n<td>CE, RoHS, ISO9001: 2000<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"attr-line\"><\/div>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Personalizaci\u00f3n:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                            Dispo\u00f1ible\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><\/p>\n<p>                                        <i class=\"ob-icon icon-fill\"><\/i>Solicitude personalizada<\/p><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<\/p><\/div>\n<\/table>\n<p><img decoding=\"async\" src=\"https:\/\/img.jiansujichilun.com\/img\/gearbox\/worm%20gearbox\/worm-gearbox13.webp\" alt=\"worm gearbox\" width=\"800\" \/><\/p>\n<h3>P\u00f3dese usar unha caixa de engrenaxes de verme para aplicaci\u00f3ns de alta velocidade?<\/h3>\n<p>As caixas de engrenaxes de verme non se recomendan xeralmente para aplicaci\u00f3ns de alta velocidade debido \u00e1s s\u00faas caracter\u00edsticas de dese\u00f1o inherentes. Velaqu\u00ed por que:<\/p>\n<ul>\n<li><strong>Eficiencia:<\/strong> As caixas de cambios de verme tenden a ter unha eficiencia menor en comparaci\u00f3n con outros tipos de caixas de cambios, o que significa que poden xerar m\u00e1is calor e experimentar unha maior perda de enerx\u00eda a altas velocidades.<\/li>\n<li><strong>Xeraci\u00f3n de calor:<\/strong> O contacto deslizante entre o senf\u00edn e a roda sen fin nunha caixa de engrenaxes sen fin pode provocar unha fricci\u00f3n e unha xeraci\u00f3n de calor significativas, especialmente a altas velocidades. Esta calor pode causar expansi\u00f3n t\u00e9rmica, o que afecta o rendemento e a lonxevidade da caixa de engrenaxes.<\/li>\n<li><strong>Desgaste e ru\u00eddo:<\/strong> As altas velocidades poden exacerbar os problemas de desgaste e ru\u00eddo nas caixas de engrenaxes sen fin. O aumento da fricci\u00f3n e o desgaste poden levar a unha degradaci\u00f3n m\u00e1is r\u00e1pida dos compo\u00f1entes, o que resulta nunha vida \u00fatil reducida e nun aumento das necesidades de mantemento.<\/li>\n<li><strong>Reacci\u00f3n negativa:<\/strong> As caixas de engrenaxes de verme poden ter unha maior folgura en comparaci\u00f3n con outros tipos de caixas de engrenaxes, o que pode afectar \u00e1 precisi\u00f3n e \u00e1 exactitude en aplicaci\u00f3ns de alta velocidade.<\/li>\n<\/ul>\n<p>A\u00ednda que as caixas de engrenaxes sen fin se usan m\u00e1is habitualmente en aplicaci\u00f3ns que requiren un par elevado e velocidades moderadas, poden non ser a mellor opci\u00f3n para escenarios de alta velocidade. Se o funcionamento a alta velocidade \u00e9 un requisito, outros tipos de caixas de engrenaxes, como as helicoidais, as de engrenaxes cil\u00edndricas ou as planetarias, adoitan ser m\u00e1is axeitadas debido \u00e1 s\u00faa maior eficiencia, menor xeraci\u00f3n de calor e menor desgaste a velocidades elevadas.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.jiansujichilun.com\/img\/gearbox\/worm%20gearbox\/worm-gearbox7.webp\" alt=\"worm gearbox\" width=\"800\" \/><\/p>\n<h3>Diagn\u00f3stico e reparaci\u00f3n de fugas de aceite nunha caixa de engrenaxes de verme<\/h3>\n<p>Unha fuga de aceite nunha caixa de cambios de sen fin pode provocar unha reduci\u00f3n da lubricaci\u00f3n, un aumento da fricci\u00f3n e posibles danos nos compo\u00f1entes da caixa de cambios. Aqu\u00ed tes un proceso paso a paso para diagnosticar e arranxar unha fuga de aceite:<\/p>\n<ol>\n<li><strong>Inspeccionar a caixa de cambios:<\/strong> Realice unha inspecci\u00f3n visual da caixa de cambios para identificar a orixe da fuga. Comprobe se hai manchas de aceite, puntos h\u00famidos ou acumulaci\u00f3n de aceite arredor da caixa de cambios.<\/li>\n<li><strong>Comprobar as xuntas e os selos:<\/strong> Inspeccione os selos, as xuntas e as xuntas t\u00f3ricas para detectar calquera signo de desgaste, fendas ou danos. Estes compo\u00f1entes son puntos com\u00fans de fugas.<\/li>\n<li><strong>Apertar os parafusos e os elementos de fixaci\u00f3n:<\/strong> Aseg\u00farate de que todos os parafusos, tornillos e elementos de fixaci\u00f3n estean ben axustados. Os elementos de fixaci\u00f3n soltos poden crear ocos que permiten que escape o aceite.<\/li>\n<li><strong>Substitu\u00edr os selos danados:<\/strong> Se atopa xuntas ou selos danados, substit\u00faaos por outros novos. Use selos que sexan compatibles coas condici\u00f3ns de funcionamento e o lubricante.<\/li>\n<li><strong>Comprobar a ventilaci\u00f3n do respirador:<\/strong> Un respiradoiro obstru\u00eddo ou defectuoso pode causar acumulaci\u00f3n de presi\u00f3n dentro da caixa de cambios, o que pode provocar fugas. Limpe ou substit\u00faa o respiradoiro se \u00e9 necesario.<\/li>\n<li><strong>Examinar os selos do eixe:<\/strong> Comprobe se as xuntas do eixe est\u00e1n desgastadas ou danadas. Se est\u00e1n desgastadas, substit\u00faaas por xuntas do tama\u00f1o e material axeitados.<\/li>\n<li><strong>Usar o lubricante axeitado:<\/strong> Aseg\u00farate de usar o lubricante correcto recomendado para a caixa de cambios. Usar un tipo de lubricante incorrecto pode causar fugas.<\/li>\n<li><strong>Aplicar selantes:<\/strong> Nalg\u00fans casos, aplicar un selante axeitado \u00e1s xuntas e conexi\u00f3ns pode axudar a evitar fugas. Siga as instruci\u00f3ns do fabricante para unha aplicaci\u00f3n correcta.<\/li>\n<li><strong>Monitorizar fugas:<\/strong> Despois de solucionar os problemas, vix\u00ede a caixa de cambios para detectar calquera sinal de fugas continuas. Se a fuga persiste, pode ser necesaria unha investigaci\u00f3n adicional.<\/li>\n<li><strong>Mantemento regular:<\/strong> Implementa un programa de mantemento regular que incl\u00faa a comprobaci\u00f3n de selos, xuntas e outros posibles puntos de fuga. Un mantemento oportuno pode evitar futuros problemas de fugas.<\/li>\n<\/ol>\n<p>Se non est\u00e1s seguro de como diagnosticar ou arranxar unha fuga de aceite nunha caixa de cambios de sen fin, considera consultar cun profesional ou co fabricante da caixa de cambios para garantir unha resoluci\u00f3n axeitada.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.jiansujichilun.com\/img\/gearbox\/worm%20gearbox\/worm-gearbox1.webp\" alt=\"worm gearbox\" width=\"800\" \/><\/p>\n<h3>Que \u00e9 unha caixa de engrenaxes de verme e como funciona?<\/h3>\n<p>Unha caixa de engrenaxes sen fin, tam\u00e9n co\u00f1ecida como redutor de engrenaxes sen fin, \u00e9 un dispositivo mec\u00e1nico que se emprega para transmitir o movemento de rotaci\u00f3n e o par entre eixes non paralelos. Consta dun parafuso sen fin e unha roda sen fin, ambos con dentes helicoidais. O parafuso sen fin semella un cilindro roscado, mentres que a roda sen fin \u00e9 unha engrenaxe con dentes que engranan co parafuso sen fin.<\/p>\n<p>O principio de funcionamento dunha caixa de engrenaxes sen fin implica a interacci\u00f3n entre o parafuso sen fin e a roda sen fin. Cando se xira o parafuso sen fin, os seus dentes helicoidais encaixan cos dentes da roda sen fin. A medida que o parafuso sen fin xira, traduce o movemento de rotaci\u00f3n nun movemento perpendicular, facendo que a roda sen fin xire. Este movemento perpendicular permite que a caixa de engrenaxes sen fin alcance unha alta relaci\u00f3n de reduci\u00f3n de engrenaxes, o que a fai axeitada para aplicaci\u00f3ns que requiren unha reduci\u00f3n de velocidade significativa.<\/p>\n<p>Unha das caracter\u00edsticas clave dunha caixa de engrenaxes de verme \u00e9 a s\u00faa capacidade para proporcionar unha alta relaci\u00f3n de reduci\u00f3n de engrenaxes nun dese\u00f1o compacto. Non obstante, debido \u00e1 natureza deslizante dos dentes engranados, as caixas de engrenaxes de verme poden presentar unha maior fricci\u00f3n e unha menor eficiencia en comparaci\u00f3n con outros tipos de caixas de engrenaxes. Polo tanto, adoitan usarse en aplicaci\u00f3ns onde a eficiencia non \u00e9 a principal preocupaci\u00f3n, pero onde son esenciais unha alta reduci\u00f3n do par e da velocidade, como sistemas de transporte, ascensores, sistemas de direcci\u00f3n de autom\u00f3biles e certa maquinaria industrial.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/gearbox\/gearbox-l1.webp\" alt=\"China high quality New Type of Shaft Mounted Multi-Stage 100% High Transmission Ratio Helical Gear Box   with Great quality \"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/gearbox\/gearbox-l2.webp\" alt=\"China high quality New Type of Shaft Mounted Multi-Stage 100% High Transmission Ratio Helical Gear Box   with Great quality \"><br \/>editor por CX 23\/09\/2023<\/p>","protected":false},"excerpt":{"rendered":"<p>Descrici\u00f3n do produto Descrici\u00f3n do produto Motor de engrenaxes c\u00f3nicas helicoidais Boqiang Drive serie K Caracter\u00edsticas: - Alta eficiencia: 92%-97%; - Estrutura compacta: sa\u00edda de desprazamento pequena, d\u00faas e tres etapas est\u00e1n na mesma caixa. - Alta precisi\u00f3n: a engrenaxe est\u00e1 feita de forxa de aceiro de aliaxe de alta calidade, tratamento de carbonitruraci\u00f3n e endurecemento, proceso de moenda para garantir unha alta precisi\u00f3n e un funcionamento estable. - Alta intercambiabilidade: dese\u00f1o en serie altamente modular, forte versatilidade e intercambiabilidade. Par\u00e1metros t\u00e9cnicos [\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[136,201,139,13,141,212,15,766,208,91,857,858,223,680,683,773,859,240,241,860],"class_list":["post-1567","post","type-post","status-publish","format-standard","hentry","category-gearboxes-worm","tag-box-gear","tag-box-gear-transmission","tag-china-gear-box","tag-gear","tag-gear-box","tag-gear-box-transmission","tag-gear-ratio","tag-gear-shaft","tag-gear-transmission","tag-helical-gear","tag-helical-gear-box","tag-helical-shaft-gear","tag-high-gear","tag-new-shaft","tag-shaft","tag-shaft-gear","tag-shaft-helical-gear","tag-transmission-gear","tag-transmission-gear-box","tag-transmission-shaft"],"_links":{"self":[{"href":"https:\/\/gearboxes-worm.top\/gl\/wp-json\/wp\/v2\/posts\/1567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearboxes-worm.top\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearboxes-worm.top\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearboxes-worm.top\/gl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearboxes-worm.top\/gl\/wp-json\/wp\/v2\/comments?post=1567"}],"version-history":[{"count":0,"href":"https:\/\/gearboxes-worm.top\/gl\/wp-json\/wp\/v2\/posts\/1567\/revisions"}],"wp:attachment":[{"href":"https:\/\/gearboxes-worm.top\/gl\/wp-json\/wp\/v2\/media?parent=1567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearboxes-worm.top\/gl\/wp-json\/wp\/v2\/categories?post=1567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearboxes-worm.top\/gl\/wp-json\/wp\/v2\/tags?post=1567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}