{"id":1511,"date":"2022-12-17T19:04:49","date_gmt":"2022-12-17T19:04:49","guid":{"rendered":"http:\/\/gearboxes-worm.top\/china-small-industrial-worm-wheel-gearbox-inch-size-available-agnee-worm-gearbox\/"},"modified":"2022-12-17T19:04:49","modified_gmt":"2022-12-17T19:04:49","slug":"china-small-industrial-worm-wheel-gearbox-inch-size-available-agnee-worm-gearbox","status":"publish","type":"post","link":"https:\/\/gearboxes-worm.top\/it\/china-small-industrial-worm-wheel-gearbox-inch-size-available-agnee-worm-gearbox\/","title":{"rendered":"Riduttore a vite senza fine industriale di piccole dimensioni in Cina disponibile in pollici"},"content":{"rendered":"<p><h2>Descrizione del prodotto<\/h2>\n<p>\n<p><h3><strong><strong><strong>Serie RV <\/strong><\/strong><strong><strong>Qualit\u00e0<\/strong><\/strong><\/strong><\/h3>\n<ul>\n<li>RV \u2013 Misure:\u2013centocinquanta<\/li>\n<li>Inserisci le scelte: con albero di ingresso, con flangia quadrata, con flangia di ingresso<\/li>\n<li>Energia in ingresso da 0,06 a 11 kW<\/li>\n<li>RV-Dimensioni da 030 a 105 in lega di alluminio pressofuso e oltre 110 in ferro pieno<\/li>\n<li>Rapporti tra 5 e 100<\/li>\n<li>Coppia massima 1550 Nm e masse radiali ammissibili in uscita max 8771 N<\/li>\n<li>Le unit\u00e0 in alluminio sono fornite complete di olio sintetico e consentono posizioni di montaggio comuni, senza la necessit\u00e0 di modificare la quantit\u00e0 di lubrificante<\/li>\n<li>Ruota elicoidale: Rame (KK Cu).\u00a0<\/li>\n<li>Capacit\u00e0 di carico in conformit\u00e0 con: ISO 9001:2015\/GB\/T 19001-2016<\/li>\n<li>Le dimensioni 030 e superiori sono verniciate con colore blu RAL 5571<\/li>\n<li>I riduttori per apparecchiature a vite senza fine sono disponibili con diverse combinazioni: NMRV+NMRV, NMRVpower+NMRV, JWB+NMRV<\/li>\n<li>NMRV, NRV+VS,NMRV+AS,NMRV+VS,NMRV+F<\/li>\n<li>Scelte: braccio di coppia, flangia di uscita, guarnizioni in viton, olio a bassa\/alta temperatura, tappo di riempimento\/scarico\/sfiato\/grado, foro piccolo<\/li>\n<\/ul>\n<p>I modelli semplici possono essere utilizzati per un'ampia gamma di rapporti di riduzione dell'elettricit\u00e0 da 5 a 1000.<br \/>Garanzia: un anno dalla data di fornitura.<\/p>\n<p>\u00a0<\/p>\n<table>\n<colgroup>\n<col \/>\n<col \/>\n<col \/>\n<col \/><\/colgroup>\n<tbody>\n<tr>\n<td>RIDUTTORE A VITE SENZA FINE<\/td>\n<td>\u00a0<\/td>\n<td>\u00a0<\/td>\n<td>\u00a0<\/td>\n<td>\u00a0<\/td>\n<td>\u00a0<\/td>\n<\/tr>\n<tr>\n<td>SERIE SNW\u00a0<\/td>\n<td>\u00a0<\/td>\n<td>\u00a0<\/td>\n<td>\u00a0<\/td>\n<td>\u00a0<\/td>\n<td>Assortimento di velocit\u00e0 di uscita:<\/td>\n<\/tr>\n<tr>\n<td>Ordinare<\/td>\n<td>Variet\u00e0 precedente<\/td>\n<td>Coppia di uscita<\/td>\n<td>Diametro albero di uscita<\/td>\n<td>\u00a0<\/td>\n<td>14 giri\/min-280 giri\/min<\/td>\n<\/tr>\n<tr>\n<td>SNW030\u00a0<\/td>\n<td>RV030\u00a0<\/td>\n<td>21 Nm\u00a0<\/td>\n<td>\u03c614<\/td>\n<td>\u00a0<\/td>\n<td>Energia del motore rilevante:<\/td>\n<\/tr>\n<tr>\n<td>SNW040\u00a0<\/td>\n<td>RV040\u00a0<\/td>\n<td>45N\u00b7m\u00a0<\/td>\n<td>\u03c619<\/td>\n<td>\u00a0<\/td>\n<td>0,06 kW-11 kW<\/td>\n<\/tr>\n<tr>\n<td>SNW050\u00a0<\/td>\n<td>RV050\u00a0<\/td>\n<td>84N.m\u00a0<\/td>\n<td>\u03c625<\/td>\n<td>\u00a0<\/td>\n<td>Inserisci Opzioni1:<\/td>\n<\/tr>\n<tr>\n<td>SNW063\u00a0<\/td>\n<td>RV063\u00a0<\/td>\n<td>160 Nm\u00a0<\/td>\n<td>\u03c625<\/td>\n<td>\u00a0<\/td>\n<td>Con motore CA in linea<\/td>\n<\/tr>\n<tr>\n<td>SNW075\u00a0<\/td>\n<td>RV075\u00a0<\/td>\n<td>230 Nm\u00a0<\/td>\n<td>\u03c628<\/td>\n<td>\u00a0<\/td>\n<td>Inserisci Opzioni2:<\/td>\n<\/tr>\n<tr>\n<td>SNW090\u00a0<\/td>\n<td>RV090\u00a0<\/td>\n<td>410 Nm\u00a0<\/td>\n<td>\u03c635<\/td>\n<td>\u00a0<\/td>\n<td>Con flangia quadrata<\/td>\n<\/tr>\n<tr>\n<td>SNW105\u00a0<\/td>\n<td>RV105\u00a0<\/td>\n<td>630N.m\u00a0<\/td>\n<td>\u03c642<\/td>\n<td>\u00a0<\/td>\n<td>Inserisci Opzioni3:<\/td>\n<\/tr>\n<tr>\n<td>SNW110\u00a0<\/td>\n<td>RV110\u00a0<\/td>\n<td>725 Nm\u00a0<\/td>\n<td>\u03c642<\/td>\n<td>\u00a0<\/td>\n<td>Con albero di ingresso<\/td>\n<\/tr>\n<tr>\n<td>SNW130\u00a0<\/td>\n<td>RV130\u00a0<\/td>\n<td>1050N.m\u00a0<\/td>\n<td>\u03c645<\/td>\n<td>\u00a0<\/td>\n<td>Opzioni di input4:<\/td>\n<\/tr>\n<tr>\n<td>SNW150\u00a0<\/td>\n<td>RV150\u00a0<\/td>\n<td>1550N.m\u00a0<\/td>\n<td>\u03c650<\/td>\n<td>\u00a0<\/td>\n<td>Con flangia di ingresso<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><h3><strong><strong><strong>Starshine Drive<\/strong><\/strong><\/strong><\/h3>\n<p>ZheJiang CZPT Co.,Ltd, il predecessore era un'impresa navale statale CZPT, fondata nel 1965. CZPT \u00e8 specializzata nella soluzione completa di trasmissione di energia per le industrie di produzione di ingranaggi di alta gamma, in base all'obiettivo di \"prodotto di sistema, design del software e servizio qualificato\".<br \/>Starshine vanta una solida competenza tecnologica, con oltre 350 dipendenti, tra cui oltre trenta ingegneri professionisti e trenta ispettori di alta qualit\u00e0, che coprono una superficie di 80.000 metri quadrati e dispongono di dispositivi di elaborazione e apparecchiature di collaudo di alta qualit\u00e0. Vantiamo solide basi per lo sviluppo e la fornitura di servizi di riduttori e variatori di velocit\u00e0 di fascia alta, grazie al centro studi provinciale di tecnologie ingegneristiche, al laboratorio di riduttori di velocit\u00e0 per apparecchiature e alle fondamenta dell'attuale R&amp;S.<\/p>\n<p><strong><strong>Il nostro gruppo<\/strong><\/strong><\/p>\n<p><strong><strong>Gestione della qualit\u00e0<\/strong><\/strong><br \/>Alta qualit\u00e0: insistere sul miglioramento, puntare all'eccellenza Con lo sviluppo del settore della produzione di attrezzature, il cliente non \u00e8 mai soddisfatto della qualit\u00e0 attuale dei nostri prodotti, al contrario, creiamo il valore della qualit\u00e0.<br \/>Politica della qualit\u00e0: migliorare il livello generale nel campo della trasmissione di potenza\u00a0\u00a0<br \/>Visione della qualit\u00e0: miglioramento continuo, ricerca dell'eccellenza<br \/>Filosofia della qualit\u00e0: la qualit\u00e0 crea valore<\/p>\n<p>3. Controllo qualit\u00e0 in entrata<br \/>Stabilire il livello accettabile di qualit\u00e0 accettabile (AQL) del controllo dei materiali in entrata, fornire il materiale per l'intera ispezione, campionamento e immunit\u00e0. All'accettazione di prodotti qualificati per lo stoccaggio, la merce scadente deve essere restituita, controllata, rilavorata e sottoposta a ispezione. Responsabile del monitoraggio dei difetti, monitorare il fornitore e adottare misure correttive.<br \/>\u00a0per prevenire la recidiva.<\/p>\n<p>quattro. Controllo di qualit\u00e0 del processo<br \/>Il sito di produzione del primo esame, ispezione e ispezione finale, campionamento secondo i requisiti di alcuni progetti, valutazione della tendenza al cambiamento della qualit\u00e0<br \/>\u00a0ha rilevato fenomeni anomali nella produzione e supervisionato il reparto di produzione per migliorare ed eliminare il fenomeno o lo stato anomalo.<\/p>\n<p>5. FQC (QC finale)<br \/>Dopo che il reparto di produzione avr\u00e0 completato il prodotto, mettersi nella posizione del cliente per la verifica della qualit\u00e0 del prodotto finito, al fine di garantire la qualit\u00e0 di\u00a0<br \/>aspettative e necessit\u00e0 dei clienti.<\/p>\n<p>6. OQC (QC in uscita)<br \/>Dopo l'ispezione del campione del prodotto per determinare la qualificazione, consentendo lo stoccaggio, ma quando il prodotto finito dal magazzino prima della consegna formale della merce, c'\u00e8 un controllo, questo \u00e8 chiamato l'ispezione della spedizione. Controllare il contenuto: nello stoccaggio del magazzino e lo stato di trasferimento per confermare, mentre si conferma la consegna del prodotto<br \/>\u00a0\u00e8 un'ispezione del prodotto per determinare i prodotti qualificati.<\/p>\n<p><strong><strong>Imballaggio<\/strong><\/strong><\/p>\n<p><strong><strong>Fornitura<\/strong><\/strong><\/p>\n<p>\n<p>\n<p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr style=\"align-items: baseline;flex-wrap: wrap\" class=\"only-one-priceNum-tr\">\n<td style=\"padding: 0 !important\">\n                                        <span style=\"font-size: 20px;font-family: Roboto, Roboto-Bold;font-weight: 700;text-align: left;color: #e64545;padding-left: 0 !important\">Stati Uniti $22.5-360.23<\/span><br \/>\n                                        <span style=\"font-size: 14px;font-family: Roboto, Roboto-Regular;font-weight: 400;color: #888888;margin-right: 10px\">\/ Pezzo<\/span><br \/>\n                                        <span style=\"color: #e6ecf2\">|<\/span>\n                                    <\/td>\n<td class=\"sa-only-property-price only-one-priceNum-price\">\n                                        <span>1 pezzo<\/span><br \/>\n                                        <span style=\"color: #888888\"><br \/>\n                                            (Ordine minimo)<br \/>\n                                        <\/span>\n                                    <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Applicazione:<\/th>\n<td>Motore, Macchinari, Macchine Agricole<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Funzione:<\/th>\n<td>Riduzione della velocit\u00e0<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Disposizione:<\/th>\n<td>Angolo<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Durezza:<\/th>\n<td>Superficie del dente indurita<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Installazione:<\/th>\n<td>Tipo orizzontale<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Fare un passo:<\/th>\n<td>Passo singolo<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Personalizzazione:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                            Disponibile\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                        <a target=\"_blank\" rel=\"nofollow noopener\" href=\" \"><br \/>\n                                        <i class=\"ob-icon icon-fill\"><\/i>Richiesta personalizzata<br \/>\n                                        <\/a>\n                                    <\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<colgroup>\n<col \/>\n<col \/>\n<col \/>\n<col \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"height:17.25pt\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>RIDUTTORE A VITE SENZA FINE<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>SERIE SNW&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Gamma di velocit\u00e0 di uscita:<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Tipo<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Vecchio tipo<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Coppia di uscita<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Diametro albero di uscita<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>14 giri\/min-280 giri\/min<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW030&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV030&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>21 Nm&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c614<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Potenza motore applicabile:<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW040&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV040&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>45N\u00b7m&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c619<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>0,06 kW-11 kW<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW050&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV050&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>84N.m&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c625<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Opzioni di input1:<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW063&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV063&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>160 Nm&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c625<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Con motore CA in linea<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW075&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV075&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>230 Nm&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c628<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Opzioni di input 2:<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW090&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV090&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>410 Nm&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c635<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Con flangia quadrata<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW105&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV105&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>630N.m&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c642<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Opzioni di input 3:<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW110&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV110&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>725 Nm&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c642<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Con albero di ingresso<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW130&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV130&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>1050N.m&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c645<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Opzioni di input4:<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW150&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV150&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>1550N.m&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c650<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Con flangia di ingresso<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr style=\"align-items: baseline;flex-wrap: wrap\" class=\"only-one-priceNum-tr\">\n<td style=\"padding: 0 !important\">\n                                        <span style=\"font-size: 20px;font-family: Roboto, Roboto-Bold;font-weight: 700;text-align: left;color: #e64545;padding-left: 0 !important\">Stati Uniti $22.5-360.23<\/span><br \/>\n                                        <span style=\"font-size: 14px;font-family: Roboto, Roboto-Regular;font-weight: 400;color: #888888;margin-right: 10px\">\/ Pezzo<\/span><br \/>\n                                        <span style=\"color: #e6ecf2\">|<\/span>\n                                    <\/td>\n<td class=\"sa-only-property-price only-one-priceNum-price\">\n                                        <span>1 pezzo<\/span><br \/>\n                                        <span style=\"color: #888888\"><br \/>\n                                            (Ordine minimo)<br \/>\n                                        <\/span>\n                                    <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Applicazione:<\/th>\n<td>Motore, Macchinari, Macchine Agricole<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Funzione:<\/th>\n<td>Riduzione della velocit\u00e0<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Disposizione:<\/th>\n<td>Angolo<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Durezza:<\/th>\n<td>Superficie del dente indurita<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Installazione:<\/th>\n<td>Tipo orizzontale<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Fare un passo:<\/th>\n<td>Passo singolo<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Personalizzazione:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                            Disponibile\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                        <a target=\"_blank\" rel=\"nofollow noopener\" href=\" \"><br \/>\n                                        <i class=\"ob-icon icon-fill\"><\/i>Richiesta personalizzata<br \/>\n                                        <\/a>\n                                    <\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<colgroup>\n<col \/>\n<col \/>\n<col \/>\n<col \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"height:17.25pt\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>RIDUTTORE A VITE SENZA FINE<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt\"><span style=\"font-size:14px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>SERIE SNW&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Gamma di velocit\u00e0 di uscita:<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Tipo<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Vecchio tipo<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Coppia di uscita<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Diametro albero di uscita<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>14 giri\/min-280 giri\/min<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW030&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV030&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>21 Nm&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c614<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Potenza motore applicabile:<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW040&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV040&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>45N\u00b7m&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c619<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>0,06 kW-11 kW<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW050&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV050&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>84N.m&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c625<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Opzioni di input1:<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW063&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV063&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>160 Nm&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c625<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Con motore CA in linea<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW075&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV075&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>230 Nm&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c628<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Opzioni di input 2:<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW090&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV090&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>410 Nm&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c635<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Con flangia quadrata<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW105&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV105&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>630N.m&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c642<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Opzioni di input 3:<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW110&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV110&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>725 Nm&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c642<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Con albero di ingresso<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW130&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV130&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>1050N.m&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c645<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Opzioni di input4:<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>SNW150&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"color:#000000\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span><span><span>RV150&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>1550N.m&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>\u03c650<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<td style=\"height:17.25pt\">&nbsp;<\/td>\n<td style=\"height:17.25pt;text-align:center\"><span style=\"font-size:12px\"><span style=\"font-family:Arial, Helvetica, sans-serif\"><span style=\"color:#000000\"><span><span><span>Con flangia di ingresso<\/span><\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><h2>Che cos'\u00e8 un riduttore a vite senza fine?<\/h2>\n<p>Il riduttore a vite senza fine viene utilizzato per variare la velocit\u00e0 di uscita del dispositivo meccanico. \u00c8 costituito da ingranaggi a vite senza fine e ingranaggi elicoidali montati sul lato di ingresso dell'apparecchiatura. In alcuni casi, questo sistema di riduzione pu\u00f2 essere multistadio, consentendo velocit\u00e0 di uscita estremamente basse. Presenta i vantaggi di un basso consumo energetico e di basse vibrazioni.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/T_worm_reducer_3.webp\" alt=\"worm reducer\" width=\"800\" \/>Riduttore a vite senza fine ad albero cavo<\/h2>\n<p>Il riduttore a vite senza fine \u00e8 un dispositivo efficace per ridurre la velocit\u00e0 delle apparecchiature meccaniche. L'utilizzo di acciaio temprato o metalli non ferrosi per la vite senza fine ne aumenta l'efficienza. Le viti senza fine in acciaio temprato generano pi\u00f9 calore rispetto a quelle in acciaio dolce. La diversa dilatazione termica provoca la formazione di spazi tra le superfici di contatto. Nonostante i numerosi vantaggi, i riduttori a vite senza fine sono soggetti a perdite d'olio, che possono rappresentare un problema per diversi motivi.<br \/>I riduttori a vite senza fine ad albero cavo sono disponibili con diversi rapporti di trasmissione e sono compatibili con molti tipi di motore. Alcuni sono disponibili in configurazioni a doppio asse e ad asse singolo e possono essere montati orizzontalmente o verticalmente. Sono disponibili anche con rapporti intermedi e con trasmissioni a quattro e cinque velocit\u00e0. Possono anche essere collegati ad alberi di uscita aggiuntivi.<br \/>Un altro tipo di riduttore a vite senza fine \u00e8 il riduttore multistadio. Questo riduttore ha pi\u00f9 stadi, consentendo di ridurre la velocit\u00e0 a velocit\u00e0 di uscita estremamente basse. Oltre all'ampio rapporto di trasmissione, il riduttore multistadio offre bassa rumorosit\u00e0, basse vibrazioni e bassi consumi energetici.<br \/>I riduttori a vite senza fine offrono soluzioni salvaspazio e una coppia elevata. Agknx Gearbox offre riduttori a vite senza fine che risolvono i comuni problemi di decelerazione. L'azienda ha inoltre ampliato la sua gamma di prodotti al mercato del bagno. Rispetto ai riduttori standard, i riduttori a vite senza fine offrono un prezzo inferiore e una migliore coppia in uscita.<br \/>Ingranaggio a vite senza fine Agknx<\/h2>\n<p>Il riduttore a vite senza fine tipo Agknx presenta un contatto lineare multi-dente ed \u00e8 ampiamente utilizzato nei macchinari pesanti. Questi ingranaggi sono caratterizzati da un'elevata capacit\u00e0 di carico, ma sono molto sensibili a disallineamenti ed errori di fabbricazione. Tuttavia, utilizzando il contatto puntiforme, questi ingranaggi possono essere resi pi\u00f9 affidabili e in grado di sopportare carichi pi\u00f9 elevati.<br \/>Un altro importante vantaggio della vite senza fine Agknx \u00e8 la sua elevata capacit\u00e0 di carico. Il design del profilo dei denti degli ingranaggi presenta un elevato rapporto di scorrimento relativo, che migliora l'efficienza e la capacit\u00e0 di carico. Inoltre, l'ampio angolo tra la direzione di scorrimento e la linea di contatto garantisce un basso coefficiente di attrito. La vite senza fine Agknx \u00e8 inoltre realizzata in acciaio cementato di alta qualit\u00e0 e fusioni in bronzo fosforoso per una durata eccezionale. Inoltre, il profilo dei denti \u00e8 estremamente preciso, il funzionamento \u00e8 silenzioso e le variazioni di velocit\u00e0 sono ridotte.<br \/>I riduttori a vite senza fine Agknx sono progettati per funzionare fino a dieci ore al giorno con un carico uniforme. Il design di questo riduttore a vite senza fine nasce dalla vasta esperienza di Sumitomo Heavy Industries nel settore dei riduttori a ingranaggi. La superficie liscia e il profilo preciso dei denti degli ingranaggi garantiscono che gli ingranaggi possano sopportare carichi elevati senza danneggiare il film lubrificante. Inoltre, gli alberi a vite senza fine Agknx sono appositamente progettati per garantire la giusta rigidit\u00e0.<br \/>I riduttori a vite senza fine Agknx sono progettati per massimizzare la capacit\u00e0 di carico riducendo al minimo il consumo energetico. I denti completamente ingranati riducono la pressione superficiale sui denti della vite senza fine e aumentano la capacit\u00e0 di carico.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/C_worm_reducer_3.webp\" alt=\"worm reducer\" width=\"800\" \/>Ingranaggio a vite senza fine a doppia gola<\/h2>\n<p>Ci sono alcuni aspetti da considerare quando si sceglie una vite senza fine a doppia gola. Innanzitutto, il diametro del cerchio di base deve corrispondere al passo del cerchio dell'ingranaggio pi\u00f9 grande. Questa misurazione viene solitamente effettuata misurando la distanza tra denti adiacenti. In alternativa, \u00e8 possibile utilizzare il modulo normale della vite senza fine. Si tratta del valore inserito nella finestra di dialogo del modulo della vite senza fine. Inoltre, il passo assiale della vite senza fine deve essere uguale al diametro primitivo del passo circolare.<br \/>Gli ingranaggi a vite senza fine a doppia gola sono una scelta eccellente per applicazioni pesanti e gravose. Il design di questo ingranaggio a vite senza fine \u00e8 ideale per applicazioni gravose in quanto garantisce una connessione pi\u00f9 salda tra la vite senza fine e l'ingranaggio. \u00c8 inoltre pi\u00f9 compatto rispetto ad altri tipi di ingranaggi ed \u00e8 paragonabile a una vite senza fine a passo fine.<br \/>L'efficienza di una vite senza fine a doppia gola dipende dal materiale dell'ingranaggio e della vite senza fine. In genere, gli ingranaggi sono realizzati in acciaio cementato, mentre le viti senza fine sono realizzate in bronzo o ghisa. In alcuni casi, \u00e8 possibile utilizzare una combinazione di ghisa e bronzo.<br \/>La flessione dell'albero della vite senza fine \u00e8 influenzata anche dai parametri dei denti. L'altezza del dente, l'angolo di pressione e i fattori dimensionali influenzano la flessione dell'albero della vite senza fine. Inoltre, il numero di filettature della vite senza fine \u00e8 un altro parametro importante che influenza la flessione dell'albero della vite senza fine.<br \/>Le viti senza fine a doppia gola sono comunemente utilizzate in applicazioni industriali in cui \u00e8 richiesta un'elevata riduzione della coppia motrice. La vite senza fine presenta una struttura dentata interna concava che pu\u00f2 essere regolata per ottenere diversi rapporti. Le viti senza fine e i gruppi vite senza fine devono essere montati correttamente sui rispettivi alberi per evitare fenomeni di inversione di marcia.<br \/>Ingranaggio a vite senza fine in ottone<\/h2>\n<p>Il principio di funzionamento di base del riduttore a vite senza fine in ottone \u00e8 lo stesso di quello del riduttore a vite senza fine tradizionale. Il suo passo assiale deve essere uguale al passo circonferenziale dell'ingranaggio pi\u00f9 grande. Il design a singolo filetto avanza di un dente per giro, mentre il design a doppio filetto avanza di due denti. Le filettature della vite senza fine sono sinistrorse o destrorse. Il passo di una vite senza fine \u00e8 la distanza percorsa da un punto sulla filettatura della vite senza fine in un giro. L'angolo di passo \u00e8 l'angolo tangente al passo del cilindro e all'asse della vite senza fine.<br \/>I riduttori a vite senza fine a doppio filetto sono ideali per carichi pesanti. Garantiscono la connessione pi\u00f9 salda tra vite senza fine e ingranaggio. Il montaggio della vite senza fine richiede un montaggio preciso. Il metodo di installazione con cava per chiavetta prevede la foratura di un taglio quadrato nel foro dell'ingranaggio. Questo impedisce alla vite senza fine di ruotare sull'albero e favorisce la trasmissione della coppia. Quindi, utilizzare la vite di fissaggio per fissare l'ingranaggio al mozzo.<br \/>L'ampio serbatoio del carburante aiuta a mantenere pulita la vite senza fine e riduce il calore. Garantisce inoltre la lubrificazione per una maggiore durata. I riduttori a vite senza fine con serbatoio dell'olio garantiscono un ambiente lubrificato e superfici a basso attrito. Inoltre, offrono flessibilit\u00e0 di installazione in pi\u00f9 posizioni. L'alloggiamento \u00e8 fresato a croce per un allineamento preciso. \u00c8 inoltre dotato di deflettori interni per una ventilazione senza perdite.<br \/>I riduttori a vite senza fine della serie I260 sono realizzati in un unico pezzo di ghisa con alberi di uscita pieni o cavi e cuscinetti a rulli conici. Questo riduttore \u00e8 progettato per applicazioni di bassa e media potenza. Rappresenta un'opzione conveniente, con un costo iniziale ridotto, un rapporto di trasmissione elevato e una coppia elevata in un formato compatto. Inoltre, \u00e8 pi\u00f9 resistente agli urti rispetto ad altri riduttori.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/B_worm_reducer_3.webp\" alt=\"worm reducer\" width=\"800\" \/>Ingranaggio a vite senza fine in ottone<\/h2>\n<p>Il riduttore a vite senza fine in ottone \u00e8 un riduttore. Questo tipo di riduttore pu\u00f2 fornire un'elevata riduzione in un piccolo ingombro. Questo tipo di riduttore ha anche la capacit\u00e0 di generare una coppia elevata. Tuttavia, \u00e8 importante comprendere che questo riduttore presenta limitazioni termiche, che ne riducono l'efficienza. La scelta del lubrificante per questo riduttore \u00e8 molto flessibile. Tuttavia, essendo un metallo giallo, \u00e8 importante ricordare che il lubrificante deve essere non reattivo.<br \/>Gli ingranaggi a vite senza fine sono utilizzati in numerose applicazioni industriali e di consumo e presentano elevati rapporti di riduzione. Questi ingranaggi sono prodotti in varie configurazioni e dimensioni. Gli ingranaggi a vite senza fine sono simili agli ingranaggi cilindrici, ma hanno alberi non paralleli. Gli ingranaggi a vite senza fine sono adatti anche per applicazioni che richiedono basse velocit\u00e0 di uscita ma coppia elevata.<br \/>Gli ingranaggi a vite senza fine presentano alcuni vantaggi rispetto ad altri ingranaggi. Innanzitutto, a differenza degli ingranaggi standard, la vite senza fine ruota con un movimento simile a quello di una vite senza fine. Questo meccanismo impedisce il movimento inverso. Questo perch\u00e9 l'angolo di inclinazione dell'ingranaggio a vite senza fine \u00e8 ridotto. Inoltre, le viti senza fine si autobloccano, contribuendo a impedire il movimento inverso. Tuttavia, questo meccanismo non \u00e8 del tutto affidabile. Gli ingranaggi a vite senza fine si trovano negli elevatori, nei mulinelli da pesca, nelle ruote dentate e nei servosterzi per automobili.<br \/>Un altro vantaggio delle ruote dentate a vite senza fine \u00e8 la loro facilit\u00e0 di fabbricazione. La logica alla base di questa progettazione \u00e8 quella di avere due assi reciprocamente perpendicolari. Successivamente, vengono aggiunte due o pi\u00f9 filettature alla ruota dentata a vite senza fine. La tangente comune tra questi due alberi interseca la linea primitiva dell'albero della ruota dentata a vite senza fine. Questa \u00e8 la base della velocit\u00e0 di trasferimento.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/Worm_Reducer_l1.webp\" alt=\"China Small Industrial Worm Wheel Gearbox Inch Size Available     agnee worm gearbox\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/Worm_Reducer_l2.webp\" alt=\"China Small Industrial Worm Wheel Gearbox Inch Size Available     agnee worm gearbox\"><br \/>curato da czh 2022-12-18<\/p>","protected":false},"excerpt":{"rendered":"<p>Product Description RV series Qualities RV &#8211; Measurements:&#8211;one hundred fifty Enter Choices: with enter shaft, With Square flange,With Input Flange Input Energy .06 to\u00a011\u00a0kW RV-Size from 030\u00a0to\u00a0105\u00a0in die-cast aluminium alloy budy and in excess of 110 in solid iron Ratios in between 5 and 100 Max torque 1550 N.m and admissible output radial masses max [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[12,20,21,194,165,287,46,7,500],"class_list":["post-1511","post","type-post","status-publish","format-standard","hentry","category-gearboxes-worm","tag-china-gearbox","tag-gearbox","tag-gearbox-china","tag-industrial-gearbox","tag-small-gearbox","tag-small-worm-gearbox","tag-worm-gearbox","tag-worm-wheel","tag-worm-wheel-gearbox"],"_links":{"self":[{"href":"https:\/\/gearboxes-worm.top\/it\/wp-json\/wp\/v2\/posts\/1511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearboxes-worm.top\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearboxes-worm.top\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearboxes-worm.top\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearboxes-worm.top\/it\/wp-json\/wp\/v2\/comments?post=1511"}],"version-history":[{"count":0,"href":"https:\/\/gearboxes-worm.top\/it\/wp-json\/wp\/v2\/posts\/1511\/revisions"}],"wp:attachment":[{"href":"https:\/\/gearboxes-worm.top\/it\/wp-json\/wp\/v2\/media?parent=1511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearboxes-worm.top\/it\/wp-json\/wp\/v2\/categories?post=1511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearboxes-worm.top\/it\/wp-json\/wp\/v2\/tags?post=1511"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}