{"id":1541,"date":"2023-06-19T09:32:46","date_gmt":"2023-06-19T09:32:46","guid":{"rendered":"https:\/\/gearboxes-worm.top\/china-2022-new-45-steel-electronic-steering-rack-worm-shaft-splined-high-precision-cnc-turned-shaft-manufacturer-worm-gearbox-back-drive\/"},"modified":"2023-06-19T09:32:46","modified_gmt":"2023-06-19T09:32:46","slug":"china-2022-new-45-steel-electronic-steering-rack-worm-shaft-splined-high-precision-cnc-turned-shaft-manufacturer-worm-gearbox-back-drive","status":"publish","type":"post","link":"https:\/\/gearboxes-worm.top\/it\/china-2022-new-45-steel-electronic-steering-rack-worm-shaft-splined-high-precision-cnc-turned-shaft-manufacturer-worm-gearbox-back-drive\/","title":{"rendered":"Cina 2022 Nuovo 45# Acciaio Cremagliera Sterzo Elettronica Albero a Vite Senza Fine Scanalato Alta Precisione CNC Tornito Produttore Riduttore a Vite Senza Fine Trasmissione Posteriore"},"content":{"rendered":"<p>Situazione: Nuova<br \/>Garanzia: 3 mesi<br \/>Settori rilevanti: sviluppo di negozi di contenuti, impianti di produzione, negozi di riparazione di macchinari, unit\u00e0 di produzione di alimenti e bevande, aziende agricole, rivenditori di stampa, lavori di costruzione, energia e attivit\u00e0 minerarie<br \/>Grassi (KG): uno<br \/>Punto vendita: nessuno<br \/>Ispezione video in uscita online: non disponibile<br \/>Macchinari Dai un'occhiata al rapporto: Non offerto<br \/>Pubblicit\u00e0 e marketing Tipo: Nuovo Articolo 2571<br \/>Garanzia dei componenti principali: 6 mesi<br \/>Componenti principali: PLC, motore, cuscinetto, riduttore, motore, nave di forza, attrezzatura, pompa<br \/>Struttura: flessibile<br \/>Sostanza: Ottone Metallo Metallo inossidabile Alluminio<br \/>Rivestimenti: Ossido nero<br \/>Capacit\u00e0 di coppia: personalizzata<br \/>Variet\u00e0 di modelli: OEM<br \/>Variet\u00e0 di lavorazione: tornitura NC, rettifica<br \/>Certificazione: ISO9001<br \/>tolleranza: .001 o Custome<br \/>Porto: ZheJiang\/HangZhou<\/p>\n<p>Panoramica degli articoli<table border=\"1\"><tr><td>Misurare<br \/><\/td><td>Richiesta del cliente<br \/><\/td><\/tr><tr><td>Quantit\u00e0 minima<br \/><\/td><td>Si basa sul disegno<br \/><\/td><\/tr><tr><td>Modello<br \/><\/td><td>BRM<br \/><\/td><\/tr><tr><td>Campione<br \/><\/td><td>Disponibile<br \/><\/td><\/tr><tr><td>Attributo<br \/><\/td><td>Grande qualit\u00e0 e precisione sostanziale<br \/><\/td><\/tr><tr><td>Garanzia<br \/><\/td><td>3 mesi<br \/><\/td><\/tr><tr><td>Affare<br \/><\/td><td>Sacchetto\/cartone PP o OEM<br \/><\/td><\/tr><tr><td>Diametro<br \/><\/td><td>Secondo le esigenze del cliente<br \/><\/td><\/tr><tr><td>Tolleranza<br \/><\/td><td>.001mm o personalizzato<br \/><\/td><\/tr><tr><td>OEM e ODM<br \/><\/td><td>Riconosciuto<br \/><\/td><\/tr><tr><td>Metodo principale<br \/><\/td><td>tornitura CNC<br \/><\/td><\/tr><tr><td>Area di origine<br \/><\/td><td>ZheJiang, Cina<br \/><\/td><\/tr><tr><td>Contenuto principale<br \/><\/td><td>Ottone, Metallo, Acciaio inossidabile, Alluminio<br \/><\/td><\/tr><tr><td>Tipo di articolo<br \/><\/td><td>Parti di alberi, alberi in metallo inossidabile, alberi prolungati, alberi di uscita, alberi motore e molti altri.<br \/><\/td><\/tr><\/table>OEM e ODM <br \/><table border=\"1\"><tr><td colspan=\"2\">Benvenuti agli ordini OEM\/ODM!<br \/><\/td><\/tr><tr><td><strong>Contenuto disponibile<\/strong><br \/><\/td><td>uno, Ferro: 1213, 12L14,1215,ect2, Metallo:C45(K1045), C46(K1046), Giunto produttore DL tipo giunto in gomma CG-M5505 giunto pneumatico per pompa motore collegare estremamente adattabile C20,ect3, Metallo inossidabile: SS201, SS303, SS304, SS316, SS416, SS4204, Ottone:C36000 (C26800), C37700,(HPb59),C38500(HPb58),C27200(CuZn37),C28000(CuZn40)5, Bronzo: C51000, C52100, C54400, ecc6, Alluminio: Al6061, Al6063, Al7571, Titanio8, Plastica: PP (Polipropilene), PC (Policarbonato), PTFE (Teflon), POM, Nylon, ecc., OEM in base alla tua richiesta<br \/><\/td><\/tr><tr><td><strong>Rimedio per il pavimento<\/strong><br \/><\/td><td>Anodizzato in vari colori, Mini abbellimento e spazzolatura, Galvanotecnica (zincato, nichelato, cromato),<br \/>Produttori di giunti e rivestimenti energetici, giunti per pneumatici come alternativa al rivestimento PVD Martin, marcatura laser e monitoraggio della seta, stampa, saldatura, tempra e cos\u00ec via.<br \/><\/td><\/tr><tr><td><strong>Metodo ottenibile<\/strong><br \/><\/td><td>Stampaggio di precisione: punzonatura, foratura, tranciatura, tranciatura, piegatura, imbutitura, ricottura Lavorazione CNC: tornitura automatica, fresatura, rettifica, maschiatura, foratura, fusione, taglio laser, stampaggio a iniezione<br \/><\/td><\/tr><tr><td><strong>Tempo di guida (approssimativo)<\/strong><br \/><\/td><td>Campioni: 7-10 giorni lavorativi, Merci sfuse: 12-15 giorni lavorativi<br \/>(Si prega di verificare l'orario preciso e diretto della creazione effettiva)<br \/><\/td><\/tr><\/table><strong>Capacit\u00e0 di lavorazione <\/strong><br \/><table border=\"1\"><tr><td>Max OD.<br \/><\/td><td>150 millimetri<br \/><\/td><\/tr><tr><td>Min OD.<br \/><\/td><td>0,6 mm<br \/><\/td><\/tr><tr><td>Lunghezza massima<br \/><\/td><td>1000 millimetri<br \/><\/td><\/tr><tr><td>Tolleranza OD<br \/><\/td><td>Rettifica senza centri 0,001 mm \/ Rettifica cilindrica 0,005 mm<br \/><\/td><\/tr><tr><td>Tolleranza di rotondit\u00e0<br \/><\/td><td>Rettifica senza centri .0005mm \/ Rettifica cilindrica .003mm<br \/><\/td><\/tr><tr><td>Tolleranza di funzionamento<br \/><\/td><td>Rettifica senza centri 0,001 mm \/ Rettifica cilindrica 0,01 mm<br \/><\/td><\/tr><tr><td>Tolleranza di rugosit\u00e0<br \/><\/td><td>Rettifica senza centri Rz0.4 \/ Rettifica cilindrica Rz2.<br \/><\/td><\/tr><\/table>Visualizzazione dell'articolo <\/p>\n<p><strong>Profilo aziendale <\/strong><br \/>Fin dalla nostra fondazione nel 2006, il team BRM&amp;ATM si \u00e8 concentrato principalmente sulla produzione di alberi di grande precisione ed elementi hardware per l'esportazione. Molte grazie a un lungo periodo di costante espansione e accumulo. Collaboriamo con i leader del settore.<\/p>\n<p>BRM&amp;ATM ha importato da Germania, Giappone e Svizzera apparecchiature di collaudo e macchine di generazione ad alta precisione. I nostri prodotti vengono ampiamente utilizzati nei settori automobilistico, degli elettrodomestici, dell'interazione, delle apparecchiature e della strumentazione, aerospaziale e in altri settori. Questi prodotti sono forniti a numerose aziende di fama internazionale, come Valeo, Siemens, Brose, MAGNA, Bosch, MTD, Karcher, Nidec, Mitsuba, SONY, B&amp;D, Liteon, Canon, HP e molti altri.<\/p>\n<p>Abbiamo ottenuto e curato successivamente le nostre certificazioni in <strong>ISO9001, QS9000:1998, ISO\/TS16949:2002 e ISO14001:2004<\/strong>Inoltre, siamo da lungo tempo partner inesperti di Sony.<br \/>Abbiamo aperto una fabbrica che ha una superficie di oltre 30.000 CZPT quadrati e impiega pi\u00f9 di 1.000 persone. Ogni anno vengono prodotti pi\u00f9 di 2 miliardi di alberi.<\/p>\n<p><strong>Impostazione dell'impianto di produzione<\/strong> <\/p>\n<p><strong>Ingranaggi CNC<\/strong> <\/p>\n<p><strong>Ispezione e laboratorio <\/strong><strong>Prodotti<\/strong> <\/p>\n<p><strong>Strumenti di produzione Quantit\u00e0 <\/strong><br \/><table border=\"1\"><tr><td><strong>Prodotti in lavorazione<\/strong><br \/><\/td><td><strong>La variet\u00e0 di<\/strong><br \/><\/td><\/tr><tr><td>tornio CNC<br \/><\/td><td>233<br \/><\/td><\/tr><tr><td>Tornio automatico<br \/><\/td><td>sei<br \/><\/td><\/tr><tr><td>Strumento automatico automatico<br \/><\/td><td>34<br \/><\/td><\/tr><tr><td>Attrezzatura per rettifica cilindrica<\/td><td>dodici<br \/><\/td><\/tr><tr><td>Rettifica senza centri<br \/><\/td><td>116<br \/><\/td><\/tr><tr><td>Fresatrice<br \/><\/td><td>5<br \/><\/td><\/tr><tr><td>Attrezzatura per la dentatura<br \/><\/td><td>11<br \/><\/td><\/tr><tr><td>Dispositivo di dentatura orizzontale CNC<br \/><\/td><td>1<br \/><\/td><\/tr><tr><td>Macchina rullatrice per filettature<\/td><td>26<\/td><\/tr><tr><td>Forno a nastro a maglie<\/td><td>due<\/td><\/tr><tr><td>Prodotti ad alta frequenza<\/td><td>quattro<\/td><\/tr><tr><td>Attrezzatura per nitrurazione<\/td><td>sei<\/td><\/tr><tr><td>Prodotti per la pulizia<br \/><\/td><td>sei<\/td><\/tr><\/table> <\/p>\n<p>Strumenti di ispezione <strong>Quantit\u00e0 <\/strong><br \/><table border=\"1\"><tr><td><strong>Il titolo dello strumento<\/strong><br \/><\/td><td><strong>Il numero di<\/strong><br \/><\/td><\/tr><tr><td>Il proiettore<br \/><\/td><td>29<br \/><\/td><\/tr><tr><td>Microscopio elettronico per utensili<br \/><\/td><td>1<\/td><\/tr><tr><td>Strumento di rotondit\u00e0<br \/><\/td><td>5<\/td><\/tr><tr><td>Rugosimetro<br \/><\/td><td>cinque<\/td><\/tr><tr><td>Strumento di misura a tre coordinate<br \/><\/td><td>1<\/td><\/tr><tr><td>Rilevatore di difetti ad ultrasuoni<br \/><\/td><td>uno<\/td><\/tr><tr><td>Durometro<br \/><\/td><td>11<\/td><\/tr><tr><td>Misuratore di spessore del rivestimento fluorescente<br \/><\/td><td>uno<\/td><\/tr><tr><td>Macchina per prove di nebbia salina<br \/><\/td><td>1<\/td><\/tr><tr><td>Strumento di misura del diametro esterno<br \/><\/td><td>1<\/td><\/tr><tr><td>Microscopio metallografico<br \/><\/td><td>uno<\/td><\/tr><tr><td>Apparecchiatura di collegamento delle attrezzature<br \/><\/td><td>1<\/td><\/tr><tr><td>Strumento di misura degli ingranaggi<br \/><\/td><td>uno<\/td><\/tr><tr><td>Rilevatore di battito dell'attrezzatura<br \/><\/td><td>1<\/td><\/tr><tr><td>Strumento di allineamento<br \/><\/td><td>1<\/td><\/tr><tr><td>Strumento di misura pneumatico elettronico<br \/><\/td><td>tre<\/td><\/tr><tr><td>Rilevatore di difetti in polvere di fosforo<br \/><\/td><td>1<\/td><\/tr><\/table><strong>Soluzioni logistiche<\/strong><\/p>\n<p><strong>personalizzato <\/strong><\/p>\n<p><strong>Domande frequenti <\/strong><br \/><strong>uno: Come posso ottenere un campione dell'albero?<\/strong><br \/>Il prezzo del campione sar\u00e0 gratuito se disponibile in magazzino, dovrai solo pagare le spese di spedizione. Va bene.<\/p>\n<p><strong>due: Come posso ottenere il preventivo?<\/strong><br \/>Ricordatevi di fornirci i dettagli per il preventivo: disegno, materiali, peso in eccesso, quantit\u00e0 e richiesta. Possiamo accettare PDF, ISGS, DWG, struttura del file di fase. Se non avete il disegno, vi preghiamo di inviarci il campione. Possiamo anche fare un preventivo in base al vostro campione.<\/p>\n<p><strong>tre: Potete aiutarmi se la mia merce \u00e8 davvero urgente?<\/strong><br \/>S\u00ec, possiamo lavorare pi\u00f9 a lungo e includere un paio di dispositivi per generare questi prodotti se ne hai bisogno con urgenza.<\/p>\n<p><strong>quattro: Offrite campioni? Sono gratuiti o richiedono un supplemento?<\/strong><br \/>In effetti, potremmo offrire il campione gratuitamente, ma non ci faremmo carico delle spese di spedizione.<\/p>\n<p><strong>cinque: Voglio che il nostro design e stile rimangano misteriosi, possiamo mantenere un accordo di riservatezza (NDA)?<\/strong><br \/>Positivo, non mostreremo il design e lo stile di alcun cliente o lo esporremo ad altri uomini e donne, Pignoni ISO normali di qualit\u00e0 sostanziale e longevit\u00e0 che possiamo CZPT NDA<br \/><strong>ENTRA NEL Negozio<\/strong><\/p>\n<p><p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/T_worm_reducer_5.webp\" alt=\"worm reducer\" width=\"800\" \/><\/p>\n<h2>Riduttore a vite senza fine<\/h2>\n<p>Un riduttore a vite senza fine \u00e8 un riduttore che utilizza un treno di ingranaggi a vite senza fine per ridurre la forza richiesta. A differenza dei tradizionali riduttori a vite senza fine, queste unit\u00e0 sono piccole e richiedono basse potenze. Questo ne riduce l'efficienza, ma il loro basso costo e il design compatto contribuiscono a compensare questa carenza. Tuttavia, questi riduttori presentano alcuni svantaggi, tra cui la tendenza al bloccaggio durante la retromarcia.<\/p>\n<h2>alta efficienza<\/h2>\n<p>I riduttori a vite senza fine ad alta efficienza sono ideali per applicazioni in cui elevate prestazioni, ripetibilit\u00e0 e precisione sono essenziali. Sono costituiti da un ingranaggio ipoide in ingresso e da un ingranaggio conico ipoide in uscita. La vite senza fine in ingresso ruota perpendicolarmente a quella in uscita, quindi per ogni giro della vite senza fine in ingresso, l'ingranaggio in uscita compie un giro. Questa disposizione riduce l'attrito (un'altra fonte di perdita di energia) in un riduttore a vite senza fine ad alta efficienza ad almeno due minuti d'arco.<br \/>Rispetto ai riduttori a vite senza fine, i motoriduttori ipoidi offrono diversi vantaggi, tra cui minori costi operativi e maggiore efficienza. Ad esempio, i motoriduttori ipoidi possono trasmettere una coppia maggiore anche con rapporti di riduzione elevati. Inoltre, sono pi\u00f9 efficienti dei riduttori a vite senza fine, il che significa che possono produrre la stessa potenza con un motore pi\u00f9 piccolo.<br \/>Negli ultimi anni, l'efficienza dei riduttori a vite senza fine \u00e8 notevolmente migliorata. I produttori hanno compiuto grandi progressi nei materiali, nella progettazione e nella produzione. I nuovi modelli, inclusi i riduttori a vite senza fine a doppio inviluppo, aumentano l'efficienza dal 3 all'8%. Questi miglioramenti sono stati resi possibili da innumerevoli ore di test e sviluppo. I riduttori a vite senza fine offrono inoltre costi iniziali inferiori e una maggiore capacit\u00e0 di sovraccarico rispetto ai sistemi concorrenti.<br \/>I riduttori a vite senza fine sono popolari perch\u00e9 offrono la massima riduzione in un ingombro ridotto. Le loro dimensioni compatte li rendono ideali per applicazioni di bassa e media potenza e sono poco ingombranti. Offrono inoltre una coppia pi\u00f9 elevata e una migliore tolleranza ai carichi d'urto. Infine, rappresentano un'opzione economica per ridurre il fabbisogno energetico del dispositivo.<\/p>\n<h2>basso rumore<\/h2>\n<p>I riduttori a vite senza fine a bassa rumorosit\u00e0 sono progettati per ridurre la rumorosit\u00e0 nelle applicazioni industriali. Questo tipo di riduttore utilizza meno cuscinetti e pu\u00f2 funzionare in diverse posizioni di montaggio. In genere, un riduttore a vite senza fine \u00e8 un'unit\u00e0 monostadio con un solo albero e un solo ingranaggio. Poich\u00e9 \u00e8 presente un solo ingranaggio, il livello di rumorosit\u00e0 del riduttore a vite senza fine sar\u00e0 inferiore rispetto ad altri tipi.<br \/>Un riduttore a vite senza fine pu\u00f2 essere integrato nel sistema di servosterzo elettrico per ridurre la rumorosit\u00e0. I \u200b\u200briduttori a vite senza fine possono essere realizzati in molti materiali diversi. Il seguente processo in tre fasi spiegher\u00e0 i componenti di un riduttore a vite senza fine a bassa rumorosit\u00e0.<br \/>I riduttori a vite senza fine possono essere montati con un angolo di 90 gradi rispetto all'albero di ingresso e sono disponibili con vari tipi di albero di uscita cavo o pieno. Questi riduttori sono particolarmente utili per le applicazioni in cui la riduzione del rumore \u00e8 essenziale. Sono inoltre composti da meno componenti e hanno dimensioni pi\u00f9 ridotte rispetto ad altri tipi di riduttori, il che li rende pi\u00f9 facili da installare.<br \/>I riduttori a vite senza fine sono disponibili presso diversi produttori. Grazie alla loro ampia disponibilit\u00e0, i produttori di ingranaggi ne mantengono ampie scorte. Il rapporto di riduzione della vite senza fine \u00e8 standard e le dimensioni del riduttore a vite senza fine sono universali. Inoltre, i riduttori a vite senza fine non devono essere dimensionati per uno scopo specifico, a differenza di altri riduttori a interruzione di carico.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/C_worm_reducer_5.webp\" alt=\"worm reducer\" width=\"800\" \/><\/p>\n<h2>tasca<\/h2>\n<p>Un riduttore a vite senza fine \u00e8 un meccanismo di trasmissione con una struttura compatta, un elevato rapporto di trasmissione e una funzione autobloccante in determinate condizioni. I prodotti della serie di riduttori a vite senza fine sono progettati con tecnologia americana e presentano le caratteristiche di trasmissione stabile, elevata capacit\u00e0 portante, bassa rumorosit\u00e0 e struttura compatta. Inoltre, questi prodotti possono fornire un'ampia gamma di alimentatori. Tuttavia, questi riduttori a vite senza fine sono soggetti a perdite, solitamente causate da difetti di progettazione.<br \/>I riduttori a vite senza fine sono disponibili in versione monostadio e bistadio. Il primo tipo \u00e8 costituito da un serbatoio dell'olio che ospita la vite senza fine e i cuscinetti. Il secondo tipo utilizza una vite senza fine con un manicotto per la prima vite senza fine.<br \/>Quando si sceglie un riduttore, \u00e8 essenziale scegliere un'unit\u00e0 di alta qualit\u00e0. Una selezione errata degli ingranaggi pu\u00f2 causare una rapida usura della vite senza fine. Sebbene i riduttori a vite senza fine siano generalmente durevoli, il loro grado di usura dipende dalla selezione e dalle condizioni operative. Ad esempio, l'uso eccessivo, un montaggio improprio o il funzionamento in condizioni estreme possono causare una rapida usura.<br \/>I riduttori a vite senza fine riducono velocit\u00e0 e coppia. Gli ingranaggi a vite senza fine possono essere utilizzati per ridurre la velocit\u00e0 di macchine rotanti o sistemi inerziali. Gli ingranaggi a vite senza fine sono un tipo di ingranaggi conici e le loro superfici di accoppiamento presentano un'elevata forza di scorrimento. Per questo motivo, gli ingranaggi a vite senza fine possono sopportare un peso maggiore rispetto agli ingranaggi cilindrici. Sono anche pi\u00f9 difficili da produrre. Tuttavia, il design di alta qualit\u00e0 degli ingranaggi a vite senza fine li rende una scelta eccellente per applicazioni che richiedono coppia elevata e alta velocit\u00e0 di rotazione.<br \/>I riduttori a vite senza fine possono essere realizzati utilizzando tre tipi di ingranaggi. Per rapporti di riduzione elevati, gli ingranaggi di ingresso e di uscita sono irreversibili. Tuttavia, il riduttore a vite senza fine pu\u00f2 essere realizzato con pi\u00f9 eliche. La trasmissione a vite senza fine a pi\u00f9 principi riduce inoltre al minimo gli effetti frenanti.<\/p>\n<h2>Funzione autobloccante<\/h2>\n<p>Il riduttore a vite senza fine \u00e8 autobloccante per impedire che il carico venga riportato a terra. La funzione autobloccante \u00e8 ottenuta tramite una vite senza fine che ingrana con la cremagliera e il pignone. Quando il carico raggiunge la posizione pi\u00f9 alta, il segnale di retromarcia viene disattivato. Il sottosistema non bloccante riporta il carico nella posizione originale, mentre il sottosistema autobloccante rimane nella posizione pi\u00f9 alta.<br \/>La funzione autobloccante del riduttore a vite senza fine \u00e8 una preziosa caratteristica meccanica. Aiuta a prevenire l'indietreggiamento e consente di risparmiare sui costi dell'impianto frenante. Inoltre, i riduttori a vite senza fine autobloccanti possono essere utilizzati per sollevare e trattenere carichi.<br \/>Il riduttore a vite senza fine autobloccante impedisce all'albero motore di ruotare all'indietro. Funziona sfruttando la forza assiale della vite senza fine. Un riduttore a vite senza fine con funzione autobloccante \u00e8 una macchina utensile molto efficiente.<br \/>I riduttori a vite senza fine possono essere realizzati con due o quattro denti. Le viti senza fine a estremit\u00e0 singola hanno un dente singolo, mentre le viti senza fine a estremit\u00e0 doppia hanno due filettature sull'ingranaggio cilindrico. Una vite senza fine a pi\u00f9 snodi pu\u00f2 avere fino a quattro snodi. I riduttori a vite senza fine possono utilizzare una variet\u00e0 di rapporti di trasmissione, ma il vantaggio principale \u00e8 il design compatto. Hanno una capacit\u00e0 di carico maggiore rispetto a un meccanismo a ingranaggi elicoidali ad albero trasversale.<br \/>La funzione autobloccante del riduttore a vite senza fine pu\u00f2 essere utilizzata anche per gruppi di ingranaggi non necessariamente paralleli all'albero. Impedisce inoltre la retromarcia e consente la marcia in avanti. La funzione autobloccante \u00e8 ottenuta tramite una camma a cricchetto disposta attorno all'ingranaggio. Consente inoltre l'accoppiamento e il disaccoppiamento selettivo tra gli ingranaggi.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/B_worm_reducer_5.webp\" alt=\"worm reducer\" width=\"800\" \/><\/p>\n<h2>rapporto di trasmissione elevato<\/h2>\n<p>I riduttori a vite senza fine rappresentano un modo semplice ed economico per aumentare i rapporti di trasmissione. Queste unit\u00e0 sono costituite da due ingranaggi a vite senza fine: un ingranaggio a vite senza fine in ingresso e uno in uscita. La vite senza fine in ingresso ruota perpendicolarmente all'ingranaggio a vite senza fine in uscita, che a sua volta ruota perpendicolarmente a se stessa. Ad esempio, un riduttore a vite senza fine con rapporto 5:1 richiede 5 giri per ingranaggio a vite senza fine, mentre un riduttore a vite senza fine con rapporto 60:1 ne richiede 60. Tuttavia, questa soluzione \u00e8 soggetta a inefficienza poich\u00e9 l'ingranaggio a vite senza fine \u00e8 soggetto solo ad attrito radente, non volvente.<br \/>Le applicazioni ad alta riduzione richiedono molti giri in ingresso per far ruotare l'ingranaggio in uscita. Al contrario, le applicazioni a bassa velocit\u00e0 in ingresso presentano gli stessi problemi di attrito, sebbene con un diverso livello di attrito. Le viti senza fine che ruotano a basse velocit\u00e0 richiedono pi\u00f9 energia per mantenere il movimento. I riduttori a vite senza fine possono essere utilizzati in molti tipi di sistemi, ma solo alcuni sono adatti per applicazioni ad alta velocit\u00e0.<br \/>Gli ingranaggi a vite senza fine sono difficili da produrre, ma il design a inviluppo \u00e8 la scelta migliore per applicazioni che richiedono elevata precisione, elevata efficienza e gioco minimo. Il design a inviluppo prevede la modifica dei denti degli ingranaggi e delle filettature della vite senza fine per migliorare il contatto superficiale. Tuttavia, questo tipo di ingranaggio a vite senza fine \u00e8 pi\u00f9 costoso da produrre.<br \/>I motoriduttori a vite senza fine hanno rapporti di ingranamento iniziali inferiori rispetto ai motoriduttori ipoidi, il che consente l'utilizzo di motori pi\u00f9 piccoli. Pertanto, un motore a vite senza fine da 1 CV pu\u00f2 raggiungere la stessa potenza di un motore da 1\/2 CV. Uno studio di Agknx ha confrontato due diversi tipi di motoriduttori, confrontandone potenza, coppia e rapporto di trasmissione. I risultati mostrano che il motoriduttore ipoide da 1\/2 CV \u00e8 pi\u00f9 efficiente del motoriduttore a vite senza fine, nonostante la stessa potenza.<br \/>Un altro vantaggio del riduttore a vite senza fine \u00e8 il basso costo iniziale e l'elevata efficienza. Offre rapporti di trasmissione elevati e coppia elevata in un ingombro ridotto, rendendolo ideale per applicazioni di bassa e media potenza. I riduttori a vite senza fine sono anche pi\u00f9 resistenti agli urti.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/gearbox\/gearbox-l1.webp\" alt=\"China 2022 New 45# Steel Electronic Steering Rack Worm Shaft Splined High Precision CNC Turned Shaft Manufacturer     worm gearbox back drive\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/gearbox\/gearbox-l2.webp\" alt=\"China 2022 New 45# Steel Electronic Steering Rack Worm Shaft Splined High Precision CNC Turned Shaft Manufacturer     worm gearbox back drive\"><br \/>curato da Cx 2023-06-19<\/p>","protected":false},"excerpt":{"rendered":"<p>Situation: NewWarranty: 3 monthsRelevant Industries: Developing Content Stores, Manufacturing Plant, Machinery Repair Stores, Food &amp; Beverage Manufacturing unit, Farms, Printing Retailers, Construction works\u00a0, Energy &amp; MiningFat (KG): oneShowroom Spot: NoneOnline video outgoing-inspection: Not ObtainableMachinery Take a look at Report: Not OfferedAdvertising and marketing Kind: New Item 2571Warranty of core components: 6 MonthsMain Components: PLC, Motor, [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[12,676,626,677,20,21,678,284,679,680,681,682,683,684,685,686,687,688,689,690,691,692,693,288,289,694,46,695],"class_list":["post-1541","post","type-post","status-publish","format-standard","hentry","category-gearboxes-worm","tag-china-gearbox","tag-cnc-drive-shaft","tag-cnc-gearbox","tag-cnc-shaft","tag-gearbox","tag-gearbox-china","tag-gearbox-shaft","tag-gearbox-worm-drive","tag-high-precision-gearbox","tag-new-shaft","tag-precision-gearbox","tag-precision-shaft","tag-shaft","tag-shaft-cnc","tag-shaft-drive","tag-shaft-rack","tag-shaft-steel","tag-shaft-steering","tag-shaft-steering-rack","tag-steel-shaft","tag-steering-gearbox","tag-steering-rack-shaft","tag-steering-shaft","tag-worm-drive","tag-worm-drive-gearbox","tag-worm-drive-shaft","tag-worm-gearbox","tag-worm-shaft"],"_links":{"self":[{"href":"https:\/\/gearboxes-worm.top\/it\/wp-json\/wp\/v2\/posts\/1541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearboxes-worm.top\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearboxes-worm.top\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearboxes-worm.top\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearboxes-worm.top\/it\/wp-json\/wp\/v2\/comments?post=1541"}],"version-history":[{"count":0,"href":"https:\/\/gearboxes-worm.top\/it\/wp-json\/wp\/v2\/posts\/1541\/revisions"}],"wp:attachment":[{"href":"https:\/\/gearboxes-worm.top\/it\/wp-json\/wp\/v2\/media?parent=1541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearboxes-worm.top\/it\/wp-json\/wp\/v2\/categories?post=1541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearboxes-worm.top\/it\/wp-json\/wp\/v2\/tags?post=1541"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}