{"id":1527,"date":"2023-04-17T03:21:12","date_gmt":"2023-04-17T03:21:12","guid":{"rendered":"http:\/\/gearboxes-worm.top\/china-nd-tracked-transporter-forward-reverse-gearbox-for-agricultural-machinery-worm-gearbox-efficiency\/"},"modified":"2023-04-17T03:21:12","modified_gmt":"2023-04-17T03:21:12","slug":"china-nd-tracked-transporter-forward-reverse-gearbox-for-agricultural-machinery-worm-gearbox-efficiency","status":"publish","type":"post","link":"https:\/\/gearboxes-worm.top\/lo\/china-nd-tracked-transporter-forward-reverse-gearbox-for-agricultural-machinery-worm-gearbox-efficiency\/","title":{"rendered":"\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0e96\u0ead\u0e8d\u0eab\u0ebc\u0eb1\u0e87\u0ec1\u0e9a\u0e9a\u0e95\u0eb4\u0e94\u0e95\u0eb2\u0ea1 ND \u0e82\u0ead\u0e87\u0e88\u0eb5\u0e99\u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0e82\u0ead\u0e87\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e88\u0eb1\u0e81\u0e81\u0eb0\u0eaa\u0eb4\u0e81\u0eb3"},"content":{"rendered":"<p><h2>\u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd\u0e94\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e95\u0eb0\u0e9e\u0eb1\u0e99<\/h2>\n<p>\n<p>\n<p>\u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd\u0e94\u0e82\u0ead\u0e87\u0ea7\u0eb4\u0e97\u0eb5\u0ec1\u0e81\u0ec9\u0ec4\u0e82<\/p>\n<p><p>\u00a0<\/p>\n<table>\n<tbody>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<p>\u0ec0\u0ea5\u0e81\u0e97\u0eb5\u0ec8\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2:<\/p>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<p>B108F, \u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0e97\u0eb5\u0ec8\u0ea2\u0eb9\u0ec8\u0ead\u0eb2\u0ec4\u0eaa\u0ec0\u0eab\u0ebc\u0eb1\u0e81\u0e9b\u0ead\u0ea1<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<p>\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99 \u0ec1\u0ea5\u0eb0 \u0ec0\u0e9e\u0ebb\u0eb2:<\/p>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<p>OEM \u0e97\u0eb5\u0ec8\u0edc\u0ec9\u0eb2\u0e9e\u0ecd\u0ec3\u0e88<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<p>\u0e84\u0eb3\u0eaa\u0eb3\u0e84\u0eb1\u0e99:<\/p>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<p>\u0e94\u0ec9\u0ea7\u0e8d\u0e9f\u0eb1\u0e87\u0e8a\u0eb1\u0e99 CZPT \u0ec1\u0ea5\u0eb0 Reverse<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><p>\u00a0<\/p>\n<\/p>\n<p>\u00a0<\/p>\n<p>\u0ec2\u0e9b\u0ea3\u0ec4\u0e9f\u0ea5\u0ecc\u0e97\u0eb8\u0ea5\u0eb0\u0e81\u0eb4\u0e94<\/p>\n<p><p>\u0ec3\u0e99\u0e9b\u0eb5 2571, <b>\u0e9a\u0ecd\u0ea5\u0eb4\u0eaa\u0eb1\u0e94 \u0eae\u0ec9\u0eb2\u0e87\u0ec2\u0e88\u0ea7 CZPT \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e88\u0eb1\u0e81 \u0e88\u0eb3\u0e81\u0eb1\u0e94<\/b> \u0ec4\u0e94\u0ec9\u0eae\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e8d\u0ead\u0ea1\u0eae\u0eb1\u0e9a\u0e88\u0eb2\u0e81\u0e97\u0ec8\u0eb2\u0e99\u0e99\u0eb2\u0e87 Iris \u0ec1\u0ea5\u0eb0\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0e99\u0eae\u0ec8\u0ea7\u0ea1\u0e87\u0eb2\u0e99 2 \u0e84\u0ebb\u0e99\u0e82\u0ead\u0e87\u0e99\u0eb2\u0e87 (\u0e97\u0ec8\u0eb2\u0e99 Tian \u0ec1\u0ea5\u0eb0\u0e97\u0ec8\u0eb2\u0e99 Yang) \u0ec3\u0e99\u0ec0\u0ea1\u0eb7\u0ead\u0e87 HangZhou, \u0ec1\u0e82\u0ea7\u0e87 ZhangZhoug, \u0e9b\u0eb0\u0ec0\u0e97\u0e94\u0e88\u0eb5\u0e99, \u0e9c\u0eb9\u0ec9\u0e81\u0ecd\u0ec8\u0e95\u0eb1\u0ec9\u0e87\u0e97\u0eb1\u0e87 3 \u0e84\u0ebb\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0ea7\u0eb4\u0eaa\u0eb0\u0ea7\u0eb0\u0e81\u0ead\u0e99\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0eab\u0ebc\u0eb2\u0e8d\u0e81\u0ea7\u0ec8\u0eb2\u0ea5\u0eb0\u0e94\u0eb1\u0e9a\u0eaa\u0eb0\u0ec0\u0ea5\u0ec8\u0e8d <b>30 \u0e9b\u0eb5 \u0eab\u0ebc\u0eb2\u0e8d\u0e9b\u0eb5<\/b> \u0e82\u0ead\u0e87\u0e81\u0eb2\u0e99\u0e9e\u0ebb\u0e9a\u0e81\u0eb1\u0e99.<\/p>\n<p>\u0e9e\u0ea7\u0e81\u0ec0\u0eae\u0ebb\u0eb2, CZPT Machinery \u0eae\u0eb1\u0e9a\u0eae\u0eb9\u0ec9\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0e81\u0eb2\u0e99\u0e84\u0eb8\u0ec9\u0ea1\u0e84\u0ead\u0e87\u0e84\u0eb8\u0e99\u0e99\u0eb0\u0e9e\u0eb2\u0e9a\u0e97\u0eb1\u0e87\u0edd\u0ebb\u0e94 \u0ec1\u0ea5\u0eb0 \u0e8a\u0eb8\u0ea1\u0e8a\u0ebb\u0e99\u0e81\u0eb2\u0e99\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e81\u0eb2\u0e99\u0e82\u0eb2\u0e8d\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0eaa\u0eb0\u0edc\u0ead\u0e87\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0e84\u0eb8\u0e99\u0e99\u0eb0\u0e9e\u0eb2\u0e9a\u0e94\u0eb5 \u0ec1\u0ea5\u0eb0 \u0e81\u0eb2\u0e99\u0eaa\u0eb0\u0edc\u0eb1\u0e9a\u0eaa\u0eb0\u0edc\u0eb9\u0e99\u0e97\u0eb5\u0ec8\u0edc\u0ec9\u0eb2\u0e9e\u0ecd\u0ec3\u0e88\u0ec3\u0eab\u0ec9\u0ec1\u0e81\u0ec8\u0ea5\u0eb9\u0e81\u0e84\u0ec9\u0eb2. \u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2\u0e82\u0ead\u0e87\u0e9e\u0ea7\u0e81\u0ec0\u0eae\u0ebb\u0eb2\u0ec1\u0ea1\u0ec8\u0e99\u0e8a\u0eb7\u0ec9\u0ec3\u0e99 <b>36 <\/b>\u0e9a\u0eb1\u0e99\u0e94\u0eb2\u0e9b\u0eb0\u0ec0\u0e97\u0e94 \u0ec1\u0ea5\u0eb0 \u0eaa\u0eb0\u0e96\u0eb2\u0e99\u0e97\u0eb5\u0ec8\u0e95\u0ec8\u0eb2\u0e87\u0ec6\u0ec3\u0e99\u0ec2\u0ea5\u0e81, \u0e95\u0eb0\u0eab\u0ebc\u0eb2\u0e94\u0eab\u0ebc\u0eb1\u0e81\u0e82\u0ead\u0e87\u0e9e\u0ea7\u0e81\u0ec0\u0eae\u0ebb\u0eb2\u0ec1\u0ea1\u0ec8\u0e99 <b>\u0e95\u0eb0\u0eab\u0ebc\u0eb2\u0e94\u0ec0\u0ead\u0eb5\u0ea3\u0ebb\u0e9a<\/b>.<\/p>\n<p>\u0ec2\u0eae\u0e87\u0e87\u0eb2\u0e99 \u0ec1\u0ea5\u0eb0 \u0e81\u0ead\u0e87\u0e9b\u0eb0\u0e8a\u0eb8\u0ea1<\/p>\n<p><p><b>\u0e9c\u0eb9\u0ec9\u0e8a\u0ec8\u0ebd\u0ea7\u0e8a\u0eb2\u0e99<\/b><br \/>\u0e8a\u0ec8\u0eb2\u0e87\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e88\u0eb1\u0e81\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0eae\u0eb9\u0ec9\u0eaa\u0eb2\u0ea1\u0eaa\u0eb4\u0e9a\u0e9b\u0eb5. \u0eaa\u0eb0\u0e96\u0eb2\u0e99\u0e97\u0eb5\u0ec8\u0ec0\u0eae\u0eb1\u0e94\u0ea7\u0ebd\u0e81 R&amp;D, \u0eab\u0ec9\u0ead\u0e87\u0e97\u0ebb\u0e94\u0ea5\u0ead\u0e87\u0e81\u0ea7\u0e94\u0eaa\u0ead\u0e9a, \u0ec2\u0eae\u0e87\u0e87\u0eb2\u0e99\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e81\u0eb6\u0e87 CNC \u0e94\u0eb3\u0ec0\u0e99\u0eb5\u0e99\u0e81\u0eb2\u0e99\u0ec2\u0e94\u0e8d\u0e9c\u0eb9\u0ec9\u0e8a\u0ec8\u0ebd\u0ea7\u0e8a\u0eb2\u0e99.<\/p>\n<p><b>\u0eae\u0eb1\u0e9a\u0e9c\u0eb4\u0e94\u0e8a\u0ead\u0e9a<\/b><br \/>\u0eae\u0eb1\u0e9a\u0e9b\u0eb0\u0e81\u0eb1\u0e99 2~10 \u0e9b\u0eb5. \u0e97\u0eb1\u0e94\u0eaa\u0eb0\u0e99\u0eb0\u0e84\u0eb0\u0e95\u0eb4\u0e81\u0eb3\u0e99\u0ebb\u0e94\u0e97\u0eb8\u0e81\u0eaa\u0eb4\u0ec8\u0e87\u0ec0\u0ea5\u0eb1\u0e81\u0ec6\u0e99\u0ec9\u0ead\u0e8d\u0ec6, \u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd\u0e94\u0e81\u0eb3\u0e99\u0ebb\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0eb3\u0ec0\u0ea5\u0eb1\u0e94 \u0eab\u0ebc\u0eb7 \u0e84\u0ea7\u0eb2\u0ea1\u0ea5\u0ebb\u0ec9\u0ea1\u0ec0\u0eab\u0ebc\u0ea7. \u0e9e\u0ea7\u0e81\u0ec0\u0eae\u0ebb\u0eb2\u0eae\u0eb1\u0e9a\u0e9c\u0eb4\u0e94\u0e8a\u0ead\u0e9a\u0e95\u0ecd\u0ec8\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2\u0e82\u0ead\u0e87\u0e97\u0ec8\u0eb2\u0e99.<\/p>\n<p><b>\u0e81\u0eb2\u0e99\u0e9a\u0ecd\u0ea5\u0eb4\u0eab\u0eb2\u0e99\u0e94\u0ec9\u0eb2\u0e99\u0ea7\u0eb4\u0e97\u0eb0\u0e8d\u0eb2\u0eaa\u0eb2\u0e94<\/b><br \/>\u0e97\u0ebb\u0e94\u0eaa\u0ead\u0e9a\u0ec1\u0ea5\u0ec9\u0ea7\u0eae\u0ec9\u0ead\u0e8d %. \u0ea7\u0eb4\u0e97\u0eb5\u0e81\u0eb2\u0e99\u0e88\u0eb1\u0e94\u0e95\u0eb1\u0ec9\u0e87\u0e97\u0eb5\u0ec8\u0ec0\u0e82\u0eb1\u0ec9\u0ea1\u0e87\u0ea7\u0e94 \u0ec1\u0ea5\u0eb0 \u0e81\u0eb2\u0e99\u0e9a\u0ecd\u0ea5\u0eb4\u0eab\u0eb2\u0e99\u0ea7\u0eb1\u0e94\u0eaa\u0eb0\u0e94\u0eb8\u0ea7\u0eb4\u0e97\u0eb0\u0e8d\u0eb2\u0eaa\u0eb2\u0e94\u0e88\u0eb0\u0eab\u0ebc\u0eb8\u0e94\u0e9c\u0ec8\u0ead\u0e99\u0ea5\u0eb2\u0e84\u0eb2\u0e84\u0ea7\u0eb2\u0ea1\u0e9c\u0eb4\u0e94\u0e9e\u0eb2\u0e94.<br \/>\u00a0<\/p>\n<p><p>\u0ec3\u0e9a\u0ea2\u0eb1\u0ec9\u0e87\u0ea2\u0eb7\u0e99<\/p>\n<p>\n<p>\u0e9e\u0ea7\u0e81\u0ec0\u0eae\u0ebb\u0eb2\u0e81\u0eb3\u0ea5\u0eb1\u0e87\u0ec0\u0eae\u0eb1\u0e94\u0ea7\u0ebd\u0e81\u0e81\u0ec8\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0eaa\u0eb7\u0e9a\u0eaa\u0ea7\u0e99 \u0ec1\u0ea5\u0eb0 \u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d \u0ec1\u0ea5\u0eb0 \u0e8a\u0eb4\u0ec9\u0e99\u0eaa\u0ec8\u0ea7\u0e99\u0e81\u0ebb\u0e99\u0e88\u0eb1\u0e81\u0e97\u0eb8\u0e81\u0e9b\u0eb0\u0ec0\u0e9e\u0e94\u0ec0\u0e9b\u0eb1\u0e99\u0ec0\u0ea7\u0ea5\u0eb2\u0eaa\u0eb4\u0e9a\u0ec0\u0ead\u0eb1\u0e94\u0e9b\u0eb5\u0ea1\u0eb2\u0e94\u0ebb\u0e99\u0ec1\u0ea5\u0ec9\u0ea7, \u0ec1\u0ea5\u0eb0\u0ec4\u0e94\u0ec9\u0eae\u0eb1\u0e9a\u0ec3\u0e9a\u0ea2\u0eb1\u0ec9\u0e87\u0ea2\u0eb7\u0e99\u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0ea5\u0ea7\u0ea1\u0ea1\u0eb5 ISO9001, \u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9a\u0eb1\u0e94\u0ec0\u0e81\u0e8d\u0e88\u0eb3\u0e99\u0ea7\u0e99\u0eab\u0ebc\u0eb2\u0e8d, SGS, BV, \u0ec1\u0ea5\u0eb0\u0ead\u0eb7\u0ec8\u0e99\u0ec6.<\/p>\n<p><p>\u0e81\u0eb2\u0e99\u0eab\u0eb8\u0ec9\u0ea1\u0eab\u0ecd\u0ec8 &amp; \u0e81\u0eb2\u0e99\u0e82\u0ebb\u0e99\u0eaa\u0ebb\u0ec8\u0e87 \u0ec1\u0ea5\u0eb0 \u0e81\u0eb2\u0e99\u0e88\u0eb1\u0e94\u0eaa\u0ebb\u0ec8\u0e87<\/p>\n<p>\n<p>\u00a0<\/p>\n<p>\u0e9e\u0eb7\u0ec9\u0e99\u0e97\u0eb5\u0ec8\u0e95\u0ebb\u0ea7\u0ea2\u0ec8\u0eb2\u0e87<\/p>\n<p><p><\/p>\n<p>\u0ec2\u0e94\u0e8d\u0ea7\u0eb4\u0e97\u0eb5\u0e81\u0eb2\u0e99\u0e8d\u0eb5\u0ec8\u0eab\u0ecd\u0ec9 CZPT \u0e82\u0ead\u0e87\u0e9e\u0ea7\u0e81\u0ec0\u0eae\u0ebb\u0eb2 <b>ND<\/b>, CZPT \u0ead\u0eb8\u0e9b\u0eb0\u0e81\u0ead\u0e99\u0eaa\u0eb0\u0edc\u0ead\u0e87\u0ea7\u0eb4\u0e97\u0eb5\u0ec1\u0e81\u0ec9\u0ec4\u0e82\u0e94\u0ec9\u0eb2\u0e99\u0e81\u0eb0\u0eaa\u0eb4\u0e81\u0eb3\u0ec3\u0eab\u0ec9\u0ec1\u0e81\u0ec8\u0e9c\u0eb9\u0ec9\u0e9c\u0eb0\u0ea5\u0eb4\u0e94 \u0ec1\u0ea5\u0eb0 \u0e9c\u0eb9\u0ec9\u0e88\u0eb3\u0edc\u0ec8\u0eb2\u0e8d\u0ead\u0eb8\u0e9b\u0eb0\u0e81\u0ead\u0e99\u0e81\u0eb0\u0eaa\u0eb4\u0e81\u0eb3 CZPT \u0ec2\u0e94\u0e8d\u0e9c\u0ec8\u0eb2\u0e99\u0eaa\u0eb2\u0e8d\u0e81\u0eb2\u0e99\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0ec1\u0e9a\u0e9a\u0e81\u0ec9\u0ebd\u0ea7\u0ea7\u0ebd\u0e99 \/ \u0ec1\u0e9a\u0e9a\u0e81\u0ebb\u0e87 \/ \u0ec1\u0e9a\u0e9a\u0ec0\u0e94\u0eb7\u0ead\u0e8d, \u0ec0\u0e9e\u0ebb\u0eb2\u0e8d\u0eb9\u0ec9, \u0ec0\u0eab\u0ebc\u0eb1\u0e81\u0ec1\u0e9c\u0ec8\u0e99, \u0e81\u0eb0\u0e9a\u0ead\u0e81\u0ec4\u0eae\u0ec2\u0e94\u0ebc\u0ea5\u0eb4\u0e81, \u0ea1\u0ecd\u0ec0\u0e95\u0eb5, \u0ea2\u0eb2\u0e87\u0ea5\u0ebb\u0e94, \u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99, \u0e95\u0ebb\u0ea7\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1\u0edc\u0ead\u0e99 \u0ec1\u0ea5\u0eb0 \u0ead\u0eb7\u0ec8\u0e99\u0ec6. \u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e9b\u0eb1\u0e9a\u0ec1\u0e95\u0ec8\u0e87\u0ec4\u0e94\u0ec9\u0e95\u0eb2\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0e95\u0ec9\u0ead\u0e87\u0e81\u0eb2\u0e99.<\/p>\n<p>\u00a0<\/p>\n<p>\u0e84\u0eb3\u0e96\u0eb2\u0ea1\u0e97\u0eb5\u0ec8\u0e96\u0eb7\u0e81\u0e96\u0eb2\u0ea1\u0ec0\u0ea5\u0eb7\u0ec9\u0ead\u0e8d\u0ec6<\/p>\n<p><p>\u0e96\u0eb2\u0ea1: \u0e97\u0ec8\u0eb2\u0e99\u0e81\u0eb3\u0ea5\u0eb1\u0e87\u0ec0\u0eae\u0eb1\u0e94\u0e97\u0eb8\u0ea5\u0eb0\u0e81\u0eb4\u0e94 \u0eab\u0ebc\u0eb7 \u0e9a\u0ecd\u0ea5\u0eb4\u0eaa\u0eb1\u0e94\u0e9a\u0ecd?<br \/>\u0e81: \u0e9e\u0ea7\u0e81\u0ec0\u0eae\u0ebb\u0eb2\u0ec1\u0ea1\u0ec8\u0e99\u0ec2\u0eae\u0e87\u0e87\u0eb2\u0e99\u0e97\u0eb5\u0ec8\u0ec1\u0e99\u0ec8\u0e99\u0ead\u0e99.<\/p>\n<p>\u0e96\u0eb2\u0ea1: \u0ec0\u0e88\u0ebb\u0ec9\u0eb2\u0ec3\u0eab\u0ec9\u0e95\u0ebb\u0ea7\u0ea2\u0ec8\u0eb2\u0e87\u0e9a\u0ecd? \u0ea1\u0eb1\u0e99\u0e9a\u0ecd\u0ec8\u0ec0\u0eaa\u0e8d\u0e84\u0ec8\u0eb2\u0e97\u0eb1\u0e87\u0edd\u0ebb\u0e94 \u0eab\u0ebc\u0eb7 \u0eab\u0ebc\u0eb2\u0e8d\u0e81\u0ea7\u0ec8\u0eb2\u0e99\u0eb1\u0ec9\u0e99\u0e9a\u0ecd?<br \/>\u0e81: \u0ec1\u0e99\u0ec8\u0e99\u0ead\u0e99, \u0e9e\u0ea7\u0e81\u0ec0\u0eae\u0ebb\u0eb2\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0eaa\u0eb0\u0ec0\u0edc\u0eb5\u0e95\u0ebb\u0ea7\u0ea2\u0ec8\u0eb2\u0e87\u0ec2\u0e94\u0e8d\u0e9a\u0ecd\u0ec8\u0ec0\u0eaa\u0e8d\u0e84\u0ec8\u0eb2\u0ec1\u0e95\u0ec8\u0e9a\u0ecd\u0ec8\u0ec4\u0e94\u0ec9\u0ec0\u0eaa\u0e8d\u0e84\u0ec8\u0eb2\u0e82\u0ebb\u0e99\u0eaa\u0ebb\u0ec8\u0e87.<\/p>\n<p>\u0e96\u0eb2\u0ea1: \u0ec0\u0ea7\u0ea5\u0eb2\u0eaa\u0ebb\u0ec8\u0e87\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2\u0e82\u0ead\u0e87\u0e97\u0ec8\u0eb2\u0e99\u0e94\u0ebb\u0e99\u0e9b\u0eb2\u0e99\u0ec3\u0e94? \u0ec0\u0e87\u0eb7\u0ec8\u0ead\u0e99\u0ec4\u0e82\u0e81\u0eb2\u0e99\u0e8a\u0eb3\u0ea5\u0eb0\u0ec0\u0e87\u0eb4\u0e99\u0e82\u0ead\u0e87\u0e97\u0ec8\u0eb2\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0eab\u0e8d\u0eb1\u0e87?<br \/>\u0e81: \u0ec2\u0e94\u0e8d\u0e97\u0ebb\u0ec8\u0ea7\u0ec4\u0e9b\u0ec1\u0ea1\u0ec8\u0e99 40-45 \u0ec0\u0e97\u0eb7\u0ec8\u0ead. \u0ec0\u0ea7\u0ea5\u0eb2\u0ead\u0eb2\u0e94\u0ec1\u0e95\u0e81\u0e95\u0ec8\u0eb2\u0e87\u0e81\u0eb1\u0e99\u0ec4\u0e9b\u0e95\u0eb2\u0ea1\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e95\u0eb0\u0e9e\u0eb1\u0e99 \u0ec1\u0ea5\u0eb0 \u0ea5\u0eb0\u0e94\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e9b\u0eb1\u0e9a\u0ec1\u0e95\u0ec8\u0e87. \u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2\u0e9b\u0ebb\u0e81\u0e81\u0eb0\u0e95\u0eb4, \u0e81\u0eb2\u0e99\u0e88\u0ec8\u0eb2\u0e8d\u0ec0\u0e87\u0eb4\u0e99\u0ec1\u0ea1\u0ec8\u0e99: \u0eaa\u0eb2\u0ea1\u0eaa\u0eb4\u0e9a% T\/T \u0e81\u0eb3\u0ea5\u0eb1\u0e87\u0e94\u0eb3\u0ec0\u0e99\u0eb5\u0e99\u0e81\u0eb2\u0e99, \u0eaa\u0eb0\u0e96\u0ebd\u0e99\u0ea5\u0eb0\u0e9e\u0eb2\u0e9a\u0e81\u0ec8\u0ead\u0e99\u0e81\u0eb2\u0e99\u0e82\u0ebb\u0e99\u0eaa\u0ebb\u0ec8\u0e87.<\/p>\n<p>\u0e96\u0eb2\u0ea1: MOQ \u0eab\u0ebc\u0eb7\u0ea1\u0eb9\u0e99\u0e84\u0ec8\u0eb2\u0eaa\u0eb0\u0ec0\u0e9e\u0eb2\u0eb0\u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e95\u0eb0\u0e9e\u0eb1\u0e99\u0e82\u0ead\u0e87\u0e97\u0ec8\u0eb2\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0eab\u0e8d\u0eb1\u0e87?<br \/>\u0e81: \u0ec3\u0e99\u0e96\u0eb2\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0ec0\u0e9b\u0eb1\u0e99\u0e9a\u0ecd\u0ea5\u0eb4\u0eaa\u0eb1\u0e94 OEM, \u0e9e\u0ea7\u0e81\u0ec0\u0eae\u0ebb\u0eb2\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0eaa\u0eb0\u0edc\u0ead\u0e87 \u0ec1\u0ea5\u0eb0 \u0e94\u0eb1\u0e94\u0ec1\u0e9b\u0e87\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2\u0e82\u0ead\u0e87\u0e9e\u0ea7\u0e81\u0ec0\u0eae\u0ebb\u0eb2\u0ec3\u0eab\u0ec9\u0ec0\u0edd\u0eb2\u0eb0\u0eaa\u0ebb\u0ea1\u0e81\u0eb1\u0e9a\u0e84\u0ea7\u0eb2\u0ea1\u0e95\u0ec9\u0ead\u0e87\u0e81\u0eb2\u0e99\u0e97\u0eb5\u0ec8\u0eab\u0ebc\u0eb2\u0e81\u0eab\u0ebc\u0eb2\u0e8d. \u0e94\u0eb1\u0ec8\u0e87\u0e99\u0eb1\u0ec9\u0e99, MOQ \u0ec1\u0ea5\u0eb0 \u0ea5\u0eb2\u0e84\u0eb2\u0ead\u0eb2\u0e94\u0e88\u0eb0\u0ea1\u0eb5\u0e81\u0eb2\u0e99\u0e9b\u0ec8\u0ebd\u0e99\u0ec1\u0e9b\u0e87\u0ea2\u0ec8\u0eb2\u0e87\u0eab\u0ebc\u0ea7\u0e87\u0eab\u0ebc\u0eb2\u0e8d\u0e95\u0eb2\u0ea1\u0e82\u0eb0\u0edc\u0eb2\u0e94, \u0ea7\u0eb1\u0e94\u0eaa\u0eb0\u0e94\u0eb8 \u0ec1\u0ea5\u0eb0 \u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd\u0e94\u0e97\u0eb2\u0e87\u0ec0\u0e97\u0eb1\u0e81\u0e99\u0eb4\u0e81\u0ead\u0eb7\u0ec8\u0e99\u0ec6. \u0e95\u0ebb\u0ea7\u0ea2\u0ec8\u0eb2\u0e87, \u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2\u0ea5\u0eb2\u0e84\u0eb2\u0ec1\u0e9e\u0e87 \u0eab\u0ebc\u0eb7 \u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2\u0e97\u0eb3\u0ea1\u0eb0\u0e94\u0eb2\u0ea1\u0eb1\u0e81\u0e88\u0eb0\u0ea1\u0eb5 MOQ \u0e95\u0ec8\u0eb3\u0e81\u0ea7\u0ec8\u0eb2. \u0e97\u0ec8\u0eb2\u0e99\u0e84\u0ea7\u0e99\u0e95\u0eb4\u0e94\u0e95\u0ecd\u0ec8\u0e9e\u0ea7\u0e81\u0ec0\u0eae\u0ebb\u0eb2\u0e94\u0ec9\u0ea7\u0e8d\u0e82\u0ecd\u0ec9\u0ea1\u0eb9\u0e99\u0eaa\u0eb0\u0ec0\u0e9e\u0eb2\u0eb0\u0e97\u0eb5\u0ec8\u0e81\u0ec8\u0ebd\u0ea7\u0e82\u0ec9\u0ead\u0e87\u0e97\u0eb1\u0e87\u0edd\u0ebb\u0e94\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0ec3\u0eab\u0ec9\u0ec4\u0e94\u0ec9\u0ec3\u0e9a\u0eaa\u0eb0\u0ec0\u0edc\u0eb5\u0ea5\u0eb2\u0e84\u0eb2\u0e97\u0eb5\u0ec8\u0e8a\u0eb1\u0e94\u0ec0\u0e88\u0e99\u0e97\u0eb5\u0ec8\u0eaa\u0eb8\u0e94.<\/p>\n<p>\u0e96\u0ec9\u0eb2\u0eab\u0eb2\u0e81\u0e97\u0ec8\u0eb2\u0e99\u0ea1\u0eb5\u0e9a\u0eb1\u0e99\u0eab\u0eb2\u0ead\u0eb7\u0ec8\u0e99, \u0ea2\u0ec8\u0eb2\u0ea5\u0eb7\u0ea1\u0e95\u0eb4\u0e94\u0e95\u0ecd\u0ec8\u0eab\u0eb2\u0e9e\u0ea7\u0e81\u0ec0\u0eae\u0ebb\u0eb2\u0ec4\u0e94\u0ec9.<\/p>\n<p>\u00a0<\/p>\n<p>\n<p>\n<p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr style=\"align-items: baseline;flex-wrap: wrap\" class=\"only-one-priceNum-tr\">\n<td style=\"padding: 0 !important\">\n                                        <span style=\"font-size: 20px;font-family: Roboto, Roboto-Bold;font-weight: 700;text-align: left;color: #e64545;padding-left: 0 !important\"><br \/>\n                                        <span style=\"font-size: 14px;font-family: Roboto, Roboto-Regular;font-weight: 400;color: #888888;margin-right: 10px\">\/ \u0e8a\u0eb4\u0ec9\u0e99<\/span><br \/>\n                                        <span style=\"color: #e6ecf2\">|<\/span>\n                                    <\/td>\n<td class=\"sa-only-property-price only-one-priceNum-price\">\n                                        <span>50 \u0e8a\u0eb4\u0ec9\u0e99<\/span><br \/>\n                                        <span style=\"color: #888888\"><br \/>\n                                            (\u0eaa\u0eb1\u0ec8\u0e87\u0e8a\u0eb7\u0ec9\u0e82\u0eb1\u0ec9\u0e99\u0e95\u0ec8\u0eb3)<br \/>\n                                        <\/span>\n                                    <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">\u0e84\u0ecd\u0eb2\u0eae\u0ec9\u0ead\u0e87\u0eaa\u0eb0\u0eab\u0ea1\u0eb1\u0e81:<\/th>\n<td>\u0ea1\u0ecd\u0ec0\u0e95\u0eb5, \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e88\u0eb1\u0e81, \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e88\u0eb1\u0e81\u0e81\u0eb0\u0eaa\u0eb4\u0e81\u0eb3, \u0eaa\u0eb2\u0e8d\u0e9e\u0eb2\u0e99\u0ea5\u0eb3\u0ea5\u0ebd\u0e87, \u0e81\u0eb2\u0e99\u0e82\u0ebb\u0e99\u0eaa\u0ebb\u0ec8\u0e87\u0e8d\u0eb2\u0e99\u0e9e\u0eb2\u0eab\u0eb0\u0e99\u0eb0\u0e84\u0eb2\u0e99, \u0ec1\u0ea5\u0eb0\u0ead\u0eb7\u0ec8\u0e99\u0ec6<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">\u0edc\u0ec9\u0eb2\u0e97\u0eb5\u0ec8:<\/th>\n<td>\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0e81\u0eb0\u0e88\u0eb2\u0e8d, \u0e9b\u0ec8\u0ebd\u0e99\u0ec1\u0eae\u0e87\u0e9a\u0eb4\u0e94\u0e82\u0ead\u0e87\u0ec4\u0e94, \u0e9b\u0ec8\u0ebd\u0e99\u0e97\u0eb4\u0e94\u0e97\u0eb2\u0e87\u0e82\u0ead\u0e87\u0ec4\u0e94, \u0e81\u0eb2\u0e99\u0e9b\u0ec8\u0ebd\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7, \u0e81\u0eb2\u0e99\u0eab\u0ebc\u0eb8\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7, \u0e81\u0eb2\u0e99\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">\u0eae\u0eb9\u0e9a\u0ec1\u0e9a\u0e9a:<\/th>\n<td>\u0e94\u0ec9\u0ea7\u0e8d\u0e81\u0eb2\u0e99\u0eaa\u0ebb\u0ec8\u0e87\u0e95\u0ecd\u0ec8 \u0ec1\u0ea5\u0eb0 \u0e81\u0eb1\u0e9a\u0e84\u0eb7\u0e99<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">\u0e84\u0ea7\u0eb2\u0ea1\u0ec1\u0e82\u0e87:<\/th>\n<td>\u0edc\u0ec9\u0eb2\u0e9c\u0eb4\u0ea7\u0ec1\u0e82\u0ec9\u0ea7\u0ec1\u0e82\u0e87<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">\u0e81\u0eb2\u0e99\u0e95\u0eb4\u0e94\u0e95\u0eb1\u0ec9\u0e87:<\/th>\n<td>\u0e9b\u0eb0\u0ec0\u0e9e\u0e94\u0ead\u0ead\u0e81\u0e95\u0eb2\u0ea1\u0ec1\u0e99\u0ea7\u0e99\u0ead\u0e99<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">\u0e82\u0eb1\u0ec9\u0e99\u0e95\u0ead\u0e99:<\/th>\n<td>\u0e82\u0eb1\u0ec9\u0e99\u0e95\u0ead\u0e99\u0e94\u0ebd\u0ea7<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">\u0e81\u0eb2\u0e99\u0e9b\u0eb1\u0e9a\u0ec1\u0e95\u0ec8\u0e87:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                            \u0ea1\u0eb5\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                        <a target=\"_blank\" rel=\"nofollow noopener\" href=\" \"><br \/>\n                                        <i class=\"ob-icon icon-fill\"><\/i><br \/>\n                                        <\/a>\n                                    <\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<td colspan=\"1\" rowspan=\"1\" style=\"background-color:#f3f4f8;width:146px;height:20px\">\n<div style=\"border:0px;padding:5px 10px;margin:0px;vertical-align:baseline\">\u0ec0\u0ea5\u0e81\u0e97\u0eb5\u0ea5\u0eb2\u0e8d\u0e81\u0eb2\u0e99:<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\" style=\"width:702px;height:20px\">\n<div style=\"border:0px;padding:5px 10px;margin:0px;vertical-align:baseline\">B108F, \u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0e97\u0eb5\u0ec8\u0ea2\u0eb9\u0ec8\u0ead\u0eb2\u0ec4\u0eaa\u0ec0\u0eab\u0ebc\u0eb1\u0e81<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\" style=\"background-color:#f3f4f8;width:146px;height:20px\">\n<div style=\"border:0px;padding:5px 10px;margin:0px;vertical-align:baseline\">\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99 \u0ec1\u0ea5\u0eb0 \u0ec0\u0e9e\u0ebb\u0eb2:<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\" style=\"width:702px;height:20px\">\n<div style=\"border:0px;padding:5px 10px;margin:0px;vertical-align:baseline\">OEM \u0e97\u0eb5\u0ec8\u0e8d\u0ead\u0ea1\u0eae\u0eb1\u0e9a\u0ec4\u0e94\u0ec9<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\" style=\"background-color:#f3f4f8;width:146px;height:20px\">\n<div style=\"border:0px;padding:5px 10px;margin:0px;vertical-align:baseline\">\u0e84\u0eb3\u0eaa\u0eb3\u0e84\u0eb1\u0e99:<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\" style=\"width:702px;height:20px\">\n<div style=\"border:0px;padding:5px 10px;margin:0px;vertical-align:baseline\">\u0e94\u0ec9\u0ea7\u0e8d\u0e9f\u0eb1\u0e87\u0e8a\u0eb1\u0e99\u0eaa\u0ebb\u0ec8\u0e87\u0e95\u0ecd\u0ec8 \u0ec1\u0ea5\u0eb0 \u0e96\u0ead\u0e8d\u0eab\u0ebc\u0eb1\u0e87<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr style=\"align-items: baseline;flex-wrap: wrap\" class=\"only-one-priceNum-tr\">\n<td style=\"padding: 0 !important\">\n                                        <span style=\"font-size: 20px;font-family: Roboto, Roboto-Bold;font-weight: 700;text-align: left;color: #e64545;padding-left: 0 !important\"><br \/>\n                                        <span style=\"font-size: 14px;font-family: Roboto, Roboto-Regular;font-weight: 400;color: #888888;margin-right: 10px\">\/ \u0e8a\u0eb4\u0ec9\u0e99<\/span><br \/>\n                                        <span style=\"color: #e6ecf2\">|<\/span>\n                                    <\/td>\n<td class=\"sa-only-property-price only-one-priceNum-price\">\n                                        <span>50 \u0e8a\u0eb4\u0ec9\u0e99<\/span><br \/>\n                                        <span style=\"color: #888888\"><br \/>\n                                            (\u0eaa\u0eb1\u0ec8\u0e87\u0e8a\u0eb7\u0ec9\u0e82\u0eb1\u0ec9\u0e99\u0e95\u0ec8\u0eb3)<br \/>\n                                        <\/span>\n                                    <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">\u0e84\u0ecd\u0eb2\u0eae\u0ec9\u0ead\u0e87\u0eaa\u0eb0\u0eab\u0ea1\u0eb1\u0e81:<\/th>\n<td>\u0ea1\u0ecd\u0ec0\u0e95\u0eb5, \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e88\u0eb1\u0e81, \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e88\u0eb1\u0e81\u0e81\u0eb0\u0eaa\u0eb4\u0e81\u0eb3, \u0eaa\u0eb2\u0e8d\u0e9e\u0eb2\u0e99\u0ea5\u0eb3\u0ea5\u0ebd\u0e87, \u0e81\u0eb2\u0e99\u0e82\u0ebb\u0e99\u0eaa\u0ebb\u0ec8\u0e87\u0e8d\u0eb2\u0e99\u0e9e\u0eb2\u0eab\u0eb0\u0e99\u0eb0\u0e84\u0eb2\u0e99, \u0ec1\u0ea5\u0eb0\u0ead\u0eb7\u0ec8\u0e99\u0ec6<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">\u0edc\u0ec9\u0eb2\u0e97\u0eb5\u0ec8:<\/th>\n<td>\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0e81\u0eb0\u0e88\u0eb2\u0e8d, \u0e9b\u0ec8\u0ebd\u0e99\u0ec1\u0eae\u0e87\u0e9a\u0eb4\u0e94\u0e82\u0ead\u0e87\u0ec4\u0e94, \u0e9b\u0ec8\u0ebd\u0e99\u0e97\u0eb4\u0e94\u0e97\u0eb2\u0e87\u0e82\u0ead\u0e87\u0ec4\u0e94, \u0e81\u0eb2\u0e99\u0e9b\u0ec8\u0ebd\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7, \u0e81\u0eb2\u0e99\u0eab\u0ebc\u0eb8\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7, \u0e81\u0eb2\u0e99\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">\u0eae\u0eb9\u0e9a\u0ec1\u0e9a\u0e9a:<\/th>\n<td>\u0e94\u0ec9\u0ea7\u0e8d\u0e81\u0eb2\u0e99\u0eaa\u0ebb\u0ec8\u0e87\u0e95\u0ecd\u0ec8 \u0ec1\u0ea5\u0eb0 \u0e81\u0eb1\u0e9a\u0e84\u0eb7\u0e99<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">\u0e84\u0ea7\u0eb2\u0ea1\u0ec1\u0e82\u0e87:<\/th>\n<td>\u0edc\u0ec9\u0eb2\u0e9c\u0eb4\u0ea7\u0ec1\u0e82\u0ec9\u0ea7\u0ec1\u0e82\u0e87<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">\u0e81\u0eb2\u0e99\u0e95\u0eb4\u0e94\u0e95\u0eb1\u0ec9\u0e87:<\/th>\n<td>\u0e9b\u0eb0\u0ec0\u0e9e\u0e94\u0ead\u0ead\u0e81\u0e95\u0eb2\u0ea1\u0ec1\u0e99\u0ea7\u0e99\u0ead\u0e99<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">\u0e82\u0eb1\u0ec9\u0e99\u0e95\u0ead\u0e99:<\/th>\n<td>\u0e82\u0eb1\u0ec9\u0e99\u0e95\u0ead\u0e99\u0e94\u0ebd\u0ea7<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">\u0e81\u0eb2\u0e99\u0e9b\u0eb1\u0e9a\u0ec1\u0e95\u0ec8\u0e87:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                            \u0ea1\u0eb5\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                        <a target=\"_blank\" rel=\"nofollow noopener\" href=\" \"><br \/>\n                                        <i class=\"ob-icon icon-fill\"><\/i><br \/>\n                                        <\/a>\n                                    <\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<td colspan=\"1\" rowspan=\"1\" style=\"background-color:#f3f4f8;width:146px;height:20px\">\n<div style=\"border:0px;padding:5px 10px;margin:0px;vertical-align:baseline\">\u0ec0\u0ea5\u0e81\u0e97\u0eb5\u0ea5\u0eb2\u0e8d\u0e81\u0eb2\u0e99:<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\" style=\"width:702px;height:20px\">\n<div style=\"border:0px;padding:5px 10px;margin:0px;vertical-align:baseline\">B108F, \u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0e97\u0eb5\u0ec8\u0ea2\u0eb9\u0ec8\u0ead\u0eb2\u0ec4\u0eaa\u0ec0\u0eab\u0ebc\u0eb1\u0e81<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\" style=\"background-color:#f3f4f8;width:146px;height:20px\">\n<div style=\"border:0px;padding:5px 10px;margin:0px;vertical-align:baseline\">\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99 \u0ec1\u0ea5\u0eb0 \u0ec0\u0e9e\u0ebb\u0eb2:<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\" style=\"width:702px;height:20px\">\n<div style=\"border:0px;padding:5px 10px;margin:0px;vertical-align:baseline\">OEM \u0e97\u0eb5\u0ec8\u0e8d\u0ead\u0ea1\u0eae\u0eb1\u0e9a\u0ec4\u0e94\u0ec9<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\" style=\"background-color:#f3f4f8;width:146px;height:20px\">\n<div style=\"border:0px;padding:5px 10px;margin:0px;vertical-align:baseline\">\u0e84\u0eb3\u0eaa\u0eb3\u0e84\u0eb1\u0e99:<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\" style=\"width:702px;height:20px\">\n<div style=\"border:0px;padding:5px 10px;margin:0px;vertical-align:baseline\">\u0e94\u0ec9\u0ea7\u0e8d\u0e9f\u0eb1\u0e87\u0e8a\u0eb1\u0e99\u0eaa\u0ebb\u0ec8\u0e87\u0e95\u0ecd\u0ec8 \u0ec1\u0ea5\u0eb0 \u0e96\u0ead\u0e8d\u0eab\u0ebc\u0eb1\u0e87<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><h2>\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7\u0e82\u0ead\u0e87\u0e95\u0ebb\u0ea7\u0edc\u0ead\u0e99 - \u0eaa\u0eb4\u0ec8\u0e87\u0e97\u0eb5\u0ec8\u0e97\u0ec8\u0eb2\u0e99\u0e95\u0ec9\u0ead\u0e87\u0eae\u0eb9\u0ec9<\/h2>\n<p>\u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0e8a\u0eb7\u0ec9\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0eaa\u0ebb\u0ec8\u0e87\u0e81\u0eb3\u0ea5\u0eb1\u0e87\u0ec1\u0e9a\u0e9a Worm reducer, \u0ea1\u0eb1\u0e99\u0ec0\u0e9b\u0eb1\u0e99\u0eaa\u0eb4\u0ec8\u0e87\u0eaa\u0eb3\u0e84\u0eb1\u0e99\u0e97\u0eb5\u0ec8\u0e88\u0eb0\u0e95\u0ec9\u0ead\u0e87\u0e9e\u0eb4\u0e88\u0eb2\u0ea5\u0eb0\u0e99\u0eb2\u0edc\u0ec9\u0eb2\u0e97\u0eb5\u0ec8 \u0ec1\u0ea5\u0eb0 \u0e84\u0eb8\u0e99\u0eaa\u0ebb\u0ea1\u0e9a\u0eb1\u0e94\u0e82\u0ead\u0e87\u0edc\u0ec8\u0ea7\u0e8d. \u0ea1\u0eb1\u0e99\u0e8d\u0eb1\u0e87\u0eaa\u0eb3\u0e84\u0eb1\u0e99\u0e97\u0eb5\u0ec8\u0e88\u0eb0\u0e95\u0ec9\u0ead\u0e87\u0e84\u0eb3\u0e99\u0eb6\u0e87\u0ec0\u0e96\u0eb4\u0e87\u0ea5\u0eb2\u0e84\u0eb2\u0e82\u0ead\u0e87\u0ea1\u0eb1\u0e99. \u0e9e\u0ea7\u0e81\u0ec0\u0eae\u0ebb\u0eb2\u0e88\u0eb0\u0e9e\u0eb4\u0e88\u0eb2\u0ea5\u0eb0\u0e99\u0eb2\u0ec0\u0e9a\u0eb4\u0ec8\u0e87\u0e9b\u0eb0\u0ec0\u0e9e\u0e94\u0e95\u0ec8\u0eb2\u0e87\u0ec6\u0e82\u0ead\u0e87\u0e81\u0ec8\u0ead\u0e87\u0eaa\u0ebb\u0ec8\u0e87\u0e81\u0eb3\u0ea5\u0eb1\u0e87\u0ec1\u0e9a\u0e9a Worm reducer \u0ec1\u0ea5\u0eb0 \u0e81\u0eb2\u0e99\u0e99\u0eb3\u0ec3\u0e8a\u0ec9\u0e97\u0eb5\u0ec8\u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec3\u0e8a\u0ec9\u0ec4\u0e94\u0ec9. \u0eaa\u0eb4\u0ec8\u0e87\u0e99\u0eb5\u0ec9\u0e88\u0eb0\u0e8a\u0ec8\u0ea7\u0e8d\u0ec3\u0eab\u0ec9\u0e97\u0ec8\u0eb2\u0e99\u0ec0\u0ea5\u0eb7\u0ead\u0e81\u0edc\u0ec8\u0ea7\u0e8d\u0e97\u0eb5\u0ec8\u0ec0\u0edd\u0eb2\u0eb0\u0eaa\u0ebb\u0ea1\u0e81\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e99\u0eb3\u0ec3\u0e8a\u0ec9\u0e82\u0ead\u0e87\u0e97\u0ec8\u0eb2\u0e99.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/T_worm_reducer_1.webp\" alt=\"worm reducer\" width=\"800\" \/><\/p>\n<h2>\u0e84\u0eb8\u0e99\u0eaa\u0ebb\u0ea1\u0e9a\u0eb1\u0e94<\/h2>\n<p>\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0ec0\u0e9b\u0eb1\u0e99\u0e97\u0eb5\u0ec8\u0e99\u0eb4\u0e8d\u0ebb\u0ea1\u0ec3\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0ea1\u0eb7\u0e97\u0eb5\u0ec8\u0e95\u0ec9\u0ead\u0e87\u0e81\u0eb2\u0e99\u0ea2\u0eb8\u0e94\u0ec4\u0ea7, \u0ec0\u0e8a\u0eb1\u0ec8\u0e99: \u0ea5\u0eb4\u0e9f \u0ec1\u0ea5\u0eb0 \u0ea5\u0eb4\u0e9f. \u0ea7\u0eb1\u0e94\u0eaa\u0eb0\u0e94\u0eb8\u0e97\u0eb5\u0ec8\u0ead\u0ec8\u0ead\u0e99\u0e99\u0eb8\u0ec9\u0ea1\u0e82\u0ead\u0e87\u0ea1\u0eb1\u0e99\u0e8a\u0ec8\u0ea7\u0e8d\u0ec3\u0eab\u0ec9\u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0e94\u0eb9\u0e94\u0e8a\u0eb6\u0ea1\u0ec1\u0eae\u0e87\u0e81\u0eb0\u0ec1\u0e97\u0e81, \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0e8a\u0ec8\u0ea7\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0e9c\u0ec8\u0ead\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e9b\u0eb1\u0e99\u0ec4\u0e9b\u0ec4\u0e94\u0ec9\u0e82\u0ead\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0ea5\u0ebb\u0ec9\u0ea1\u0ec0\u0eab\u0ebc\u0ea7. \u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0e8d\u0eb1\u0e87\u0ea1\u0eb5\u0e9b\u0eb0\u0ec2\u0eab\u0e8d\u0e94\u0ec3\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e88\u0eb1\u0e81\u0e97\u0eb5\u0ec8\u0ec0\u0eae\u0eb1\u0e94\u0ea7\u0ebd\u0e81\u0edc\u0eb1\u0e81, \u0ec0\u0e8a\u0eb1\u0ec8\u0e99: \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e9a\u0ebb\u0e94\u0eab\u0eb5\u0e99. \u0e9c\u0eb9\u0ec9\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e9a\u0eb2\u0e87\u0e84\u0ebb\u0e99\u0eaa\u0eb0\u0ec0\u0edc\u0eb5\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0e9e\u0eb4\u0ec0\u0eaa\u0e94\u0e97\u0eb5\u0ec8\u0e9a\u0ecd\u0ec8\u0ea1\u0eb5\u0e81\u0eb2\u0e99\u0e81\u0eb0\u0e97\u0ebb\u0e9a\u0e81\u0eb0\u0ec0\u0e97\u0eb7\u0ead\u0e99 \u0ec1\u0ea5\u0eb0 \u0e81\u0eb2\u0e99\u0eab\u0ebc\u0eb8\u0e94\u0e9c\u0ec8\u0ead\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0ec1\u0ea1\u0ec8\u0e99\u0e8d\u0eb3\u0eaa\u0eb9\u0e87. \u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0ea1\u0eb5\u0e84\u0eb8\u0e99\u0eaa\u0ebb\u0ea1\u0e9a\u0eb1\u0e94\u0eab\u0ebc\u0eb2\u0e81\u0eab\u0ebc\u0eb2\u0e8d, \u0ea5\u0ea7\u0ea1\u0e97\u0eb1\u0e87\u0ea1\u0eb8\u0ea1\u0ec1\u0e81\u0e99 \u0ec1\u0ea5\u0eb0 \u0ea1\u0eb8\u0ea1\u0ea7\u0ebb\u0e87. \u0ea1\u0eb8\u0ea1\u0ec1\u0e81\u0e99\u0e82\u0ead\u0e87\u0edc\u0ead\u0e99\u0e95\u0ec9\u0ead\u0e87\u0e81\u0ebb\u0e87\u0e81\u0eb1\u0e9a\u0ea1\u0eb8\u0ea1\u0ea7\u0ebb\u0e87\u0e82\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0e82\u0eb0\u0edc\u0eb2\u0e94\u0ec3\u0eab\u0e8d\u0ec8. \u0ec0\u0eaa\u0eb1\u0ec9\u0e99\u0e94\u0ec9\u0eb2\u0e8d\u0e82\u0ead\u0e87\u0ea1\u0eb1\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0e8a\u0ec9\u0eb2\u0e8d \u0eab\u0ebc\u0eb7 \u0e82\u0ea7\u0eb2, \u0ec1\u0ea5\u0eb0 \u0ea1\u0eb8\u0ea1\u0e99\u0eb3\u0e82\u0ead\u0e87\u0ea1\u0eb1\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0ec4\u0ea5\u0e8d\u0eb0\u0e97\u0eb2\u0e87\u0e97\u0eb5\u0ec8\u0e88\u0eb8\u0e94\u0edc\u0eb6\u0ec8\u0e87\u0ec3\u0e99\u0ec0\u0eaa\u0eb1\u0ec9\u0e99\u0e94\u0ec9\u0eb2\u0e8d\u0ec0\u0e94\u0eb5\u0e99\u0e97\u0eb2\u0e87\u0ec3\u0e99\u0ea5\u0eb0\u0eab\u0ea7\u0ec8\u0eb2\u0e87\u0e81\u0eb2\u0e99\u0edd\u0eb9\u0e99\u0ea7\u0ebd\u0e99\u0e82\u0ead\u0e87\u0edc\u0ead\u0e99. \u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0ea1\u0eb5\u0ea2\u0eb9\u0ec8\u0ea2\u0ec8\u0eb2\u0e87\u0e81\u0ea7\u0ec9\u0eb2\u0e87\u0e82\u0ea7\u0eb2\u0e87, \u0ec1\u0ea5\u0eb0 \u0e9c\u0eb9\u0ec9\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0ec0\u0e81\u0e8d\u0ea1\u0eb1\u0e81\u0e88\u0eb0\u0eae\u0eb1\u0e81\u0eaa\u0eb2\u0eaa\u0eb2\u0e87\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2\u0e88\u0eb3\u0e99\u0ea7\u0e99\u0eab\u0ebc\u0ea7\u0e87\u0eab\u0ebc\u0eb2\u0e8d. \u0ec0\u0e99\u0eb7\u0ec8\u0ead\u0e87\u0e88\u0eb2\u0e81\u0ea7\u0ec8\u0eb2\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0ec4\u0e94\u0ec9\u0ea1\u0eb2\u0e94\u0e95\u0eb0\u0e96\u0eb2\u0e99, \u0e82\u0eb0\u0edc\u0eb2\u0e94\u0e81\u0eb2\u0e99\u0e95\u0eb4\u0e94\u0e95\u0eb1\u0ec9\u0e87\u0e82\u0ead\u0e87\u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0ec2\u0e94\u0e8d\u0e97\u0ebb\u0ec8\u0ea7\u0ec4\u0e9b\u0ec1\u0ea1\u0ec8\u0e99\u0e84\u0eb7\u0e81\u0eb1\u0e99\u0ec3\u0e99\u0e97\u0ebb\u0ec8\u0ea7\u0e9c\u0eb9\u0ec9\u0e9c\u0eb0\u0ea5\u0eb4\u0e94. \u0e99\u0eb5\u0ec9\u0edd\u0eb2\u0e8d\u0e84\u0ea7\u0eb2\u0ea1\u0ea7\u0ec8\u0eb2\u0e81\u0eb2\u0e99\u0ec0\u0ea5\u0eb7\u0ead\u0e81\u0ead\u0eb1\u0e99\u0edc\u0eb6\u0ec8\u0e87\u0e88\u0eb0\u0e9a\u0ecd\u0ec8\u0eae\u0ebd\u0e81\u0eae\u0ec9\u0ead\u0e87\u0ec3\u0eab\u0ec9\u0e97\u0ec8\u0eb2\u0e99\u0e9b\u0ec8\u0ebd\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0eb9\u0e87, \u0e84\u0ea7\u0eb2\u0ea1\u0e8d\u0eb2\u0ea7, \u0eab\u0ebc\u0eb7 \u0ec0\u0eaa\u0eb1\u0ec9\u0e99\u0e9c\u0ec8\u0eb2\u0eaa\u0eb9\u0e99\u0e81\u0eb2\u0e87\u0e82\u0ead\u0e87\u0ec0\u0e9e\u0ebb\u0eb2\u0e9c\u0ebb\u0e99\u0e9c\u0eb0\u0ea5\u0eb4\u0e94. \u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0e8d\u0eb1\u0e87\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0ead\u0e94\u0e84\u0ec8\u0ead\u0e87\u0e82\u0ead\u0e87\u0ea1\u0eb4\u0e95\u0eb4. \u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0ea1\u0eb5\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0eab\u0ebc\u0eb2\u0e8d. \u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0eae\u0eb1\u0e9a\u0e99\u0ec9\u0eb3\u0edc\u0eb1\u0e81\u0eaa\u0eb9\u0e87 \u0ec1\u0ea5\u0eb0 \u0e84\u0ec8\u0eb2\u0eaa\u0eb3\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0ec1\u0eae\u0e87\u0eaa\u0ebd\u0e94\u0e97\u0eb2\u0e99\u0e95\u0ec8\u0eb3. \u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0e8d\u0eb1\u0e87\u0ea1\u0eb5\u0eae\u0eb9\u0e9a\u0ec1\u0e9a\u0e9a\u0ec1\u0e82\u0ec9\u0ea7\u0e97\u0eb5\u0ec8\u0e8a\u0eb1\u0e94\u0ec0\u0e88\u0e99, \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0e8a\u0ec8\u0ea7\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0e9c\u0ec8\u0ead\u0e99\u0e81\u0eb2\u0e99\u0e9b\u0ec8\u0ebd\u0e99\u0ec1\u0e9b\u0e87\u0e82\u0ead\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7 \u0ec1\u0ea5\u0eb0 \u0e8a\u0ec8\u0ea7\u0e8d\u0ec3\u0eab\u0ec9\u0e81\u0eb2\u0e99\u0ec0\u0eae\u0eb1\u0e94\u0ea7\u0ebd\u0e81\u0e87\u0ebd\u0e9a.<\/p>\n<h2>\u0e9f\u0eb1\u0e87\u0e8a\u0eb1\u0e99\u0e95\u0ec8\u0eb2\u0e87\u0ec6<\/h2>\n<p>\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0ea1\u0eb5\u0edc\u0ec9\u0eb2\u0e97\u0eb5\u0ec8\u0e97\u0eb5\u0ec8\u0ec1\u0e95\u0e81\u0e95\u0ec8\u0eb2\u0e87\u0e81\u0eb1\u0e99. \u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec3\u0e8a\u0ec9\u0ec4\u0e94\u0ec9\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0e99\u0eb3\u0ec3\u0e8a\u0ec9\u0e97\u0eb5\u0ec8\u0eab\u0ebc\u0eb2\u0e81\u0eab\u0ebc\u0eb2\u0e8d. \u0e95\u0ebb\u0ea7\u0ea2\u0ec8\u0eb2\u0e87, \u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec3\u0e8a\u0ec9\u0ec3\u0e99\u0ea5\u0eb4\u0e9f\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0eab\u0ebc\u0eb8\u0e94\u0e9c\u0ec8\u0ead\u0e99\u0e9e\u0eb2\u0ea5\u0eb0\u0ec3\u0e99\u0ea5\u0eb4\u0e9f. \u0ec0\u0e81\u0e8d\u0ec0\u0eab\u0ebc\u0ebb\u0ec8\u0eb2\u0e99\u0eb5\u0ec9\u0e8d\u0eb1\u0e87\u0ea1\u0eb5\u0ea5\u0eb0\u0e94\u0eb1\u0e9a\u0eaa\u0ebd\u0e87\u0e95\u0ecd\u0ec8\u0eb2\u0ec0\u0e9e\u0eb2\u0eb0\u0ea7\u0ec8\u0eb2\u0ea1\u0eb1\u0e99\u0ec0\u0eae\u0eb1\u0e94\u0e94\u0ec9\u0ea7\u0e8d\u0ec2\u0ea5\u0eab\u0eb0\u0e97\u0eb5\u0ec8\u0ec1\u0e95\u0e81\u0e95\u0ec8\u0eb2\u0e87\u0e81\u0eb1\u0e99. \u0e8d\u0eb4\u0ec8\u0e87\u0ec4\u0e9b\u0e81\u0ea7\u0ec8\u0eb2\u0e99\u0eb1\u0ec9\u0e99, \u0ec0\u0e81\u0e8d\u0ec0\u0eab\u0ebc\u0ebb\u0ec8\u0eb2\u0e99\u0eb5\u0ec9\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec3\u0e8a\u0ec9\u0ec3\u0e99\u0ea5\u0eb4\u0e9f\u0ec4\u0e94\u0ec9\u0ec0\u0e9e\u0eb2\u0eb0\u0ea7\u0ec8\u0eb2\u0ea1\u0eb1\u0e99\u0ec0\u0edd\u0eb2\u0eb0\u0eaa\u0ebb\u0ea1\u0e81\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e99\u0eb3\u0ec3\u0e8a\u0ec9\u0e9b\u0eb0\u0ec0\u0e9e\u0e94\u0e99\u0eb5\u0ec9. \u0ea2\u0ec8\u0eb2\u0e87\u0ec3\u0e94\u0e81\u0ecd\u0e95\u0eb2\u0ea1, \u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0e95\u0ec9\u0ead\u0e87\u0e81\u0eb2\u0e99\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ea5\u0eb0\u0e94\u0eb1\u0e9a\u0e94\u0ebd\u0ea7\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0ec3\u0eab\u0ec9\u0ec0\u0eae\u0eb1\u0e94\u0ea7\u0ebd\u0e81\u0ec4\u0e94\u0ec9\u0ea2\u0ec8\u0eb2\u0e87\u0e96\u0eb7\u0e81\u0e95\u0ec9\u0ead\u0e87. \u0e84\u0eb8\u0e99\u0eaa\u0ebb\u0ea1\u0e9a\u0eb1\u0e94\u0e97\u0eb5\u0ec8\u0eaa\u0eb3\u0e84\u0eb1\u0e99\u0ead\u0eb5\u0e81\u0ead\u0eb1\u0e99\u0edc\u0eb6\u0ec8\u0e87\u0e82\u0ead\u0e87\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ea5\u0eb0\u0e94\u0eb1\u0e9a\u0edc\u0ead\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0ea7\u0ec8\u0eb2\u0ea1\u0eb1\u0e99\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec0\u0eae\u0eb1\u0e94\u0ea7\u0ebd\u0e81\u0ec4\u0e94\u0ec9\u0ec3\u0e99\u0e97\u0eb4\u0e94\u0e97\u0eb2\u0e87\u0e81\u0ebb\u0e87\u0e81\u0eb1\u0e99\u0e82\u0ec9\u0eb2\u0ea1. \u0e99\u0eb5\u0ec9\u0edd\u0eb2\u0e8d\u0e84\u0ea7\u0eb2\u0ea1\u0ea7\u0ec8\u0eb2\u0ec0\u0e9e\u0ebb\u0eb2\u0e9b\u0ec9\u0ead\u0e99\u0e82\u0ecd\u0ec9\u0ea1\u0eb9\u0e99\u0eab\u0eb1\u0e99\u0ec4\u0e9b\u0e97\u0eb2\u0e87\u0eab\u0ebc\u0eb1\u0e87, \u0ec3\u0e99\u0e82\u0eb0\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0ec0\u0e9e\u0ebb\u0eb2\u0eaa\u0ebb\u0ec8\u0e87\u0ead\u0ead\u0e81\u0edd\u0eb8\u0e99\u0ec4\u0e9b\u0e97\u0eb2\u0e87\u0edc\u0ec9\u0eb2. \u0e95\u0ebb\u0ea7\u0ea2\u0ec8\u0eb2\u0e87\u0e82\u0ead\u0e87\u0e81\u0eb2\u0e99\u0e99\u0eb3\u0ec3\u0e8a\u0ec9\u0e94\u0eb1\u0ec8\u0e87\u0e81\u0ec8\u0eb2\u0ea7\u0ea5\u0ea7\u0ea1\u0ea1\u0eb5\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e9b\u0e31\u0e48\u0e19\u0ec1\u0e8d\u0e81\u0e94\u0ec9\u0ea7\u0e8d\u0ea1\u0eb7, \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0ec0\u0e9b\u0ebb\u0ec8\u0eb2\u0ea5\u0ebb\u0ea1\u0e82\u0ead\u0e87\u0e8a\u0ec8\u0eb2\u0e87\u0e95\u0eb5\u0ec0\u0eab\u0ebc\u0eb1\u0e81, \u0ec1\u0ea5\u0eb0\u0e95\u0ebb\u0ea7\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1\u0ea5\u0ebb\u0ea1\u0e82\u0ead\u0e87\u0e81\u0ec8\u0ead\u0e87\u0e94\u0ebb\u0e99\u0e95\u0eb5. \u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0ea1\u0eb5\u0ea2\u0eb9\u0ec8\u0ec3\u0e99\u0eae\u0eb9\u0e9a\u0eae\u0ec8\u0eb2\u0e87\u0ec1\u0ea5\u0eb0\u0e82\u0eb0\u0edc\u0eb2\u0e94\u0e97\u0eb5\u0ec8\u0ec1\u0e95\u0e81\u0e95\u0ec8\u0eb2\u0e87\u0e81\u0eb1\u0e99, \u0e95\u0eb1\u0ec9\u0e87\u0ec1\u0e95\u0ec8\u0e8a\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0e88\u0ebb\u0e99\u0ec0\u0e96\u0eb4\u0e87\u0edc\u0ec8\u0ea7\u0e8d\u0e97\u0eb5\u0ec8\u0e95\u0eb4\u0e94\u0e95\u0eb1\u0ec9\u0e87\u0ec4\u0ea7\u0ec9. \u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0e8d\u0eb1\u0e87\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e95\u0eb1\u0ec9\u0e87\u0e84\u0ec8\u0eb2\u0ec0\u0e9b\u0eb1\u0e99\u0e81\u0eb2\u0e99\u0ead\u0ead\u0e81\u0ec1\u0e9a\u0e9a\u0eab\u0ebc\u0eb2\u0e8d\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7. \u0e9c\u0eb9\u0ec9\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e9a\u0eb2\u0e87\u0e84\u0ebb\u0e99\u0e8d\u0eb1\u0e87\u0eaa\u0eb0\u0ec0\u0edc\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0ec1\u0ea1\u0ec8\u0e99\u0e8d\u0eb3\u0e9e\u0eb4\u0ec0\u0eaa\u0e94\u0ec1\u0ea5\u0eb0\u0edc\u0ead\u0e99\u0e97\u0eb5\u0ec8\u0e9a\u0ecd\u0ec8\u0ea1\u0eb5\u0e81\u0eb2\u0e99\u0e81\u0eb0\u0e97\u0ebb\u0e9a\u0e81\u0eb0\u0ec0\u0e97\u0eb7\u0ead\u0e99. \u0eae\u0eb9\u0e9a\u0eae\u0ec8\u0eb2\u0e87\u0ec1\u0e82\u0ec9\u0ea7\u0e82\u0ead\u0e87\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ea5\u0eb0\u0e94\u0eb1\u0e9a\u0edc\u0ead\u0e99\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0eb3\u0e84\u0eb1\u0e99\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0e81\u0eb3\u0e99\u0ebb\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ead\u0eb2\u0e94\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e82\u0ead\u0e87\u0ead\u0eb8\u0e9b\u0eb0\u0e81\u0ead\u0e99. \u0ec2\u0e94\u0e8d\u0e9b\u0ebb\u0e81\u0e81\u0eb0\u0e95\u0eb4\u0ec1\u0ea5\u0ec9\u0ea7, \u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0eaa\u0eb2\u0e8d\u0e94\u0ebd\u0ea7\u0ea1\u0eb5\u0eaa\u0eb2\u0e8d\u0e94\u0ebd\u0ea7\u0e81\u0eb1\u0e99\u0ea2\u0eb9\u0ec8\u0edc\u0ec9\u0eb2\u0ec1\u0e82\u0ec9\u0ea7\u0e8a\u0ec9\u0eb2\u0e8d \u0ec1\u0ea5\u0eb0 \u0e82\u0ea7\u0eb2, \u0ec0\u0e96\u0eb4\u0e87\u0ec1\u0ea1\u0ec8\u0e99\u0ea7\u0ec8\u0eb2\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0eaa\u0eb2\u0e8d\u0e84\u0eb9\u0ec8\u0ea1\u0eb5\u0eaa\u0eb2\u0e8d\u0e97\u0eb5\u0ec8\u0ec1\u0e95\u0e81\u0e95\u0ec8\u0eb2\u0e87\u0e81\u0eb1\u0e99\u0ec3\u0e99\u0ec1\u0e95\u0ec8\u0ea5\u0eb0\u0e94\u0ec9\u0eb2\u0e99. \u0e84\u0eb8\u0e99\u0eaa\u0ebb\u0ea1\u0e9a\u0eb1\u0e94\u0e99\u0eb5\u0ec9\u0e8a\u0ec8\u0ea7\u0e8d\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0e81\u0eb3\u0e88\u0eb1\u0e94\u0e81\u0eb2\u0e99\u0eaa\u0eb9\u0e99\u0ec0\u0eaa\u0e8d\u0e81\u0eb2\u0e99\u0eab\u0ebc\u0eb4\u0ec9\u0e99\u0ec3\u0e99\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99. \u0ea2\u0ec8\u0eb2\u0e87\u0ec3\u0e94\u0e81\u0ecd\u0e95\u0eb2\u0ea1, \u0ea1\u0eb1\u0e99\u0ec0\u0e9b\u0eb1\u0e99\u0eaa\u0eb4\u0ec8\u0e87\u0eaa\u0eb3\u0e84\u0eb1\u0e99\u0e97\u0eb5\u0ec8\u0e84\u0ea7\u0e99\u0eaa\u0eb1\u0e87\u0ec0\u0e81\u0e94\u0ea7\u0ec8\u0eb2\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7\u0edc\u0ead\u0e99\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e94\u0ec9\u0ea7\u0e8d\u0eae\u0eb9\u0e9a\u0eae\u0ec8\u0eb2\u0e87\u0ec1\u0e82\u0ec9\u0ea7\u0e97\u0eb5\u0ec8\u0ec1\u0e95\u0e81\u0e95\u0ec8\u0eb2\u0e87\u0e81\u0eb1\u0e99\u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e99\u0eb3\u0ec3\u0e8a\u0ec9\u0e97\u0eb5\u0ec8\u0ec1\u0e95\u0e81\u0e95\u0ec8\u0eb2\u0e87\u0e81\u0eb1\u0e99. \u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0e97\u0eb2\u0e87\u0ec0\u0ea5\u0eb7\u0ead\u0e81\u0ead\u0eb7\u0ec8\u0e99\u0ec1\u0e97\u0e99\u0ec0\u0e81\u0e8d\u0e97\u0eb3\u0ea1\u0eb0\u0e94\u0eb2. \u0ea1\u0eb1\u0e99\u0ec0\u0eae\u0eb1\u0e94\u0ea7\u0ebd\u0e81\u0ec3\u0e99\u0ea5\u0eb1\u0e81\u0eaa\u0eb0\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0e84\u0ec9\u0eb2\u0e8d\u0e84\u0eb7\u0e81\u0eb1\u0e99\u0e81\u0eb1\u0e9a\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0e82\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99\u0ec0\u0e81\u0e8d\u0e97\u0eb3\u0ea1\u0eb0\u0e94\u0eb2. \u0e82\u0ecd\u0ec9\u0ec4\u0e94\u0ec9\u0e9b\u0ebd\u0e9a\u0e95\u0ebb\u0ec9\u0e99\u0e95\u0ecd\u0e82\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0ea7\u0ec8\u0eb2\u0ea1\u0eb1\u0e99\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0eab\u0ebc\u0eb8\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0edd\u0eb9\u0e99 \u0ec1\u0ea5\u0eb0 \u0ec1\u0eae\u0e87\u0e9a\u0eb4\u0e94\u0e82\u0ead\u0e87\u0ec0\u0e9e\u0ebb\u0eb2\u0edd\u0eb9\u0e99. \u0ea1\u0eb1\u0e99\u0e8d\u0eb1\u0e87\u0ea1\u0eb5\u0e9c\u0ebb\u0e99\u0e9b\u0eb0\u0ec2\u0eab\u0e8d\u0e94\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0ec0\u0e95\u0eb5\u0ea1\u0e84\u0eb7\u0e81\u0eb2\u0e99\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e96\u0ec8\u0eb2\u0e8d\u0ec2\u0ead\u0e99\u0e81\u0eb2\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99\u0ec4\u0eab\u0ea7\u0ec3\u0e99\u0ea1\u0eb8\u0ea1 90 \u0ead\u0ebb\u0e87\u0eaa\u0eb2. \u0e82\u0ecd\u0ec9\u0ec0\u0eaa\u0e8d\u0e9b\u0ebd\u0e9a\u0e9e\u0ebd\u0e87\u0ea2\u0ec8\u0eb2\u0e87\u0e94\u0ebd\u0ea7\u0e82\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0ea7\u0ec8\u0eb2\u0ea1\u0eb1\u0e99\u0e9a\u0ecd\u0ec8\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e9b\u0eb5\u0ec9\u0e99\u0e81\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99\u0ec4\u0eab\u0ea7\u0ec4\u0e94\u0ec9.<\/p>\n<h2>\u0ec1\u0ead\u0eb1\u0e9a\u0e9e\u0ea5\u0eb4\u0ec0\u0e84\u0e8a\u0eb1\u0e99<\/h2>\n<p>\u0e9a\u0ebb\u0e94\u0ea5\u0eb2\u0e8d\u0e87\u0eb2\u0e99\u0e81\u0eb2\u0e99\u0e95\u0eb0\u0eab\u0ebc\u0eb2\u0e94\u0e99\u0eb5\u0ec9\u0ea7\u0eb4\u0ec0\u0e84\u0eb2\u0eb0\u0e95\u0eb0\u0eab\u0ebc\u0eb2\u0e94\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7\u0e82\u0ead\u0e87\u0e95\u0ebb\u0ea7\u0edc\u0ead\u0e99\u0e88\u0eb2\u0e81\u0e97\u0eb1\u0e94\u0eaa\u0eb0\u0e99\u0eb0\u0e97\u0ebb\u0ec8\u0ea7\u0ec2\u0ea5\u0e81. \u0ea1\u0eb1\u0e99\u0e9b\u0eb0\u0e81\u0ead\u0e9a\u0ea1\u0eb5\u0e81\u0eb2\u0e99\u0ea7\u0eb4\u0ec0\u0e84\u0eb2\u0eb0\u0e97\u0eb5\u0ec8\u0eaa\u0ebb\u0ea1\u0e9a\u0eb9\u0e99\u0ec1\u0e9a\u0e9a\u0e81\u0ec8\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0ec1\u0e99\u0ea7\u0ec2\u0e99\u0ec9\u0ea1\u0e82\u0ead\u0e87\u0e95\u0eb0\u0eab\u0ebc\u0eb2\u0e94\u0ec3\u0e99\u0e9b\u0eb0\u0e88\u0eb8\u0e9a\u0eb1\u0e99 \u0ec1\u0ea5\u0eb0 \u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0ebb\u0e94\u0ec3\u0eaa\u0e94\u0ec9\u0eb2\u0e99\u0e81\u0eb2\u0e99\u0ec0\u0e95\u0eb5\u0e9a\u0ec2\u0e95\u0ec3\u0e99\u0ead\u0eb0\u0e99\u0eb2\u0e84\u0ebb\u0e94. \u0ea1\u0eb1\u0e99\u0e8d\u0eb1\u0e87\u0ec3\u0eab\u0ec9\u0e82\u0ecd\u0ec9\u0ea1\u0eb9\u0e99\u0e81\u0ec8\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0e9e\u0eb9\u0ea1\u0eaa\u0eb1\u0e99\u0e96\u0eb2\u0e99\u0e81\u0eb2\u0e99\u0ec1\u0e82\u0ec8\u0e87\u0e82\u0eb1\u0e99 \u0ec1\u0ea5\u0eb0 \u0e9c\u0eb9\u0ec9\u0eab\u0ebc\u0eb4\u0ec9\u0e99\u0eab\u0ebc\u0eb1\u0e81\u0ec3\u0e99\u0ead\u0eb8\u0e94\u0eaa\u0eb2\u0eab\u0eb0\u0e81\u0ecd\u0eb2. \u0e9a\u0ebb\u0e94\u0ea5\u0eb2\u0e8d\u0e87\u0eb2\u0e99\u0e8d\u0eb1\u0e87\u0ec4\u0e94\u0ec9\u0ec0\u0e99\u0eb1\u0ec9\u0e99\u0ec3\u0eab\u0ec9\u0ec0\u0eab\u0eb1\u0e99\u0ec0\u0e96\u0eb4\u0e87\u0e9b\u0eb1\u0e94\u0ec4\u0e88\u0eaa\u0ecd\u0eb2\u0e84\u0eb1\u0e99\u0e97\u0eb5\u0ec8\u0eaa\u0ebb\u0ec8\u0e87\u0e9c\u0ebb\u0e99\u0e81\u0eb0\u0e97\u0ebb\u0e9a\u0e95\u0ecd\u0ec8\u0e81\u0eb2\u0e99\u0ec0\u0e95\u0eb5\u0e9a\u0ec2\u0e95\u0e82\u0ead\u0e87\u0e95\u0eb0\u0eab\u0ebc\u0eb2\u0e94\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7\u0e82\u0ead\u0e87\u0e95\u0ebb\u0ea7\u0edc\u0ead\u0e99.<br \/>\u0e95\u0eb0\u0eab\u0ebc\u0eb2\u0e94\u0e9e\u0eb2\u0e81\u0e9e\u0eb7\u0ec9\u0e99\u0e97\u0eb5\u0ec8\u0eaa\u0eb3\u0e84\u0eb1\u0e99\u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7\u0e82\u0ead\u0e87\u0e95\u0ebb\u0ea7\u0edc\u0ead\u0e99\u0e9b\u0eb0\u0e81\u0ead\u0e9a\u0ea1\u0eb5\u0ead\u0eb2\u0ec0\u0ea1\u0ea5\u0eb4\u0e81\u0eb2\u0ec0\u0edc\u0eb7\u0ead, \u0ead\u0eb2\u0e8a\u0eb5\u0e9b\u0eb2\u0e8a\u0eb5\u0e9f\u0eb4\u0e81, \u0e95\u0eb2\u0ec0\u0ea7\u0eb1\u0e99\u0ead\u0ead\u0e81\u0e81\u0eb2\u0e87 \u0ec1\u0ea5\u0eb0 \u0ead\u0eb2\u0e9f\u0ea3\u0eb4\u0e81\u0eb2, \u0ead\u0eb2\u0ec0\u0ea1\u0ea5\u0eb4\u0e81\u0eb2\u0ea5\u0eb2\u0e95\u0eb4\u0e99, \u0ec1\u0ea5\u0eb0 \u0ec0\u0ead\u0eb5\u0ea3\u0ebb\u0e9a. \u0e95\u0eb0\u0eab\u0ebc\u0eb2\u0e94\u0ec3\u0e99\u0e9e\u0eb2\u0e81\u0e9e\u0eb7\u0ec9\u0e99\u0ec0\u0eab\u0ebc\u0ebb\u0ec8\u0eb2\u0e99\u0eb5\u0ec9\u0ea1\u0eb5\u0ec1\u0e99\u0ea7\u0ec2\u0e99\u0ec9\u0ea1\u0e97\u0eb5\u0ec8\u0e88\u0eb0\u0e8d\u0eb1\u0e87\u0e84\u0ebb\u0e87\u0edd\u0eb1\u0ec9\u0e99\u0e84\u0ebb\u0e87\u0e94\u0ec9\u0ea7\u0e8d\u0e81\u0eb2\u0e99\u0ec0\u0e95\u0eb5\u0e9a\u0ec2\u0e95\u0e97\u0eb5\u0ec8\u0e88\u0eb3\u0e81\u0eb1\u0e94\u0ec3\u0e99\u0ec4\u0ea5\u0e8d\u0eb0\u0eaa\u0ead\u0e87\u0eaa\u0eb2\u0ea1\u0e9b\u0eb5\u0e82\u0ec9\u0eb2\u0e87\u0edc\u0ec9\u0eb2. \u0ec0\u0e81\u0e8d\u0e95\u0ebb\u0ea7\u0edc\u0ead\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0ead\u0eb8\u0e9b\u0eb0\u0e81\u0ead\u0e99\u0e81\u0ebb\u0e99\u0e88\u0eb1\u0e81\u0e82\u0eb0\u0edc\u0eb2\u0e94\u0e99\u0ec9\u0ead\u0e8d\u0e97\u0eb5\u0ec8\u0ec0\u0e8a\u0eb7\u0ec8\u0ead\u0ea1\u0e95\u0ecd\u0ec8\u0e81\u0eb1\u0e9a\u0ec0\u0e81\u0e8d\u0e82\u0eb0\u0edc\u0eb2\u0e94\u0ec3\u0eab\u0e8d\u0ec8\u0e81\u0ea7\u0ec8\u0eb2. \u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0ec0\u0e8a\u0eb7\u0ec8\u0ead\u0ea1\u0e95\u0ecd\u0ec8\u0e81\u0eb1\u0e99, \u0ea1\u0eb1\u0e99\u0e88\u0eb0\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7\u0e9c\u0ebb\u0e99\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e95\u0ec8\u0eb3\u0ec1\u0e95\u0ec8\u0ea1\u0eb5\u0ec1\u0eae\u0e87\u0e9a\u0eb4\u0e94\u0eaa\u0eb9\u0e87. \u0ec0\u0e81\u0e8d\u0ec3\u0e99\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0e82\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99\u0e95\u0ebb\u0ea7\u0edc\u0ead\u0e99\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec0\u0e9b\u0eb1\u0e99\u0ec1\u0e9a\u0e9a\u0e82\u0ea7\u0eb2 \u0eab\u0ebc\u0eb7 \u0e8a\u0ec9\u0eb2\u0e8d, \u0ec1\u0ea5\u0eb0\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0edd\u0eb8\u0e99\u0ec4\u0e94\u0ec9\u0e95\u0eb2\u0ea1\u0ec0\u0e82\u0eb1\u0ea1\u0ec2\u0ea1\u0e87 \u0eab\u0ebc\u0eb7 \u0e97\u0ea7\u0e99\u0ec0\u0e82\u0eb1\u0ea1\u0ec2\u0ea1\u0e87. \u0e82\u0eb6\u0ec9\u0e99\u0e81\u0eb1\u0e9a\u0ea1\u0eb8\u0ea1\u0e81\u0ec9\u0ebd\u0ea7\u0ea7\u0ebd\u0e99\u0e82\u0ead\u0e87\u0e95\u0ebb\u0ea7\u0edc\u0ead\u0e99, \u0e81\u0eb2\u0e99\u0e82\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99\u0e81\u0eb1\u0e9a\u0e84\u0eb7\u0e99 \u0ec1\u0ea5\u0eb0 \u0ec1\u0eae\u0e87\u0eaa\u0ebd\u0e94\u0e97\u0eb2\u0e99\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0eab\u0ebc\u0eb8\u0e94\u0ea5\u0ebb\u0e87\u0ec4\u0e94\u0ec9. \u0ec0\u0e81\u0e8d\u0e95\u0ebb\u0ea7\u0edc\u0ead\u0e99\u0ea1\u0eb5\u0ea2\u0eb9\u0ec8\u0ec3\u0e99\u0edc\u0ec8\u0ea7\u0e8d\u0e97\u0eb5\u0ec8\u0e95\u0eb4\u0e94\u0e95\u0eb1\u0ec9\u0e87\u0ec4\u0ea7\u0ec9 \u0eab\u0ebc\u0eb7 \u0ec3\u0e99\u0e8a\u0eb8\u0e94\u0ec0\u0e81\u0e8d. \u0e9c\u0eb9\u0ec9\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e9a\u0eb2\u0e87\u0e84\u0ebb\u0e99\u0eaa\u0eb0\u0ec0\u0edc\u0eb5\u0ea1\u0ecd\u0ec0\u0e95\u0eb5\u0ec0\u0e8a\u0eb5\u0ec2\u0ea7\u0ec0\u0e95\u0eb5\u0e9b\u0eb0\u0eaa\u0ebb\u0ea1\u0e9b\u0eb0\u0eaa\u0eb2\u0e99 \u0ec1\u0ea5\u0eb0 \u0e81\u0eb2\u0e99\u0ead\u0ead\u0e81\u0ec1\u0e9a\u0e9a\u0eab\u0ebc\u0eb2\u0e8d\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7. \u0e95\u0ebb\u0ea7\u0edc\u0ead\u0e99\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0ec1\u0ea1\u0ec8\u0e99\u0e8d\u0eb3\u0eaa\u0eb9\u0e87 \u0ec1\u0ea5\u0eb0 \u0e9a\u0ecd\u0ec8\u0ea1\u0eb5 backlash \u0ea1\u0eb5\u0ec3\u0eab\u0ec9. \u0ec0\u0e81\u0e8d\u0e95\u0ebb\u0ea7\u0edc\u0ead\u0e99\u0ec0\u0e9b\u0eb1\u0e99\u0e97\u0eb5\u0ec8\u0e99\u0eb4\u0e8d\u0ebb\u0ea1\u0ec2\u0e94\u0e8d\u0eaa\u0eb0\u0ec0\u0e9e\u0eb2\u0eb0\u0ec3\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0ea1\u0eb7\u0e97\u0eb5\u0ec8\u0e95\u0ec9\u0ead\u0e87\u0e81\u0eb2\u0e99\u0ea2\u0eb8\u0e94\u0ec4\u0ea7. \u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0e8d\u0eb1\u0e87\u0e9e\u0ebb\u0e9a\u0ec0\u0eab\u0eb1\u0e99\u0e97\u0ebb\u0ec8\u0ea7\u0ec4\u0e9b\u0ec3\u0e99\u0ea5\u0eb4\u0e9f \u0ec1\u0ea5\u0eb0 \u0ea5\u0eb4\u0e9f. \u0ea5\u0eb1\u0e81\u0eaa\u0eb0\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0ead\u0ec8\u0ead\u0e99\u0e99\u0eb8\u0ec9\u0ea1 \u0ec1\u0ea5\u0eb0 \u0e84\u0eb8\u0e99\u0ea5\u0eb1\u0e81\u0eaa\u0eb0\u0e99\u0eb0\u0e81\u0eb2\u0e99\u0e8a\u0eca\u0ead\u0e81\u0e95\u0ec8\u0eb3\u0e82\u0ead\u0e87\u0ea1\u0eb1\u0e99\u0ec0\u0eae\u0eb1\u0e94\u0ec3\u0eab\u0ec9\u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0ec0\u0edd\u0eb2\u0eb0\u0eaa\u0ebb\u0ea1\u0eab\u0ebc\u0eb2\u0e8d\u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e88\u0eb1\u0e81\u0e9b\u0eb0\u0ec0\u0e9e\u0e94\u0ec0\u0eab\u0ebc\u0ebb\u0ec8\u0eb2\u0e99\u0eb5\u0ec9.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/C_worm_reducer_1.webp\" alt=\"worm reducer\" width=\"800\" \/><\/p>\n<h2>\u0e84\u0ec8\u0eb2\u0ec3\u0e8a\u0ec9\u0e88\u0ec8\u0eb2\u0e8d<\/h2>\n<p>\u0e84\u0ec8\u0eb2\u0ec3\u0e8a\u0ec9\u0e88\u0ec8\u0eb2\u0e8d\u0ec1\u0ea1\u0ec8\u0e99\u0e81\u0eb2\u0e99\u0e9e\u0eb4\u0e88\u0eb2\u0ea5\u0eb0\u0e99\u0eb2\u0e97\u0eb5\u0ec8\u0eaa\u0eb3\u0e84\u0eb1\u0e99\u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0ec0\u0ea5\u0eb7\u0ead\u0e81\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99. \u0ea5\u0eb2\u0e84\u0eb2\u0ec0\u0e9a\u0eb7\u0ec9\u0ead\u0e87\u0e95\u0ebb\u0ec9\u0e99\u0e82\u0ead\u0e87\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0e95\u0ecd\u0ec8\u0eb2\u0e81\u0ea7\u0ec8\u0eb2\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0e9b\u0eb0\u0ec0\u0e9e\u0e94\u0ead\u0eb7\u0ec8\u0e99\u0ec6\u0ea2\u0ec8\u0eb2\u0e87\u0eab\u0ebc\u0ea7\u0e87\u0eab\u0ebc\u0eb2\u0e8d. \u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0e8d\u0eb1\u0e87\u0ea1\u0eb5\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0e94\u0ec9\u0eb2\u0e99\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0eab\u0ebc\u0eb2\u0e8d\u0e81\u0ea7\u0ec8\u0eb2, \u0ec1\u0ea5\u0eb0\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec2\u0eab\u0ebc\u0e94\u0ec0\u0e81\u0eb5\u0e99\u0eaa\u0eb9\u0e87\u0e81\u0ea7\u0ec8\u0eb2\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0e81\u0eb2\u0e99\u0ec1\u0e82\u0ec8\u0e87\u0e82\u0eb1\u0e99. \u0e95\u0ecd\u0ec8\u0ec4\u0e9b\u0e99\u0eb5\u0ec9\u0ec1\u0ea1\u0ec8\u0e99\u0e9b\u0eb1\u0e94\u0ec3\u0e88\u0e97\u0eb5\u0ec8\u0eaa\u0ebb\u0ec8\u0e87\u0e9c\u0ebb\u0e99\u0e81\u0eb0\u0e97\u0ebb\u0e9a\u0e95\u0ecd\u0ec8\u0ea5\u0eb2\u0e84\u0eb2\u0e82\u0ead\u0e87\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99. \u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0ec0\u0eab\u0ebc\u0eb1\u0e81\u0eaa\u0eb0\u0ec1\u0e95\u0e99\u0ec0\u0ea5\u0e94\u0e88\u0eb2\u0e81 Agknx \u0eaa\u0eb0\u0ec0\u0edc\u0eb5\u0e84\u0eb8\u0e99\u0e84\u0ec8\u0eb2\u0e97\u0eb5\u0ec8\u0e94\u0eb5\u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0ec0\u0e87\u0eb4\u0e99. \u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0eaa\u0eb0\u0ec0\u0edc\u0eb5\u0e82\u0eb0\u0edc\u0eb2\u0e94\u0eae\u0eb9\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e82\u0ead\u0e87\u0ec1\u0e9b\u0e99 \u0ec1\u0ea5\u0eb0 \u0eae\u0eb9\u0ead\u0ead\u0e81\u0ec0\u0e9b\u0eb1\u0e99\u0eae\u0eb9, \u0ec0\u0e8a\u0eb1\u0ec8\u0e99\u0e94\u0ebd\u0ea7\u0e81\u0eb1\u0e99\u0e81\u0eb1\u0e9a\u0ec4\u0ea5\u0e8d\u0eb0\u0eab\u0ec8\u0eb2\u0e87\u0e81\u0eb2\u0e87\u0e95\u0eb1\u0ec9\u0e87\u0ec1\u0e95\u0ec8 1.75\u2033 \u0eab\u0eb2 3.25\u2033. \u0e99\u0ead\u0e81\u0ec0\u0edc\u0eb7\u0ead\u0ec4\u0e9b\u0e88\u0eb2\u0e81\u0ea5\u0eb8\u0ec9\u0e99\u0ea1\u0eb2\u0e94\u0e95\u0eb0\u0e96\u0eb2\u0e99, \u0e8a\u0eb8\u0e94\u0e9a\u0eb9\u0e94\u0ec0\u0eab\u0ebc\u0eb1\u0e81\u0eaa\u0eb0\u0ec1\u0e95\u0e99\u0ec0\u0ea5\u0e94\u0e8d\u0eb1\u0e87\u0ea1\u0eb5\u0ec3\u0eab\u0ec9\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99, \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0e8a\u0ec8\u0ea7\u0e8d\u0ec3\u0eab\u0ec9\u0e9c\u0eb9\u0ec9\u0ec3\u0e8a\u0ec9\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec3\u0e8a\u0ec9\u0e82\u0eb0\u0edc\u0eb2\u0e94\u0e82\u0ead\u0e87\u0ec1\u0e81\u0e99\u0eab\u0ebb\u0ea7\u0e97\u0eb5\u0ec8\u0e81\u0ea7\u0ec9\u0eb2\u0e87\u0e82\u0ea7\u0eb2\u0e87\u0e81\u0ea7\u0ec8\u0eb2. \u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0ec0\u0eab\u0ebc\u0eb1\u0e81\u0eaa\u0eb0\u0ec1\u0e95\u0e99\u0ec0\u0ea5\u0e94\u0ea1\u0eb5\u0ea2\u0eb9\u0ec8\u0ec3\u0e99\u0eaa\u0eb0\u0e95\u0eb1\u0ead\u0e81\u0e88\u0eb2\u0e81\u0eaa\u0eb2\u0e87\u0e9e\u0eb2\u0e81\u0e9e\u0eb7\u0ec9\u0e99\u0e97\u0eb1\u0e87\u0eab\u0ebb\u0e81\u0ec1\u0eab\u0ec8\u0e87\u0e82\u0ead\u0e87 Agknx. \u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0e8d\u0eb1\u0e87\u0ea1\u0eb2\u0e9e\u0ec9\u0ead\u0ea1\u0e81\u0eb1\u0e9a\u0e84\u0ec8\u0eb2\u0e82\u0ebb\u0e99\u0eaa\u0ebb\u0ec8\u0e87\u0ea5\u0ec8\u0ea7\u0e87\u0edc\u0ec9\u0eb2\u0e9f\u0ea3\u0eb5. \u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0ea1\u0eb1\u0e81\u0e96\u0eb7\u0e81\u0e99\u0eb3\u0ec3\u0e8a\u0ec9\u0ec3\u0e99\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0eaa\u0ebb\u0ec8\u0e87\u0e81\u0eb3\u0ea5\u0eb1\u0e87, \u0ea5\u0eb4\u0e9f, \u0eaa\u0eb2\u0e8d\u0e9e\u0eb2\u0e99\u0ea5\u0eb3\u0ea5\u0ebd\u0e87, \u0ec1\u0ea5\u0eb0\u0ead\u0eb8\u0e9b\u0eb0\u0e81\u0ead\u0e99\u0e81\u0eb2\u0e99\u0ec1\u0e9e\u0e94. \u0ec3\u0e99\u0e81\u0eb2\u0e99\u0e99\u0eb3\u0ec3\u0e8a\u0ec9\u0ec0\u0eab\u0ebc\u0ebb\u0ec8\u0eb2\u0e99\u0eb5\u0ec9, \u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0e96\u0eb7\u0e81\u0e99\u0eb3\u0ec3\u0e8a\u0ec9\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7\u0e82\u0ead\u0e87\u0e81\u0eb2\u0e99\u0ec2\u0eab\u0ebc\u0e94 \u0ec1\u0ea5\u0eb0 \u0e9b\u0ec9\u0ead\u0e87\u0e81\u0eb1\u0e99\u0e9a\u0ecd\u0ec8\u0ec3\u0eab\u0ec9\u0ea1\u0eb1\u0e99\u0e95\u0ebb\u0e81. \u0ec3\u0e99\u0e82\u0eb0\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0e9a\u0ecd\u0ec8\u0ea1\u0eb5\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0ec0\u0e97\u0ebb\u0ec8\u0eb2\u0e81\u0eb1\u0e9a\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0ec1\u0e9a\u0e9a\u0e81\u0ec9\u0ebd\u0ea7\u0ea7\u0ebd\u0e99, \u0ec1\u0e95\u0ec8\u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0e8d\u0eb1\u0e87\u0ea1\u0eb5\u0e9b\u0eb0\u0ec2\u0eab\u0e8d\u0e94\u0eab\u0ebc\u0eb2\u0e8d\u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e99\u0eb3\u0ec3\u0e8a\u0ec9\u0e97\u0eb5\u0ec8\u0e95\u0ec9\u0ead\u0e87\u0e81\u0eb2\u0e99\u0ec1\u0eae\u0e87\u0e9a\u0eb4\u0e94\u0eaa\u0eb9\u0e87 \u0eab\u0ebc\u0eb7 \u0ead\u0eb1\u0e94\u0e95\u0eb2\u0e9c\u0ebb\u0e99\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0eaa\u0eb9\u0e87. \u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0ec0\u0ea5\u0eb7\u0ead\u0e81\u0e9b\u0eb0\u0ec0\u0e9e\u0e94\u0e82\u0ead\u0e87\u0edc\u0ead\u0e99\u0e97\u0eb5\u0ec8\u0ec0\u0edd\u0eb2\u0eb0\u0eaa\u0ebb\u0ea1\u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e99\u0eb3\u0ec3\u0e8a\u0ec9\u0e82\u0ead\u0e87\u0e97\u0ec8\u0eb2\u0e99, \u0e97\u0ec8\u0eb2\u0e99\u0e84\u0ea7\u0e99\u0e9e\u0eb4\u0e88\u0eb2\u0ea5\u0eb0\u0e99\u0eb2\u0e88\u0eb3\u0e99\u0ea7\u0e99\u0ec1\u0e82\u0ec9\u0ea7\u0e97\u0eb5\u0ec8\u0ea1\u0eb1\u0e99\u0ea1\u0eb5. \u0ea1\u0eb1\u0e99\u0e94\u0eb5\u0e97\u0eb5\u0ec8\u0eaa\u0eb8\u0e94\u0e97\u0eb5\u0ec8\u0e88\u0eb0\u0ec0\u0ea5\u0eb7\u0ead\u0e81\u0edc\u0ead\u0e99\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0ec1\u0e82\u0ec9\u0ea7\u0ea5\u0ea7\u0ea1\u0e97\u0eb1\u0e87\u0edd\u0ebb\u0e94 40 \u0ec1\u0e82\u0ec9\u0ea7 \u0eab\u0ebc\u0eb7 \u0eab\u0ebc\u0eb2\u0e8d\u0e81\u0ea7\u0ec8\u0eb2\u0e99\u0eb1\u0ec9\u0e99.<\/p>\n<h2>\u0ea5\u0eb1\u0e81\u0eaa\u0eb0\u0e99\u0eb0<\/h2>\n<p>\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7\u0e82\u0ead\u0e87\u0e95\u0ebb\u0ea7\u0edc\u0ead\u0e99\u0ea1\u0eb5\u0e82\u0eb0\u0edc\u0eb2\u0e94\u0ec1\u0e95\u0e81\u0e95\u0ec8\u0eb2\u0e87\u0e81\u0eb1\u0e99. \u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0ea1\u0eb5\u0ec0\u0eaa\u0eb1\u0ec9\u0e99\u0e94\u0ec9\u0eb2\u0e8d\u0edc\u0eb6\u0ec8\u0e87, \u0eaa\u0ead\u0e87\u0ec0\u0eaa\u0eb1\u0ec9\u0e99 \u0eab\u0ebc\u0eb7 \u0eab\u0ebc\u0eb2\u0e8d\u0e81\u0ea7\u0ec8\u0eb2\u0e99\u0eb1\u0ec9\u0e99. \u0ec1\u0e95\u0ec8\u0ea5\u0eb0\u0ec0\u0eaa\u0eb1\u0ec9\u0e99\u0e94\u0ec9\u0eb2\u0e8d\u0ea1\u0eb5\u0ea1\u0eb8\u0ea1\u0e99\u0eb3. \u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99\u0eaa\u0eb9\u0e87\u0ea1\u0eb5\u0ec1\u0e82\u0ec9\u0ea7\u0eab\u0ebc\u0eb2\u0e8d\u0e81\u0ea7\u0ec8\u0eb2\u0ec0\u0e81\u0e8d\u0e95\u0ec8\u0eb3, \u0ec1\u0ea5\u0eb0\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99\u0e95\u0ec8\u0eb3\u0ea1\u0eb5\u0ec1\u0e82\u0ec9\u0ea7\u0edc\u0ec9\u0ead\u0e8d\u0e81\u0ea7\u0ec8\u0eb2. \u0e84\u0ea7\u0eb2\u0ea1\u0ec1\u0e95\u0e81\u0e95\u0ec8\u0eb2\u0e87\u0ec0\u0eab\u0ebc\u0ebb\u0ec8\u0eb2\u0e99\u0eb5\u0ec9\u0ec1\u0ea1\u0ec8\u0e99\u0e9c\u0ebb\u0e99\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0ec0\u0e81\u0e8d. \u0e82\u0eb0\u0edc\u0eb2\u0e94\u0e82\u0ead\u0e87\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7\u0e82\u0ead\u0e87\u0e95\u0ebb\u0ea7\u0edc\u0ead\u0e99\u0e84\u0ea7\u0e99\u0ec4\u0e94\u0ec9\u0eae\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0ec0\u0ea5\u0eb7\u0ead\u0e81\u0e95\u0eb2\u0ea1\u0e81\u0eb2\u0e99\u0e99\u0eb3\u0ec3\u0e8a\u0ec9\u0eaa\u0eb0\u0ec0\u0e9e\u0eb2\u0eb0. \u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7\u0e82\u0ead\u0e87\u0e95\u0ebb\u0ea7\u0edc\u0ead\u0e99\u0e8a\u0ec8\u0ea7\u0e8d\u0e9b\u0eb0\u0ea2\u0eb1\u0e94\u0e9e\u0eb7\u0ec9\u0e99\u0e97\u0eb5\u0ec8 \u0ec1\u0ea5\u0eb0 \u0ec3\u0eab\u0ec9\u0ec1\u0eae\u0e87\u0e9a\u0eb4\u0e94\u0eab\u0ebc\u0eb2\u0e8d\u0e82\u0eb6\u0ec9\u0e99. \u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d Agknx \u0ec4\u0e94\u0ec9\u0eaa\u0ec9\u0eb2\u0e87\u0eae\u0eb9\u0e9a\u0ec1\u0e9a\u0e9a\u0eab\u0ebc\u0eb2\u0e81\u0eab\u0ebc\u0eb2\u0e8d\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0ec0\u0ead\u0ebb\u0eb2\u0e8a\u0eb0\u0e99\u0eb0\u0eaa\u0eb4\u0ec8\u0e87\u0e97\u0ec9\u0eb2\u0e97\u0eb2\u0e8d\u0e81\u0eb2\u0e99\u0e8a\u0eb0\u0ea5\u0ecd\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7\u0e97\u0ebb\u0ec8\u0ea7\u0ec4\u0e9b, \u0e95\u0eb1\u0ec9\u0e87\u0ec1\u0e95\u0ec8\u0e95\u0eb0\u0eab\u0ebc\u0eb2\u0e94\u0ea1\u0eb2\u0e94\u0e95\u0eb0\u0e96\u0eb2\u0e99\u0e88\u0ebb\u0e99\u0ec0\u0e96\u0eb4\u0e87\u0e95\u0eb0\u0eab\u0ebc\u0eb2\u0e94\u0e97\u0eb5\u0ec8\u0eaa\u0eb8\u0e82\u0eb0\u0ead\u0eb0\u0e99\u0eb2\u0ec4\u0ea1. \u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0eaa\u0ebb\u0ec8\u0e87\u0e81\u0eb3\u0ea5\u0eb1\u0e87 Agknx \u0ea5\u0eb8\u0ec9\u0e99\u0e97\u0eb5\u0ec8\u0e94\u0eb5\u0e81\u0ea7\u0ec8\u0eb2\u0e96\u0eb7\u0e81\u0ead\u0ead\u0e81\u0ec1\u0e9a\u0e9a\u0ea1\u0eb2\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0ec1\u0e81\u0ec9\u0ec4\u0e82\u0e9a\u0eb1\u0e99\u0eab\u0eb2\u0e81\u0eb2\u0e99\u0e8a\u0eb0\u0ea5\u0ecd\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7\u0e97\u0ebb\u0ec8\u0ea7\u0ec4\u0e9b \u0ec1\u0ea5\u0eb0 \u0e82\u0eb0\u0eab\u0e8d\u0eb2\u0e8d\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0e95\u0ead\u0e9a\u0eaa\u0eb0\u0edc\u0ead\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0e95\u0ec9\u0ead\u0e87\u0e81\u0eb2\u0e99\u0e82\u0ead\u0e87\u0ead\u0eb8\u0e94\u0eaa\u0eb2\u0eab\u0eb0\u0e81\u0eb3\u0eaa\u0eb8\u0e82\u0eb2\u0e9e\u0eb4\u0e9a\u0eb2\u0e99. \u0ec0\u0eaa\u0eb1\u0ec9\u0e99\u0e9c\u0ec8\u0eb2\u0eaa\u0eb9\u0e99\u0e81\u0eb2\u0e87\u0e82\u0ead\u0e87\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7\u0e82\u0ead\u0e87\u0e95\u0ebb\u0ea7\u0edc\u0ead\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0e81\u0eb2\u0e99\u0e9e\u0eb4\u0e88\u0eb2\u0ea5\u0eb0\u0e99\u0eb2\u0e97\u0eb5\u0ec8\u0eaa\u0eb3\u0e84\u0eb1\u0e99. \u0ec0\u0eaa\u0eb1\u0ec9\u0e99\u0e9c\u0ec8\u0eb2\u0eaa\u0eb9\u0e99\u0e81\u0eb2\u0e87\u0e82\u0ead\u0e87\u0ea1\u0eb1\u0e99\u0e84\u0ea7\u0e99\u0e88\u0eb0\u0ec0\u0e97\u0ebb\u0ec8\u0eb2\u0e81\u0eb1\u0e9a \u0eab\u0ebc\u0eb7 \u0ec3\u0eab\u0e8d\u0ec8\u0e81\u0ea7\u0ec8\u0eb2\u0ec0\u0eaa\u0eb1\u0ec9\u0e99\u0e9c\u0ec8\u0eb2\u0eaa\u0eb9\u0e99\u0e81\u0eb2\u0e87\u0e82\u0ead\u0e87\u0ea5\u0ecd\u0ec9\u0e9a\u0ebb\u0e94 \u0eab\u0ebc\u0eb7 \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0ea1\u0eb7\u0ec0\u0ea5\u0eb1\u0e81\u0e99\u0ec9\u0ead\u0e8d. \u0eaa\u0eb4\u0ec8\u0e87\u0e99\u0eb5\u0ec9\u0e88\u0eb0\u0eaa\u0ebb\u0ec8\u0e87\u0e9c\u0ebb\u0e99\u0e81\u0eb0\u0e97\u0ebb\u0e9a\u0e95\u0ecd\u0ec8\u0ea1\u0eb8\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0e81\u0ebb\u0e94\u0e94\u0eb1\u0e99. \u0ea1\u0eb8\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0e81\u0ebb\u0e94\u0e94\u0eb1\u0e99\u0ec3\u0e99\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7\u0e82\u0ead\u0e87\u0e95\u0ebb\u0ea7\u0edc\u0ead\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0e82\u0eb6\u0ec9\u0e99\u0e81\u0eb1\u0e9a\u0eab\u0ebc\u0eb2\u0e8d\u0e9b\u0eb1\u0e94\u0ec3\u0e88, \u0ea5\u0ea7\u0ea1\u0e97\u0eb1\u0e87\u0ec0\u0eaa\u0eb1\u0ec9\u0e99\u0e9c\u0ec8\u0eb2\u0eaa\u0eb9\u0e99\u0e81\u0eb2\u0e87 \u0ec1\u0ea5\u0eb0 \u0ea1\u0eb8\u0ea1\u0e99\u0eb3. \u0ec0\u0eaa\u0eb1\u0ec9\u0e99\u0e9c\u0ec8\u0eb2\u0eaa\u0eb9\u0e99\u0e81\u0eb2\u0e87\u0e82\u0ead\u0e87\u0ea5\u0ecd\u0ec9\u0e9a\u0ebb\u0e94 \u0eab\u0ebc\u0eb7 \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0ea1\u0eb7\u0e8d\u0eb1\u0e87\u0ea1\u0eb5\u0e9c\u0ebb\u0e99\u0e81\u0eb0\u0e97\u0ebb\u0e9a\u0e95\u0ecd\u0ec8\u0ec2\u0e9b\u0ea3\u0ec4\u0e9f\u0ea5\u0ecc\u0e82\u0ead\u0e87\u0e95\u0ebb\u0ea7\u0edc\u0ead\u0e99. \u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7\u0e82\u0ead\u0e87\u0e95\u0ebb\u0ea7\u0edc\u0ead\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0e9e\u0ebb\u0e9a\u0ec0\u0ea5\u0eb7\u0ec9\u0ead\u0e8d. \u0e9c\u0eb9\u0ec9\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb2\u0e8d\u0e84\u0ebb\u0e99\u0ea1\u0eb5\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7\u0ec0\u0eab\u0ebc\u0ebb\u0ec8\u0eb2\u0e99\u0eb5\u0ec9\u0e88\u0eb3\u0e99\u0ea7\u0e99\u0eab\u0ebc\u0ea7\u0e87\u0eab\u0ebc\u0eb2\u0e8d. \u0ec0\u0e99\u0eb7\u0ec8\u0ead\u0e87\u0e88\u0eb2\u0e81\u0ec0\u0e81\u0e8d\u0ec4\u0e94\u0ec9\u0e96\u0eb7\u0e81\u0ea1\u0eb2\u0e94\u0e95\u0eb0\u0e96\u0eb2\u0e99, \u0e82\u0eb0\u0edc\u0eb2\u0e94\u0e81\u0eb2\u0e99\u0e95\u0eb4\u0e94\u0e95\u0eb1\u0ec9\u0e87\u0e82\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0e88\u0eb6\u0ec8\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0ec0\u0ea5\u0eb7\u0ec8\u0ead\u0e87\u0e97\u0eb3\u0ea1\u0eb0\u0e94\u0eb2\u0ec3\u0e99\u0e9a\u0eb1\u0e99\u0e94\u0eb2\u0e9c\u0eb9\u0ec9\u0e9c\u0eb0\u0ea5\u0eb4\u0e94. \u0eaa\u0eb4\u0ec8\u0e87\u0e99\u0eb5\u0ec9\u0ec0\u0eae\u0eb1\u0e94\u0ec3\u0eab\u0ec9\u0ea1\u0eb1\u0e99\u0e87\u0ec8\u0eb2\u0e8d\u0e95\u0ecd\u0ec8\u0e81\u0eb2\u0e99\u0ec0\u0ea5\u0eb7\u0ead\u0e81\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e99\u0eb3\u0ec3\u0e8a\u0ec9\u0e82\u0ead\u0e87\u0e97\u0ec8\u0eb2\u0e99. \u0e99\u0ead\u0e81\u0e88\u0eb2\u0e81\u0e99\u0eb1\u0ec9\u0e99, \u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0e8d\u0eb1\u0e87\u0e87\u0ec8\u0eb2\u0e8d\u0e95\u0ecd\u0ec8\u0e81\u0eb2\u0e99\u0e95\u0eb4\u0e94\u0e95\u0eb1\u0ec9\u0e87 \u0ec1\u0ea5\u0eb0 \u0e9a\u0eb3\u0ea5\u0eb8\u0e87\u0eae\u0eb1\u0e81\u0eaa\u0eb2.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/B_worm_reducer_1.webp\" alt=\"worm reducer\" width=\"800\" \/><\/p>\n<h2>\u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0e95\u0ebb\u0ea7\u0edc\u0ead\u0e99<\/h2>\n<p>\u0ec2\u0e94\u0e8d\u0e97\u0ebb\u0ec8\u0ea7\u0ec4\u0e9b\u0ec1\u0ea5\u0ec9\u0ea7, \u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0ea1\u0eb1\u0e81\u0ec3\u0e8a\u0ec9\u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0ec0\u0e81\u0e8d. \u0ea1\u0eb5\u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb2\u0e8d\u0e8a\u0eb0\u0e99\u0eb4\u0e94\u0ec3\u0eab\u0ec9\u0ec0\u0ea5\u0eb7\u0ead\u0e81, \u0ea5\u0ea7\u0ea1\u0e97\u0eb1\u0e87\u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0eaa\u0eb1\u0e87\u0ec0\u0e84\u0eb2\u0eb0, \u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0ec2\u0e9e\u0ea5\u0eb5\u0ead\u0eb2\u0ea5\u0e84\u0eb5\u0ea5\u0eb5\u0e99\u0ec4\u0e81\u0e84\u0ecd, \u0ec1\u0ea5\u0eb0\u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0ec1\u0eae\u0ec8\u0e97\u0eb2\u0e94. \u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0e97\u0eb5\u0ec8\u0ec3\u0e8a\u0ec9\u0ec3\u0e99\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0e95\u0ec9\u0ead\u0e87\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0edc\u0eb7\u0e94\u0e97\u0eb5\u0ec8\u0ec0\u0edd\u0eb2\u0eb0\u0eaa\u0ebb\u0ea1\u0e81\u0eb1\u0e9a\u0ec0\u0e81\u0e8d. \u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0e9a\u0eb2\u0e87\u0e8a\u0eb0\u0e99\u0eb4\u0e94\u0ea1\u0eb5\u0eaa\u0eb2\u0e99\u0e81\u0eb1\u0e94\u0e81\u0ec8\u0ead\u0e99\u0eab\u0ebc\u0eb2\u0e8d\u0e81\u0ea7\u0ec8\u0eb2\u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0ead\u0eb7\u0ec8\u0e99\u0ec6 \u0ec1\u0ea5\u0eb0 \u0e84\u0ea7\u0e99\u0eab\u0ebc\u0eb5\u0e81\u0ea5\u0ec8\u0ebd\u0e87\u0e96\u0ec9\u0eb2\u0eaa\u0eb0\u0e9e\u0eb2\u0e9a\u0ec1\u0ea7\u0e94\u0ea5\u0ec9\u0ead\u0ea1\u0ec0\u0e9b\u0eb1\u0e99\u0e9e\u0eb4\u0e94. \u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0e82\u0ead\u0e87\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0e95\u0ec9\u0ead\u0e87\u0ec4\u0e94\u0ec9\u0eae\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e9b\u0ebb\u0e81\u0e9b\u0ec9\u0ead\u0e87\u0e88\u0eb2\u0e81\u0e81\u0eb2\u0e99\u0e81\u0eb1\u0e94\u0e81\u0ec8\u0ead\u0e99, \u0e81\u0eb2\u0e99\u0eaa\u0ea7\u0ea1\u0ec3\u0eaa\u0ec8 \u0ec1\u0ea5\u0eb0 \u0ec1\u0eae\u0e87\u0eaa\u0ebd\u0e94\u0e97\u0eb2\u0e99. \u0e94\u0eb5\u0e97\u0eb5\u0ec8\u0eaa\u0eb8\u0e94\u0e97\u0eb5\u0ec8\u0e88\u0eb0\u0ec0\u0ea5\u0eb7\u0ead\u0e81\u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0eab\u0ea5\u0ecd\u0ec8\u0ea5\u0eb7\u0ec8\u0e99\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0e81\u0eb2\u0e99\u0eaa\u0ebd\u0e94\u0e97\u0eb2\u0e99\u0e95\u0ec8\u0eb3, \u0e97\u0ebb\u0e99\u0e97\u0eb2\u0e99\u0e95\u0ecd\u0ec8\u0e81\u0eb2\u0e99\u0e9c\u0eb8\u0e9e\u0eb1\u0e87\u0eaa\u0eb9\u0e87 \u0ec1\u0ea5\u0eb0 \u0e9b\u0ec9\u0ead\u0e87\u0e81\u0eb1\u0e99\u0e81\u0eb2\u0e99\u0eaa\u0ea7\u0ea1\u0ec3\u0eaa\u0ec8\u0ec4\u0e94\u0ec9\u0e94\u0eb5. \u0ec3\u0e99\u0e82\u0eb0\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0ec1\u0eae\u0ec8\u0e97\u0eb2\u0e94\u0ec0\u0e9b\u0eb1\u0e99\u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0eab\u0ea5\u0ecd\u0ec8\u0ea5\u0eb7\u0ec8\u0e99\u0e97\u0eb5\u0ec8\u0e9e\u0ebb\u0e9a\u0ec0\u0ea5\u0eb7\u0ec9\u0ead\u0e8d\u0e97\u0eb5\u0ec8\u0eaa\u0eb8\u0e94, \u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0e9e\u0eb7\u0ec9\u0e99\u0e96\u0eb2\u0e99\u0eaa\u0eb1\u0e87\u0ec0\u0e84\u0eb2\u0eb0\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e9b\u0eb1\u0e9a\u0e9b\u0eb8\u0e87\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0e82\u0ead\u0e87\u0ec0\u0e81\u0e8d \u0ec1\u0ea5\u0eb0 \u0eab\u0ebc\u0eb8\u0e94\u0ead\u0eb8\u0e99\u0eab\u0eb0\u0e9e\u0eb9\u0ea1\u0e9b\u0eb0\u0e95\u0eb4\u0e9a\u0eb1\u0e94\u0e81\u0eb2\u0e99. \u0e99\u0eb5\u0ec9\u0ec1\u0ea1\u0ec8\u0e99\u0e8d\u0ec9\u0ead\u0e99\u0ea7\u0ec8\u0eb2\u0e81\u0ebb\u0e94\u0ead\u0eb1\u0e94\u0e95\u0eb2 Arrhenius \u0ea5\u0eb0\u0e9a\u0eb8\u0ea7\u0ec8\u0eb2\u0e9b\u0eb0\u0e95\u0eb4\u0e81\u0eb4\u0ea5\u0eb4\u0e8d\u0eb2\u0ec0\u0e84\u0ea1\u0eb5\u0ec3\u0e99\u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e82\u0eb6\u0ec9\u0e99\u0eaa\u0ead\u0e87\u0ec0\u0e97\u0ebb\u0ec8\u0eb2\u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0e97\u0eb8\u0e81\u0ec6 10 \u0ead\u0ebb\u0e87\u0eaa\u0eb2\u0ec0\u0e8a\u0e99\u0e8a\u0ebd\u0e94\u0e97\u0eb5\u0ec8\u0ead\u0eb8\u0e99\u0eab\u0eb0\u0e9e\u0eb9\u0ea1\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e82\u0eb6\u0ec9\u0e99. \u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0ea1\u0eb5\u0eab\u0ebc\u0eb2\u0e8d\u0e82\u0eb0\u0edc\u0eb2\u0e94 \u0ec1\u0ea5\u0eb0 \u0e81\u0eb2\u0e99\u0e95\u0eb1\u0ec9\u0e87\u0e84\u0ec8\u0eb2. \u200b\u200b\u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0ec0\u0edd\u0eb2\u0eb0\u0eaa\u0ebb\u0ea1\u0e81\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e88\u0eb1\u0e81 \u0ec1\u0ea5\u0eb0 \u0ead\u0eb8\u0e9b\u0eb0\u0e81\u0ead\u0e99\u0e97\u0eb8\u0e81\u0e9b\u0eb0\u0ec0\u0e9e\u0e94. \u0e81\u0eb2\u0e99\u0ec0\u0ea5\u0eb7\u0ec8\u0ead\u0e99\u0ea5\u0eb0\u0eab\u0ea7\u0ec8\u0eb2\u0e87\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99 \u0ec1\u0ea5\u0eb0 \u0ec0\u0e9e\u0ebb\u0eb2\u0ead\u0ead\u0e81\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0ec1\u0eae\u0e87\u0e9a\u0eb4\u0e94\u0eaa\u0eb9\u0e87 \u0ec1\u0ea5\u0eb0 \u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0eaa\u0eb9\u0e87. \u0e96\u0ec9\u0eb2\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7\u0eaa\u0ebb\u0ec8\u0e87\u0e81\u0eb3\u0ea5\u0eb1\u0e87\u0e95\u0ecd\u0ec8\u0eb2, \u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99 \u0ec1\u0ea5\u0eb0 \u0ec0\u0e9e\u0ebb\u0eb2\u0eaa\u0ebb\u0ec8\u0e87\u0e81\u0eb3\u0ea5\u0eb1\u0e87\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ea5\u0ea7\u0ea1\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e81\u0eb1\u0e99\u0ec4\u0e94\u0ec9\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94. \u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0edc\u0ead\u0e99\u0e95\u0ec9\u0ead\u0e87\u0e81\u0eb2\u0e99\u0e81\u0eb2\u0e99\u0e9b\u0ec8\u0ebd\u0e99\u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0edc\u0ec9\u0ead\u0e8d\u0e81\u0ea7\u0ec8\u0eb2\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0ec0\u0e81\u0e8d\u0e9b\u0eb0\u0ec0\u0e9e\u0e94\u0ead\u0eb7\u0ec8\u0e99\u0ec6. \u0ea2\u0ec8\u0eb2\u0e87\u0ec3\u0e94\u0e81\u0ecd\u0e95\u0eb2\u0ea1, \u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e97\u0eb3\u0ea1\u0eb0\u0e94\u0eb2\u0e84\u0ea7\u0e99\u0e9b\u0ec8\u0ebd\u0e99\u0e97\u0eb8\u0e81\u0ec6\u0eab\u0ebb\u0e81\u0ec0\u0e94\u0eb7\u0ead\u0e99 \u0eab\u0ebc\u0eb7 2,500 \u0e8a\u0ebb\u0ec8\u0ea7\u0ec2\u0ea1\u0e87, \u0ead\u0eb1\u0e99\u0ec3\u0e94\u0ec0\u0e81\u0eb5\u0e94\u0e82\u0eb6\u0ec9\u0e99\u0e81\u0ec8\u0ead\u0e99. \u0e99\u0ead\u0e81\u0e88\u0eb2\u0e81\u0e99\u0eb5\u0ec9, \u0ea1\u0eb1\u0e99\u0ec0\u0e9b\u0eb1\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0e84\u0eb4\u0e94\u0e97\u0eb5\u0ec8\u0e94\u0eb5\u0e97\u0eb5\u0ec8\u0e88\u0eb0\u0e95\u0eb4\u0e94\u0e95\u0eb2\u0ea1\u0e81\u0ea7\u0e94\u0e81\u0eb2\u0ea5\u0eb0\u0e94\u0eb1\u0e9a\u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0e9b\u0eb0\u0e88\u0eb3\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0e9b\u0ec9\u0ead\u0e87\u0e81\u0eb1\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0ea5\u0ebb\u0ec9\u0ea1\u0ec0\u0eab\u0ebc\u0ea7\u0e82\u0ead\u0e87\u0e81\u0ec8\u0ead\u0e87\u0ec0\u0e81\u0e8d\u0e97\u0eb5\u0ec8\u0e81\u0ec8\u0ebd\u0ea7\u0e82\u0ec9\u0ead\u0e87\u0e81\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0eab\u0ebc\u0ecd\u0ec8\u0ea5\u0eb7\u0ec8\u0e99. \u0ea1\u0eb1\u0e99\u0e8d\u0eb1\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0e81\u0eb2\u0e99\u0eaa\u0eb0\u0eab\u0ebc\u0eb2\u0e94\u0e97\u0eb5\u0ec8\u0e88\u0eb0\u0ec3\u0e8a\u0ec9\u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0eaa\u0eb1\u0e87\u0ec0\u0e84\u0eb2\u0eb0, \u0ec0\u0e9e\u0eb2\u0eb0\u0ea1\u0eb1\u0e99\u0e88\u0eb0\u0ec3\u0e8a\u0ec9\u0ec4\u0e94\u0ec9\u0e94\u0ebb\u0e99\u0e81\u0ea7\u0ec8\u0eb2\u0ea5\u0eb0\u0eab\u0ea7\u0ec8\u0eb2\u0e87\u0e81\u0eb2\u0e99\u0e9b\u0ec8\u0ebd\u0e99\u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/Worm_Reducer_l1.webp\" alt=\"China ND Tracked Transporter Forward Reverse Gearbox for Agricultural Machinery     worm gearbox efficiency\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/Worm_Reducer_l2.webp\" alt=\"China ND Tracked Transporter Forward Reverse Gearbox for Agricultural Machinery     worm gearbox efficiency\"><br \/>\u0e9a\u0eb1\u0e99\u0e99\u0eb2\u0e97\u0eb4\u0e81\u0eb2\u0e99\u0ec2\u0e94\u0e8d CX 2023-04-17<\/p>","protected":false},"excerpt":{"rendered":"<p>\u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd\u0e94\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e95\u0eb0\u0e9e\u0eb1\u0e99 \u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd\u0e94\u0ea7\u0eb4\u0e97\u0eb5\u0ec1\u0e81\u0ec9\u0ec4\u0e82 \u0ec0\u0ea5\u0e81\u0e97\u0eb5\u0ec8\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2: B108F, \u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99\u0ec0\u0e81\u0e8d \u0ec1\u0ea5\u0eb0 \u0ec0\u0e9e\u0ebb\u0eb2\u0ec0\u0e81\u0e8d\u0e82\u0ead\u0e87\u0e95\u0ebb\u0ea7\u0ec0\u0eae\u0eb7\u0ead\u0e99\u0ec0\u0eab\u0ebc\u0eb1\u0e81\u0eab\u0ea5\u0ecd\u0ec8: OEM \u0e97\u0eb5\u0ec8\u0edc\u0ec9\u0eb2\u0e9e\u0ecd\u0ec3\u0e88 \u0e84\u0eb3\u0eaa\u0eb3\u0e84\u0eb1\u0e99: \u0ea1\u0eb5 CZPT \u0ec1\u0ea5\u0eb0 \u0edc\u0ec9\u0eb2\u0e97\u0eb5\u0ec8\u0e9b\u0eb5\u0ec9\u0e99\u0e81\u0eb1\u0e9a\u0e81\u0eb1\u0e99 \u0e82\u0ecd\u0ec9\u0ea1\u0eb9\u0e99\u0e97\u0eb8\u0ea5\u0eb0\u0e81\u0eb4\u0e94 \u0ec3\u0e99\u0e9b\u0eb5 2571, \u0e9a\u0ecd\u0ea5\u0eb4\u0eaa\u0eb1\u0e94 HangZhou CZPT Machinery Co.,ltd \u0ec4\u0e94\u0ec9\u0eae\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e8d\u0ead\u0ea1\u0eae\u0eb1\u0e9a\u0e88\u0eb2\u0e81\u0e97\u0ec8\u0eb2\u0e99\u0e99\u0eb2\u0e87 Iris \u0ec1\u0ea5\u0eb0 \u0e9e\u0eb0\u0e99\u0eb1\u0e81\u0e87\u0eb2\u0e99 2 \u0e84\u0ebb\u0e99\u0e82\u0ead\u0e87\u0e99\u0eb2\u0e87 (\u0e97\u0ec8\u0eb2\u0e99 Tian \u0ec1\u0ea5\u0eb0 \u0e97\u0ec8\u0eb2\u0e99 Yang) \u0ec3\u0e99\u0ec0\u0ea1\u0eb7\u0ead\u0e87 HangZhou, \u0ec1\u0e82\u0ea7\u0e87 ZHangZhoug, \u0e9b\u0eb0\u0ec0\u0e97\u0e94\u0e88\u0eb5\u0e99, \u0e97\u0eb1\u0e87 3 \u0e9c\u0eb9\u0ec9\u0e81\u0ecd\u0ec8\u0e95\u0eb1\u0ec9\u0e87 [\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[501,502,504,12,505,579,20,21,580,581,509,510,524,511,582,583,584,46,514],"class_list":["post-1527","post","type-post","status-publish","format-standard","hentry","category-gearboxes-worm","tag-agricultural-gearbox","tag-agricultural-machinery-china","tag-china-agricultural-machinery","tag-china-gearbox","tag-china-machinery","tag-forward-reverse-gearbox","tag-gearbox","tag-gearbox-china","tag-gearbox-for-agricultural-machinery","tag-gearbox-reverse","tag-machinery","tag-machinery-china","tag-machinery-for","tag-machinery-machinery","tag-reverse-forward-gearbox","tag-reverse-gearbox","tag-tracked-gearbox","tag-worm-gearbox","tag-worm-gearbox-agricultural"],"_links":{"self":[{"href":"https:\/\/gearboxes-worm.top\/lo\/wp-json\/wp\/v2\/posts\/1527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearboxes-worm.top\/lo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearboxes-worm.top\/lo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearboxes-worm.top\/lo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearboxes-worm.top\/lo\/wp-json\/wp\/v2\/comments?post=1527"}],"version-history":[{"count":0,"href":"https:\/\/gearboxes-worm.top\/lo\/wp-json\/wp\/v2\/posts\/1527\/revisions"}],"wp:attachment":[{"href":"https:\/\/gearboxes-worm.top\/lo\/wp-json\/wp\/v2\/media?parent=1527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearboxes-worm.top\/lo\/wp-json\/wp\/v2\/categories?post=1527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearboxes-worm.top\/lo\/wp-json\/wp\/v2\/tags?post=1527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}